{"id":1465800,"date":"2025-08-23T22:03:38","date_gmt":"2025-08-24T05:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/"},"modified":"2025-08-23T22:03:38","modified_gmt":"2025-08-24T05:03:38","slug":"aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/","title":{"rendered":"El pasatiempo que les est\u00e1 costando a los j\u00f3venes decenas de miles de d\u00f3lares"},"content":{"rendered":"<p>Cuando Ethan perdi\u00f3 US$ 11.000 en un solo partido de hockey el pasado marzo, fue la gota que colm\u00f3 el vaso.<\/p>\n<p>Ethan, quien prefiri\u00f3 no compartir su apellido por miedo a perder su trabajo, apost\u00f3 \u201cel spread\u201d en un partido de hockey entre los Hurricanes y los Flames. Eso significa que un equipo no solo debe ganar, sino que debe hacerlo por m\u00e1s de cierta cantidad de puntos. Los Hurricanes s\u00ed ganaron, pero solo por un punto, no por los dos o m\u00e1s que Ethan necesitaba.<\/p>\n<p>Ethan, de 27 a\u00f1os, se derrumb\u00f3 y llor\u00f3 frente a su novia. Ya no pod\u00eda m\u00e1s.<\/p>\n<p>Lo que comenz\u00f3 como un pasatiempo casual en la universidad con sus compa\u00f1eros de fraternidad, de alguna manera se convirti\u00f3 en una adicci\u00f3n grave al juego que dur\u00f3 a\u00f1os. Y Ethan quer\u00eda salir de eso.<\/p>\n<p>Aunque su historia es extrema, Ethan es un ejemplo de una tendencia cada vez m\u00e1s preocupante en Estados Unidos.<\/p>\n<p>Una encuesta nacional reciente de votantes registrados en EE.UU., realizada por la Universidad Fairleigh Dickinson, encontr\u00f3 que una cuarta parte de los hombres menores de 30 a\u00f1os apuestan en deportes en l\u00ednea, y el 10 % de los hombres de 18 a 30 a\u00f1os tiene un problema de juego, en comparaci\u00f3n con solo el 3 % de la poblaci\u00f3n general.<\/p>\n<p>En esa encuesta, el 68 % de las personas que apuestan en deportes en l\u00ednea reportaron al menos una conducta de juego considerada da\u00f1ina, como pedir dinero prestado para apostar o decir que el juego les ha causado problemas financieros o emocionales.<\/p>\n<p>El Dr. Timothy Fong, profesor de psiquiatr\u00eda en UCLA y certificado en psiquiatr\u00eda de adicciones, le dijo a Nick Watt de CNN que los j\u00f3venes son particularmente vulnerables a las apuestas deportivas porque sus l\u00f3bulos frontales a\u00fan no pueden manejar la impulsividad y la toma de riesgos. Watt explora m\u00e1s a fondo en \u201cThe Whole Story with Anderson Cooper\u201d, que se transmite a las 10:00 p.m. este domingo 24 de agosto.<\/p>\n<p>\u201cSabemos que cuanto m\u00e1s joven se empieza a apostar en deportes, mayor es la probabilidad de desarrollar un problema de juego cuando sean mayores\u201d, dijo Fong.<\/p>\n<p>Eso fue lo que le pas\u00f3 a Ethan.<\/p>\n<p>Cuando Ethan estaba en la universidad, las apuestas deportivas a\u00fan no eran legales, as\u00ed que \u00e9l y sus compa\u00f1eros de fraternidad usaban sitios ilegales para apostar.<\/p>\n<p>En 2018, la Corte Suprema dictamin\u00f3 que los estados deb\u00edan decidir si legalizaban las apuestas deportivas. Eso marc\u00f3 un punto de inflexi\u00f3n para la industria, y ahora es legal en 38 estados y en la ciudad Washington.<\/p>\n<p>De repente, Ethan y otros como \u00e9l tuvieron acceso a varias aplicaciones legales. Eso hizo que su adicci\u00f3n se intensificara r\u00e1pidamente: renunci\u00f3 a su trabajo de ventas, donde casi ganaba seis cifras, en agosto pasado, decidido a convertir las apuestas deportivas en su ocupaci\u00f3n a tiempo completo.<\/p>\n<p>En septiembre pasado, hac\u00eda lo que hac\u00eda todas las ma\u00f1anas: tomaba caf\u00e9 con su novia y revisaba las predicciones diarias de los partidos. Esa vez se top\u00f3 con un influencer de apuestas deportivas que presum\u00eda de ganar partido tras partido, y aunque Ethan normalmente no ca\u00eda en ese tipo de contenido, le intrig\u00f3 lo que parec\u00eda ser una prueba contundente. El influencer promocionaba sus selecciones para cinco partidos ese d\u00eda.<\/p>\n<p>\u201cApost\u00e9 US$ 2.000 en cada partido y los perd\u00ed todos\u201d, le cuenta Ethan a CNN.<\/p>\n<p>Ethan entr\u00f3 en un \u201cfrenes\u00ed ansioso\u201d. Al d\u00eda siguiente, hizo una apuesta arriesgada de US$ 10.000 en un partido de los Chicago Bears e intent\u00f3 ocultar el miedo paralizante a su novia. Ethan logr\u00f3 ganar US$ 20.000 y salir de los n\u00fameros rojos. Se sinti\u00f3 aliviado; y de vuelta en el juego. Los meses siguientes fueron una vor\u00e1gine de altibajos, victorias y derrotas.<\/p>\n<p>Poco a poco, se dio cuenta de que ni siquiera pod\u00eda disfrutar las victorias en medio de tanta ansiedad.<\/p>\n<p>La p\u00e9rdida de US$ 11.000 en el partido de hockey entre los Hurricanes y los Flames en marzo fue el final. Decidi\u00f3 \u201cautoexcluirse\u201d oficialmente, prohibi\u00e9ndose a s\u00ed mismo apostar en todas las aplicaciones, lo que significa que ya no podr\u00eda volver a iniciar sesi\u00f3n.<\/p>\n<p>Hace 20 a\u00f1os, la palabra \u201capuestas\u201d evocaba m\u00e1quinas tragamonedas en Las Vegas y mesas de p\u00f3ker en Atlantic City: en su mayor\u00eda personas mayores y, tal vez, alguna despedida de soltera ocasional, jugando en persona.<\/p>\n<p>Ahora, las apuestas en l\u00ednea y las apuestas deportivas han ampliado significativamente esa definici\u00f3n. Aunque los casinos todav\u00eda representan la mayor parte de las ganancias de la industria del juego, las apuestas deportivas est\u00e1n creciendo r\u00e1pidamente: los ingresos en ese sector alcanzaron los <a href=\"https:\/\/www.americangaming.org\/2024-commercial-gaming-revenue-reaches-71-9b-marking-fourth-straight-year-of-record-revenue\/\">US$ 13.700 millones en 2024<\/a>, un aumento del 25 % en solo un a\u00f1o, seg\u00fan la Asociaci\u00f3n Estadounidense de Juegos de Azar.<\/p>\n<p>Gran parte de esta actividad ocurre en aplicaciones de apuestas deportivas. El sitio de FanDuel dice que la app tiene 12 millones de usuarios registrados, mientras que DraftKings confirm\u00f3 a CNN que tienen 10 millones de usuarios.<\/p>\n<p>Las apuestas tambi\u00e9n se han entrelazado profundamente con las propias ligas, con anuncios durante los partidos y comentaristas deportivos discutiendo diferentes probabilidades. El sitio web de FanDuel presume asociaciones con la mayor\u00eda de las principales ligas profesionales estadounidenses y varios equipos.<\/p>\n<p>El cambio hacia las apuestas en aplicaciones tambi\u00e9n implica un cambio hacia apostadores m\u00e1s j\u00f3venes. FanDuel y DraftKings no quisieron compartir la distribuci\u00f3n por edades de sus usuarios, pero varias encuestas indican un perfil demogr\u00e1fico m\u00e1s joven.<\/p>\n<p>El estudio de Fairleigh Dickinson mostr\u00f3 que las apuestas deportivas en l\u00ednea se concentran entre los hombres j\u00f3venes: solo el 10 % de los votantes encuestados apost\u00f3 en deportes o carreras en l\u00ednea el a\u00f1o pasado. Pero para los hombres menores de 45 a\u00f1os, esa cifra sube al 26 %.<\/p>\n<p>Para algunos de esos hombres j\u00f3venes, entran en juego tendencias econ\u00f3micas m\u00e1s amplias.<\/p>\n<p>Su apuesta se convierte en adicci\u00f3n en parte porque sienten que no pueden comprar casas ni pagar pr\u00e9stamos estudiantiles con sus salarios actuales, dice Jonathan D. Cohen, Ph.D, autor de \u201cLosing Big: America\u2019s Reckless Bet on Sports Gambling\u201d.<\/p>\n<p>\u201cPor eso ves a todas estas personas apostando en estas situaciones locas\u201d, dijo Cohen. \u201cNo les importa tener US$ 10.000. Prefieren tener una posibilidad remota de ganar US$ 100.000\u201d.<\/p>\n<p>No est\u00e1 claro si las apuestas deportivas han contagiado a una nueva generaci\u00f3n con problemas de juego, ya que los datos disponibles suelen provenir de encuestas autoinformadas como la de FDU. Jugadores An\u00f3nimos tampoco recopila informaci\u00f3n de sus miembros por razones de privacidad, pero el grupo afirma que ha visto un aumento de adictos j\u00f3venes.<\/p>\n<p>\u201cVimos un gran aumento. Muchos j\u00f3venes est\u00e1n entrando\u2026 es un n\u00famero mucho mayor que en el pasado\u201d, seg\u00fan el presidente de relaciones p\u00fablicas de Jugadores An\u00f3nimos, quien prefiere no dar su nombre ya que el liderazgo del grupo est\u00e1 compuesto por miembros.<\/p>\n<p>Un m\u00e9todo para medir la adicci\u00f3n son los datos de autoexclusi\u00f3n: cu\u00e1ntas personas se proh\u00edben a s\u00ed mismas apostar, como Ethan. En Pensilvania, uno de los pocos estados que <a href=\"https:\/\/archive.ph\/o\/qVxCG\/https:\/\/gamingcontrolboard.pa.gov\/compulsive-and-problem-gambling\">mantiene datos p\u00fablicos y completos sobre el programa<\/a>, solo el 6 % de las personas que se autoexcluyeron de todas las apuestas en 2015 ten\u00edan entre 21 y 34 a\u00f1os; una d\u00e9cada despu\u00e9s, esa cifra es ahora del 28 %.<\/p>\n<p>Joe Maloney, portavoz de la Asociaci\u00f3n Estadounidense de Juegos de Azar, no cree que la autoexclusi\u00f3n indique necesariamente adicci\u00f3n. Puede simplemente significar que un apostador quiere tomarse un descanso.<\/p>\n<p>Tambi\u00e9n cit\u00f3 una <a href=\"https:\/\/archive.ph\/o\/qVxCG\/https:\/\/www.ncpgambling.org\/wp-content\/uploads\/2025\/06\/NGAGE-3.0-Key-Findings-FINAL-FOR-DISTRIBUTION.pdf\">encuesta reciente del Consejo Nacional sobre Problemas de Juego<\/a> que mostr\u00f3 que el juego problem\u00e1tico no ha aumentado mucho desde la decisi\u00f3n de la Corte Suprema, y que el n\u00famero de personas que apuestan en deportes tambi\u00e9n se mantuvo similar, independientemente de su estatus legal.<\/p>\n<p>Kevin Vo, que ahora tiene 25 a\u00f1os, nunca hab\u00eda apostado antes de hacer su primera apuesta en partidos de baloncesto a trav\u00e9s de FanDuel hace tres a\u00f1os. Acababa de conseguir su primer trabajo, en finanzas, y ten\u00eda algo de dinero para jugar.<\/p>\n<p>\u201cHonestamente, ca\u00ed en la presi\u00f3n de mis amigos: literalmente todos publicaban sus parlays (en redes sociales)\u201d, dijo Vo.<\/p>\n<p>Un parlay combina dos o m\u00e1s apuestas individuales en una sola, y todas las condiciones deben cumplirse para que el apostador gane dinero; es una estrategia de alto riesgo y alta recompensa que Vo encontr\u00f3 atractiva.<\/p>\n<p>Como Ethan, ve\u00eda los partidos con amigos que tambi\u00e9n hab\u00edan apostado al resultado y participaba en chats grupales dedicados \u00fanicamente a las apuestas del d\u00eda. El pasatiempo casual de Vo se intensific\u00f3 en cuesti\u00f3n de meses.<\/p>\n<p>\u201cTodos los d\u00edas ten\u00eda un parlay\u201d, cuenta Vo a CNN.<\/p>\n<p>Al principio, Vo solo apostaba en deportes que conoc\u00eda bien, pero a medida que se adentraba m\u00e1s en las aplicaciones de apuestas, empez\u00f3 a apostar en opciones de las que no sab\u00eda nada. En un momento lleg\u00f3 a apostar en baloncesto polaco, en partidos que ni siquiera pod\u00eda ver.<\/p>\n<p>\u201cLlegu\u00e9 a perder un par de miles en un momento. Pude recuperarlo. Y luego todo se vino abajo\u201d, dijo Vo.<\/p>\n<p>Vo pas\u00f3 meses entre altibajos con sus victorias y derrotas, y finalmente se retir\u00f3 cuando solo hab\u00eda perdido unos pocos miles y acababa de mudarse a su propio apartamento.<\/p>\n<p>En un correo electr\u00f3nico a CNN, FanDuel describi\u00f3 varias formas en que act\u00faa para prevenir el juego da\u00f1ino: la posibilidad de establecer l\u00edmites de dep\u00f3sito y alertas, el env\u00edo de un estado de cuenta mensual con la situaci\u00f3n financiera en la aplicaci\u00f3n, un sistema de revisi\u00f3n que se activa por actividades como pasar demasiadas horas en el sitio o intentar recuperarse de grandes p\u00e9rdidas, y programas de autoexclusi\u00f3n que incluyen la oferta de una evaluaci\u00f3n gratuita de salud mental.<\/p>\n<p>\u201cTrabajamos para identificar se\u00f1ales de da\u00f1o y comprometernos con el usuario para evitar que ese da\u00f1o ocurra\u201d, dijo Cory Fox, vicepresidente s\u00e9nior de Pol\u00edticas P\u00fablicas y Sostenibilidad de FanDuel.<\/p>\n<p>DraftKings tiene medidas de seguridad similares y les invita a los usuarios a establecer l\u00edmites con una p\u00e1gina emergente inmediatamente al crear una cuenta.<\/p>\n<p>\u201cEstos recursos se presentan al registrarse y se refuerzan a lo largo de la experiencia del cliente\u201d, dijo Lori Kalani, directora de Juego Responsable de DraftKings, en un correo electr\u00f3nico a CNN. \u201cEs m\u00e1s divertido cuando es solo por diversi\u00f3n, y esa es la experiencia que queremos ofrecer\u201d.<\/p>\n<p>\ufeffFanDuel tambi\u00e9n le dijo a CNN que considera las apuestas deportivas como una forma de entretenimiento.<\/p>\n<p>\u201cQueremos que nuestros clientes piensen en su tiempo y presupuesto en nuestra plataforma de la misma manera que podr\u00edan pensar en ir al cine\u201d, dijo Fox de FanDuel.<\/p>\n<p>Pero al menos algunos apostadores intentan convertirlo en una fuente de ingresos, como Colby Aaron Wells, que ahora tiene 33 a\u00f1os y comenz\u00f3 a apostar en deportes en Tennessee hace casi una d\u00e9cada para ganar dinero extra. (El estado legaliz\u00f3 ciertos concursos diarios de deportes de fantas\u00eda en aplicaciones en 2016).<\/p>\n<p>Dijo que en ese momento \u201ctrabajaba muy duro\u201d en un empleo de jardiner\u00eda y pens\u00f3 que podr\u00eda ganar un poco m\u00e1s de dinero para pagar las cuentas.<\/p>\n<p>En los a\u00f1os que Wells apost\u00f3 en aplicaciones, incluso despu\u00e9s de que las apuestas deportivas se legalizaran m\u00e1s ampliamente, hubo meses en los que gan\u00f3 miles de d\u00f3lares. Dos veces, la empresa de apuestas BetMGM incluso le regal\u00f3 habitaciones gratis en Las Vegas por apostar tanto.<\/p>\n<p>Pero tambi\u00e9n hubo muchas p\u00e9rdidas. Wells dice que podr\u00eda haber comprado y pagado una casa en Tennessee con la cantidad de dinero que perdi\u00f3, y desde entonces ha dejado de apostar por completo. BetMGM rechaz\u00f3 la solicitud de CNN para hacer comentarios.<\/p>\n<p>Los tres j\u00f3venes entrevistados para esta historia cre\u00edan que ten\u00edan una ventaja competitiva por su conocimiento de diferentes deportes, vi\u00e9ndolo de manera diferente a una m\u00e1quina tragamonedas o un billete de loter\u00eda.<\/p>\n<p>Y aunque han dejado de apostar, dicen que la publicidad constante de las apuestas deportivas es dif\u00edcil de evitar. Ven promociones como \u201capuesta US$ 5 y recibe US$ 150\u201d, y saben lo f\u00e1cil que es dejarse atrapar.<\/p>\n<p>\u201cLa cantidad de anuncios y comerciales que ves en todas partes\u201d, dijo Vo, \u201cliteralmente est\u00e1 en todas partes\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando Ethan perdi\u00f3 US$ 11.000 en un solo partido de hockey el pasado marzo, fue la gota que colm\u00f3 el vaso. Ethan, quien prefiri\u00f3 no compartir su apellido por miedo a perder su trabajo, apost\u00f3 \u201cel spread\u201d en un partido de hockey entre los Hurricanes y los Flames. Eso significa que un equipo no solo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465800","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El pasatiempo que les est\u00e1 costando a los j\u00f3venes decenas de miles de d\u00f3lares - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El pasatiempo que les est\u00e1 costando a los j\u00f3venes decenas de miles de d\u00f3lares - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuando Ethan perdi\u00f3 US$ 11.000 en un solo partido de hockey el pasado marzo, fue la gota que colm\u00f3 el vaso. Ethan, quien prefiri\u00f3 no compartir su apellido por miedo a perder su trabajo, apost\u00f3 \u201cel spread\u201d en un partido de hockey entre los Hurricanes y los Flames. Eso significa que un equipo no solo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-24T05:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El pasatiempo que les est\u00e1 costando a los j\u00f3venes decenas de miles de d\u00f3lares\",\"datePublished\":\"2025-08-24T05:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/\"},\"wordCount\":2149,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/\",\"name\":\"El pasatiempo que les est\u00e1 costando a los j\u00f3venes decenas de miles de d\u00f3lares - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-24T05:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El pasatiempo que les est\u00e1 costando a los j\u00f3venes decenas de miles de d\u00f3lares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El pasatiempo que les est\u00e1 costando a los j\u00f3venes decenas de miles de d\u00f3lares - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El pasatiempo que les est\u00e1 costando a los j\u00f3venes decenas de miles de d\u00f3lares - Noticias","og_description":"Cuando Ethan perdi\u00f3 US$ 11.000 en un solo partido de hockey el pasado marzo, fue la gota que colm\u00f3 el vaso. Ethan, quien prefiri\u00f3 no compartir su apellido por miedo a perder su trabajo, apost\u00f3 \u201cel spread\u201d en un partido de hockey entre los Hurricanes y los Flames. Eso significa que un equipo no solo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-24T05:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/"},"author":{"name":"","@id":""},"headline":"El pasatiempo que les est\u00e1 costando a los j\u00f3venes decenas de miles de d\u00f3lares","datePublished":"2025-08-24T05:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/"},"wordCount":2149,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/","name":"El pasatiempo que les est\u00e1 costando a los j\u00f3venes decenas de miles de d\u00f3lares - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-24T05:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El pasatiempo que les est\u00e1 costando a los j\u00f3venes decenas de miles de d\u00f3lares"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El pasatiempo que les est\u00e1 costando a los j\u00f3venes decenas de miles de d\u00f3lares","url":"http:\/\/noticiasya.com\/palm-springs\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2025\/08\/23\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-24T05:03:38Z","datePublished":"2025-08-24T05:03:38Z","dateModified":"2025-08-24T05:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El pasatiempo que les est\\u00e1 costando a los j\\u00f3venes decenas de miles de d\\u00f3lares\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2025\\\/08\\\/23\\\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2025\\\/08\\\/23\\\/aplicaciones-apuestas-deportes-pasatiempo-jovenes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-24T05:03:38Z\",\"datePublished\":\"2025-08-24T05:03:38Z\",\"dateModified\":\"2025-08-24T05:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1445020,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/06\/declaran-culpable-de-homicidio-involuntario-a-jennifer-crumbley-madre-del-atacante-de-michigan\/","url_meta":{"origin":1465800,"position":0},"title":"Declaran culpable de homicidio involuntario a Jennifer Crumbley, madre del atacante de Michigan","author":"","date":"febrero 6, 2024","format":false,"excerpt":"(CNN) -- Jennifer Crumbley, la madre del adolescente que mat\u00f3 a cuatro estudiantes en un tiroteo en una escuela secundaria de Oxford, Michigan, en 2021, fue declarada culpable de los cuatro cargos de homicidio involuntario en un novedoso caso legal que se erigi\u00f3 como una prueba de los l\u00edmites de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464146,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/02\/influencer-ethan-guo-arraigo-aterrizar-antartida-orix\/","url_meta":{"origin":1465800,"position":1},"title":"El influencer estadounidense Ethan Guo queda con arraigo nacional en Chile tras aterrizar sin permiso en la Ant\u00e1rtida","author":"","date":"julio 2, 2025","format":false,"excerpt":"El influencer y piloto estadounidense Ethan Guo, de 19 a\u00f1os, quien llam\u00f3 la atenci\u00f3n al aterrizar una peque\u00f1a aeronave en la Ant\u00e1rtida sin permiso, continuaba detenido este martes luego de que la Fiscal\u00eda de Magallanes y la Ant\u00e1rtica Chilena determinara el domingo que el joven debe permanecer en el sector\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462853,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/05\/27\/mision-imposible-pelicula-momentos-tom-cruise-orix\/","url_meta":{"origin":1465800,"position":2},"title":"Tres momentos incre\u00edbles de &#171;Misi\u00f3n imposible&#187; que hace que valgan la pena verla","author":"","date":"mayo 27, 2025","format":false,"excerpt":"Con una duraci\u00f3n de casi tres horas, aunque no ser\u00e1 la pel\u00edcula m\u00e1s larga del verano, \u201cMission: Impossible \u2013 The Final Reckoning\u201d satisface de sobra a quienes buscan liberar adrenalina. Y con solo tres secuencias o momentos de inagotable acci\u00f3n, satisface tambi\u00e9n a quien espera ver retribuido el precio de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464163,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/02\/fiscalia-chilena-ethan-guo-antartica-vuelo-punta-arenas-orix\/","url_meta":{"origin":1465800,"position":3},"title":"Fiscal\u00eda chilena confirma que Ethan Guo permanece en la Ant\u00e1rtica esperando un vuelo comercial para volver a Punta Arenas","author":"","date":"julio 2, 2025","format":false,"excerpt":"La Fiscal\u00eda de Magallanes y la Ant\u00e1rtica Chilena confirm\u00f3 este mi\u00e9rcoles a CNN que el piloto e influencer estadounidense de 19 a\u00f1os, Ethan Guo, permanece en la Ant\u00e1rtica a la espera de un vuelo comercial para regresar a la ciudad de Punta Arenas, lugar desde donde el 28 de junio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465435,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/12\/piloto-ee-uu-aterrizar-antartida-acuerdo-chile-trax\/","url_meta":{"origin":1465800,"position":4},"title":"Piloto e influencer estadounidense acusado de aterrizar sin permiso en la Ant\u00e1rtida llega a un acuerdo para salir de Chile","author":"","date":"agosto 12, 2025","format":false,"excerpt":"Un juez en Chile accedi\u00f3 a suspender el proceso contra un piloto estadounidense adolescente e influencer en redes sociales que ha estado atrapado en una remota isla ant\u00e1rtica desde finales de junio, despu\u00e9s de que se le acusara de aterrizar all\u00ed sin permiso.Ethan Guo intentaba volar solo a los siete\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451312,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/22\/kamala-harris-candidata-democrata-respuestas-preguntas-decision-biden-abandonar-carrera-electoral-trax\/","url_meta":{"origin":1465800,"position":5},"title":"\u00bfEs Kamala Harris ahora la candidata dem\u00f3crata? Respuestas a las preguntas clave sobre la decisi\u00f3n de Biden de abandonar la carrera electoral","author":"","date":"julio 22, 2024","format":false,"excerpt":"(CNN) -- El presidente Joe Biden anunci\u00f3 este domingo que no buscar\u00e1 ser reelegido como presidente en 2024, y respald\u00f3 a la vicepresidenta Kamala Harris para convertirse en la candidata dem\u00f3crata.Pero la decisi\u00f3n del presidente de 81 a\u00f1os \u2014a poco m\u00e1s de 100 d\u00edas de las elecciones\u2014 dio lugar a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1465800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1465800"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1465800\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1465800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1465800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1465800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}