{"id":1465812,"date":"2025-08-24T12:03:47","date_gmt":"2025-08-24T19:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/"},"modified":"2025-08-24T12:03:47","modified_gmt":"2025-08-24T19:03:47","slug":"venezolanos-caracas-unirse-milicia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/","title":{"rendered":"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU."},"content":{"rendered":"<p>Multitudes se convocaron Caracas el s\u00e1bado para inscribirse en la milicia venezolana despu\u00e9s de que el presidente Nicol\u00e1s Maduro hiciera un llamado a reforzar la defensa ante amenazas de Estados Unidos.<\/p>\n<p>CNN observ\u00f3 a los inscritos formar largas filas en la Plaza Bol\u00edvar, ubicada en el coraz\u00f3n de Caracas, para entregar sus datos y unirse a la milicia. La Milicia Bolivariana es una rama de las Fuerzas Armadas de Venezuela y fue creada por el fallecido presidente Hugo Ch\u00e1vez.<\/p>\n<p>\u201cDebemos continuar con el legado de Hugo Ch\u00e1vez: luchar por la patria y los derechos de todos los venezolanos\u201d, dijo Doris Pe\u00f1a, trabajadora comunitaria que se alist\u00f3 en la milicia el s\u00e1bado.<\/p>\n<p>Robert Nieves, profesor, dijo que nunca ha usado un arma, pero que \u201cdefender el pa\u00eds no es solo tener un arma\u201d.<\/p>\n<p>Maduro orden\u00f3 el despliegue de 4,5 millones de milicianos en todo el pa\u00eds luego de que Estados Unidos duplicara la recompensa por informaci\u00f3n que conduzca a su arresto e incrementara el n\u00famero de tropas que navegan por Am\u00e9rica Latina y el Caribe.<\/p>\n<p>La administraci\u00f3n del presidente de EE.UU., Donald Trump, ha dicho que estas acciones son un intento de contener amenazas de los grupos de narcotr\u00e1fico en la regi\u00f3n. Maduro ha denunciado las \u201camenazas extravagantes, extra\u00f1as y descabelladas\u201d.<\/p>\n<p>Algunos de los nuevos miembros de la milicia coincidieron en que el pa\u00eds enfrenta una amenaza.<\/p>\n<p>\u201cDefendemos a nuestro pueblo y, de una u otra forma, nos vamos a defender\u201d, dijo a CNN Rogelia Mart\u00ednez, trabajadora social.<\/p>\n<p>El ministro de Defensa, Vladimir Padrino, public\u00f3 este domingo un <a href=\"https:\/\/www.instagram.com\/reel\/DNvc9dI3OmG\/\">video<\/a> en redes sociales con im\u00e1genes del proceso de inscripci\u00f3n y asegur\u00f3: \u201cEl pueblo de Venezuela va a las calles a sumarse no solamente a las filas de la Milicia Bolivariana (\u2026), tambi\u00e9n es un llamado y una expresi\u00f3n del pueblo de Venezuela en rechazo a las agresiones imperialistas\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Multitudes se convocaron Caracas el s\u00e1bado para inscribirse en la milicia venezolana despu\u00e9s de que el presidente Nicol\u00e1s Maduro hiciera un llamado a reforzar la defensa ante amenazas de Estados Unidos. CNN observ\u00f3 a los inscritos formar largas filas en la Plaza Bol\u00edvar, ubicada en el coraz\u00f3n de Caracas, para entregar sus datos y unirse [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465812","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"Multitudes se convocaron Caracas el s\u00e1bado para inscribirse en la milicia venezolana despu\u00e9s de que el presidente Nicol\u00e1s Maduro hiciera un llamado a reforzar la defensa ante amenazas de Estados Unidos. CNN observ\u00f3 a los inscritos formar largas filas en la Plaza Bol\u00edvar, ubicada en el coraz\u00f3n de Caracas, para entregar sus datos y unirse [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-24T19:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU.\",\"datePublished\":\"2025-08-24T19:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/\"},\"wordCount\":368,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/\",\"name\":\"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-24T19:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU. - Noticias","og_description":"Multitudes se convocaron Caracas el s\u00e1bado para inscribirse en la milicia venezolana despu\u00e9s de que el presidente Nicol\u00e1s Maduro hiciera un llamado a reforzar la defensa ante amenazas de Estados Unidos. CNN observ\u00f3 a los inscritos formar largas filas en la Plaza Bol\u00edvar, ubicada en el coraz\u00f3n de Caracas, para entregar sus datos y unirse [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-24T19:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/"},"author":{"name":"","@id":""},"headline":"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU.","datePublished":"2025-08-24T19:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/"},"wordCount":368,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/","name":"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-24T19:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU.","url":"http:\/\/noticiasya.com\/palm-springs\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-24T19:03:47Z","datePublished":"2025-08-24T19:03:47Z","dateModified":"2025-08-24T19:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Venezolanos se re\\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2025\\\/08\\\/24\\\/venezolanos-caracas-unirse-milicia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2025\\\/08\\\/24\\\/venezolanos-caracas-unirse-milicia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-24T19:03:47Z\",\"datePublished\":\"2025-08-24T19:03:47Z\",\"dateModified\":\"2025-08-24T19:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1466168,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/09\/04\/maduro-convoca-activacion-milicia-bolivariana-orix\/","url_meta":{"origin":1465812,"position":0},"title":"Maduro anuncia &#171;primera activaci\u00f3n&#187; de la Milicia Bolivariana. Dice que alistamiento ser\u00e1 permanente","author":"","date":"septiembre 4, 2025","format":false,"excerpt":"El presidente de Venezuela, Nicol\u00e1s Maduro, convoc\u00f3 este jueves a que las personas que en las \u00faltimas dos semanas se inscribieron en la Milicia Bolivariana, un cuerpo de reservistas integrado por voluntarios, acudan este viernes al \u201cprimera activaci\u00f3n\u201d para defender al pa\u00eds.Maduro lanz\u00f3 la convocatoria durante una transmisi\u00f3n de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465937,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/28\/venezolanos-rutina-tensiones-eeuu-orix\/","url_meta":{"origin":1465812,"position":1},"title":"&#171;Puro teatro, no hay nada&#187;: muchos venezolanos viven inmersos en la rutina en medio de las tensiones con EE.UU.","author":"","date":"agosto 28, 2025","format":false,"excerpt":"Mientras crecen las tensiones entre Venezuela y Estados Unidos por el anuncio del despliegue de buques en el Caribe, y el Gobierno del presidente Nicol\u00e1s Maduro llama a \u201cdefender la patria\u201d a trav\u00e9s de la Milicia Bolivariana, varios venezolanos entrevistados por CNN en las calles de Caracas aseguraron que, m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466295,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/09\/09\/como-funciona-milicia-boliviariana-moviliza-orix\/","url_meta":{"origin":1465812,"position":2},"title":"La milicia venezolana se moviliza mientras la Casa Blanca eval\u00faa sus golpes. As\u00ed es como funciona la fuerza","author":"","date":"septiembre 9, 2025","format":false,"excerpt":"Cuando suena la campana, H\u00e9ctor Carrillo, un panadero que trabaja en las afueras de Caracas, saca del horno galletas y tortas para su comunidad. Pero cuando suena el llamado militar, alista sus botas y uniforme para defender a su patria.Carrillo es reservista y miembro de la Milicia Bolivariana, una fuerza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466779,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/09\/24\/trump-burla-milicia-venezolana-supremacista-orix\/","url_meta":{"origin":1465812,"position":3},"title":"Trump se burl\u00f3 de la milicia venezolana y Caracas lo llam\u00f3 supremacista","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"El Gobierno de Venezuela respondi\u00f3 al mensaje de burla que public\u00f3 el presidente de Estados Unidos, Donald Trump, sobre la Milicia Bolivariana, y acus\u00f3 al mandatario de supremacismo por sus comentarios.Trump divulg\u00f3 el lunes en redes sociales un video que mostraba a mujeres civiles participando de un entrenamiento armado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465829,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/25\/5-cosas-25-agosto-orix\/","url_meta":{"origin":1465812,"position":4},"title":"Las 5 cosas que debes saber este 25 de agosto: ofensiva inmigratoria, Milicia Bolivariana, Gaza, Julio C\u00e9sar Ch\u00e1vez Jr.","author":"","date":"agosto 25, 2025","format":false,"excerpt":"Venezolanos se unen a la milicia tras llamado de Maduro. Los consumidores de EE.UU. asumen el costo extra de los aranceles de Trump. Cancelan otro intento de lanzamiento de SpaceX. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467220,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/10\/08\/encienden-luces-navidad-venezuela-sombra-conflicto-eeuu-orix\/","url_meta":{"origin":1465812,"position":5},"title":"Encienden las luces navide\u00f1as en Venezuela bajo la sombra del conflicto con EE.UU. por el despliegue militar en el Caribe","author":"","date":"octubre 8, 2025","format":false,"excerpt":"\u201c\u00a1Bienvenida la Navidad a nuestro Helicoide!\u201d. El mensaje de la Polic\u00eda Nacional Bolivariana en las redes sociales acompa\u00f1a un video en el que se ve el edificio capitalino iluminado con luces de varios colores. Segundos despu\u00e9s, estallan los fuegos artificiales. La paradoja es doble. Por un lado, sobre el Helicoide,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1465812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1465812"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1465812\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1465812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1465812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1465812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}