{"id":1470803,"date":"2026-02-03T05:03:46","date_gmt":"2026-02-03T13:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/"},"modified":"2026-02-03T05:03:46","modified_gmt":"2026-02-03T13:03:46","slug":"jueza-bloquea-temporalmente-fin-tps-haitianos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/","title":{"rendered":"Jueza federal bloquea temporalmente el fin del TPS para los haitianos"},"content":{"rendered":"<p>Una jueza federal suspendi\u00f3 temporalmente la cancelaci\u00f3n del Estatus de Protecci\u00f3n Temporal (TPS) impuesta por la administraci\u00f3n Trump a m\u00e1s de 350.000 haitianos. El TPS permite a sus titulares vivir y trabajar en Estados Unidos y expiraba el martes.<\/p>\n<p>En un severo dictamen de 83 p\u00e1ginas, la jueza Ana Reyes, del Distrito de Columbia, concedi\u00f3 el lunes la solicitud de cinco haitianos beneficiarios del TPS de bloquear temporalmente la cancelaci\u00f3n mientras el caso se tramita en los tribunales.<\/p>\n<p>Los demandantes impugnan la cancelaci\u00f3n del TPS por parte del Departamento de Seguridad Nacional, argumentando que la agencia no realiz\u00f3 la revisi\u00f3n necesaria para determinar si era seguro regresar a Hait\u00ed antes de decidir cancelar la protecci\u00f3n. La demanda tambi\u00e9n alega que la decisi\u00f3n de la agencia se debe, en parte, a la \u201canimosidad racial, \u00e9tnica y por naci\u00f3n de origen\u201d del presidente Donald Trump hacia los haitianos.<\/p>\n<p>Reyes critic\u00f3 duramente a la secretaria del Departamento de Seguridad Naciona (DHS), Kristi Noem, por referirse a ciertos inmigrantes, incluyendo haitianos, como \u201casesinos, sanguijuelas o adictos a los derechos sociales\u201d en X en diciembre. Adem\u00e1s, la jueza escribi\u00f3 que Noem \u201cignor\u00f3 el requisito del Congreso de que \u2018revise las condiciones\u2019 en Hait\u00ed solo \u2018despu\u00e9s\u2019 de consultar \u2018con las agencias correspondientes\u2019\u201d.<\/p>\n<p>\u201cLos demandantes alegan que la secretaria Noem predetermin\u00f3 su decisi\u00f3n de terminaci\u00f3n (de los beneficios) y lo hizo debido a su hostilidad hacia los inmigrantes no blancos\u201d, escribi\u00f3 Reyes. \u201cEsto parece bastante probable\u201d.<\/p>\n<p>La jueza tambi\u00e9n cit\u00f3 los reiterados comentarios despectivos de Trump sobre los haitianos.<\/p>\n<p>\u201cEl presidente Trump se ha referido a Hait\u00ed como un \u2018pa\u00eds de m*****\u2019, ha sugerido que los haitianos \u2018probablemente tienen SIDA\u2019 y se ha quejado de que la inmigraci\u00f3n haitiana es \u2018como una sentencia de muerte para nuestro pa\u00eds\u2019\u201d, escribi\u00f3. \u201cTambi\u00e9n ha promovido la falsa teor\u00eda de la conspiraci\u00f3n de que los inmigrantes haitianos se estaban \u2018comiendo las mascotas de la gente\u2019 en Springfield, Ohio\u201d.<\/p>\n<p>Los beneficiarios haitianos del TPS se encuentran entre los \u00faltimos residentes nacidos en el extranjero cuyas vidas se han visto trastocadas por la administraci\u00f3n Trump, centrada en reducir dr\u00e1sticamente el n\u00famero de inmigrantes que entran y viven en Estados Unidos. El DHS anunci\u00f3 la cancelaci\u00f3n de la designaci\u00f3n del TPS para inmigrantes de varios pa\u00edses, como Honduras, Nepal y Sud\u00e1n del Sur, aunque los jueces federales han obstaculizado muchos de esos intentos.<\/p>\n<p>El TPS se concede a personas que enfrentar\u00edan dificultades extremas si se vieran obligadas a regresar a sus pa\u00edses de origen devastados por conflictos armados o desastres naturales. Los beneficiarios son investigados y no son elegibles si han sido condenados por alg\u00fan delito grave o m\u00e1s de un delito menor en Estados Unidos. El secretario del DHS tiene la facultad discrecional de designar un pa\u00eds para el TPS.<\/p>\n<p>Los inmigrantes haitianos se volvieron elegibles despu\u00e9s de que un terremoto sacudiera el pa\u00eds en 2010. Desde entonces, la designaci\u00f3n se ha renovado en m\u00faltiples ocasiones, ya que el pa\u00eds enfrenta diversas crisis, como la violencia generalizada por parte de bandas armadas, la inseguridad alimentaria, el desplazamiento y un vac\u00edo de liderazgo tras el asesinato del presidente en 2021.<\/p>\n<p>Tras su terminaci\u00f3n la semana pasada, el DHS afirm\u00f3 que el programa TPS de Hait\u00ed \u201cnunca tuvo la intenci\u00f3n de ser un programa de asilo de facto, pero as\u00ed lo han utilizado las administraciones anteriores durante d\u00e9cadas\u201d.<\/p>\n<p>\u201cLa afirmaci\u00f3n de que la \u00fanica manera de cuidar de nuestros adultos mayores es permitiendo que extranjeros ilegales sin antecedentes penales y extranjeros con antecedentes penales permanezcan en el pa\u00eds es totalmente falsa y negligente\u201d, declar\u00f3 a CNN la portavoz del DHS, Tricia McLaughlin.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una jueza federal suspendi\u00f3 temporalmente la cancelaci\u00f3n del Estatus de Protecci\u00f3n Temporal (TPS) impuesta por la administraci\u00f3n Trump a m\u00e1s de 350.000 haitianos. El TPS permite a sus titulares vivir y trabajar en Estados Unidos y expiraba el martes. En un severo dictamen de 83 p\u00e1ginas, la jueza Ana Reyes, del Distrito de Columbia, concedi\u00f3 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470803","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jueza federal bloquea temporalmente el fin del TPS para los haitianos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jueza federal bloquea temporalmente el fin del TPS para los haitianos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una jueza federal suspendi\u00f3 temporalmente la cancelaci\u00f3n del Estatus de Protecci\u00f3n Temporal (TPS) impuesta por la administraci\u00f3n Trump a m\u00e1s de 350.000 haitianos. El TPS permite a sus titulares vivir y trabajar en Estados Unidos y expiraba el martes. En un severo dictamen de 83 p\u00e1ginas, la jueza Ana Reyes, del Distrito de Columbia, concedi\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T13:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Jueza federal bloquea temporalmente el fin del TPS para los haitianos\",\"datePublished\":\"2026-02-03T13:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/\"},\"wordCount\":666,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/\",\"name\":\"Jueza federal bloquea temporalmente el fin del TPS para los haitianos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-03T13:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jueza federal bloquea temporalmente el fin del TPS para los haitianos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jueza federal bloquea temporalmente el fin del TPS para los haitianos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Jueza federal bloquea temporalmente el fin del TPS para los haitianos - Noticias","og_description":"Una jueza federal suspendi\u00f3 temporalmente la cancelaci\u00f3n del Estatus de Protecci\u00f3n Temporal (TPS) impuesta por la administraci\u00f3n Trump a m\u00e1s de 350.000 haitianos. El TPS permite a sus titulares vivir y trabajar en Estados Unidos y expiraba el martes. En un severo dictamen de 83 p\u00e1ginas, la jueza Ana Reyes, del Distrito de Columbia, concedi\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-03T13:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/"},"author":{"name":"","@id":""},"headline":"Jueza federal bloquea temporalmente el fin del TPS para los haitianos","datePublished":"2026-02-03T13:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/"},"wordCount":666,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/","name":"Jueza federal bloquea temporalmente el fin del TPS para los haitianos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-03T13:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Jueza federal bloquea temporalmente el fin del TPS para los haitianos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Jueza federal bloquea temporalmente el fin del TPS para los haitianos","url":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/03\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-03T13:03:46Z","datePublished":"2026-02-03T13:03:46Z","dateModified":"2026-02-03T13:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Jueza federal bloquea temporalmente el fin del TPS para los haitianos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/03\\\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/03\\\/jueza-bloquea-temporalmente-fin-tps-haitianos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-03T13:03:46Z\",\"datePublished\":\"2026-02-03T13:03:46Z\",\"dateModified\":\"2026-02-03T13:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460362,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/24\/beneficiarios-tps-manifestacion-corte-cancelacion-orix\/","url_meta":{"origin":1470803,"position":0},"title":"Beneficiarios del Estatus de Protecci\u00f3n Temporal piden ante una corte frenar la cancelaci\u00f3n del programa","author":"","date":"marzo 24, 2025","format":false,"excerpt":"Beneficiarios del Estatus de Protecci\u00f3n Temporal (TPS, por sus siglas en ingl\u00e9s) y defensores de los derechos civiles se manifestaron este lunes en San Francisco, afuera de donde se llev\u00f3 a cabo la primera audiencia de un caso que impugna la terminaci\u00f3n del programa bajo la administraci\u00f3n del presidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472252,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/03\/16\/corte-suprema-revisara-tps-migrantes-haiti-siria-trax\/","url_meta":{"origin":1470803,"position":1},"title":"La Corte Suprema revisar\u00e1 el intento de Trump de acabar el TPS para inmigrantes de Hait\u00ed y Siria","author":"","date":"marzo 16, 2026","format":false,"excerpt":"La Corte Suprema anunci\u00f3 este lunes que decidir\u00e1 si el presidente Donald Trump puede terminar las protecciones temporales contra la deportaci\u00f3n para cientos de miles de ciudadanos extranjeros, y acept\u00f3 escuchar argumentos el pr\u00f3ximo mes sobre un asunto que ha sido central en la agenda migratoria del Gobierno.La decisi\u00f3n se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473646,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/04\/29\/corte-suprema-tps-haitianos-sirios-trax\/","url_meta":{"origin":1470803,"position":2},"title":"La Corte Suprema indica que se pondr\u00e1 del lado de Trump sobre los migrantes haitianos y sirios","author":"","date":"abril 29, 2026","format":false,"excerpt":"La Corte Suprema indic\u00f3 el mi\u00e9rcoles que respaldar\u00e1 el impulso del presidente de EE.UU. Donald Trump para poner fin a las protecciones temporales contra la deportaci\u00f3n para potencialmente millones de ciudadanos extranjeros que provienen de pa\u00edses que atraviesan guerras y desastres naturales.En una de las apelaciones inmigratorias m\u00e1s importantes que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473558,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/04\/28\/haitianos-tps-corte-suprema-previa-trax\/","url_meta":{"origin":1470803,"position":3},"title":"Estos inmigrantes haitianos aportan cerca de US$ 6.000 millones a la econom\u00eda. Su destino est\u00e1 en manos de la Corte Suprema","author":"","date":"abril 28, 2026","format":false,"excerpt":"Es posible que Jan Gautam pronto tenga que despedir a cientos de trabajadores de decenas de hoteles en Florida. Por este motivo es que el director ejecutivo de IHRMC Hotels & Resorts sigue muy de cerca un caso de inmigraci\u00f3n que se presenta ante la Corte Suprema esta semana.Los empleados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473622,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/04\/29\/influira-retorica-antiinmigrante-trump-corte-suprema-trax\/","url_meta":{"origin":1470803,"position":4},"title":"\u00bfInfluir\u00e1 la ret\u00f3rica antiinmigrante de Trump en la decisi\u00f3n de la Corte Suprema de Justicia de EE.UU.?","author":"","date":"abril 29, 2026","format":false,"excerpt":"Hace ocho a\u00f1os, en la primera batalla importante en la Corte Suprema de Justicia de EE.UU. sobre una pol\u00edtica de Donald Trump, los magistrados desestimaron la ret\u00f3rica antimusulmana del presidente y confirmaron la prohibici\u00f3n de viaje a pa\u00edses de mayor\u00eda musulmana.Ahora, los abogados de Trump invocan esta decisi\u00f3n judicial para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464927,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/28\/inmigrantes-haitianos-temen-deportacion-trax\/","url_meta":{"origin":1470803,"position":5},"title":"&#171;Regresar es pr\u00e1cticamente la muerte&#187;: Inmigrantes haitianos temen los intentos de Trump por enviarlos de regreso a su pa\u00eds","author":"","date":"julio 28, 2025","format":false,"excerpt":"Con ocho meses de embarazo, Titi, una inmigrante haitiana de 28 a\u00f1os, teme ser deportada a su pa\u00eds natal.Titi, quien pidi\u00f3 ser identificada solo con un seud\u00f3nimo por temor a ser objeto de las autoridades migratorias, lleg\u00f3 a Estados Unidos con su hermana menor en 2024 tras huir de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1470803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1470803"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1470803\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1470803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1470803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1470803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}