{"id":1470830,"date":"2026-02-03T19:03:52","date_gmt":"2026-02-04T03:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/"},"modified":"2026-02-03T19:03:52","modified_gmt":"2026-02-04T03:03:52","slug":"trump-petro-reunion-optimista-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/","title":{"rendered":"Petro y Trump tuvieron una reuni\u00f3n &#171;muy buena&#187; que dej\u00f3 un &#171;aire optimista&#187;, tras un a\u00f1o marcado por el choque constante"},"content":{"rendered":"<p>Despu\u00e9s de <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/03\/colombia\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\">un a\u00f1o marcado por cruces verbales y amenazas,<\/a> y en el que la relaci\u00f3n entre Colombia y Estados Unidos estuvo constantemente al borde de la <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/03\/colombia\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\">ruptura<\/a>, los presidentes Gustavo Petro y Donald Trump finalmente se vieron este martes cara a cara en Washington.<\/p>\n<p>Puede que los l\u00edderes no hayan hecho grandes anuncios ni alcanzado importantes acuerdos, pero al menos los dos parecieron llevarse bien, se mostraron satisfechos con el encuentro y mostraron se\u00f1ales concretas de distensi\u00f3n.<\/p>\n<p>El due\u00f1o de casa fue el primero en hablar sobre la reuni\u00f3n de esta ma\u00f1ana, en la que participaron tambi\u00e9n el secretario de Estado de EE.UU., Marco Rubio, y el el vicepresidente J. D. Vance, adem\u00e1s de la canciller colombiana, Rosa Yolanda Villavicencio, entre otros altos funcionarios de ambos gobiernos.<\/p>\n<p>Consultado en un evento posterior si hab\u00eda hablado con Petro sobre los esfuerzos en el combate al tr\u00e1fico de drogas, uno los puntos m\u00e1s tensos de su relaci\u00f3n, Trump <a href=\"https:\/\/cnnespanol.cnn.com\/colombia\/live-news\/reunion-trump-y-petro-en-vivo-ultima-hora-noticias-orix?post-id=cml6zvav3004r356n4q3sm6dm\">dijo <\/a>que \u201ctrabajamos en eso y nos llevamos muy bien\u201d.<\/p>\n<p>\u201c\u00c9l y yo no \u00e9ramos exactamente los mejores amigos, pero no me sent\u00ed ofendido porque nunca lo hab\u00eda conocido. No lo conoc\u00eda en absoluto\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/colombia\/live-news\/reunion-trump-y-petro-en-vivo-ultima-hora-noticias-orix?post-id=cml6zvav3004r356n4q3sm6dm\">agreg\u00f3 <\/a>Trump, quien calific\u00f3 a la reuni\u00f3n de \u201cmuy buena\u201d y dijo que Petro era \u201cfant\u00e1stico\u201d.<\/p>\n<p>Poco despu\u00e9s, Petro ofreci\u00f3 una conferencia de prensa y asegur\u00f3 que la reuni\u00f3n hab\u00eda sido \u201cpositiva\u201d y que se iba de la Casa Blanca \u201ccon un aire de optimismo\u201d.<\/p>\n<p>\u201cTrump y yo podemos ser muy diferentes, civilizatoriamente hablando, hist\u00f3ricamente hablando, pero lo que nos junta es la libertad. Se puede hacer un pacto por la libertad, un pacto por la vida, y de eso va la conversaci\u00f3n\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/colombia\/live-news\/reunion-trump-y-petro-en-vivo-ultima-hora-noticias-orix?post-id=cml75qp410000356pneji9s8j\">dijo <\/a>el presidente de Colombia.<\/p>\n<p>Petro asegur\u00f3 adem\u00e1s que junto a Trump lograron encontrar \u201ccaminos conjuntos\u201d a pesar de los desacuerdos, sin ofrecer m\u00e1s detalles, y <a href=\"https:\/\/cnnespanol.cnn.com\/colombia\/live-news\/reunion-trump-y-petro-en-vivo-ultima-hora-noticias-orix?post-id=cml75qp410000356pneji9s8j\">se\u00f1al\u00f3 <\/a>que hablaron de c\u00f3mo Colombia podr\u00eda prestar ayuda \u201cen la reactivaci\u00f3n de Venezuela\u201d.<\/p>\n<p>\u201cHablamos de problemas concretos y caminos conjuntos. \u00c9l no cambi\u00f3 de forma de pensar, yo tampoco, pero un pacto no es entre hermanos gemelos, un pacto es entre contradictores que pueden cencontrar caminos\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/colombia\/live-news\/reunion-trump-y-petro-en-vivo-ultima-hora-noticias-orix?post-id=cml75qp410000356pneji9s8j\">consider\u00f3<\/a>.<\/p>\n<p>Al encuentro tampoco le faltaron s\u00edmbolos de distensi\u00f3n. Petro y Trump se <a href=\"https:\/\/cnnespanol.cnn.com\/colombia\/live-news\/reunion-trump-y-petro-en-vivo-ultima-hora-noticias-orix?post-id=cml6tjt0v001z356njitvzx1g\">dieron <\/a>un fuerte apret\u00f3n de manos en la Casa Blanca antes de comenzar la reuni\u00f3n en la Oficina Oval, y, al terminar, Petro r\u00e1pidamente mostr\u00f3 en sus redes sociales los dos regalos que le hizo Trump.<\/p>\n<p>El primero es un <a href=\"https:\/\/cnnespanol.cnn.com\/colombia\/live-news\/reunion-trump-y-petro-en-vivo-ultima-hora-noticias-orix?post-id=cml6yfaoc004i356njy7wate2\">mensaje escrito a mano alzada <\/a>por el presidente de EE.UU. en una hoja membretada de la Casa Blanca, junto a una foto de los dos l\u00edderes. El documento dice: \u201cGustavo: Un gran Honor. Amo a Colombia\u201d.<\/p>\n<p>El segundo<a href=\"https:\/\/cnnespanol.cnn.com\/colombia\/live-news\/reunion-trump-y-petro-en-vivo-ultima-hora-noticias-orix?post-id=cml77s4xs000h356pu6osrn8p\"> es una gorra roja MAGA,<\/a> una regalo que ya es costumbre para los visitantes de la Casa Blanca. Maga es un acr\u00f3nimo de Make America Great Again, el lema de campa\u00f1a de Trump que se traduce como \u201cHagamos a EE.UU. grande de nuevo\u201d. Petro recibi\u00f3 el regalo y le dio una vuelta de tuerca: con un bol\u00edgrafo le puso una \u201cs\u201d al final de America.<\/p>\n<p>\u201cLe propuse a Donald Trump un cambio en la moda: ponerle una \u2018S\u2019 a Am\u00e9rica. Parece que le gust\u00f3. Am\u00e9ricas\u201d, dijo Petro en su cuenta de X.<\/p>\n<p>El orgulloso Petro incluso <a href=\"https:\/\/cnnespanol.cnn.com\/colombia\/live-news\/reunion-trump-y-petro-en-vivo-ultima-hora-noticias-orix?post-id=cml6yfaoc004i356njy7wate2\">llev\u00f3 <\/a>una copia del libro m\u00e1s famoso de Trump \u201cThe art of the deal\u201d (El arte de negociar), para que el estadounidense se lo firmara. \u201cYou are great\u201d, le escribi\u00f3 Trump, que significa \u201cEres genial\u201d.<\/p>\n<p>Entre tantos apretones de manos, regalos y optimismo, cualquiera podr\u00eda r\u00e1pidamente olvidar que Trump y Petro estuvieron al borde de una crisis terminal durante 2025. Excepto por la relaci\u00f3n con Nicol\u00e1s Maduro, el presidente de Venezuela que finalmente fue derrocado por orden de Trump en una operaci\u00f3n militar sin precedentes en Caracas, la de Trump y Petro fue una de las m\u00e1s tensas en todo el continente.<\/p>\n<p>El presidente estadounidense incluso <a href=\"https:\/\/cnnespanol.cnn.com\/colombia\/live-news\/reunion-trump-y-petro-en-vivo-ultima-hora-noticias-orix?post-id=cml6pn4dg0000356nccoulvu8\">dijo <\/a>este martes, con algo de iron\u00eda y momentos antes de la reuni\u00f3n, que \u201ctras la redada en Venezuela, (Petro) se volvi\u00f3 muy amable\u201d.<\/p>\n<p>La primera crisis entre ambos comenz\u00f3 en enero de 2025, cuando Trump reci\u00e9n comenzaba su segundo mandato y Petro orden\u00f3<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/02\/colombia\/petro-reunion-trump-washington-orix\"> devolver dos vuelos cargados con migrantes que ya estaban en el aire y se dirig\u00edan a Colombia.<\/a><\/p>\n<p>En marzo, la secretaria de Seguridad Nacional de Estados Unidos, Kristi Noem, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/02\/colombia\/petro-reunion-trump-washington-orix\">afirm\u00f3 <\/a>que Petro consideraba a miembros del Tren de Aragua, un grupo criminal designado como terrorista por EE.UU., como \u201csus amigos\u201d, lo que el mandatario neg\u00f3.<\/p>\n<p>En la segunda mitad del a\u00f1o la crisis se profundiz\u00f3: en septiembre el Gobierno de Trump <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/16\/colombia\/que-pierde-colombia-descertificacion-millones-usd-orix\">descertific\u00f3 a Colombia <\/a>como aliado en la lucha contra las drogas y luego anunci\u00f3<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/27\/colombia\/departamento-estado-ee-uu-revocara-visa-petro-trax\"> que revocar\u00eda la visa de Petro para entrar en Estados Unidos.<\/a><\/p>\n<p>Y en octubre llegaron las sanciones personales: Petro fue <a href=\"https:\/\/cnnespanol.cnn.com\/colombia\/live-news\/reunion-trump-y-petro-en-vivo-ultima-hora-noticias-orix?post-id=cml6ujzwc002g356nlfbl93ia\">incluido <\/a>en la lista gubernamental de Nacionales Especialmente Designados (SDN), que maneja la Oficina de Control de Activos Extranjeros (OFAC) del Departamento del Tesoro de Estados Unidos, \u201cpor su papel en el comercio mundial il\u00edcito de drogas\u201d, lo cual Petro <a href=\"https:\/\/cnnespanol.cnn.com\/colombia\/live-news\/reunion-trump-y-petro-en-vivo-ultima-hora-noticias-orix?post-id=cml75qp410000356pneji9s8j\">rechaza<\/a>.<\/p>\n<p>En plena escalada militar en el Caribe entre Venezuela y Estados Unidos para lo que Washington dijo que era una operaci\u00f3n contra el narcotr\u00e1fico, Trump dijo en diciembre que Petro ser\u00eda<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/10\/eeuu\/trump-petro-siguiente-maduro-efe\"> \u201cel siguiente\u201d <\/a>tras la ca\u00edda de Maduro, que ocurri\u00f3 finalmente el 3 de enero de 2026. \u201cHa sido bastante hostil con Estados Unidos\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/10\/eeuu\/trump-petro-siguiente-maduro-efe\">asegur\u00f3 <\/a>en ese momento.<\/p>\n<p>La reuni\u00f3n de este martes ha calmado las aguas, y parece haberle hecho recordado al mundo que la relaci\u00f3n entre Colombia y Estados Unidos es una de las m\u00e1s estables de las \u00faltimas d\u00e9cadas, sin importar qui\u00e9n gobierna: EE.UU. <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/02\/colombia\/petro-reunion-trump-washington-orix\">es el principal socio comercial<\/a> de Colombia, mientras que Colombia<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/02\/colombia\/petro-reunion-trump-washington-orix\"> ha sido una aliado estrat\u00e9gico<\/a> de EE.UU. en la lucha contra las drogas y el terrorismo.<\/p>\n<p>Solo queda por ver si, m\u00e1s all\u00e1 de los gestos y del optimismo de este martes, Trump y Petro alcanzan un acuerdo concreto que permita dejar atr\u00e1s la sombra de Venezuela <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/09\/eeuu\/analisis-donald-trump-aprendido-poder-global-trax\">y este nuevo \u201cCorolario Trump\u201d de la Doctrina Monroe<\/a>. Ambos parecen dispuestos a hacerlo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de un a\u00f1o marcado por cruces verbales y amenazas, y en el que la relaci\u00f3n entre Colombia y Estados Unidos estuvo constantemente al borde de la ruptura, los presidentes Gustavo Petro y Donald Trump finalmente se vieron este martes cara a cara en Washington. Puede que los l\u00edderes no hayan hecho grandes anuncios ni [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470830","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Petro y Trump tuvieron una reuni\u00f3n &quot;muy buena&quot; que dej\u00f3 un &quot;aire optimista&quot;, tras un a\u00f1o marcado por el choque constante - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petro y Trump tuvieron una reuni\u00f3n &quot;muy buena&quot; que dej\u00f3 un &quot;aire optimista&quot;, tras un a\u00f1o marcado por el choque constante - Noticias\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de un a\u00f1o marcado por cruces verbales y amenazas, y en el que la relaci\u00f3n entre Colombia y Estados Unidos estuvo constantemente al borde de la ruptura, los presidentes Gustavo Petro y Donald Trump finalmente se vieron este martes cara a cara en Washington. Puede que los l\u00edderes no hayan hecho grandes anuncios ni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-04T03:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Petro y Trump tuvieron una reuni\u00f3n &#171;muy buena&#187; que dej\u00f3 un &#171;aire optimista&#187;, tras un a\u00f1o marcado por el choque constante\",\"datePublished\":\"2026-02-04T03:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/\"},\"wordCount\":1106,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/\",\"name\":\"Petro y Trump tuvieron una reuni\u00f3n \\\"muy buena\\\" que dej\u00f3 un \\\"aire optimista\\\", tras un a\u00f1o marcado por el choque constante - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-04T03:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Petro y Trump tuvieron una reuni\u00f3n &#171;muy buena&#187; que dej\u00f3 un &#171;aire optimista&#187;, tras un a\u00f1o marcado por el choque constante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petro y Trump tuvieron una reuni\u00f3n \"muy buena\" que dej\u00f3 un \"aire optimista\", tras un a\u00f1o marcado por el choque constante - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Petro y Trump tuvieron una reuni\u00f3n \"muy buena\" que dej\u00f3 un \"aire optimista\", tras un a\u00f1o marcado por el choque constante - Noticias","og_description":"Despu\u00e9s de un a\u00f1o marcado por cruces verbales y amenazas, y en el que la relaci\u00f3n entre Colombia y Estados Unidos estuvo constantemente al borde de la ruptura, los presidentes Gustavo Petro y Donald Trump finalmente se vieron este martes cara a cara en Washington. Puede que los l\u00edderes no hayan hecho grandes anuncios ni [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/","og_site_name":"Noticias","article_published_time":"2026-02-04T03:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/"},"author":{"name":"","@id":""},"headline":"Petro y Trump tuvieron una reuni\u00f3n &#171;muy buena&#187; que dej\u00f3 un &#171;aire optimista&#187;, tras un a\u00f1o marcado por el choque constante","datePublished":"2026-02-04T03:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/"},"wordCount":1106,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/","url":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/","name":"Petro y Trump tuvieron una reuni\u00f3n \"muy buena\" que dej\u00f3 un \"aire optimista\", tras un a\u00f1o marcado por el choque constante - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-04T03:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Petro y Trump tuvieron una reuni\u00f3n &#171;muy buena&#187; que dej\u00f3 un &#171;aire optimista&#187;, tras un a\u00f1o marcado por el choque constante"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Petro y Trump tuvieron una reuni\u00f3n &#171;muy buena&#187; que dej\u00f3 un &#171;aire optimista&#187;, tras un a\u00f1o marcado por el choque constante","url":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-04T03:03:52Z","datePublished":"2026-02-04T03:03:52Z","dateModified":"2026-02-04T03:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Petro y Trump tuvieron una reuni\\u00f3n &#171;muy buena&#187; que dej\\u00f3 un &#171;aire optimista&#187;, tras un a\\u00f1o marcado por el choque constante\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/03\\\/trump-petro-reunion-optimista-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/03\\\/trump-petro-reunion-optimista-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-04T03:03:52Z\",\"datePublished\":\"2026-02-04T03:03:52Z\",\"dateModified\":\"2026-02-04T03:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472404,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/03\/20\/petro-niega-vinculos-narcotrafico-ninguna-notificacion-formal-eeuu-orix\/","url_meta":{"origin":1470830,"position":0},"title":"Petro niega v\u00ednculos con el narcotr\u00e1fico y su gobierno dice que no ha sido notificado de posibles investigaciones en EE.UU.","author":"","date":"marzo 20, 2026","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, neg\u00f3 este viernes tener alg\u00fan v\u00ednculo con grupos del narcotr\u00e1fico, luego de que se difundieran reportes de medios sobre posibles investigaciones de Estados Unidos contra el mandatario por este motivo, al tiempo que la Embajada de Colombia en Washington dijo que no ha recibido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470796,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/","url_meta":{"origin":1470830,"position":1},"title":"\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia","author":"","date":"febrero 3, 2026","format":false,"excerpt":"En el primer a\u00f1o del segundo mandato de Donald Trump, su relaci\u00f3n con el Gobierno de Colombia parece haber estado siempre al borde de la ruptura: Gustavo Petro ha caminado en el filo del abismo con declaraciones incendiarias mutuas y disputas en redes sociales.Pero en lo que amenazaba con ser\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470108,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/01\/15\/petro-trump-reunion-eeuu-febrero-orix\/","url_meta":{"origin":1470830,"position":2},"title":"\u00bfQu\u00e9 buscar\u00e1 Petro en la reuni\u00f3n con Trump en Washington el 3 de febrero?","author":"","date":"enero 15, 2026","format":false,"excerpt":"En un Consejo de ministros, realizado en la noche del mi\u00e9rcoles en la Casa de Nari\u00f1o en Bogot\u00e1, Gustavo Petro dijo que el 3 de febrero se reunir\u00e1 con el presidente de Estados Unidos, Donald Trump, en Washington. Petro resalt\u00f3 que la intenci\u00f3n de este encuentro es que los colombianos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470825,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/03\/petro-victoria-geopolitica-reunion-trump-orix\/","url_meta":{"origin":1470830,"position":3},"title":"Petro logra una victoria geopol\u00edtica tras mantener una reuni\u00f3n &#171;positiva&#187; con Trump en la Casa Blanca","author":"","date":"febrero 3, 2026","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, logr\u00f3 una victoria pol\u00edtica significativa tras mantener una reuni\u00f3n \u201cpositiva\u201d con el presidente de EE.UU., Donald Trump, este martes en la Casa Blanca.Fue apenas en octubre cuando el Gobierno de Estados Unidos acus\u00f3 a Petro de estar involucrado en el narcotr\u00e1fico (Petro ha negado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472144,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/03\/12\/trump-petro-llamada-energia-narcotrafico-trax\/","url_meta":{"origin":1470830,"position":4},"title":"Trump y Petro hablan por tel\u00e9fono sobre energ\u00eda, narcotr\u00e1fico y Venezuela","author":"","date":"marzo 12, 2026","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, sostuvo una llamada telef\u00f3nica de casi media hora la tarde de este jueves con el presidente de Colombia, Gustavo Petro, seg\u00fan inform\u00f3 el asesor presidencial colombiano Andr\u00e9s Hern\u00e1ndez Ram\u00edrez.La conversaci\u00f3n se centr\u00f3 en la cooperaci\u00f3n energ\u00e9tica, los esfuerzos para combatir el narcotr\u00e1fico y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470755,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/02\/petro-reunion-trump-washington-orix\/","url_meta":{"origin":1470830,"position":5},"title":"Petro lleg\u00f3 a Washington para su reuni\u00f3n con Trump tras un a\u00f1o de fuertes tensiones","author":"","date":"febrero 2, 2026","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, lleg\u00f3 este lunes a Washington para reunirse con el mandatario estadounidense, Donald Trump, quien lo recibir\u00e1 el martes en la Casa Blanca tras un a\u00f1o de varios ataques verbales y tensiones que se aliviaron en las \u00faltimas semanas.\u201cEmpiezo mi jornada de comunicaci\u00f3n intensa con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1470830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1470830"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1470830\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1470830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1470830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1470830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}