{"id":1470908,"date":"2026-02-05T14:03:52","date_gmt":"2026-02-05T22:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/"},"modified":"2026-02-05T14:03:52","modified_gmt":"2026-02-05T22:03:52","slug":"hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/","title":{"rendered":"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes"},"content":{"rendered":"<p>La decisi\u00f3n del Gobierno de Trump de otorgar a los funcionarios de deportaci\u00f3n <a href=\"https:\/\/apnews.com\/article\/immigration-medicaid-trump-ice-ab9c2267ce596089410387bfcb40eeb7\">acceso a los datos de Medicaid<\/a> est\u00e1 poniendo a los hospitales y a los estados en una posici\u00f3n dif\u00edcil, ya que deben considerar si alertan a los pacientes inmigrantes de que su informaci\u00f3n personal, incluyendo las direcciones de sus hogares, podr\u00eda ser utilizada en esfuerzos para expulsarlos del pa\u00eds.<\/p>\n<p>Advertir a los pacientes podr\u00eda disuadirlos de inscribirse en un programa llamado Medicaid de Emergencia, a trav\u00e9s del cual <a href=\"https:\/\/kffhealthnews.org\/news\/medicaid-illegal-immigrant-emergency-care\/\">el Gobierno reembolsa a los hospitales el costo del tratamiento de emergencia<\/a> para inmigrantes que no son elegibles para la cobertura est\u00e1ndar de Medicaid.<\/p>\n<p>Pero si los hospitales no divulgan que la informaci\u00f3n de los pacientes se comparte con las autoridades federales, es posible que los pacientes no sepan que su cobertura m\u00e9dica los pone en riesgo de ser localizados por el ICE.<\/p>\n<p>\u201cSi los hospitales le dicen a las personas que su informaci\u00f3n de Medicaid de Emergencia ser\u00e1 compartida con ICE, es previsible que muchos inmigrantes simplemente dejar\u00edan de recibir tratamiento m\u00e9dico de emergencia\u201d, dijo <a href=\"https:\/\/ccf.georgetown.edu\/author\/leonardo-cuello\/\">Leonardo Cuello<\/a>, profesor investigador en el Centro para Ni\u00f1os y Familias de la Universidad de Georgetown. \u201cLa mitad de los casos de Medicaid de Emergencia son para el parto de beb\u00e9s ciudadanos estadounidenses. \u00bfQueremos que estas madres eviten el hospital cuando entran en trabajo de parto?\u201d<\/p>\n<p>Durante m\u00e1s de una d\u00e9cada, los hospitales y los estados han asegurado a los pacientes que su informaci\u00f3n personal, incluidas sus direcciones y estatus migratorio, no ser\u00eda compartida con funcionarios de inmigraci\u00f3n cuando solicitan cobertura federal de atenci\u00f3n m\u00e9dica. <a href=\"https:\/\/www.ice.gov\/doclib\/ero-outreach\/pdf\/ice-aca-memo.pdf\">Un memorando de pol\u00edtica de ICE de 2013<\/a> garantizaba que la agencia no usar\u00eda informaci\u00f3n de las solicitudes de cobertura m\u00e9dica para actividades de cumplimiento de la ley.<\/p>\n<p>Pero eso cambi\u00f3 el a\u00f1o pasado, despu\u00e9s de que el presidente Donald Trump regres\u00f3 a la Casa Blanca y orden\u00f3 una de las represalias migratorias m\u00e1s agresivas en la historia reciente. Su Gobierno comenz\u00f3 a canalizar datos de varias agencias gubernamentales al Departamento de Seguridad Nacional, <a href=\"https:\/\/www.propublica.org\/article\/trump-irs-share-tax-records-ice-dhs-deportations\">incluida la informaci\u00f3n fiscal<\/a> presentada ante el IRS.<\/p>\n<p>Los Centros de Servicios de Medicare y Medicaid, parte del Departamento de Salud y Servicios Humanos, acordaron la primavera pasada dar a los funcionarios de ICE acceso directo a una base de datos de Medicaid que incluye direcciones y estatus de ciudadan\u00eda de los beneficiarios.<\/p>\n<p>Veintid\u00f3s estados, todos menos uno, gobernados por dem\u00f3cratas, <a href=\"https:\/\/apnews.com\/article\/trump-medicaid-immigrant-california-161f7e1b9087512d674258f32f822878\">demandaron para bloquear el acuerdo de intercambio de datos de Medicaid<\/a>, que la administraci\u00f3n no anunci\u00f3 formalmente hasta que un juez federal se lo orden\u00f3 el verano pasado. El juez <a href=\"https:\/\/apnews.com\/article\/medicaid-data-hhs-rfk-sharing-immigration-trump-30784ce01a403a16aca504980e4c7bc9\">fall\u00f3 en diciembre<\/a> que en esos estados, ICE solo podr\u00eda acceder a la informaci\u00f3n en la base de datos de Medicaid sobre personas en el pa\u00eds ilegalmente. KFF Health News contact\u00f3 a m\u00e1s de una docena de hospitales y asociaciones hospitalarias en estados y ciudades que han sido objetivo de redadas de ICE. Muchos se negaron a comentar sobre si han actualizado sus pol\u00edticas de divulgaci\u00f3n tras la sentencia.<\/p>\n<p>De los que respondieron, ninguno dijo que est\u00e9n advirtiendo directamente a los pacientes que su informaci\u00f3n personal puede ser compartida con ICE cuando solicitan cobertura de Medicaid.<\/p>\n<p>\u201cNo proporcionamos asesoramiento legal sobre el intercambio de datos del gobierno federal entre agencias\u201d, dijo Aimee Jordon, portavoz de M Health Fairview, un sistema hospitalario con sede en Minneapolis, en un correo electr\u00f3nico a KFF Health News. \u201cAnimamos a los pacientes con preguntas sobre beneficios o inquietudes relacionadas con inmigraci\u00f3n a buscar orientaci\u00f3n en los recursos estatales apropiados y abogados calificados\u201d.<\/p>\n<p>Algunas solicitudes de Medicaid de emergencia de ciertos estados piden espec\u00edficamente el estatus migratorio del paciente \u2014 y a\u00fan as\u00ed aseguran a las personas que su informaci\u00f3n se mantendr\u00e1 segura y fuera del alcance de las autoridades de inmigraci\u00f3n.<\/p>\n<p>Por ejemplo, al 3 de febrero, la solicitud de California a\u00fan inclu\u00eda un lenguaje que advert\u00eda a los solicitantes que su informaci\u00f3n migratoria es \u201cconfidencial\u201d.<\/p>\n<p>\u201cSolo la usamos para ver si califica para un seguro de salud\u201d, dice el formulario de 44 p\u00e1ginas que el programa estatal de Medicaid, conocido como Medi-Cal, <a href=\"https:\/\/www.instagram.com\/p\/DTlTg7xjdGl\/\">public\u00f3 en las redes sociales<\/a> en enero.<\/p>\n<p>Anthony Cava, portavoz del Departamento de Servicios de Salud de California, dijo en un comunicado que la agencia, que supervisa Medi-Cal, \u201cgarantizar\u00e1 que los californianos tengan informaci\u00f3n precisa sobre la privacidad de sus datos, incluso revisando y modificando publicaciones adicionales seg\u00fan sea necesario.\u201d<\/p>\n<p>Hasta finales de enero, el sitio web de Medicaid de Utah tambi\u00e9n afirmaba que su programa de Medicaid de emergencia no compart\u00eda informaci\u00f3n con las autoridades migratorias. Tras ser contactada por KFF Health News, Kolbi Young, portavoz, dijo el 23 de enero que ese lenguaje ser\u00eda eliminado de inmediato. Se elimin\u00f3 ese mismo d\u00eda.<\/p>\n<p>La Universidad de Ciencias y Salud de Oregon, un sistema hospitalario con sede en Portland, ofrece a los pacientes inmigrantes <a href=\"https:\/\/sharedsystems.dhsoha.state.or.us\/DHSForms\/Served\/le-1086100c.pdf\">un documento de preguntas y respuestas<\/a> desarrollado por el programa estatal de Medicaid para quienes tienen inquietudes sobre el uso de su informaci\u00f3n. El documento no indica directamente que la informaci\u00f3n de los inscritos en Medicaid sea compartida con funcionarios del ICE.<\/p>\n<p>Los hospitales dependen de Medicaid de emergencia para que se les reembolsen los tratamientos a personas que calificar\u00edan para Medicaid si no fuera por su estatus de ciudadan\u00eda \u2014 ya sea personas en el pa\u00eds ilegalmente o inmigrantes con presencia legal, como aquellos con visa de estudiante o trabajo. La cobertura solo paga la atenci\u00f3n m\u00e9dica de emergencia y la atenci\u00f3n por embarazo. T\u00edpicamente, representantes del hospital ayudan a los pacientes a solicitar mientras a\u00fan est\u00e1n en la instalaci\u00f3n m\u00e9dica.<\/p>\n<p>El programa principal de Medicaid, que cubre una gama mucho m\u00e1s amplia de servicios para m\u00e1s de 77 millones de personas de bajos ingresos y personas con discapacidades, no cubre a quienes viven en el pa\u00eds ilegalmente.<\/p>\n<p>Entonces, examinar la inscripci\u00f3n en Medicaid de emergencia es la forma m\u00e1s obvia para que las autoridades de deportaci\u00f3n identifiquen a inmigrantes, incluidos aquellos que no residen legalmente en los EE.UU.<\/p>\n<p>El portavoz del HHS, Rich Danker, dijo en un correo electr\u00f3nico que CMS \u2014 que supervisa Medicaid, un programa conjunto estatal-federal \u2014 est\u00e1 compartiendo datos con ICE tras la decisi\u00f3n del juez. Pero no respondi\u00f3 c\u00f3mo la agencia garantiza que solo comparte informaci\u00f3n de personas que no est\u00e1n legalmente presentes, como exig\u00eda el juez.<\/p>\n<p>Ahora que ICE tiene acceso directo a la informaci\u00f3n personal de millones de inscritos en Medicaid, los hospitales \u2014 aunque \u201cdefinitivamente est\u00e1n en una posici\u00f3n dif\u00edcil\u201d \u2014 deben ser transparentes sobre los cambios, dijo Sarah Grusin, <a href=\"https:\/\/healthlaw.org\/team\/sarah-grusin\/\">abogada del National Health Law Program<\/a>, un grupo de defensa.<\/p>\n<p>\u201cDeben decirles a las personas que el juez ha permitido el intercambio de informaci\u00f3n, incluido su domicilio, para quienes no residen legalmente\u201d, dijo. \u201cUna vez que se env\u00eda esta informaci\u00f3n, no se puede proteger de su divulgaci\u00f3n en este punto.\u201d<\/p>\n<p>Grusin dijo que recomienda a las familias sopesar la importancia de buscar atenci\u00f3n m\u00e9dica frente al riesgo de que su informaci\u00f3n sea compartida con ICE.<\/p>\n<p>\u201cQueremos brindar informaci\u00f3n franca y honesta, aunque signifique que la decisi\u00f3n que deben tomar las personas sea realmente dif\u00edcil\u201d, dijo.<\/p>\n<p>Quienes ya se han inscrito previamente en Medicaid o pueden buscar f\u00e1cilmente su direcci\u00f3n en Internet deben asumir que las autoridades migratorias ya tienen su informaci\u00f3n, a\u00f1adi\u00f3.<\/p>\n<p>La cobertura de Medicaid de emergencia se estableci\u00f3 a mediados de los a\u00f1os ochenta, cuando una ley federal comenz\u00f3 a exigir que los hospitales trataran y estabilizaran a todos los pacientes que llegaran a sus puertas con una condici\u00f3n potencialmente mortal.<\/p>\n<p>El gasto del Gobierno federal en Medicaid de emergencia represent\u00f3 casi US$ 4.000 millones en 2023, o <a href=\"https:\/\/www.kff.org\/racial-equity-and-health-policy\/5-key-facts-about-immigrants-and-medicaid\/#:~:text=3.,in%20FY%202023:%20$860%20Billion\">aproximadamente el 0,4 %<\/a> del gasto federal total en Medicaid.<\/p>\n<p>Los estados env\u00edan informes mensuales al Gobierno federal con informaci\u00f3n detallada sobre qui\u00e9nes se inscriben en Medicaid y qu\u00e9 servicios reciben. El fallo del juez en diciembre limit\u00f3 lo que CMS puede compartir con ICE solo a informaci\u00f3n b\u00e1sica, incluidas direcciones, sobre los inscritos en Medicaid en los 22 estados que demandaron por el acuerdo de intercambio de datos. Seg\u00fan la orden del juez, los funcionarios de ICE no deben acceder a informaci\u00f3n sobre los servicios m\u00e9dicos que reciben las personas.<\/p>\n<p>El juez tambi\u00e9n prohibi\u00f3 que la agencia comparta los datos de ciudadanos estadounidenses o inmigrantes con presencia legal de esos estados.<\/p>\n<p>Los funcionarios de deportaci\u00f3n tienen acceso a la informaci\u00f3n personal de Medicaid de todos los inscritos en los 28 estados restantes.<\/p>\n<p>La agencia federal de salud no ha aclarado c\u00f3mo garantiza que la informaci\u00f3n de ciertos estados sobre ciudadanos y residentes legales no sea compartida con ICE. Pero los expertos en Medicaid dicen que ser\u00eda casi imposible para la agencia separar los datos, lo que plantea dudas sobre si el Gobierno de Trump est\u00e1 cumpliendo con la orden del juez.<\/p>\n<p>Los esfuerzos del Gobierno de Trump por deportar a inmigrantes que viven ilegalmente en el pa\u00eds han tenido implicaciones para las familias inmigrantes que buscan atenci\u00f3n. Aproximadamente un tercio de los inmigrantes adultos inform\u00f3 haber omitido o pospuesto atenci\u00f3n m\u00e9dica en el \u00faltimo a\u00f1o, seg\u00fan <a href=\"https:\/\/www.kff.org\/immigrant-health\/kff-new-york-times-2025-survey-of-immigrants-health-and-health-care-experiences-during-the-second-trump-administration\/\">una encuesta de KFF\/The New York Times<\/a> publicada en noviembre. (KFF es una organizaci\u00f3n sin fines de lucro de informaci\u00f3n sobre salud que incluye KFF Health News.)<\/p>\n<p>Bethany Pray, jefa de asuntos legales y pol\u00edticas del Colorado Center on Law and Policy, advirti\u00f3 que compartir datos de Medicaid directamente con funcionarios de deportaci\u00f3n obligar\u00e1 a algunas familias a tomar decisiones a\u00fan m\u00e1s dif\u00edciles.<\/p>\n<p>\u201cEsto es muy preocupante\u201d, dijo Pray. \u201cLa gente no deber\u00eda tener que elegir entre dar a luz en un hospital y preguntarse si eso significa que corren el riesgo de ser deportados\u201d.<\/p>\n<p><a href=\"https:\/\/kffhealthnews.org\/about-us\/\"><em>KFF Health News<\/em><\/a><em> es una sala de redacci\u00f3n nacional que produce periodismo en profundidad sobre temas de salud y es uno de los programas operativos principales de <\/em><a href=\"https:\/\/www.kff.org\/about-us\/\"><em>KFF<\/em><\/a><em>\u2014 la fuente independiente de investigaciones de pol\u00edticas de salud, encuestas y periodismo.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La decisi\u00f3n del Gobierno de Trump de otorgar a los funcionarios de deportaci\u00f3n acceso a los datos de Medicaid est\u00e1 poniendo a los hospitales y a los estados en una posici\u00f3n dif\u00edcil, ya que deben considerar si alertan a los pacientes inmigrantes de que su informaci\u00f3n personal, incluyendo las direcciones de sus hogares, podr\u00eda ser [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470908","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes - Noticias\" \/>\n<meta property=\"og:description\" content=\"La decisi\u00f3n del Gobierno de Trump de otorgar a los funcionarios de deportaci\u00f3n acceso a los datos de Medicaid est\u00e1 poniendo a los hospitales y a los estados en una posici\u00f3n dif\u00edcil, ya que deben considerar si alertan a los pacientes inmigrantes de que su informaci\u00f3n personal, incluyendo las direcciones de sus hogares, podr\u00eda ser [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-05T22:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes\",\"datePublished\":\"2026-02-05T22:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/\"},\"wordCount\":1786,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/\",\"name\":\"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-05T22:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes - Noticias","og_description":"La decisi\u00f3n del Gobierno de Trump de otorgar a los funcionarios de deportaci\u00f3n acceso a los datos de Medicaid est\u00e1 poniendo a los hospitales y a los estados en una posici\u00f3n dif\u00edcil, ya que deben considerar si alertan a los pacientes inmigrantes de que su informaci\u00f3n personal, incluyendo las direcciones de sus hogares, podr\u00eda ser [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-05T22:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/"},"author":{"name":"","@id":""},"headline":"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes","datePublished":"2026-02-05T22:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/"},"wordCount":1786,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/","name":"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-05T22:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes","url":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-05T22:03:52Z","datePublished":"2026-02-05T22:03:52Z","dateModified":"2026-02-05T22:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/05\\\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/05\\\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-05T22:03:52Z\",\"datePublished\":\"2026-02-05T22:03:52Z\",\"dateModified\":\"2026-02-05T22:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455505,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/01\/pacientes-hospitales-texas-consultados-legalmente-ap\/","url_meta":{"origin":1470908,"position":0},"title":"A partir de este viernes, los pacientes de hospitales de Texas ser\u00e1n consultados sobre si se encuentran en Estados Unidos legalmente","author":"","date":"noviembre 1, 2024","format":false,"excerpt":"(AP) -- A partir de este viernes se les preguntar\u00e1 a los pacientes de los hospitales de Texas si est\u00e1n en EE.UU. legalmente.La nueva pol\u00edtica surge de una orden del gobernador republicano Greg Abbott y representa una escalada en el enfrentamiento del estado con la administraci\u00f3n Biden en materia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457802,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/","url_meta":{"origin":1470908,"position":1},"title":"Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes","author":"","date":"enero 23, 2025","format":false,"excerpt":"Autoridades de California est\u00e1n aconsejando a los proveedores de atenci\u00f3n m\u00e9dica que no escriban el estatus migratorio de los pacientes en las facturas y los registros m\u00e9dicos y les dijeron que no tienen que ayudar a los agentes federales en las detenciones. Algunos hospitales y cl\u00ednicas de Massachusetts est\u00e1n publicando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467103,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/10\/04\/cierre-gobierno-atencion-medica-inmigrantes-trax\/","url_meta":{"origin":1470908,"position":2},"title":"La verdad sobre el cierre del Gobierno y la atenci\u00f3n m\u00e9dica para los inmigrantes","author":"","date":"octubre 4, 2025","format":false,"excerpt":"La guerra de mensajes sobre el cierre del Gobierno est\u00e1 en pleno apogeo, y los primeros indicios son que los republicanos se encuentran en una situaci\u00f3n dif\u00edcil, dado que la demanda de los dem\u00f3cratas de extender los subsidios mejorados del Obamacare parece bastante popular.As\u00ed, los l\u00edderes republicanos han vuelto a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467895,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/10\/31\/salud-trump-medicaid-inmigrantes-indocumentados-trax\/","url_meta":{"origin":1470908,"position":3},"title":"El Departamento de Salud de Trump ordena a programas estatales de Medicaid que ayuden a encontrar inmigrantes indocumentados","author":"","date":"octubre 31, 2025","format":false,"excerpt":"La administraci\u00f3n Trump ha ordenado a los estados que investiguen a ciertas personas inscritas en Medicaid para determinar si no son elegibles debido a su estatus migratorio.Cinco estados informaron haber recibido consultas sobre m\u00e1s de 170.000 nombres en conjunto, una medida \u201csin precedentes\u201d del Gobierno federal que involucra al programa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450045,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/04\/ciberataque-ransomware-interrumpio-atencion-pacientes-hospitales-londres-cancelaron-operaciones-trax\/","url_meta":{"origin":1470908,"position":4},"title":"Un ciberataque interrumpi\u00f3 la atenci\u00f3n a los pacientes en los hospitales de Londres y se cancelaron varias operaciones","author":"","date":"junio 4, 2024","format":false,"excerpt":"(CNN) --Un ciberataque contra un contratista del Servicio Nacional de Salud de Inglaterra oblig\u00f3 a varios grandes hospitales de Londres a cancelar operaciones, an\u00e1lisis de sangre, citas y\u00a0 a reubicar a los pacientes a otros lugares.El King's College Hospital, el Guy's y el St Thomas' fueron afectados, al igual que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471469,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/20\/inmigracion-medicos-ice-atencion-sanitaria-crisis-trax\/","url_meta":{"origin":1470908,"position":5},"title":"La ofensiva migratoria de Trump est\u00e1 generando una crisis sanitaria en Estados Unidos, advierten los m\u00e9dicos","author":"","date":"febrero 20, 2026","format":false,"excerpt":"Dado que muchas personas no pueden o tienen miedo de acceder a la atenci\u00f3n m\u00e9dica, algunos proveedores dicen que est\u00e1n viendo una disminuci\u00f3n en el n\u00famero de pacientes que no hab\u00edan visto desde la pandemia de covid-19, esta vez brindando atenci\u00f3n mientras potencialmente tratan con agentes federales con equipo t\u00e1ctico.Los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1470908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1470908"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1470908\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1470908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1470908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1470908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}