{"id":1470918,"date":"2026-02-05T17:03:44","date_gmt":"2026-02-06T01:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/"},"modified":"2026-02-05T17:03:44","modified_gmt":"2026-02-06T01:03:44","slug":"fda-aprueba-colorante-alimentario-natural-rojo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/","title":{"rendered":"La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\u00eda el uso de la espirulina"},"content":{"rendered":"<p>Como parte de las labores del movimiento \u201c<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/22\/eeuu\/video\/make-america-health-again-baile-investidura-kennedy-jr-trax-ush\">Make America Healthy Again<\/a>\u201d para reemplazar los colorantes artificiales, derivados del petr\u00f3leo, por alternativas naturales, la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, por sus siglas en ingl\u00e9s) anunci\u00f3 que aprob\u00f3 el uso del colorante rojo de remolacha y ampli\u00f3 el uso del extracto de espirulina.<\/p>\n<p>El n\u00famero de colorantes naturales aprobados durante el actual Gobierno asciende ahora a seis, <a href=\"https:\/\/www.fda.gov\/news-events\/press-announcements\/fda-takes-new-approach-no-artificial-colors-claims\">seg\u00fan inform\u00f3 la agencia el jueves.<\/a><\/p>\n<p>El rojo de remolacha es un l\u00edquido o polvo de color rojizo-p\u00farpura. El extracto de espirulina, un polvo o l\u00edquido verde azulado obtenido del alga Arthrospira platensis, que se encuentra en oc\u00e9anos y lagos salinos, <a href=\"https:\/\/hfpappexternal.fda.gov\/scripts\/fdcc\/index.cfm?set=ColorAdditives&#038;id=SpirulinaExtract\">ya estaba aprobado para su uso<\/a> en numerosos alimentos y bebidas. Entre ellos se incluyen dulces, chicles, glaseados, algunos productos l\u00e1cteos, cereales, condimentos y bebidas alcoh\u00f3licas y no alcoh\u00f3licas.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/04\/22\/eeuu\/fda-eliminara-colorantes-alimentarios-petroleo-trax\">La acci\u00f3n m\u00e1s reciente de la FDA<\/a> permite que este ingrediente se utilice de manera m\u00e1s general en otros alimentos destinados al consumo humano, con excepci\u00f3n de la f\u00f3rmula infantil y de ciertos productos sujetos a inspecci\u00f3n del Departamento de Agricultura de Estados Unidos (USDA, por sus siglas en ingl\u00e9s).<\/p>\n<p>La FDA tambi\u00e9n anunci\u00f3 que los productos que contengan colorantes naturales ahora pueden llevar la etiqueta \u201csin colorantes artificiales\u201d, lo que facilitar\u00e1 a los consumidores distinguir entre alimentos te\u00f1idos de manera sint\u00e9tica y natural. Antes, las empresas por lo general solo pod\u00edan hacer este tipo de afirmaciones si sus productos no conten\u00edan ning\u00fan colorante a\u00f1adido.<\/p>\n<p>\u201cEsto es un avance real\u201d, dijo el secretario del Departamento de Salud y Servicios Humanos de Estados Unidos, Robert F. Kennedy Jr., en un comunicado. \u201cEstamos facilitando que las empresas se alejen de los colorantes sint\u00e9ticos derivados del petr\u00f3leo y adopten alternativas m\u00e1s seguras, de origen natural. Este impulso fortalece nuestro esfuerzo m\u00e1s amplio para ayudar a los estadounidenses a comer alimentos reales y a Make America Healthy Again\u201d.<\/p>\n<p>Los colorantes sint\u00e9ticos m\u00e1s utilizados en Estados Unidos son los rojos n\u00fameros 3 y 40, los amarillos n\u00fameros 5 y 6, y los azules n\u00fameros 1 y 2. Estos colorantes han sido asociados con un mayor riesgo para la salud, incluidos, en algunos casos, c\u00e1ncer y problemas neuroconductuales en animales y ni\u00f1os.<\/p>\n<p>\u201cLos colorantes artificiales dominaron porque son m\u00e1s baratos, m\u00e1s estables al calor y al almacenamiento, y m\u00e1s f\u00e1ciles de estandarizar en alimentos ultraprocesados\u201d, explic\u00f3 por correo electr\u00f3nico el Dr. Wesley McWhorter, dietista registrado y vocero de la Academia de Nutrici\u00f3n y Diet\u00e9tica. \u201cPero esas ventajas de fabricaci\u00f3n no implican que sean m\u00e1s saludables o necesarios, raz\u00f3n por la cual muchas marcas enfocadas en alimentos integrales han vuelto a fuentes de coloraci\u00f3n basadas en plantas y algas\u201d.<\/p>\n<p>California comenz\u00f3 a sentar las bases para una legislaci\u00f3n contra los colorantes sint\u00e9ticos hace varios a\u00f1os. Desde entonces, <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/\">el estado prohibi\u00f3 el uso del colorante rojo n\u00famero 3<\/a> en todo su territorio y de otros seis colorantes comunes en los alimentos escolares. Estas leyes entrar\u00e1n en vigor el 1 de enero de 2027 y el 31 de diciembre de 2027, respectivamente. La FDA prohibi\u00f3 el colorante rojo n\u00famero 3 en enero de 2025.<\/p>\n<p>Otros 26 estados han seguido el ejemplo de California con iniciativas legislativas \u2014<a href=\"https:\/\/governor.wv.gov\/article\/governor-patrick-morrisey-signs-food-dye-legislation-law\">algunas ya convertidas en ley<\/a> y <a href=\"https:\/\/www.ewg.org\/news-insights\/news\/2026\/02\/interactive-map-tracking-state-food-chemical-regulation-us\">otras a\u00fan en proceso<\/a>\u2014 que buscan prohibir, restringir o exigir el etiquetado de los colorantes artificiales.<\/p>\n<p>Algunos estados como <a href=\"https:\/\/arkleg.state.ar.us\/Bills\/Detail?id=sb9&#038;ddBienniumSession=2025%2F2025R\">Arkansas<\/a>, <a href=\"https:\/\/gov.texas.gov\/news\/post\/governor-abbott-signs-texas-make-america-healthy-again-legislation#:~:text=The%20%22Make%20Texas%20Healthy%20Again%22%20Act%2C%20Senate,a%20part%20of%20free%20or%20reduced%2Dprice%20meals\">Texas <\/a>y Virginia Occidental han se\u00f1alado que se inspiraron en Kennedy.<\/p>\n<p>En abril, la FDA anunci\u00f3 planes para trabajar con la industria en la eliminaci\u00f3n gradual del uso de colorantes sint\u00e9ticos en el suministro de alimentos. Muchos fabricantes, restaurantes y comercios populares ya han seguido ese camino, entre ellos Kraft Heinz, General Mills, WK Kellogg Co., The Campbell\u2019s Company, PepsiCo, Nestl\u00e9, The Hershey Company, Utz,<a href=\"https:\/\/www.cnn.com\/2025\/05\/14\/food\/in-n-out-removal-artificial-ingredients\"> In-N-Out<\/a>, Walmart y Sam\u2019s Club.<\/p>\n<p>La FDA ha dicho que quiere eliminar los colorantes sint\u00e9ticos del sistema alimentario de Estados Unidos para enero de 2027. Mientras tanto, los consumidores pueden identificar los productos que los contienen leyendo las listas de ingredientes al hacer sus compras.<\/p>\n<p>En las listas de ingredientes, estos colorantes artificiales <a href=\"https:\/\/www.fda.gov\/industry\/color-additives\/color-additives-history\">se denominan a veces<\/a> con diferentes t\u00e9rminos:<\/p>\n<ul>\n<li>Rojo n\u00famero 3: red 3, FD&#038;C Red No. 3 o eritrosina<\/li>\n<li>Rojo n\u00famero 40: red 40, FD&#038;C Red No. 40 o Allura Red AC<\/li>\n<li>Azul n\u00famero 1: blue 1, FD&#038;C Blue No. 1 o Brilliant Blue FCF<\/li>\n<li>Azul n\u00famero 2: FD&#038;C Blue No. 2 o indigotina<\/li>\n<li>Amarillo n\u00famero 5: yellow 5, FD&#038;C Yellow No. 5 o tartrazina<\/li>\n<li>Amarillo n\u00famero 6: yellow 6, FD&#038;C Yellow No. 6 o amarillo ocaso<\/li>\n<\/ul>\n<p>Los colorantes que aparecen con la palabra \u201claca\u201d en la lista de ingredientes significan que el colorante es una versi\u00f3n insoluble en agua, por lo que puede disolverse en alimentos grasos o con bajo contenido de humedad.<\/p>\n<p>La petici\u00f3n que plante\u00f3 el color rojo remolacha para su consideraci\u00f3n por parte de la FDA fue <a href=\"https:\/\/hfpappexternal.fda.gov\/scripts\/fdcc\/index.cfm?set=FAP-CAP&#038;id=CAP_4C0326\">presentada<\/a> en noviembre de 2023 por Phytolon, un fabricante de colorantes naturales con sede en Israel.<\/p>\n<p>\u201cLos colorantes a base de remolacha tiene una larga historia culinaria y se han utilizado habitualmente en los sistemas alimentarios modernos durante d\u00e9cadas\u201d, se\u00f1al\u00f3 McWhorter, quien tambi\u00e9n es vicepresidente de medicina del estilo de vida en Suvida Healthcare.<\/p>\n<p>Los colorantes de color azul a marr\u00f3n producidos a partir de remolacha exprimida, en polvo o deshidratada ya han sido aprobados por la FDA.<\/p>\n<p>El uso ampliado del extracto de espirulina concede una petici\u00f3n presentada en <a href=\"https:\/\/hfpappexternal.fda.gov\/scripts\/fdcc\/index.cfm?set=FAP-CAP&#038;id=CAP_4C0334\">julio de 2024<\/a> por GNT, un fabricante de colorantes vegetales con sede en Dallas.<\/p>\n<p>Aunque se han realizado algunas investigaciones con animales y seres humanos sobre los colorantes alimentarios artificiales, la financiaci\u00f3n para seguir investigando es insuficiente, y a\u00fan menos para el estudio de alternativas emergentes, seg\u00fan informaron los expertos a <a href=\"https:\/\/www.cnn.com\/2025\/05\/09\/health\/natural-food-dyes-fda-approved-wellness\">CNN en mayo<\/a>, por lo que no est\u00e1 claro si los colorantes naturales podr\u00edan tener alg\u00fan efecto sobre la salud humana.<\/p>\n<p>Y aunque \u201cnatural\u201d no significa autom\u00e1ticamente que algo sea seguro para el consumo, \u201ces dif\u00edcil creer\u201d que los colorantes provenientes de plantas y utilizados en cantidades peque\u00f1as sean perjudiciales para la poblaci\u00f3n general, afirm\u00f3 la Dra. Marion Nestle, profesora em\u00e9rita Paulette Goddard de Nutrici\u00f3n, Estudios de la Alimentaci\u00f3n y Salud P\u00fablica en la Universidad de Nueva York, en una entrevista en abril.<\/p>\n<p>\u201cEl principal riesgo que se menciona en la investigaci\u00f3n est\u00e1 relacionado con la contaminaci\u00f3n en productos de espirulina mal controlados, m\u00e1s que con su uso regulado en alimentos\u201d, explic\u00f3 McWhorter.<\/p>\n<p>La espirulina ha sido popular entre entusiastas de la salud durante siglos. Cuando se consume como alimento completo o suplemento, es nutritiva por su contenido de prote\u00ednas, cobre, hierro, antioxidantes y vitaminas del complejo B, se\u00f1al\u00f3 por correo electr\u00f3nico Julia Zumpano, dietista registrada de la Cl\u00ednica Cleveland.<\/p>\n<p>Pero los extractos de espirulina y remolacha utilizados como colorantes no aportan ning\u00fan nutriente significativo, dijo McWhorter, debido a las peque\u00f1as cantidades que se consumen y al efecto que el procesamiento puede tener sobre los nutrientes.<\/p>\n<p>En 2025, la FDA <a href=\"https:\/\/www.cnn.com\/2025\/05\/09\/health\/natural-food-dyes-fda-approved-wellness\">aprob\u00f3<\/a> o ampli\u00f3 el uso de otros cuatro colorantes naturales: el extracto azul de Galdieria, el extracto de flor de guisante mariposa, el fosfato de calcio y el azul de gardenia (genipina).<\/p>\n<p>\u201cIndependientemente del tipo de colorante, los resultados en salud est\u00e1n mucho m\u00e1s determinados por una dieta equilibrada, rica en fibra y basada en alimentos integrales, que incluya prote\u00ednas magras, verduras y grasas saludables, que por el color de los alimentos en s\u00ed\u201d, concluy\u00f3 McWhorter.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de las labores del movimiento \u201cMake America Healthy Again\u201d para reemplazar los colorantes artificiales, derivados del petr\u00f3leo, por alternativas naturales, la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, por sus siglas en ingl\u00e9s) anunci\u00f3 que aprob\u00f3 el uso del colorante rojo de remolacha y ampli\u00f3 el uso del extracto de espirulina. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470918","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\u00eda el uso de la espirulina - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\u00eda el uso de la espirulina - Noticias\" \/>\n<meta property=\"og:description\" content=\"Como parte de las labores del movimiento \u201cMake America Healthy Again\u201d para reemplazar los colorantes artificiales, derivados del petr\u00f3leo, por alternativas naturales, la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, por sus siglas en ingl\u00e9s) anunci\u00f3 que aprob\u00f3 el uso del colorante rojo de remolacha y ampli\u00f3 el uso del extracto de espirulina. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-06T01:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\u00eda el uso de la espirulina\",\"datePublished\":\"2026-02-06T01:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/\"},\"wordCount\":1323,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/\",\"name\":\"La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\u00eda el uso de la espirulina - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-06T01:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\u00eda el uso de la espirulina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\u00eda el uso de la espirulina - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\u00eda el uso de la espirulina - Noticias","og_description":"Como parte de las labores del movimiento \u201cMake America Healthy Again\u201d para reemplazar los colorantes artificiales, derivados del petr\u00f3leo, por alternativas naturales, la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, por sus siglas en ingl\u00e9s) anunci\u00f3 que aprob\u00f3 el uso del colorante rojo de remolacha y ampli\u00f3 el uso del extracto de espirulina. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-06T01:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/"},"author":{"name":"","@id":""},"headline":"La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\u00eda el uso de la espirulina","datePublished":"2026-02-06T01:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/"},"wordCount":1323,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/","name":"La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\u00eda el uso de la espirulina - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-06T01:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\u00eda el uso de la espirulina"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\u00eda el uso de la espirulina","url":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/05\/fda-aprueba-colorante-alimentario-natural-rojo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-06T01:03:44Z","datePublished":"2026-02-06T01:03:44Z","dateModified":"2026-02-06T01:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La FDA aprueba el colorante alimentario natural rojo de remolacha y ampl\\u00eda el uso de la espirulina\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/05\\\/fda-aprueba-colorante-alimentario-natural-rojo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/05\\\/fda-aprueba-colorante-alimentario-natural-rojo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-06T01:03:44Z\",\"datePublished\":\"2026-02-06T01:03:44Z\",\"dateModified\":\"2026-02-06T01:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457602,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/17\/colorante-rojo-3-prohibido-estudios-otros-colorantes-trax\/","url_meta":{"origin":1470918,"position":0},"title":"El colorante rojo n\u00famero 3 ya est\u00e1 prohibido en Estados Unidos. \u00bfQu\u00e9 dicen los estudios sobre otros colorantes?","author":"","date":"enero 17, 2025","format":false,"excerpt":"Ahora que la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA) prohibi\u00f3 el colorante rojo n\u00famero 3, son muchos los que critican o cuestionan la seguridad y la autorizaci\u00f3n por parte de la FDA del colorante rojo n\u00famero 40 y otros cinco aditivos colorantes de uso com\u00fan en Estados Unidos.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457553,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/15\/fda-prohibe-colorante-rojo-alimentos-ee-uu-trax\/","url_meta":{"origin":1470918,"position":1},"title":"FDA proh\u00edbe el colorante rojo n\u00famero 3, vinculado con c\u00e1ncer en estudios, en alimentos, bebidas y medicamentos","author":"","date":"enero 15, 2025","format":false,"excerpt":"La Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s) prohibi\u00f3 el uso del colorante rojo n\u00famero 3 en alimentos, bebidas y medicamentos ingeridos, m\u00e1s de 30 a\u00f1os despu\u00e9s de que los cient\u00edficos descubrieran v\u00ednculos con el c\u00e1ncer en animales, anunci\u00f3 la agencia este mi\u00e9rcoles.Un aditivo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461512,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/04\/22\/fda-eliminara-colorantes-alimentarios-petroleo-trax\/","url_meta":{"origin":1470918,"position":2},"title":"La FDA eliminar\u00e1 gradualmente los colorantes alimentarios a base de petr\u00f3leo; autorizar\u00e1 cuatro aditivos de color naturales","author":"","date":"abril 22, 2025","format":false,"excerpt":"La Administraci\u00f3n de Alimentos y Medicamentos (FDA, por sus siglas en ingl\u00e9s) de EE.UU. planea eliminar gradualmente el uso de colorantes sint\u00e9ticos a base de petr\u00f3leo en el suministro de alimentos del pa\u00eds debido a preocupaciones de salud, anunci\u00f3 este martes el comisionado Dr. Marty Makary.\u201cDurante los \u00faltimos 50 a\u00f1os,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471113,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/11\/alimentos-bebes-ultraprocesados-nuevo-estudio-trax\/","url_meta":{"origin":1470918,"position":3},"title":"M\u00e1s del 70 % de los alimentos para beb\u00e9s analizados son ultraprocesados \u200b\u200by est\u00e1n llenos de aditivos, dice nuevo estudio","author":"","date":"febrero 11, 2026","format":false,"excerpt":"Un nuevo estudio descubri\u00f3 que la gran mayor\u00eda de los alimentos, bebidas y refrigerios para beb\u00e9s que se venden en Estados Unidos para ni\u00f1os de 6 a 36 meses son ultraprocesados \u200b\u200by podr\u00edan contener aditivos cada vez m\u00e1s vinculados a posibles da\u00f1os para la salud.M\u00e1s del 70 % de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459818,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/","url_meta":{"origin":1470918,"position":4},"title":"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante?","author":"","date":"marzo 12, 2025","format":false,"excerpt":"El secretario de Salud y Servicios Humanos de Estados Unidos, Robert F. Kennedy, ha iniciado el proceso de eliminaci\u00f3n de un programa de la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, por sus siglas en ingl\u00e9s) llamado GRAS, o \u201cgeneralmente reconocido como seguro\u201d. Seg\u00fan los cr\u00edticos, la industria\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452300,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/","url_meta":{"origin":1470918,"position":5},"title":"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os","author":"","date":"agosto 30, 2024","format":false,"excerpt":"(CNN) -- La Legislatura de California aprob\u00f3 un proyecto de ley con apoyo bipartidista que proh\u00edbe el uso del colorante rojo n\u00ba 40 y otras cinco sustancias qu\u00edmicas presentes en los alimentos que se sirven en las escuelas p\u00fablicas.El jueves, el llamado Estado Dorado se convirti\u00f3 en el primero del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1470918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1470918"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1470918\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1470918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1470918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1470918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}