{"id":1470967,"date":"2026-02-06T19:03:42","date_gmt":"2026-02-07T03:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/"},"modified":"2026-02-06T19:03:42","modified_gmt":"2026-02-07T03:03:42","slug":"ordena-descongelar-millones-tunel-nueva-york-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/","title":{"rendered":"Jueza ordena al Gobierno de Trump descongelar m\u00e1s de US$ 16.000 millones para proyecto de t\u00fanel en Nueva York"},"content":{"rendered":"<p>Una jueza federal en Nueva York dictamin\u00f3 el viernes que el Gobierno de Trump debe descongelar m\u00e1s de US$ 16.000 millones destinados a un importante proyecto de infraestructura en Nueva York y permitir que la construcci\u00f3n contin\u00fae, bajo el argumento de que el inter\u00e9s p\u00fablico se ver\u00eda \u201cperjudicado por un retraso\u201d.<\/p>\n<p>La orden de restricci\u00f3n temporal concedida por la jueza de distrito Jeanette Vargas en el Distrito Sur de Nueva York se produce luego de que el presidente Donald Trump retuviera los fondos destinados al proyecto, planificado desde hace tiempo, que conecta Nueva York y Nueva Jersey a trav\u00e9s de un nuevo t\u00fanel ferroviario bajo el r\u00edo Hudson.<\/p>\n<p>Vargas se\u00f1al\u00f3 en un escrito judicial que los estados de Nueva York y Nueva Jersey \u201csufrir\u00edan un da\u00f1o irreparable\u201d si el Gobierno de Trump continuaba reteniendo los fondos para el proyecto.<\/p>\n<p>\u201cLos demandantes han demostrado adecuadamente que el inter\u00e9s p\u00fablico se ver\u00eda perjudicado por una demora en un proyecto de infraestructura cr\u00edtico\u201d, escribi\u00f3.<\/p>\n<p>CNN contact\u00f3 a la Casa Blanca para obtener comentarios.<\/p>\n<p>CNN inform\u00f3 previamente que Trump le dijo al l\u00edder de la minor\u00eda del Senado, Chuck Schumer, el mes pasado que estaba dispuesto a levantar el congelamiento de los fondos bajo la condici\u00f3n de que Schumer aceptara renombrar la estaci\u00f3n Penn de Nueva York y el Aeropuerto Internacional Dulles de Washington en honor a Trump.<\/p>\n<p>El presidente dijo a los periodistas a bordo del Air Force One este viernes por la noche que fue idea de Schumer renombrar la estaci\u00f3n Penn como \u201cestaci\u00f3n Trump\u201d.<\/p>\n<p>Schumer desestim\u00f3 de inmediato la afirmaci\u00f3n de Trump y lo acus\u00f3 de mentir sobre los detalles de su conversaci\u00f3n.<\/p>\n<p>\u201cMentira absoluta. \u00c9l lo sabe. Todos lo saben. Solo un hombre puede reiniciar el proyecto y puede hacerlo en un abrir y cerrar de ojos\u201d, escribi\u00f3 Schumer en X.<\/p>\n<p>La comisi\u00f3n a cargo del proyecto del t\u00fanel advirti\u00f3 previamente que pronto tendr\u00eda que detener los trabajos del proyecto y despedir a aproximadamente 1.000 trabajadores si el Gobierno de Trump no libera los fondos necesarios.<\/p>\n<p>La fiscal general de Nueva York, Letitia James, quien demand\u00f3 al Gobierno de Trump a principios de este mes, celebr\u00f3 el fallo como una \u201cvictoria crucial para los trabajadores y viajeros de Nueva York y Nueva Jersey\u201d.<\/p>\n<p>\u201cAgradezco que el tribunal haya actuado con rapidez para bloquear esta insensata congelaci\u00f3n de fondos, que amenazaba con descarrilar un proyecto del que depende toda nuestra regi\u00f3n. El Proyecto del T\u00fanel del Hudson es uno de los proyectos de infraestructura m\u00e1s importantes del pa\u00eds, y seguiremos luchando para garantizar que la construcci\u00f3n pueda continuar sin interferencias federales innecesarias\u201d, dijo James en un comunicado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una jueza federal en Nueva York dictamin\u00f3 el viernes que el Gobierno de Trump debe descongelar m\u00e1s de US$ 16.000 millones destinados a un importante proyecto de infraestructura en Nueva York y permitir que la construcci\u00f3n contin\u00fae, bajo el argumento de que el inter\u00e9s p\u00fablico se ver\u00eda \u201cperjudicado por un retraso\u201d. La orden de restricci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470967","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jueza ordena al Gobierno de Trump descongelar m\u00e1s de US$ 16.000 millones para proyecto de t\u00fanel en Nueva York - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jueza ordena al Gobierno de Trump descongelar m\u00e1s de US$ 16.000 millones para proyecto de t\u00fanel en Nueva York - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una jueza federal en Nueva York dictamin\u00f3 el viernes que el Gobierno de Trump debe descongelar m\u00e1s de US$ 16.000 millones destinados a un importante proyecto de infraestructura en Nueva York y permitir que la construcci\u00f3n contin\u00fae, bajo el argumento de que el inter\u00e9s p\u00fablico se ver\u00eda \u201cperjudicado por un retraso\u201d. La orden de restricci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-07T03:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Jueza ordena al Gobierno de Trump descongelar m\u00e1s de US$ 16.000 millones para proyecto de t\u00fanel en Nueva York\",\"datePublished\":\"2026-02-07T03:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/\"},\"wordCount\":504,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/\",\"name\":\"Jueza ordena al Gobierno de Trump descongelar m\u00e1s de US$ 16.000 millones para proyecto de t\u00fanel en Nueva York - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-07T03:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jueza ordena al Gobierno de Trump descongelar m\u00e1s de US$ 16.000 millones para proyecto de t\u00fanel en Nueva York\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jueza ordena al Gobierno de Trump descongelar m\u00e1s de US$ 16.000 millones para proyecto de t\u00fanel en Nueva York - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Jueza ordena al Gobierno de Trump descongelar m\u00e1s de US$ 16.000 millones para proyecto de t\u00fanel en Nueva York - Noticias","og_description":"Una jueza federal en Nueva York dictamin\u00f3 el viernes que el Gobierno de Trump debe descongelar m\u00e1s de US$ 16.000 millones destinados a un importante proyecto de infraestructura en Nueva York y permitir que la construcci\u00f3n contin\u00fae, bajo el argumento de que el inter\u00e9s p\u00fablico se ver\u00eda \u201cperjudicado por un retraso\u201d. La orden de restricci\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-07T03:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/"},"author":{"name":"","@id":""},"headline":"Jueza ordena al Gobierno de Trump descongelar m\u00e1s de US$ 16.000 millones para proyecto de t\u00fanel en Nueva York","datePublished":"2026-02-07T03:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/"},"wordCount":504,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/","name":"Jueza ordena al Gobierno de Trump descongelar m\u00e1s de US$ 16.000 millones para proyecto de t\u00fanel en Nueva York - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-07T03:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Jueza ordena al Gobierno de Trump descongelar m\u00e1s de US$ 16.000 millones para proyecto de t\u00fanel en Nueva York"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Jueza ordena al Gobierno de Trump descongelar m\u00e1s de US$ 16.000 millones para proyecto de t\u00fanel en Nueva York","url":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/06\/ordena-descongelar-millones-tunel-nueva-york-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-07T03:03:42Z","datePublished":"2026-02-07T03:03:42Z","dateModified":"2026-02-07T03:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Jueza ordena al Gobierno de Trump descongelar m\\u00e1s de US$ 16.000 millones para proyecto de t\\u00fanel en Nueva York\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/06\\\/ordena-descongelar-millones-tunel-nueva-york-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/06\\\/ordena-descongelar-millones-tunel-nueva-york-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-07T03:03:42Z\",\"datePublished\":\"2026-02-07T03:03:42Z\",\"dateModified\":\"2026-02-07T03:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471061,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/10\/juez-mas-tiempo-trump-tunel-nueva-york-trax\/","url_meta":{"origin":1470967,"position":0},"title":"Juez da m\u00e1s tiempo a Trump para descongelar US$ 16.000 millones para t\u00fanel en Nueva York","author":"","date":"febrero 10, 2026","format":false,"excerpt":"El gobierno de Trump deber\u00e1 descongelar m\u00e1s de US$ 16 mil millones destinados a un importante proyecto de infraestructura en Nueva York antes del jueves, a menos que un tribunal federal de apelaciones permita al gobierno continuar reteniendo los fondos, dictamin\u00f3 una jueza federal el lunes.La jueza Jeannette Vargas, del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452490,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/09\/06\/conceden-trasladar-ismael-mayo-zambada-texas-nueva-york-orix\/","url_meta":{"origin":1470967,"position":1},"title":"Conceden trasladar a Ismael &#171;el Mayo&#187; Zambada de Texas a Nueva York","author":"","date":"septiembre 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Una jueza federal de Estados Unidos concedi\u00f3 este viernes el traslado de Texas a Nueva York a Ismael \"el Mayo\" Zambada para que siga el proceso penal que tiene en el pa\u00eds por varios cargos de narcotr\u00e1fico, seg\u00fan documentos judiciales que revis\u00f3 CNN.En su decisi\u00f3n, la jueza del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461338,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/04\/18\/paula-xinis-jueza-kilmar-abrego-garcia-trax\/","url_meta":{"origin":1470967,"position":2},"title":"\u00bfQui\u00e9n es la jueza Paula Xinis? Qu\u00e9 sabemos sobre la jueza en el caso de un hombre deportado por error a El Salvador","author":"","date":"abril 18, 2025","format":false,"excerpt":"La jueza federal Paula Xinis est\u00e1 en el centro del caso del hombre de Maryland deportado por error a El Salvador por la administraci\u00f3n Trump. El caso se ha convertido en una prueba cr\u00edtica para la en\u00e9rgica ofensiva de Trump contra la inmigraci\u00f3n en Estados Unidos.Tras un fallo de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469209,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/12\/12\/jueza-impide-nueva-detencion-kilmar-abrego-trax\/","url_meta":{"origin":1470967,"position":3},"title":"Jueza federal impide temporalmente que el Gobierno de Trump vuelva a detener a Kilmar \u00c1brego Garc\u00eda","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"Una jueza federal impid\u00f3 temporalmente que la administraci\u00f3n Trump vuelva a detener a Kilmar \u00c1brego Garc\u00eda, horas despu\u00e9s de que ordenara su liberaci\u00f3n de un centro de detenci\u00f3n de inmigrantes.La orden de restricci\u00f3n temporal, emitida la madrugada de este viernes por la jueza federal de distrito Paula Xinis, supone el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452471,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/09\/05\/zambada-acepta-traslado-nueva-york-proceso-penal-orix\/","url_meta":{"origin":1470967,"position":4},"title":"&#171;El Mayo&#187; Zambada acepta ser trasladado de Texas a Nueva York para seguir su proceso penal","author":"","date":"septiembre 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 Ismael \"el Mayo\" Zambada, uno de los l\u00edderes del c\u00e1rtel de Sinaloa, acept\u00f3 ser trasladado de Texas a Nueva York para seguir el proceso penal en su contra, seg\u00fan documentos judiciales revisados este jueves por CNN.La respuesta de la defensa de Zambada a la solicitud del Gobierno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471074,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/10\/mejia-democrata-gana-primarias-nueva-jersey-trax\/","url_meta":{"origin":1470967,"position":5},"title":"Analilia Mej\u00eda, aliada de Bernie Sanders, gana la primaria especial dem\u00f3crata de Nueva Jersey","author":"","date":"febrero 10, 2026","format":false,"excerpt":"Analilia Mej\u00eda ganar\u00e1 las primarias especiales en el 11\u00ba Distrito Congresional de Nueva Jersey tras una re\u00f1ida contienda contra el exrepresentante Tom Malinowski, una importante victoria para una aliada del senador Bernie Sanders y otros progresistas.Malinowski reconoci\u00f3 su derrota este martes en un comunicado en el que concedi\u00f3 a Mej\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1470967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1470967"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1470967\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1470967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1470967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1470967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}