{"id":1470974,"date":"2026-02-07T07:03:41","date_gmt":"2026-02-07T15:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/"},"modified":"2026-02-07T07:03:41","modified_gmt":"2026-02-07T15:03:41","slug":"todd-blanche-ed-martin-division-maga-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/","title":{"rendered":"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno"},"content":{"rendered":"<p>La disputa entre dos de los fiscales favoritos del presidente Donald Trump lleg\u00f3 a su punto \u00e1lgido a principios de a\u00f1o, cuando el fiscal general adjunto Todd Blanche, exabogado personal del presidente, destituy\u00f3 al activista de MAGA, Ed Martin, de un puesto clave que investigaba a los enemigos pol\u00edticos del presidente.<\/p>\n<p>La decisi\u00f3n de dejar en el banquillo a Martin \u2014quiz\u00e1s el funcionario m\u00e1s comprometido p\u00fablicamente con la persecuci\u00f3n de los adversarios pol\u00edticos de Trump en los tribunales\u2014 ha revelado una divisi\u00f3n entre dos facciones dentro del Gobierno.<\/p>\n<p>Un grupo celebra a Blanche por lo que considera un respeto a las salvaguardias del Estado de derecho. El otro cree que Martin es un m\u00e1rtir del movimiento MAGA y el \u00fanico dispuesto a hacer lo que sea necesario para cumplir con las prioridades de Trump.<\/p>\n<p>En las \u00faltimas semanas, los desacuerdos sobre la agresividad con la que los fiscales persiguen a los adversarios pol\u00edticos de Trump se han agudizado, ya que el presidente ha dejado claro su descontento con el progreso del Departamento de Justicia en la presentaci\u00f3n de procesos penales contra personas que, seg\u00fan \u00e9l, lo atacaron injustamente en investigaciones que se remontan a 2016.<\/p>\n<p>Durante la primera administraci\u00f3n de Trump, las disputas entre funcionarios se desarrollaban regularmente en p\u00fablico y en redes sociales. Pero la actual secretaria general de la Casa Banca, Susie Wiles, se ha esforzado por moderar los desacuerdos y el drama p\u00fablico en su segundo mandato.<\/p>\n<p>\u201cQue estos asuntos se manifiesten p\u00fablicamente no favorece la agenda del presidente\u201d, declar\u00f3 a CNN un aliado de Trump que los conoce a ambos. \u201cSe puede comprender la frustraci\u00f3n de que la oficina de Blanche sea el lugar donde todo se desmorona, porque todo avanza con mucha lentitud. Pero las estrategias de Ed, en \u00faltima instancia, no ayudan a conseguir lo que el presidente quiere\u201d.<\/p>\n<p>Blanche y Martin llegaron a trabajar para Trump por caminos diferentes.<\/p>\n<p>Blanche, exprofesor de un gran estudio de abogados en Nueva York, fund\u00f3 un bufete hom\u00f3nimo en 2023 y represent\u00f3 a Trump en tres de sus cuatro casos penales. Se gan\u00f3 la reputaci\u00f3n de gestionar con destreza la pol\u00edtica interna del mundo trumpista y cuando Trump regres\u00f3 al cargo fue nombrado n\u00famero dos del Departamento de Justicia.<\/p>\n<p>Martin, expol\u00edtico de Missouri, obtuvo el reconocimiento de MAGA como organizador del movimiento \u201cStop the Steal\u201d (Detengamos el robo), un firme defensor de las acusaciones infundadas de Trump sobre fraude electoral generalizado en las elecciones de 2020 y como abogado de los acusados de los disturbios del Capitolio del 6 de enero de 2021.<\/p>\n<p>Al comienzo del segundo mandato de Trump, fue designado fiscal federal en la ciudad de Washington, y se puso a trabajar de inmediato en la implementaci\u00f3n de la agenda de Trump, incluyendo la degradaci\u00f3n de los fiscales superiores que trabajaron en casos relacionados con el 6 de enero y la promesa de proteger a los empleados del Departamento de Eficiencia Gubernamental (DOGE).<\/p>\n<p>\u201cSeamos claros: este cambio no es temporal\u201d, escribi\u00f3 Martin sobre la degradaci\u00f3n de los fiscales en un memorando obtenido en su momento por CNN.<\/p>\n<p>Tras un mandato de 15 semanas marcado por una gesti\u00f3n ca\u00f3tica y publicaciones en redes sociales que inclu\u00edan amenazas contra los cr\u00edticos del presidente, no logr\u00f3 la confirmaci\u00f3n.<\/p>\n<p>Su nominaci\u00f3n fue retirada en mayo de 2025 y Trump lo nombr\u00f3 entonces en dos nuevos puestos en el Departamento de Justicia, incluyendo el de director del Grupo de Trabajo sobre Armamentizaci\u00f3n y el de abogado de indultos, todos ellos bajo la cadena de mando de Blanche.<\/p>\n<p>Se espera que Martin deje el Departamento de Justicia en las pr\u00f3ximas semanas, seg\u00fan inform\u00f3 CNN anteriormente. Su destituci\u00f3n represent\u00f3 la culminaci\u00f3n de una campa\u00f1a de meses de Blanche para mantener a Martin operando dentro de los l\u00edmites de la ley. Las investigaciones del Grupo de Trabajo sobre Armamentismo que Martin deb\u00eda dirigir se estancaron r\u00e1pidamente. Obtuvo escasos o nulos resultados en la investigaci\u00f3n de las principales prioridades de Trump, incluyendo lo que Trump alega como una extralimitaci\u00f3n generalizada en la gesti\u00f3n del Departamento de Justicia de Biden de los disturbios del 6 de enero y en los ahora obsoletos procesos judiciales de Trump y miembros de su personal a cargo del exfiscal especial Jack Smith.<\/p>\n<p>Aun as\u00ed, Martin encontr\u00f3 otras maneras de complacer al presidente.<\/p>\n<p>Una vez en la sede del Departamento de Justicia, Martin continu\u00f3 con lo que hab\u00eda hecho en la Fiscal\u00eda Federal: presionar para que se procesara a los adversarios pol\u00edticos de Trump. El verano pasado, Martin pos\u00f3 para fotos frente a la casa de Letitia James en Brooklyn, Nueva York, mientras realizaba una investigaci\u00f3n sobre si hab\u00eda cometido fraude hipotecario.<\/p>\n<p>La frustraci\u00f3n de Blanche con Martin segu\u00eda creciendo. Ambos discrepaban sobre las t\u00e1cticas de Martin, en particular sobre su tendencia a coordinarse directamente con la Casa Blanca sin que Blanche lo supiera.<\/p>\n<p>Pero no fue hasta diciembre cuando Martin cometi\u00f3 un error lo suficientemente grave como para que Blanche intentara expulsarlo por completo del Departamento de Justicia. Se inform\u00f3 que hab\u00eda manejado incorrectamente pruebas secretas del jurado investigador en un caso sobre el senador dem\u00f3crata Adam Schiff, uno de los principales objetivos de Trump.<\/p>\n<p>La oficina de Blanche inici\u00f3 r\u00e1pidamente una revisi\u00f3n del incidente en diciembre, y finalmente concluy\u00f3 que Martin hab\u00eda cometido una falta de conducta, seg\u00fan informaron previamente a CNN dos fuentes familiarizadas con la revisi\u00f3n.<\/p>\n<p>A principios de diciembre, Martin fue destituido de su cargo como l\u00edder del grupo de armamentismo y enviado a trabajar a un edificio separado al otro lado de la ciudad, frente a la sede del Departamento de Justicia. Ahora est\u00e1 considerando dejar el departamento por completo.<\/p>\n<p>En una declaraci\u00f3n a CNN del martes, Blanche afirm\u00f3: \u201cNo hay investigaciones por falta de conducta contra Ed Martin. Ed est\u00e1 haciendo un excelente trabajo como abogado de indultos\u201d.<\/p>\n<p>El episodio entre Blanche y Martin ilustra una divisi\u00f3n fundamental en el departamento. Algunos quieren trabajar dentro de las tradiciones legales del Departamento de Justicia para llevar a cabo la agenda del presidente. Otros consideran que las limitaciones de las tradiciones legales del Departamento de Justicia son demasiado engorrosas para cumplir las \u00f3rdenes del presidente.<\/p>\n<p>La divisi\u00f3n no es in\u00e9dita; algo similar se manifest\u00f3 durante el primer mandato de Trump como presidente. Aliados de Trump, como Matthew Whitaker, exjefe de gabinete del fiscal general Jeff Sessions y posteriormente sustituto interino de Sessions, se mostraron irritados por la resistencia de los propios funcionarios designados por el presidente respecto a la gesti\u00f3n de la investigaci\u00f3n sobre Rusia del fiscal especial Robert Mueller.<\/p>\n<p>En aquel momento, los enfrentamientos se centraron en si los intereses del presidente se ve\u00edan mejor servidos al no socavar la investigaci\u00f3n en curso, a pesar de las frecuentes frustraciones p\u00fablicas de Trump.<\/p>\n<p>Un aliado del presidente observ\u00f3 que, si bien el Departamento de Justicia, por dise\u00f1o, avanza con lentitud, al final, prescindir de sus restricciones legales ha da\u00f1ado la credibilidad del departamento y su capacidad para llevar a cabo su agenda, citando el rechazo de los intentos de enjuiciamiento por parte de grandes jurados y jueces en los \u00faltimos meses.<\/p>\n<p>\u201cEl hecho de que esto siga sucediendo de nuestro lado dice mucho\u201d, dijo la fuente. \u201cEst\u00e1n compitiendo por ver qui\u00e9n es m\u00e1s MAGA\u201d.<\/p>\n<p>\u201cEl Partido Republicano sigue haciendo esto, nosotros nos lo hacemos a nosotros mismos y no podemos hacer nada\u201d, a\u00f1adi\u00f3 la fuente. El mes pasado, Trump critic\u00f3 duramente a los fiscales durante una reuni\u00f3n en la Casa Blanca, afirmando que quer\u00eda medidas m\u00e1s en\u00e9rgicas en los procesos contra sus enemigos pol\u00edticos, as\u00ed como en sus quejas recurrentes sobre las elecciones presidenciales de 2020.<\/p>\n<p>El presidente tambi\u00e9n se ha quejado directamente con la fiscal general Pam Bondi sobre el retraso en dichas investigaciones, seg\u00fan inform\u00f3 a CNN una fuente familiarizada con el asunto.<\/p>\n<p>El Departamento parece ser sensible a estas presiones. CNN inform\u00f3 el lunes que el Grupo de Trabajo sobre Armamentizaci\u00f3n comenzar\u00eda a reunirse diariamente para determinar c\u00f3mo implementar la agenda del presidente. Con Martin fuera del escenario, se espera que el grupo redoble sus esfuerzos para abordar estos temas con la expectativa de obtener resultados en los pr\u00f3ximos meses.<\/p>\n<p>Mientras Martin se encuentra al margen, contin\u00faa ejerciendo como abogado de indultos, seg\u00fan fuentes cercanas. Ha participado activamente en la revisi\u00f3n de solicitudes de clemencia. Si bien el t\u00edtulo suena elevado, la decisi\u00f3n final sobre los indultos en la administraci\u00f3n Trump, como en otras administraciones, se toma en gran medida dentro de la Casa Blanca.<\/p>\n<p>No est\u00e1 claro ad\u00f3nde ir\u00e1 Martin si deja el Departamento de Justicia, pero una fuente le dijo a CNN que Martin pas\u00f3 toda la semana pasada trabajando en la Casa Blanca.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La disputa entre dos de los fiscales favoritos del presidente Donald Trump lleg\u00f3 a su punto \u00e1lgido a principios de a\u00f1o, cuando el fiscal general adjunto Todd Blanche, exabogado personal del presidente, destituy\u00f3 al activista de MAGA, Ed Martin, de un puesto clave que investigaba a los enemigos pol\u00edticos del presidente. La decisi\u00f3n de dejar [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470974","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno - Noticias\" \/>\n<meta property=\"og:description\" content=\"La disputa entre dos de los fiscales favoritos del presidente Donald Trump lleg\u00f3 a su punto \u00e1lgido a principios de a\u00f1o, cuando el fiscal general adjunto Todd Blanche, exabogado personal del presidente, destituy\u00f3 al activista de MAGA, Ed Martin, de un puesto clave que investigaba a los enemigos pol\u00edticos del presidente. La decisi\u00f3n de dejar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-07T15:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno\",\"datePublished\":\"2026-02-07T15:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/\"},\"wordCount\":1551,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/\",\"name\":\"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-07T15:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno - Noticias","og_description":"La disputa entre dos de los fiscales favoritos del presidente Donald Trump lleg\u00f3 a su punto \u00e1lgido a principios de a\u00f1o, cuando el fiscal general adjunto Todd Blanche, exabogado personal del presidente, destituy\u00f3 al activista de MAGA, Ed Martin, de un puesto clave que investigaba a los enemigos pol\u00edticos del presidente. La decisi\u00f3n de dejar [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-07T15:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/"},"author":{"name":"","@id":""},"headline":"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno","datePublished":"2026-02-07T15:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/"},"wordCount":1551,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/","name":"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-07T15:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno","url":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-07T15:03:41Z","datePublished":"2026-02-07T15:03:41Z","dateModified":"2026-02-07T15:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\\u00f3n de MAGA dentro del Gobierno\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/07\\\/todd-blanche-ed-martin-division-maga-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/07\\\/todd-blanche-ed-martin-division-maga-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-07T15:03:41Z\",\"datePublished\":\"2026-02-07T15:03:41Z\",\"dateModified\":\"2026-02-07T15:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473357,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/","url_meta":{"origin":1470974,"position":0},"title":"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU.","author":"","date":"abril 21, 2026","format":false,"excerpt":"El secretario interino de Justicia de EE.UU. Todd Blanche viaj\u00f3 a Florida el lunes, donde se reuni\u00f3 con el nuevo fiscal designado para encargarse de uno de los casos m\u00e1s importantes para el presidente Donald Trump: la investigaci\u00f3n sobre el exdirector de la CIA y cr\u00edtico de Trump, John Brennan.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472826,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/04\/03\/blanche-departamento-justicia-ee-uu-archivos-epstein-trax\/","url_meta":{"origin":1470974,"position":1},"title":"Blanche asume el cargo del Departamento de Justicia de EE.UU., donde sigue omnipresente la sombra de los archivos de Epstein","author":"","date":"abril 3, 2026","format":false,"excerpt":"El vicesecretario de Justicia de EE.UU., Todd Blanche, a quien el presidente Donald Trump design\u00f3 el jueves para dirigir interinamente el Departamento de Justicia, gestion\u00f3 las operaciones diarias de esta agencia federal durante el \u00faltimo a\u00f1o, asumiendo a menudo un papel m\u00e1s visible para el p\u00fablico cuando Pam Bondi se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464774,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/23\/departamento-justicia-trump-epstein-maxwell-analisis-trax\/","url_meta":{"origin":1470974,"position":2},"title":"La \u00faltima apuesta de Trump para acabar con la tormenta de Epstein: convertir al gobierno federal en un arma","author":"","date":"julio 23, 2025","format":false,"excerpt":"El intento de Donald Trump de acallar el revuelo en torno al presunto traficante sexual Jeffrey Epstein demuestra que ya ha logrado uno de los objetivos que sus cr\u00edticos m\u00e1s tem\u00edan de su segunda presidencia.El Departamento de Justicia y el jefe de la comunidad de inteligencia de Estados Unidos ahora\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464706,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/21\/preguntas-semana-trump-tormenta-epstein-presidencia-trax\/","url_meta":{"origin":1470974,"position":3},"title":"Las grandes preguntas de esta semana: \u00bfPodr\u00e1 Trump finalmente calmar la tormenta sobre Epstein? \u00bfPerjudicar\u00e1 su presidencia?","author":"","date":"julio 21, 2025","format":false,"excerpt":"Incluso el presidente Donald Trump no parece creer que sus furiosos y ca\u00f3ticos esfuerzos para poner fin a la renovada tormenta en torno al delincuente sexual convicto Jeffrey Epstein funcionar\u00e1n.En una publicaci\u00f3n en las redes sociales el fin de semana, advirti\u00f3 que \u201cnada ser\u00e1 lo suficientemente bueno\u201d para satisfacer a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464520,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/15\/teorias-conspirativas-epstein-bondi-trump-analisis-trax\/","url_meta":{"origin":1470974,"position":4},"title":"Trump tambalea mientras la tormenta Epstein sacude a su gobierno","author":"","date":"julio 15, 2025","format":false,"excerpt":"Donald Trump rara vez pierde el control de su propia historia. Pero la saga de Jeffrey Epstein escapa a su control.Se trata de un nuevo giro para el presidente, que se encuentra en desacuerdo con la facci\u00f3n m\u00e1s ruidosa y conspirativa de su movimiento MAGA.Por una vez, se est\u00e1 convirtiendo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464995,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/31\/apoyo-eeuu-israel-gaza-republicanos-democratas-trax\/","url_meta":{"origin":1470974,"position":5},"title":"Disminuye apoyo de EE.UU. a las acciones de Israel en Gaza, mientras crece la presi\u00f3n dem\u00f3crata y se divide movimiento MAGA","author":"","date":"julio 31, 2025","format":false,"excerpt":"El apoyo de los estadounidenses a las acciones militares de Israel en Gaza est\u00e1 cayendo r\u00e1pidamente, lo que ha llevado a los dem\u00f3cratas pro-Israel y a algunos de los aliados de larga data del presidente Donald Trump a advertir de que el pa\u00eds podr\u00eda da\u00f1ar permanentemente su reputaci\u00f3n en los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1470974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1470974"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1470974\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1470974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1470974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1470974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}