{"id":1471004,"date":"2026-02-08T12:03:50","date_gmt":"2026-02-08T20:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/"},"modified":"2026-02-08T12:03:50","modified_gmt":"2026-02-08T20:03:50","slug":"operativos-ice-minneapolis-familias-escondidas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/","title":{"rendered":"Familias escondidas y observadores desafiantes: as\u00ed es Minneapolis tras la llamada &#171;reducci\u00f3n&#187; de ICE"},"content":{"rendered":"<p>Con su largo cabello oscuro saliendo de un gorro rosa brillante, la ni\u00f1a de 11 a\u00f1os, originaria de Ecuador, record\u00f3 con calma cuando su madre sali\u00f3 de su peque\u00f1o apartamento en el sur de Minneapolis el lunes pasado por la ma\u00f1ana, por primera vez en mes y medio.<\/p>\n<p>\u201cAdi\u00f3s, querida, cu\u00eddate mucho\u201d, le dijo su madre en espa\u00f1ol.<\/p>\n<p>\u201cMami, por favor, ten cuidado\u201d, respondi\u00f3 la ni\u00f1a \u2014cuyo nombre CNN no publica por su edad\u2014. \u201cEsa fue la \u00faltima vez que la vi\u201d.<\/p>\n<p>La estudiante de sexto grado estaba somnolienta ese primer lunes de febrero. La noche anterior se hab\u00eda quedado despierta con su madre, contemplando los riesgos de una r\u00e1pida salida a una tienda de comestibles cercana para abastecerse.<\/p>\n<p>La comida y el dinero se estaban agotando. Hab\u00edan dependido de donaciones de alimentos de su escuela, pero su madre, que no hab\u00eda trabajado en m\u00e1s de un mes, se sent\u00eda avergonzada de pedir m\u00e1s.<\/p>\n<p>\u201cDecidi\u00f3 que era demasiado peligroso salir\u201d, dijo la ni\u00f1a a CNN, reflejando la par\u00e1lisis y el miedo generalizados entre muchas familias en una ciudad donde, durante semanas, agentes federales de inmigraci\u00f3n han realizado operativos cerca de escuelas, en viviendas y en lugares de trabajo, en medio de choques con residentes indignados.<\/p>\n<p>\u201cFue como si mi madre hubiera tenido una premonici\u00f3n de que algo iba a pasar. Me record\u00f3 d\u00f3nde guardaba un sobre con nuestros documentos de inmigraci\u00f3n. Ten\u00eda problemas para dormir\u201d.<\/p>\n<p>A la ma\u00f1ana siguiente, la ni\u00f1a recibi\u00f3 una breve llamada: llorando, su madre le dijo que agentes federales de inmigraci\u00f3n la estaban buscando. Luego la llamada se cort\u00f3. En un video publicado en redes sociales momentos despu\u00e9s, vio c\u00f3mo los agentes federales deten\u00edan a su madre.<\/p>\n<p>Su madre hab\u00eda sido trasladada del edificio federal en Minneapolis a un controvertido centro de detenci\u00f3n en Texas, a unos 2.250 kil\u00f3metros de distancia, seg\u00fan John Hayden, un abogado que en cuesti\u00f3n de d\u00edas obtuvo una orden de un tribunal federal que exig\u00eda su regreso a Minnesota. Hayden pidi\u00f3 que su clienta, que ha solicitado asilo en EE.UU., no fuera identificada por temor a represalias. Fue devuelta a un centro de detenci\u00f3n en Minneapolis el viernes por la ma\u00f1ana.<\/p>\n<p>D\u00edas despu\u00e9s de que agentes federales arrestaran a la madre ecuatoriana mientras se escond\u00eda debajo de un remolque en una calle nevada de Minneapolis, el zar de la frontera de la Casa Blanca, Tom Homan, dijo que 700 agentes federales de las fuerzas del orden ser\u00e1n retirados del estado. Aun as\u00ed, la salida de unos pocos cientos dejar\u00eda a m\u00e1s de 2.000 agentes en las Ciudades Gemelas y \u00e1reas circundantes: una fuerza federal m\u00e1s de tres veces mayor que el Departamento de Polic\u00eda de Minneapolis.<\/p>\n<p>Incluso con la llamada \u201creducci\u00f3n\u201d, muchos activistas del \u00e1rea de Minneapolis dicen que poco ha cambiado y que se preparan para una resistencia prolongada. Los reportes de agentes federales cerca de escuelas y viviendas contin\u00faan circulando en grupos de chat y redes sociales, manteniendo a muchas familias inmigrantes dentro de sus casas.<\/p>\n<p>La ansiedad ha aumentado desde dos tiroteos mortales de ciudadanos estadounidenses a manos de agentes federales en enero: la madre de tres hijos Renee Nicole Good y el enfermero de UCI Alex Pretti.<\/p>\n<p>Peque\u00f1os grupos de residentes siguen reuni\u00e9ndose para vigilar a los agentes federales desde autos o a pie \u2014tocando bocinas y haciendo sonar silbatos para alertar a los vecinos\u2014. Voluntarios trasladan a personas hacia y desde sus lugares de trabajo. Docentes y personal escolar supervisan a los padres al dejar y recoger a los estudiantes. Individuos, organizaciones sin fines de lucro y comercios locales re\u00fanen bolsas de comida, f\u00f3rmula para beb\u00e9s, pa\u00f1ales y otros art\u00edculos y los entregan a personas demasiado asustadas para salir de sus hogares.<\/p>\n<p>Un amplio memorial improvisado a lo largo de la avenida Nicollet, en Minneapolis \u2014una concurrida zona de restaurantes y tiendas\u2014 marca el lugar donde Pretti fue matado a tiros. Hay velas y flores marchitas y secas por el aire fr\u00edo, rodeadas de cartas, poemas y carteles escritos a mano.<\/p>\n<p>Afuera de una tienda, un par de afiches est\u00e1n pegados uno junto al otro con fotos de Good y Pretti \u2014dos personas cuyos tiroteos a manos de agentes federales han sido defendidos por el Departamento de Seguridad Nacional (DHS)\u2014 junto a las palabras \u201cMadre estadounidense\u201d y \u201cEnfermero de UCI\u201d. Grandes letras rojas bajo sus im\u00e1genes dicen: \u201cMatados por ICE\u201d.<\/p>\n<p>Cerca de la entrada de un restaurante cercano, un grupo de m\u00fasicos de viento interpret\u00f3 \u201cAngels from the Realms of Glory\u201d detr\u00e1s de un cartel que dec\u00eda: \u201cApoyamos a nuestros vecinos\u201d.<\/p>\n<p>De pie en la esquina, a pocos metros, Laura Purdie Salas, quien escribe libros infantiles y poes\u00eda, sosten\u00eda un cartel de cart\u00f3n con el mensaje \u201cTodos pertenecemos\u201d de un lado y \u201cICE fuera\u201d del otro. Algunos automovilistas que pasaban tocaron la bocina en se\u00f1al de apoyo.<\/p>\n<p>\u201cSe siente que ya no puedes quedarte en silencio\u201d, dijo mientras su esposo tocaba un instrumento de viento afuera del restaurante.<\/p>\n<p>Las Ciudades Gemelas han sido el epicentro de la aplicaci\u00f3n de mano dura del presidente Donald Trump desde principios de diciembre, cuando el Departamento de Seguridad Nacional lanz\u00f3 la Operaci\u00f3n Metro Surge, desplegando aproximadamente 3.000 agentes federales en Minnesota y desatando protestas a nivel nacional por sus t\u00e1cticas militarizadas y enfrentamientos con el p\u00fablico.<\/p>\n<p>La Casa Blanca ha justificado la ofensiva migratoria como una respuesta a un fraude generalizado en programas de asistencia financiados por el Gobierno, especialmente en la comunidad somal\u00ed de Minnesota.<\/p>\n<p>\u201cEsto es una enorme llamada de atenci\u00f3n\u201d, dijo Purdie Salas. \u201cComo alguien que no enfrenta mucho sesgo personalmente, ha sido una verdadera revelaci\u00f3n e inspiraci\u00f3n ver que hay personas aqu\u00ed, como yo, que quieren que sus familias est\u00e9n seguras y que ya es hora de levantarme y hacerme escuchar sobre esto, incluso cuando no es algo con lo que me sienta c\u00f3moda\u201d.<\/p>\n<p>El obispo Kevin Kenney, quien naci\u00f3 en Minneapolis y ha servido durante a\u00f1os a la comunidad latina, record\u00f3 una letan\u00eda de tragedias que han sacudido y transformado a las Ciudades Gemelas en los \u00faltimos a\u00f1os, incluido el homicidio de George Floyd a manos de un agente de Polic\u00eda de la ciudad.<\/p>\n<p>\u201cCada vez nos estamos acostumbrando m\u00e1s a estas concentraciones y protestas, pero es lamentable que as\u00ed sea. Este es un momento hist\u00f3rico\u201d, dijo Kenney, quien el mes pasado bendijo a miembros de una familia ecuatoriana de Minneapolis que decidi\u00f3 salir voluntariamente de EE.UU. en lugar de arriesgarse a la deportaci\u00f3n, a pesar de que estaban en camino a obtener estatus legal.<\/p>\n<p>Tras el tiroteo mortal de Pretti, Homan reemplaz\u00f3 al funcionario de la Patrulla Fronteriza Greg Bovino, conocido por su l\u00ednea dura, como jefe de la operaci\u00f3n en Minnesota.<\/p>\n<p>\u201cCreo que la muerte de Alex Pretti despert\u00f3 a Estados Unidos. No creo que sea solo inmigraci\u00f3n. Creo que tenemos que mirar nuestra libertad\u201d, dijo Kenney.<\/p>\n<p>Al otro lado de la calle de Hamburguesas El Gordo, un local de comida callejera mexicana en Cedar Avenue, en Minneapolis, un arborista de 29 a\u00f1os permanec\u00eda de pie en una esquina la ma\u00f1ana del mi\u00e9rcoles, con una chaqueta negra con capucha bajo un chaleco reflectante y un silbato naranja colgado del cuello.<\/p>\n<p>El hombre, que declin\u00f3 dar su nombre por temor a represalias, dijo que decidi\u00f3 convertirse en observador tras el tiroteo de Pretti.<\/p>\n<p>\u201cMe siento especial como alguien que vive en esta zona, y siento un orgullo por Minneapolis, por Minnesota y por la comunidad en general\u201d, dijo.<\/p>\n<p>Ha considerado los riesgos.<\/p>\n<p>\u201cHay partes de esto que dan miedo\u201d, afirm\u00f3. \u201cPero est\u00e1n pasando muchas cosas, hay personas muriendo en detenci\u00f3n y quiero intentar ayudar de las formas en que pueda. Es la primera vez que hago algo as\u00ed\u201d.<\/p>\n<p>Bajo las imponentes vigas de madera y los vitrales relucientes de una iglesia en Saint Paul, la noche del mi\u00e9rcoles, m\u00e1s de 400 personas asistieron a una sesi\u00f3n de capacitaci\u00f3n para observadores legales que supervisan y documentan acciones de aplicaci\u00f3n migratoria de ICE.<\/p>\n<p>\u201cNo se equivoquen: estamos en un cruce muy peligroso. Nuestro estado est\u00e1 actualmente dominado por el miedo, la ira, el dolor, pero tambi\u00e9n por la determinaci\u00f3n\u201d, dijo a los asistentes una voluntaria llamada Karmit, en el encuentro patrocinado por una coalici\u00f3n llamada Monarca, que afirma haber instruido a m\u00e1s de 26.000 personas sobre sus derechos constitucionales como observadores de operativos de ICE.<\/p>\n<p>\u201cLo que estamos enfrentando ahora \u2014las muertes, el caos, el miedo\u2014 es una campa\u00f1a de brutalidad organizada y no podemos quedarnos en silencio\u201d.<\/p>\n<p>Un participante dijo que vive en Eau Claire, Wisconsin, a unos 145 kil\u00f3metros al este de las Ciudades Gemelas. Un d\u00eda antes, asegur\u00f3, hubo reportes de agentes de ICE cerca de la escuela primaria de su hijo.<\/p>\n<p>\u201cSe siente como si hubiera una gran nube oscura avanzando hacia nuestra ciudad y quisiera entender qu\u00e9 hacer\u201d, dijo.<\/p>\n<p>En su introducci\u00f3n, Karmit dijo a los participantes: \u201cNos han llamado terroristas internos por nuestras protestas pac\u00edficas\u2026 Tenemos que ser los ojos y los o\u00eddos que exijan responsabilidades a los agentes federales. La informaci\u00f3n que documentamos con nuestras c\u00e1maras puede usarse en casos legales. Puede usarse en litigios contra entidades federales o agentes\u201d.<\/p>\n<p>Voluntarios hablaron de los riesgos de confrontaciones verbales y f\u00edsicas con agentes de ICE, incluido el uso de gas pimienta y otros irritantes contra observadores e incluso arrestos.<\/p>\n<p>\u201cNo debemos actuar solos\u201d, dijo Karmit. \u201cDeben ir con un compa\u00f1ero. Deben asegurarse de que haya otras personas con ustedes. Deben avisar a las personas con las que viven a d\u00f3nde van, y puede haber violencia. No dejemos que eso nos intimide hasta la inacci\u00f3n\u201d.<\/p>\n<p>En los d\u00edas posteriores a la sesi\u00f3n de capacitaci\u00f3n, unas 190 de las m\u00e1s de 400 personas que asistieron se hab\u00edan inscrito como observadores, seg\u00fan Luis Argueta, portavoz de la organizaci\u00f3n comunitaria Unidos MN y orador en el evento.<\/p>\n<p>Amplios memoriales para Good han sido levantados cerca del lugar donde fue baleada y alrededor del poste de madera donde su SUV se estrell\u00f3 despu\u00e9s de que fue matada por un agente del Servicio de Inmigraci\u00f3n y Control de Aduanas de EE.UU. (ICE). Hay cruces de madera y pinturas, flores y velas, y cientos de mensajes y cartas a lo largo de la acera nevada. Voluntarios sentados junto a una fogata vigilan el memorial las 24 horas.<\/p>\n<p>Uno de ellos es un fot\u00f3grafo de Atlanta llamado Ryan Vizzions, quien dijo que llevaba cinco a\u00f1os viajando mientras trabajaba en un fotolibro sobre \u201cd\u00f3nde estamos como pa\u00eds\u201d. Estaba en Minneapolis el d\u00eda en que Good fue matada.<\/p>\n<p>\u201cSimplemente guard\u00e9 la c\u00e1mara, tom\u00e9 una pala y empec\u00e9 a cuidar la vigilia\u201d, dijo. \u201cCualquier d\u00eda ver\u00e1s personas de distintos \u00e1mbitos venir aqu\u00ed y mostrar su respeto. Ha sido muy hermoso sentarme aqu\u00ed y ver todo el amor que llega\u201d.<\/p>\n<p>Otra voluntaria que cuida el memorial es una mujer de Ecuador llamada Fabiola Rodr\u00edguez, madre soltera que trabaja como contratista de construcci\u00f3n. Dijo que conoce al menos a 30 personas que han sido detenidas por ICE en Minneapolis en los \u00faltimos dos meses.<\/p>\n<p>\u201cNo importa ahora si tienes estatus legal o no\u201d, dijo. \u201cPero somos habitantes de Minnesota. No vamos a rendirnos. Me di cuenta de que qued\u00e1ndome en casa no estoy haciendo nada. Es mejor levantarse, hablar y pedir justicia\u201d.<\/p>\n<p>La entrada de la Escuela Primaria Valley View, en el suburbio de Columbia Heights, en Minneapolis, se asemeja estos d\u00edas a una despensa de alimentos, con gabinetes llenos de latas de comida y cajas pl\u00e1sticas repletas de ropa infantil. Jason Kuhlman, el director, dijo que la escuela entrega alimentos a 140 familias por semana.<\/p>\n<p>Kuhlman se\u00f1al\u00f3 que 100 de los 570 estudiantes del plantel est\u00e1n recibiendo clases de forma virtual. Aproximadamente el 66 % de los alumnos son latinos, en su mayor\u00eda de Ecuador.<\/p>\n<p>\u201cLa mayor\u00eda de esas familias no est\u00e1n saliendo de sus casas\u201d, dijo. \u201cTienen tarjetas de residencia. Tienen visas. Tienen permisos de trabajo. Est\u00e1n en medio de solicitudes de asilo. Y hay algunos que probablemente son indocumentados\u201d.<\/p>\n<p>Cuatro d\u00edas antes de que Pretti fuera matado, una fotograf\u00eda del estudiante de Valley View Liam Conejo Ramos, de 5 a\u00f1os, circul\u00f3 ampliamente. El ni\u00f1o lleva un gorro azul de conejo y una mochila de Spider-Man. Un agente federal se alza sobre el menor, con la mano sobre la mochila, mientras el ni\u00f1o y su padre son detenidos tras la salida de clases.<\/p>\n<p>Ramos y su padre, Adrian Alexander Conejo Arias, fueron detenidos el mes pasado en la entrada nevada de su casa, en un suburbio de Minneapolis, y trasladados a un centro de detenci\u00f3n familiar en Dilley, Texas, lo que desat\u00f3 indignaci\u00f3n generalizada.<\/p>\n<p>Tras m\u00e1s de una semana en el centro de Dilley, el ni\u00f1o en edad preescolar y su padre ecuatoriano regresaron a su hogar en Minneapolis despu\u00e9s de que un juez ordenara su liberaci\u00f3n. Su detenci\u00f3n termin\u00f3, pero su futuro en Estados Unidos sigue siendo incierto, ya que la familia ahora deber\u00e1 presentar su caso de asilo.<\/p>\n<p>Casi 30 estudiantes de Valley View, as\u00ed como padres o cuidadores, han sido detenidos por agentes federales durante los operativos migratorios, seg\u00fan Kuhlman.<\/p>\n<p>Otra madre detenida por agentes federales en las calles de Minneapolis es la de la ni\u00f1a ecuatoriana de 11 a\u00f1os, quien ha estado aloj\u00e1ndose en la casa de un observador de ICE que conoci\u00f3 apenas esta semana.<\/p>\n<p>La ni\u00f1a dijo que ha hablado por tel\u00e9fono con su madre varias veces desde su arresto y posterior traslado. Su abogado indic\u00f3 que fue llevada al centro de detenci\u00f3n Camp East Montana, en Texas, y, seg\u00fan el sistema en l\u00ednea de localizaci\u00f3n de detenidos de ICE, posteriormente trasladada a una c\u00e1rcel en Willmar, una ciudad a unos 145 kil\u00f3metros al oeste de Minneapolis.<\/p>\n<p>\u201cLe dec\u00eda que yo estaba bien para que no se preocupara\u201d, cont\u00f3.<\/p>\n<p>ICE y el Departamento de Seguridad Nacional no respondieron a la solicitud de comentarios de CNN.<\/p>\n<p>Record\u00f3 los largos d\u00edas que pas\u00f3 dentro del apartamento con su madre mientras agentes federales realizaban operativos y, en ocasiones, se enfrentaban con manifestantes. No hay televisi\u00f3n en el apartamento, pero ve\u00edan videos y fotos en sus tel\u00e9fonos.<\/p>\n<p>Su madre, que lavaba platos en un restaurante los fines de semana y limpiaba habitaciones de hotel seis d\u00edas a la semana, dej\u00f3 de ir a trabajar. La ni\u00f1a recib\u00eda paquetes con tareas escolares que le entregaba su escuela \u2014que tambi\u00e9n dejaba bolsas de comida en algunas ocasiones\u2014. Dijo que le gustaba ordenar el apartamento para mantenerse ocupada.<\/p>\n<p>\u201cMam\u00e1 cocinaba. Todas las noches era sopa\u201d, record\u00f3. \u201cEn la ma\u00f1ana hac\u00eda huevos y arroz\u201d.<\/p>\n<p>El d\u00eda del arresto, la ni\u00f1a dijo que llam\u00f3 varias veces al tel\u00e9fono de su madre y no obtuvo respuesta. Despu\u00e9s de un rato, tom\u00f3 el sobre con sus documentos de inmigraci\u00f3n, tal como su madre le hab\u00eda indicado, y sali\u00f3 por primera vez en m\u00e1s de un mes para caminar hasta la casa de una amiga de la familia.<\/p>\n<p>\u201cAl principio ten\u00eda miedo. Sab\u00eda que era peligroso\u201d, dijo. \u201cPero pens\u00e9 en mi mam\u00e1. \u00bfQu\u00e9 le pasar\u00eda si no la ayudaba? Rec\u00e9 a Dios todo el camino\u201d.<\/p>\n<p>El viernes, su madre la llam\u00f3 para decirle que hab\u00eda sido devuelta a Minneapolis, pero que segu\u00eda detenida en el edificio federal del centro. Le dijo a su hija y a su cuidadora que no sab\u00eda si ser\u00eda liberada. Hayden, su abogado, dijo que no hab\u00eda sido notificado del traslado.<\/p>\n<p>Un d\u00eda antes, cont\u00f3 la ni\u00f1a, su cuidadora la llev\u00f3 al apartamento donde viv\u00eda con su madre para recoger algo de ropa.<\/p>\n<p>\u201cLimpi\u00e9 el apartamento. Tend\u00ed la cama. Lav\u00e9 los platos. Dej\u00e9 todo en orden por si mami vuelve a casa\u201d, dijo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con su largo cabello oscuro saliendo de un gorro rosa brillante, la ni\u00f1a de 11 a\u00f1os, originaria de Ecuador, record\u00f3 con calma cuando su madre sali\u00f3 de su peque\u00f1o apartamento en el sur de Minneapolis el lunes pasado por la ma\u00f1ana, por primera vez en mes y medio. \u201cAdi\u00f3s, querida, cu\u00eddate mucho\u201d, le dijo su [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471004","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Familias escondidas y observadores desafiantes: as\u00ed es Minneapolis tras la llamada &quot;reducci\u00f3n&quot; de ICE - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Familias escondidas y observadores desafiantes: as\u00ed es Minneapolis tras la llamada &quot;reducci\u00f3n&quot; de ICE - Noticias\" \/>\n<meta property=\"og:description\" content=\"Con su largo cabello oscuro saliendo de un gorro rosa brillante, la ni\u00f1a de 11 a\u00f1os, originaria de Ecuador, record\u00f3 con calma cuando su madre sali\u00f3 de su peque\u00f1o apartamento en el sur de Minneapolis el lunes pasado por la ma\u00f1ana, por primera vez en mes y medio. \u201cAdi\u00f3s, querida, cu\u00eddate mucho\u201d, le dijo su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-08T20:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Familias escondidas y observadores desafiantes: as\u00ed es Minneapolis tras la llamada &#171;reducci\u00f3n&#187; de ICE\",\"datePublished\":\"2026-02-08T20:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/\"},\"wordCount\":2783,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/\",\"name\":\"Familias escondidas y observadores desafiantes: as\u00ed es Minneapolis tras la llamada \\\"reducci\u00f3n\\\" de ICE - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-08T20:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Familias escondidas y observadores desafiantes: as\u00ed es Minneapolis tras la llamada &#171;reducci\u00f3n&#187; de ICE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Familias escondidas y observadores desafiantes: as\u00ed es Minneapolis tras la llamada \"reducci\u00f3n\" de ICE - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Familias escondidas y observadores desafiantes: as\u00ed es Minneapolis tras la llamada \"reducci\u00f3n\" de ICE - Noticias","og_description":"Con su largo cabello oscuro saliendo de un gorro rosa brillante, la ni\u00f1a de 11 a\u00f1os, originaria de Ecuador, record\u00f3 con calma cuando su madre sali\u00f3 de su peque\u00f1o apartamento en el sur de Minneapolis el lunes pasado por la ma\u00f1ana, por primera vez en mes y medio. \u201cAdi\u00f3s, querida, cu\u00eddate mucho\u201d, le dijo su [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-08T20:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/"},"author":{"name":"","@id":""},"headline":"Familias escondidas y observadores desafiantes: as\u00ed es Minneapolis tras la llamada &#171;reducci\u00f3n&#187; de ICE","datePublished":"2026-02-08T20:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/"},"wordCount":2783,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/","name":"Familias escondidas y observadores desafiantes: as\u00ed es Minneapolis tras la llamada \"reducci\u00f3n\" de ICE - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-08T20:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Familias escondidas y observadores desafiantes: as\u00ed es Minneapolis tras la llamada &#171;reducci\u00f3n&#187; de ICE"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Familias escondidas y observadores desafiantes: as\u00ed es Minneapolis tras la llamada &#171;reducci\u00f3n&#187; de ICE","url":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2026\/02\/08\/operativos-ice-minneapolis-familias-escondidas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-08T20:03:50Z","datePublished":"2026-02-08T20:03:50Z","dateModified":"2026-02-08T20:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Familias escondidas y observadores desafiantes: as\\u00ed es Minneapolis tras la llamada &#171;reducci\\u00f3n&#187; de ICE\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/08\\\/operativos-ice-minneapolis-familias-escondidas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2026\\\/02\\\/08\\\/operativos-ice-minneapolis-familias-escondidas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-08T20:03:50Z\",\"datePublished\":\"2026-02-08T20:03:50Z\",\"dateModified\":\"2026-02-08T20:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470447,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/01\/24\/ice-detuvo-nina-traslado-estado-trax\/","url_meta":{"origin":1471004,"position":0},"title":"ICE detuvo a una ni\u00f1a con su padre y la traslad\u00f3 de estado antes de devolverla a su madre al d\u00eda siguiente, seg\u00fan su abogada","author":"","date":"enero 24, 2026","format":false,"excerpt":"Una ni\u00f1a de dos a\u00f1os fue detenida por ICE junto con su padre el jueves en Minneapolis y trasladada en avi\u00f3n a Texas antes de ser devuelta a su madre el viernes por la tarde, seg\u00fan inform\u00f3 una abogada de la familia.El traslado de la ni\u00f1a a Texas se produjo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470871,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/04\/liberan-elizabeth-zuna-nina-minnesota-madre-detenidas-ice-texas-trax\/","url_meta":{"origin":1471004,"position":1},"title":"Liberan a ni\u00f1a de Minnesota y a su madre tras casi un mes detenidas en Texas","author":"","date":"febrero 4, 2026","format":false,"excerpt":"Una ni\u00f1a de 10 a\u00f1os del mismo distrito escolar suburbano de Minneapolis que Liam Conejo Ramos, fue liberada del Centro Residencial Familiar del Sur de Texas en Dilley, seg\u00fan inform\u00f3 un abogado que asiste a la familia.Elizabeth Zuna Caisaguano y su madre, Rosa, fueron liberadas la tarde del martes y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461819,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/04\/30\/venezuela-estados-unidos-secuestro-nina-separada-padres-deportados-trax\/","url_meta":{"origin":1471004,"position":2},"title":"Venezuela acusa a Estados Unidos del &#171;secuestro&#187; de una ni\u00f1a de 2 a\u00f1os que fue separada de sus padres deportados","author":"","date":"abril 30, 2025","format":false,"excerpt":"Venezuela exige que una ni\u00f1a de 2 a\u00f1os sea devuelta a su familia despu\u00e9s de que Estados Unidos deportara a sus padres y mantuviera a la menor en custodia del Gobierno.El Ministerio de Relaciones Exteriores de Venezuela acus\u00f3 este lunes a Estados Unidos de \u201csecuestrar\u201d a Maikelys Antonella Espinoza Bernal,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470502,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/01\/26\/ecuador-cancilleria-caso-liam-conejo-familia-orix\/","url_meta":{"origin":1471004,"position":3},"title":"Canciller\u00eda de Ecuador dice que da seguimiento al caso de Liam Conejo y que su familia &#171;ha pedido que no intervengamos&#187;","author":"","date":"enero 26, 2026","format":false,"excerpt":"La canciller de Ecuador, Gabriela Sommerfeld, dijo este lunes que el Gobierno est\u00e1 pendiente del caso del ni\u00f1o ecuatoriano de cinco a\u00f1os Liam Conejo, quien fue detenido la semana pasada por agentes del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Minneapolis, junto a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468390,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/11\/16\/nina-florida-desaparecida-madre-carcel-trax\/","url_meta":{"origin":1471004,"position":4},"title":"Una ni\u00f1a de Florida fue vista por \u00faltima vez en un autob\u00fas con su madre en junio. Ahora la madre est\u00e1 en la c\u00e1rcel","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"Gordon Terrelonge dice que han pasado m\u00e1s de seis meses desde la \u00faltima vez que vio o tuvo noticias de su hija de 10 a\u00f1os, Gabrielle Terrelonge.Perdi\u00f3 el contacto con Gabrielle y su madre, Passha Davis, esta primavera pasada despu\u00e9s de una disputa con Davis en Kissimmee, Florida, pero dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461647,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/04\/25\/ciudadana-estadounidense-2-anios-deportada-madre-honduras-trax\/","url_meta":{"origin":1471004,"position":5},"title":"Juez federal dice que una ciudadana estadounidense de 2 a\u00f1os fue deportada con su madre a Honduras","author":"","date":"abril 25, 2025","format":false,"excerpt":"Un juez federal dijo este viernes que una ciudadana estadounidense de dos a\u00f1os fue deportada con su madre a Honduras. La administraci\u00f3n Trump dice que su madre pidi\u00f3 a los funcionarios que la llevaran con ella, seg\u00fan muestran los documentos.El juez de distrito de EE.UU., Terry Doughty, dijo que la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1471004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1471004"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1471004\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1471004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1471004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1471004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}