{"id":1446251,"date":"2024-03-03T14:02:00","date_gmt":"2024-03-03T22:02:00","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/"},"modified":"2024-03-03T14:02:00","modified_gmt":"2024-03-03T22:02:00","slug":"erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/phoenix\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/","title":{"rendered":"Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El volc\u00e1n La Cumbre, ubicado en la isla Fernandina del archipi\u00e9lago de las Gal\u00e1pagos en Ecuador, entr\u00f3 en erupci\u00f3n cerca de la medianoche de este s\u00e1bado, inform\u00f3 en un comunicado el Ministerio del Ambiente, Agua y Transici\u00f3n Ecol\u00f3gica (MAATE).<\/p>\n<p>Aunque la isla no est\u00e1 habitada, la Direcci\u00f3n del Parque Nacional Gal\u00e1pagos emiti\u00f3 una alerta, se explic\u00f3 en la nota de prensa publicada este domingo.<\/p>\n<p>Se agreg\u00f3 que se realizar\u00e1n monitoreos para registrar posibles cambios en el ecosistema, ya que &#171;las erupciones forman parte del ciclo natural de las islas e influencian en la particular ecolog\u00eda y biodiversidad&#187;.<\/p>\n<p>Volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador. Cr\u00e9dito: MAATE<\/p>\n<p>Seg\u00fan el MAATE, la erupci\u00f3n no representa una amenaza para el turismo y no se han cerrado los sitios con acceso a visitantes.<\/p>\n<p>El Ministerio inform\u00f3 que se desconoce cu\u00e1nto pueda durar el fen\u00f3meno o si el material arrojado por el volc\u00e1n llegar\u00e1 hasta la orilla del mar.<\/p>\n<p>Con informaci\u00f3n de Ana Mar\u00eda Ca\u00f1izares<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El volc\u00e1n La Cumbre, ubicado en la isla Fernandina del archipi\u00e9lago de las Gal\u00e1pagos en Ecuador, entr\u00f3 en erupci\u00f3n cerca de la medianoche de este s\u00e1bado, inform\u00f3 en un comunicado el Ministerio del Ambiente, Agua y Transici\u00f3n Ecol\u00f3gica (MAATE). Aunque la isla no est\u00e1 habitada, la Direcci\u00f3n del Parque Nacional Gal\u00e1pagos emiti\u00f3 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446251","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El volc\u00e1n La Cumbre, ubicado en la isla Fernandina del archipi\u00e9lago de las Gal\u00e1pagos en Ecuador, entr\u00f3 en erupci\u00f3n cerca de la medianoche de este s\u00e1bado, inform\u00f3 en un comunicado el Ministerio del Ambiente, Agua y Transici\u00f3n Ecol\u00f3gica (MAATE). Aunque la isla no est\u00e1 habitada, la Direcci\u00f3n del Parque Nacional Gal\u00e1pagos emiti\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-03T22:02:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador\",\"datePublished\":\"2024-03-03T22:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/\"},\"wordCount\":219,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/\",\"url\":\"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/\",\"name\":\"Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-03T22:02:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El volc\u00e1n La Cumbre, ubicado en la isla Fernandina del archipi\u00e9lago de las Gal\u00e1pagos en Ecuador, entr\u00f3 en erupci\u00f3n cerca de la medianoche de este s\u00e1bado, inform\u00f3 en un comunicado el Ministerio del Ambiente, Agua y Transici\u00f3n Ecol\u00f3gica (MAATE). Aunque la isla no est\u00e1 habitada, la Direcci\u00f3n del Parque Nacional Gal\u00e1pagos emiti\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-03T22:02:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/"},"author":{"name":"","@id":""},"headline":"Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador","datePublished":"2024-03-03T22:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/"},"wordCount":219,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/","url":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/","name":"Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-03T22:02:00+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/phoenix\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador","url":"http:\/\/noticiasya.com\/phoenix\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/phoenix\/2024\/03\/03\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-03T22:02:00Z","datePublished":"2024-03-03T22:02:00Z","dateModified":"2024-03-03T22:02:00Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Entra en erupci\\u00f3n volc\\u00e1n La Cumbre en las islas Gal\\u00e1pagos de Ecuador\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/phoenix\\\/2024\\\/03\\\/03\\\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/phoenix\\\/2024\\\/03\\\/03\\\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-03T22:02:00Z\",\"datePublished\":\"2024-03-03T22:02:00Z\",\"dateModified\":\"2024-03-03T22:02:00Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446419,"url":"https:\/\/noticiasya.com\/phoenix\/2024\/03\/04\/erupcion-volcan-la-cumbre-islas-galapagos-ecuador-orix-2\/","url_meta":{"origin":1446251,"position":0},"title":"Entra en erupci\u00f3n volc\u00e1n La Cumbre en las islas Gal\u00e1pagos de Ecuador","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El volc\u00e1n La Cumbre, ubicado en la isla Fernandina del archipi\u00e9lago de las Gal\u00e1pagos en Ecuador, entr\u00f3 en erupci\u00f3n cerca de la medianoche de este s\u00e1bado, inform\u00f3 en un comunicado el Ministerio del Ambiente, Agua y Transici\u00f3n Ecol\u00f3gica (MAATE).Aunque la isla no est\u00e1 habitada, la Direcci\u00f3n del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459504,"url":"https:\/\/noticiasya.com\/phoenix\/2025\/03\/04\/incautacion-droga-mar-galapagos-ecuador-narcotrafico-orix\/","url_meta":{"origin":1446251,"position":1},"title":"Nueva incautaci\u00f3n de droga en el mar de las Gal\u00e1pagos; Ecuador busca m\u00e1s apoyo internacional en el combate al narcotr\u00e1fico","author":"","date":"marzo 4, 2025","format":false,"excerpt":"La Polic\u00eda de Ecuador inform\u00f3 este martes sobre la incautaci\u00f3n de m\u00e1s de una tonelada de droga en el mar que rodea las emblem\u00e1ticas islas Gal\u00e1pagos, donde las autoridades del pa\u00eds realizan labores en cooperaci\u00f3n con Estados Unidos.La operaci\u00f3n de incautaci\u00f3n se realiz\u00f3 en alta mar cerca de la isla\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457195,"url":"https:\/\/noticiasya.com\/phoenix\/2025\/01\/03\/volcan-misterioso-erupcion-1831-enfrio-tierra-trax\/","url_meta":{"origin":1446251,"position":2},"title":"Identifican el &#171;volc\u00e1n misterioso&#187; que entr\u00f3 en erupci\u00f3n en 1831 y enfri\u00f3 la Tierra","author":"","date":"enero 3, 2025","format":false,"excerpt":"Un volc\u00e1n desconocido entr\u00f3 en erupci\u00f3n en 1831 de forma tan explosiva que enfri\u00f3 las condiciones clim\u00e1ticas de la Tierra. Ahora, casi 200 a\u00f1os despu\u00e9s, los cient\u00edficos identificaron al \u201cvolc\u00e1n misterioso\u201d.La erupci\u00f3n fue una de las m\u00e1s potentes del siglo XIX, arrojando tanto di\u00f3xido de azufre a la estratosfera que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456916,"url":"https:\/\/noticiasya.com\/phoenix\/2024\/12\/24\/kilauea-volcan-erupcion-hawai-23-diciembre-trax\/","url_meta":{"origin":1446251,"position":3},"title":"El volc\u00e1n Kilauea entra en erupci\u00f3n en la isla de Hawai y atrae a multitudes por las fiestas","author":"","date":"diciembre 24, 2024","format":false,"excerpt":"Uno de los volcanes m\u00e1s activos del mundo entr\u00f3 en erupci\u00f3n este lunes despu\u00e9s de tres meses de interrupci\u00f3n, arrojando lava de color naranja brillante a una altura de hasta 90 metros, seg\u00fan el Servicio Geol\u00f3gico de Estados Unidos (USGS, por sus siglas en ingl\u00e9s).El volc\u00e1n Kilauea, situado en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461770,"url":"https:\/\/noticiasya.com\/phoenix\/2025\/04\/29\/galapagos-narcotrafico-ecuador-incautacion-droga-orix\/","url_meta":{"origin":1446251,"position":4},"title":"El mar de las Gal\u00e1pagos vuelve a ser escenario de narcotr\u00e1fico. Polic\u00eda de Ecuador report\u00f3 millonaria incautaci\u00f3n de droga","author":"","date":"abril 29, 2025","format":false,"excerpt":"La Polic\u00eda de Ecuador report\u00f3 este martes un nuevo golpe al narcotr\u00e1fico en el mar que rodea a las emblem\u00e1ticas islas Gal\u00e1pagos.La instituci\u00f3n indic\u00f3 que dos toneladas y media de droga fueron identificadas a una distancia de 175 millas n\u00e1uticas al noreste de la isla San Crist\u00f3bal, la segunda m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448226,"url":"https:\/\/noticiasya.com\/phoenix\/2024\/04\/17\/indonesia-alerta-tsunami-erupcion-volcan-monte-ruang-isla-remota-trax\/","url_meta":{"origin":1446251,"position":5},"title":"Indonesia emite una alerta de tsunami tras la erupci\u00f3n del volc\u00e1n monte Ruang en una isla remota","author":"","date":"abril 17, 2024","format":false,"excerpt":"(CNN) -- Las autoridades indonesias ordenaron este mi\u00e9rcoles la evacuaci\u00f3n de cientos de habitantes tras las m\u00faltiples erupciones del volc\u00e1n de una remota isla, lo que hace temer que pueda desplomarse sobre el mar y desencadenar un tsunami.El monte Ruang, un estratovolc\u00e1n c\u00f3nico de 725 metros de altura situado en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts\/1446251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/comments?post=1446251"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts\/1446251\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/media?parent=1446251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/categories?post=1446251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/tags?post=1446251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}