{"id":1446415,"date":"2024-03-04T09:47:48","date_gmt":"2024-03-04T17:47:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax\/"},"modified":"2024-03-07T04:50:27","modified_gmt":"2024-03-07T12:50:27","slug":"guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/phoenix\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/","title":{"rendered":"Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024"},"content":{"rendered":"<p>Esta cobertura en vivo finaliz\u00f3. Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta cobertura en vivo finaliz\u00f3. Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed. The-CNN-Wire&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446415","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024 - Noticias\" \/>\n<meta property=\"og:description\" content=\"Esta cobertura en vivo finaliz\u00f3. Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed. The-CNN-Wire&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-04T17:47:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T12:50:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024\",\"datePublished\":\"2024-03-04T17:47:48+00:00\",\"dateModified\":\"2024-03-07T12:50:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/\"},\"wordCount\":44,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/\",\"name\":\"Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-04T17:47:48+00:00\",\"dateModified\":\"2024-03-07T12:50:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/phoenix\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/","og_locale":"es_ES","og_type":"article","og_title":"Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024 - Noticias","og_description":"Esta cobertura en vivo finaliz\u00f3. Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed. The-CNN-Wire&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/","og_site_name":"Noticias","article_published_time":"2024-03-04T17:47:48+00:00","article_modified_time":"2024-03-07T12:50:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/"},"author":{"name":"","@id":""},"headline":"Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024","datePublished":"2024-03-04T17:47:48+00:00","dateModified":"2024-03-07T12:50:27+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/"},"wordCount":44,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/","name":"Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-04T17:47:48+00:00","dateModified":"2024-03-07T12:50:27+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/phoenix\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/phoenix\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024","url":"http:\/\/noticiasya.com\/phoenix\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/phoenix\/2024\/03\/04\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-04T17:47:48Z","datePublished":"2024-03-04T17:47:48Z","dateModified":"2024-03-07T12:50:27Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Resumen de la guerra entre Israel y Hamas este domingo 3 de marzo del 2024\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/phoenix\\\/2024\\\/03\\\/04\\\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/phoenix\\\/2024\\\/03\\\/04\\\/guerra-entre-israel-y-hamas-en-vivo-liberacion-de-rehenes-trax-3\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-04T17:47:48Z\",\"datePublished\":\"2024-03-04T17:47:48Z\",\"dateModified\":\"2024-03-07T12:50:27Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1395528,"url":"https:\/\/noticiasya.com\/phoenix\/2022\/06\/06\/tras-elecciones-morena-aventaja-en-4-estados-de-mexico-y-gana-territorio-en-el-pais\/","url_meta":{"origin":1446415,"position":0},"title":"Tras elecciones, Morena aventaja en 4 estados de M\u00e9xico y gana territorio en el pa\u00eds","author":"agomez","date":"junio 6, 2022","format":false,"excerpt":"El partido guinda podr\u00eda llegar a gobernar 22 de los 32 estados del pa\u00eds.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1395503,"url":"https:\/\/noticiasya.com\/phoenix\/2022\/06\/06\/inicia-gran-construccion-en-el-aeropuerto-internacional-de-san-diego\/","url_meta":{"origin":1446415,"position":1},"title":"Inicia gran construcci\u00f3n en el Aeropuerto Internacional de San Diego","author":"agomez","date":"junio 6, 2022","format":false,"excerpt":"La construcci\u00f3n dar\u00e1 paso a una nueva plaza de estacionamiento de la Terminal 1 que se espera que abra a finales de 2024.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456439,"url":"https:\/\/noticiasya.com\/phoenix\/2024\/12\/10\/aumento-salario-minimo-ee-uu-2025-cantidad-orix\/","url_meta":{"origin":1446415,"position":2},"title":"Aumento del salario m\u00ednimo en EE.UU. en 2025: \u00bfde cu\u00e1nto ser\u00e1 y cu\u00e1ndo entra en vigor?","author":"agomez","date":"diciembre 10, 2024","format":false,"excerpt":"El salario m\u00ednimo en Estados Unidos \u2014que es el pago m\u00ednimo que por ley debe recibir un trabajador en el pa\u00eds\u2014 aumentar\u00e1 en m\u00e1s de dos decenas de estados a partir del 1 de enero de 2025.De acuerdo con GovDocs, un proveedor de software de cumplimiento para grandes empresas con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452247,"url":"https:\/\/noticiasya.com\/phoenix\/2024\/08\/28\/fotos-ceremonia-inauguracion-juegos-paralimpicos-paris-2024-orix\/","url_meta":{"origin":1446415,"position":3},"title":"FOTOS | Ceremonia de inauguraci\u00f3n de los Juegos Paral\u00edmpicos de Par\u00eds 2024","author":"","date":"agosto 28, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Los Juegos Paral\u00edmpicos de Par\u00eds 2024 iniciaron este mi\u00e9rcoles con su ceremonia de inauguraci\u00f3n en la plaza de la Concordia y los Campos El\u00edseos.El evento reunen a los 4.400 atletas paral\u00edmpicos m\u00e1s destacados del mundo, quienes competir\u00e1n en diversas disciplinas durante once d\u00edas.Los Juegos Paral\u00edmpicos de Par\u00eds 2024\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451485,"url":"https:\/\/noticiasya.com\/phoenix\/2024\/07\/29\/elecciones-presidenciales-en-venezuela-de-2024-en-vivo-votaciones-y-ultima-hora-orix-2\/","url_meta":{"origin":1446415,"position":4},"title":"Resumen de noticias de las elecciones en Venezuela 2024, Maduro, Edmundo Gonz\u00e1lez del 29 de julio de 2024","author":"","date":"julio 29, 2024","format":false,"excerpt":"Este cubrimiento ha finalizado. Para m\u00e1s noticias sobre Venezuela visita CNNEE.com,Cr\u00e9dito: FEDERICO PARRA\/AFP via Getty ImagesThe-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451487,"url":"https:\/\/noticiasya.com\/phoenix\/2024\/07\/29\/resumen-noticas-elecciones-presidenciales-en-venezuela-de-2024-29-jul-orix\/","url_meta":{"origin":1446415,"position":5},"title":"Resumen de noticias de las elecciones en Venezuela 2024, Maduro, Edmundo Gonz\u00e1lez del 29 de julio de 2024","author":"","date":"julio 29, 2024","format":false,"excerpt":"Esta cobertura ha finalizado. Para ver las entradas m\u00e1s recientes haz clic aqu\u00edCr\u00e9dito: FEDERICO PARRA\/AFP via Getty ImagesThe-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts\/1446415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/comments?post=1446415"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts\/1446415\/revisions"}],"predecessor-version":[{"id":1446711,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts\/1446415\/revisions\/1446711"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/media?parent=1446415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/categories?post=1446415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/tags?post=1446415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}