{"id":1446467,"date":"2024-03-04T09:48:32","date_gmt":"2024-03-04T17:48:32","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax\/"},"modified":"2024-03-07T04:50:06","modified_gmt":"2024-03-07T12:50:06","slug":"rana-india-hongo-cientificos-descubrimiento-trax-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/phoenix\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/","title":{"rendered":"A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto"},"content":{"rendered":"<p>(CNN) &#8212; Al observar una multitud de ranas de lomo dorado en un estanque al borde de una carretera en Karnataka, India, un grupo de naturalistas not\u00f3 algo extra\u00f1o en uno de los anfibios: el animal ten\u00eda un peque\u00f1o hongo que brotaba de su costado.<\/p>\n<p>La forma en que la rana aparentemente sana lleg\u00f3 a desarrollar su compa\u00f1ero hongo, un hecho que nunca antes se hab\u00eda documentado, ha dejado desconcertados a los cient\u00edficos, seg\u00fan una nota publicada en enero en la revista Reptiles and Amphibians.<\/p>\n<p>\u201cCuando observ\u00e9 por primera vez la rana con el hongo, qued\u00e9 asombrado e intrigado por el avistamiento\u201d, dijo Lohit Y T, especialista en r\u00edos y humedales del Fondo Mundial para la Naturaleza India en Bengaluru, por correo electr\u00f3nico. Y T fue parte del grupo que descubri\u00f3 la rana. \u201cMi idea era documentarlo, ya que este fen\u00f3meno es algo de lo que nunca hab\u00edamos o\u00eddo hablar. Solo esper\u00e1bamos que esto fuera un incidente raro y no un fen\u00f3meno peligroso para la rana\u201d.<\/p>\n<p>\u00bfPuede el \u201chongo zombi\u201d Cordyceps afectar al humano? Esto es lo que dice la ciencia al respecto<\/p>\n<p>La especie, conocida como rana intermedia de lomo dorado de Rao, o nombre cient\u00edfico Hylarana intermedia, se encuentra en abundancia en los estados de Karnataka y Kerala, en el suroeste de la India. Las ranas son peque\u00f1as y crecen hasta medir solo 7,4 cent\u00edmetros de largo.<\/p>\n<p>Mientras los naturalistas observaban a la rana con el crecimiento del hongo, el animal se movi\u00f3 desde el centro de la ramita en la que estaba sentado hasta la punta, girando y cambiando de posici\u00f3n, pero el hongo permaneci\u00f3 perfectamente en su lugar, dijo Y T. El grupo no toc\u00f3 a la rana.<\/p>\n<p>La rana se movi\u00f3 desde el centro de la ramita sobre la que se asentaba hasta la punta, girando y cambiando de posici\u00f3n, pero el hongo permaneci\u00f3 perfectamente en su lugar, dijo Y T. (Cr\u00e9dito: Lohit Y T)<\/p>\n<p>Los autores descubrieron al anfibio en junio de 2023 y no lo recolectaron, por lo que no se conoce ni la causa del fen\u00f3meno ni el destino de la rana.<\/p>\n<p>Pero, a trav\u00e9s de im\u00e1genes, los mic\u00f3logos identificaron m\u00e1s tarde el hongo que crece en el flanco de la rana como un cap\u00f3 com\u00fan, parte del g\u00e9nero Mycena, un tipo de hongo que crece principalmente en la madera podrida de \u00e1rboles muertos, escribieron los autores en el art\u00edculo publicado. El hongo es un descomponedor saprotr\u00f3fico que normalmente obtiene sus nutrientes de materia org\u00e1nica muerta o en descomposici\u00f3n, pero un estudio de 2023 encontr\u00f3 que\u00a0 podr\u00eda evolucionar para prosperar tambi\u00e9n en plantas vivas.<\/p>\n<p>El estudio de 2023 sugiri\u00f3 adem\u00e1s que el hongo Mycena podr\u00eda desarrollarse para tener una relaci\u00f3n simbi\u00f3tica con plantas o \u00e1rboles vivos, lo que significa que tanto la planta como el hongo que crece en ella se beneficiar\u00edan de la disposici\u00f3n: los hongos tomar\u00edan nutrientes y los transferir\u00edan a la planta hu\u00e9sped. En los \u00e1rboles, Mycena podr\u00eda resultar \u00fatil podando las ramas muertas, a\u00f1adieron los autores.<\/p>\n<p>Se desconoce el pron\u00f3stico de la rana con el polizonte hongo, pero existen varias teor\u00edas sobre la causa de su afecci\u00f3n.<\/p>\n<p>Destino de la rana hongo<\/p>\n<p>Al ver por primera vez el informe de la rana con un hongo adherido a su flanco, Alyssa Wetterau Kaganer, asociada postdoctoral en el departamento de salud p\u00fablica y de ecosistemas de la Facultad de Medicina Veterinaria de la Universidad de Cornell, encontr\u00f3 fascinante el descubrimiento.<\/p>\n<p>&#171;Los hongos son organismos din\u00e1micos que se adaptan a los cambios en su entorno y, al exponerse a nuevos hu\u00e9spedes potenciales en diferentes entornos o climas, pueden crecer en lugares que antes no esper\u00e1bamos&#187;, dijo en un correo electr\u00f3nico.<\/p>\n<p>C\u00f3mo fue que las ara\u00f1as saltarinas se convirtieron en las nuevas mascotas de moda<\/p>\n<p>Si bien es dif\u00edcil predecir el destino de la rana sin m\u00e1s estudios de su condici\u00f3n, es posible que \u201cuna rana sana pueda resistir una leve colonizaci\u00f3n de su piel por este hongo sin ning\u00fan efecto adverso para la salud\u201d, dijo Kaganer. Sin embargo, las infecciones por hongos en las ranas son muy comunes, y si el hongo &#171;creciera extensamente en la piel o se enterrara dentro del cuerpo del animal, la rana podr\u00eda desarrollar signos de una enfermedad f\u00fangica&#187;, a\u00f1adi\u00f3. Kaganer no particip\u00f3 en el descubrimiento.<\/p>\n<p>Hay muchos tipos de hongos que pueden infectar a las ranas, y es posible que a\u00fan haya interacciones entre hongos y ranas por descubrir. Una rana con signos de enfermedad f\u00fangica, como &#171;comportamiento alterado de la rana&#187; o &#171;da\u00f1o en la piel que incluye ulceraci\u00f3n o n\u00f3dulos similares a tumores&#187;, tiene una infecci\u00f3n que a menudo puede provocar la muerte de al menos algunos de los animales infectados, dijo Kaganer.<\/p>\n<p>Cualquier cosa fuera de lo com\u00fan, incluido un crecimiento de hongos como este, es motivo de preocupaci\u00f3n para las especies de ranas, dijo Karthikeyan Vasudevan, cient\u00edfico jefe del Laboratorio para la Conservaci\u00f3n de Especies en Peligro del Centro de Biolog\u00eda Celular y Molecular en Telangana, India. Vasudevan no particip\u00f3 en el descubrimiento y tambi\u00e9n qued\u00f3 sorprendido por el hallazgo.<\/p>\n<p>\u201cLos animales enfermos en la naturaleza tienen muy pocas posibilidades de sobrevivir. Es dif\u00edcil detectar a un animal enfermo, ya que muere o es devorado r\u00e1pidamente. Por lo tanto, algo como esto es interesante y deber\u00eda ir seguido de observaciones y ex\u00e1menes de ranas\u201d, dijo Vasudevan en un correo electr\u00f3nico.<\/p>\n<p>Inicialmente, Vasudevan hab\u00eda pensado que el hongo estaba pegado a la piel de la rana en lugar de un crecimiento, pero las fotos de la criatura lo convencieron de lo contrario. &#171;De hecho, es el caso de un hongo vivo sobre una rana viva&#187;, dijo Vasudevan. &#171;Pero una de las posibilidades es que haya un peque\u00f1o trozo de restos de madera debajo de la piel de la rana y de ella brot\u00f3 un hongo&#187;.<\/p>\n<p>Una enfermedad causada por hongos<\/p>\n<p>India se enfrenta actualmente a una epidemia de una enfermedad que mata ranas conocida como quitridiomicosis, una infecci\u00f3n f\u00fangica que afecta a m\u00e1s de 700 especies de anfibios en todo el mundo. La enfermedad se ha observado en niveles bajos en todos los puntos cr\u00edticos de ranas en toda la India, escribieron los autores de la nueva nota.<\/p>\n<p>La enfermedad quitridiosa es un ejemplo de una interacci\u00f3n com\u00fan entre anfibios y hongos. Pero los autores no saben si est\u00e1 relacionada con este descubrimiento, dijo Y T.<\/p>\n<p>&#171;Este tipo espec\u00edfico de hongo no est\u00e1 estrechamente relacionado con las especies de hongos que causan quitridiomicosis, por lo que no me preocupa que este hongo sea un signo directo de quitridiomicosis&#187;, dijo Kaganer, que estudia la enfermedad. &#171;Sin embargo, es posible que una rana con Mycena haya alterado la susceptibilidad a una infecci\u00f3n por quitridio&#187;.<\/p>\n<p>La rana con el hongo en su costado podr\u00eda tener un aumento en la susceptibilidad a la quitridiomicosis al verse comprometida por Mycena, o podr\u00eda ser m\u00e1s inmune &#171;porque Mycena ha acelerado el sistema inmunol\u00f3gico de la rana&#187;, agreg\u00f3.<\/p>\n<p>&#171;No tenemos ninguna esperanza de perseguir a la rana, ya que no es un fen\u00f3meno com\u00fan&#187;, dijo Y T. Los autores visitar\u00e1n el lugar nuevamente durante la pr\u00f3xima temporada de monzones, cuando el clima sea c\u00e1lido y lluvioso y las ranas sean m\u00e1s abundantes, a\u00f1adi\u00f3.<\/p>\n<p>&#171;Si logramos encontrarla, ser\u00e1 genial&#187;, dijo Y T. \u201cEl lugar ha sido frecuentado tanto por entusiastas como por expertos. Ser\u00eda fant\u00e1stico si alg\u00fan investigador la pusiera en sus manos y pudiera avanzar en la investigaci\u00f3n, pero repito, es muy poco probable que suceda\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Al observar una multitud de ranas de lomo dorado en un estanque al borde de una carretera en Karnataka, India, un grupo de naturalistas not\u00f3 algo extra\u00f1o en uno de los anfibios: el animal ten\u00eda un peque\u00f1o hongo que brotaba de su costado. La forma en que la rana aparentemente sana lleg\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446467","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Al observar una multitud de ranas de lomo dorado en un estanque al borde de una carretera en Karnataka, India, un grupo de naturalistas not\u00f3 algo extra\u00f1o en uno de los anfibios: el animal ten\u00eda un peque\u00f1o hongo que brotaba de su costado. La forma en que la rana aparentemente sana lleg\u00f3 a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-04T17:48:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T12:50:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto\",\"datePublished\":\"2024-03-04T17:48:32+00:00\",\"dateModified\":\"2024-03-07T12:50:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/\"},\"wordCount\":1372,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/\",\"name\":\"A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-04T17:48:32+00:00\",\"dateModified\":\"2024-03-07T12:50:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/phoenix\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/","og_locale":"es_ES","og_type":"article","og_title":"A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto - Noticias","og_description":"(CNN) &#8212; Al observar una multitud de ranas de lomo dorado en un estanque al borde de una carretera en Karnataka, India, un grupo de naturalistas not\u00f3 algo extra\u00f1o en uno de los anfibios: el animal ten\u00eda un peque\u00f1o hongo que brotaba de su costado. La forma en que la rana aparentemente sana lleg\u00f3 a [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/","og_site_name":"Noticias","article_published_time":"2024-03-04T17:48:32+00:00","article_modified_time":"2024-03-07T12:50:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/"},"author":{"name":"","@id":""},"headline":"A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto","datePublished":"2024-03-04T17:48:32+00:00","dateModified":"2024-03-07T12:50:06+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/"},"wordCount":1372,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/","name":"A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-04T17:48:32+00:00","dateModified":"2024-03-07T12:50:06+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/phoenix\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/phoenix\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto","url":"http:\/\/noticiasya.com\/phoenix\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/phoenix\/2024\/03\/04\/rana-india-hongo-cientificos-descubrimiento-trax-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-04T17:48:32Z","datePublished":"2024-03-04T17:48:32Z","dateModified":"2024-03-07T12:50:06Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"A una rana en la India le brot\\u00f3 un hongo, algo que los cient\\u00edficos jam\\u00e1s hab\\u00edan visto\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/phoenix\\\/2024\\\/03\\\/04\\\/rana-india-hongo-cientificos-descubrimiento-trax-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/phoenix\\\/2024\\\/03\\\/04\\\/rana-india-hongo-cientificos-descubrimiento-trax-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-04T17:48:32Z\",\"datePublished\":\"2024-03-04T17:48:32Z\",\"dateModified\":\"2024-03-07T12:50:06Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446124,"url":"https:\/\/noticiasya.com\/phoenix\/2024\/02\/29\/rana-india-hongo-cientificos-descubrimiento-trax\/","url_meta":{"origin":1446467,"position":0},"title":"A una rana en la India le brot\u00f3 un hongo, algo que los cient\u00edficos jam\u00e1s hab\u00edan visto","author":"","date":"febrero 29, 2024","format":false,"excerpt":"(CNN) -- Al observar una multitud de ranas de lomo dorado en un estanque al borde de una carretera en Karnataka, India, un grupo de naturalistas not\u00f3 algo extra\u00f1o en uno de los anfibios: el animal ten\u00eda un peque\u00f1o hongo que brotaba de su costado.La forma en que la rana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471643,"url":"https:\/\/noticiasya.com\/phoenix\/2026\/02\/25\/ranas-banos-medicinales-sauna-cte-llamado-tierra\/","url_meta":{"origin":1446467,"position":1},"title":"De saunas para ranas a ba\u00f1os medicinales: la lucha de los cient\u00edficos contra una plaga mundial que mata a los anfibios","author":"","date":"febrero 25, 2026","format":false,"excerpt":"En una tarde luminosa bajo el c\u00e1lido sol australiano, peque\u00f1os rostros h\u00famedos se asoman por los agujeros en los ladrillos de mamposter\u00eda. Rodeados por un sencillo invernadero, los ladrillos forman \u201csaunas\u201d para ranas que est\u00e1n demostrando ser un c\u00e1lido refugio, protegiendo a estos anfibios en peligro de extinci\u00f3n de una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463202,"url":"https:\/\/noticiasya.com\/phoenix\/2025\/06\/04\/investigadores-chinos-contrabandear-patogenos-biologicos-michigan-trax\/","url_meta":{"origin":1446467,"position":2},"title":"Acusan a investigadores chinos de contrabandear pat\u00f3genos biol\u00f3gicos para estudios en laboratorio de Universidad de Michigan","author":"","date":"junio 4, 2025","format":false,"excerpt":"Dos investigadores chinos fueron acusados de contrabandear un pat\u00f3geno biol\u00f3gico que planeaban estudiar en un laboratorio de la Universidad de Michigan el verano pasado, seg\u00fan una denuncia presentada el martes.Yunqing Jian, de 33 a\u00f1os, y Zunyong Liu, de 34, fueron acusados de conspiraci\u00f3n para cometer un delito o defraudar a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470905,"url":"https:\/\/noticiasya.com\/phoenix\/2026\/02\/05\/analisis-fosil-prototaxites-vida-desconocida-trax\/","url_meta":{"origin":1446467,"position":3},"title":"Un an\u00e1lisis sugiere que un f\u00f3sil de hace millones de a\u00f1os pudo ser una forma de vida desconocida","author":"","date":"febrero 5, 2026","format":false,"excerpt":"Hace unos 400 millones de a\u00f1os, mucho antes de que evolucionaran los dinosaurios o incluso los \u00e1rboles, un enigm\u00e1tico organismo se alzaba sobre el paisaje como un monolito prehist\u00f3rico.Ahora, una nueva investigaci\u00f3n plantea que esta antigua forma de vida no es una planta, un animal ni un hongo, sino que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463922,"url":"https:\/\/noticiasya.com\/phoenix\/2025\/06\/24\/fosil-ambar-hongo-the-last-of-us-dinosaurios-trax\/","url_meta":{"origin":1446467,"position":4},"title":"F\u00f3sil de \u00e1mbar revela que un hongo similar al de &#171;The Last of Us&#187; probablemente convivi\u00f3 con los dinosaurios","author":"","date":"junio 24, 2025","format":false,"excerpt":"Una gota de \u00e1mbar de 99 millones de a\u00f1os ha conservado una antigua mosca de manera impactante: con el cuerpo fruct\u00edfero, similar a un champi\u00f1\u00f3n, de un hongo \u201czombi\u201d brotando de su cabeza.El insecto, junto con un segundo ejemplar de una hormiga joven infectada con un hongo similar, son dos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462765,"url":"https:\/\/noticiasya.com\/phoenix\/2025\/05\/24\/hongo-comerte-adentro-propagarse-clima-trax\/","url_meta":{"origin":1446467,"position":5},"title":"Un hongo que puede &#171;comerte desde adentro&#187; podr\u00eda propagarse a medida que el mundo se calienta","author":"","date":"mayo 24, 2025","format":false,"excerpt":"Hongos causantes de infecciones, que son responsables de millones de muertes al a\u00f1o, se extender\u00e1n significativamente a nuevas regiones a medida que el planeta se caliente, seg\u00fan prev\u00e9 una nueva investigaci\u00f3n, y el mundo no est\u00e1 preparado.Los hongos est\u00e1n en todas partes. Son un vasto reino de organismos, desde el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts\/1446467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/comments?post=1446467"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts\/1446467\/revisions"}],"predecessor-version":[{"id":1446659,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts\/1446467\/revisions\/1446659"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/media?parent=1446467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/categories?post=1446467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/tags?post=1446467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}