{"id":1452231,"date":"2024-08-28T08:03:56","date_gmt":"2024-08-28T15:03:56","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/"},"modified":"2024-08-28T08:03:56","modified_gmt":"2024-08-28T15:03:56","slug":"muertos-inundaciones-nigeria-sudan-africa-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/phoenix\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/","title":{"rendered":"Cientos de personas muertas por inundaciones en Nigeria y Sud\u00e1n"},"content":{"rendered":"<p>(CNN) &#8212; Al menos 170 personas han muerto y m\u00e1s de 200.000 han sido desplazadas tras semanas de inundaciones en el pa\u00eds m\u00e1s poblado de \u00c1frica, dijo a CNN el martes un portavoz de la agencia de gesti\u00f3n de desastres de Nigeria.<\/p>\n<p>El norte de Nigeria ha sido el m\u00e1s afectado por las inundaciones, seg\u00fan Manzo Ezekiel, que habla en nombre de la Autoridad Nacional de Gesti\u00f3n de Emergencias (NEMA). Sin embargo, otras partes del pa\u00eds siguen en riesgo, a\u00f1adi\u00f3, en medio de lluvias torrenciales y el aumento del nivel del agua de sus dos r\u00edos m\u00e1s grandes: el N\u00edger y el Benue.<\/p>\n<p>\u201cEl patr\u00f3n de inundaciones en Nigeria es tal que normalmente ocurre en el lado norte antes de pasar a las partes central y sur\u2026 porque el agua fluye hacia abajo\u201d, dijo Ezekiel. \u201cEn los pr\u00f3ximos d\u00edas, las partes centrales pronto ser\u00e1n testigos de inundaciones similares, e incluso hacia abajo, hacia las partes del sur\u201d.<\/p>\n<p>Aunque algunas partes de Nigeria son propensas a inundaciones durante la temporada de lluvias, Ezekiel indic\u00f3 que las inundaciones de este a\u00f1o se han reportado en \u00e1reas donde anteriormente hab\u00edan sido raras.<\/p>\n<p>\u201cLa situaci\u00f3n es tal que algunos lugares que antes no se sab\u00eda que eran propensos a inundaciones ahora sufren debido al cambio clim\u00e1tico\u201d, dijo a CNN.<\/p>\n<p>Los ambientalistas culpan en parte de las inundaciones anuales del pa\u00eds a la mala infraestructura de drenaje.<\/p>\n<p>M\u00e1s de 600 personas murieron en inundaciones en todo el pa\u00eds en 2022, las peores registradas en la naci\u00f3n de \u00c1frica occidental en m\u00e1s de una d\u00e9cada.<\/p>\n<p>Las autoridades atribuyeron esas inundaciones a unas precipitaciones superiores a la media y al desbordamiento de la presa de Lagdo en Camer\u00fan.<\/p>\n<p>La semana pasada, la Agencia de Servicios Hidrol\u00f3gicos de Nigeria (NIHSA) advirti\u00f3 que se esperaba que las aguas de las inundaciones de los vecinos N\u00edger y Mal\u00ed \u201cse trasladaran gradualmente a Nigeria\u201d, al tiempo que inst\u00f3 a los estados ubicados a lo largo del r\u00edo N\u00edger a estar en alerta.<\/p>\n<p>La agencia meteorol\u00f3gica del pa\u00eds, NIMET, tambi\u00e9n advirti\u00f3 sobre el riesgo de inundaciones repentinas en todo el pa\u00eds.<\/p>\n<p>Las recientes inundaciones han herido a casi 2.000 personas y destruido m\u00e1s de 100.000 hect\u00e1reas de tierras de cultivo, seg\u00fan los datos m\u00e1s recientes de la agencia de gesti\u00f3n de desastres compartidos con CNN.<\/p>\n<p>Camiones da\u00f1ados enterrados en el barro tras el colapso de la presa de Arbaat, a 40 km al norte de Puerto Sud\u00e1n, tras las fuertes lluvias e inundaciones torrenciales del 25 de agosto de 2024. AFP\/Getty Images<\/p>\n<p>Sud\u00e1n sufre el impacto de las inundaciones y la guerra civil<\/p>\n<p>El n\u00famero de muertos por las inundaciones en Sud\u00e1n aument\u00f3 a 132, inform\u00f3 el martes la agencia de noticias estatal SUNA, citando a un comit\u00e9 gubernamental; la m\u00e1s reciente tragedia para la naci\u00f3n del noreste de \u00c1frica ya asolada por la guerra civil.<\/p>\n<p>Las inundaciones repentinas causadas por las fuertes lluvias y el colapso de una presa arrasaron aldeas y destruy\u00f3 m\u00e1s de 12.000 casas en 10 de las provincias del pa\u00eds, con m\u00e1s de 30.000 familias afectadas, dijo el comit\u00e9.<\/p>\n<p>Muchas de las v\u00edctimas se registraron en el estado del mar Rojo, en el noroeste de Sud\u00e1n, donde al menos 30 personas murieron despu\u00e9s del colapso de la presa de Arba&#8217;at en Puerto Sud\u00e1n el domingo, dijo el lunes la agencia de ayuda de emergencia de las Naciones Unidas.<\/p>\n<p>Seg\u00fan la Oficina de las Naciones Unidas para la Coordinaci\u00f3n de Asuntos Humanitarios (OCHA), el n\u00famero de muertos podr\u00eda aumentar significativamente, ya que muchas personas siguen desaparecidas y desplazadas por las inundaciones. Agreg\u00f3 que algunos residentes se vieron obligados a escapar a las monta\u00f1as en busca de seguridad, mientras que otros fueron evacuados.<\/p>\n<p>La OCHA se\u00f1al\u00f3 que la interrupci\u00f3n de la red de telecomunicaciones debido a los da\u00f1os &#171;ha dificultado la recopilaci\u00f3n de informaci\u00f3n m\u00e1s precisa sobre la situaci\u00f3n&#187;. Agreg\u00f3 en una declaraci\u00f3n a CNN el martes que el da\u00f1o a la presa, que suministra la &#171;fuente principal de agua dulce para Port Sudan&#187;, la quinta ciudad m\u00e1s grande del pa\u00eds, &#171;afectar\u00eda los suministros de agua&#187; y empeorar\u00eda la situaci\u00f3n humanitaria en el estado del mar Rojo.<\/p>\n<p>Al menos 30 muertos tras el colapso de una presa en Sud\u00e1n, seg\u00fan agencia de la ONU<\/p>\n<p>Las \u00faltimas inundaciones exacerban los efectos devastadores de las inundaciones que han destrozado partes del pa\u00eds desde junio, dejando a m\u00e1s de 100.000 personas desplazadas, seg\u00fan la OCHA.<\/p>\n<p>La crisis clim\u00e1tica generada por el hombre hace que el clima extremo sea m\u00e1s frecuente y severo, dicen los cient\u00edficos. Sud\u00e1n es una de las naciones m\u00e1s vulnerables al clima del mundo, lidiando con lluvias e inundaciones mortales, as\u00ed como sequ\u00edas devastadoras.<\/p>\n<p>M\u00e1s de 10 millones de personas ya se encuentran desplazadas por una guerra civil que dura ya un a\u00f1o entre las Fuerzas Armadas Sudanesas (SAF) y las Fuerzas de Apoyo R\u00e1pido (RSF), un grupo paramilitar que ha dejado al menos 18.000 muertos.<\/p>\n<p>M\u00e1s de la mitad de la poblaci\u00f3n del pa\u00eds tambi\u00e9n se enfrenta a una hambruna aguda, seg\u00fan afirm\u00f3 la OCHA el mes pasado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Al menos 170 personas han muerto y m\u00e1s de 200.000 han sido desplazadas tras semanas de inundaciones en el pa\u00eds m\u00e1s poblado de \u00c1frica, dijo a CNN el martes un portavoz de la agencia de gesti\u00f3n de desastres de Nigeria. El norte de Nigeria ha sido el m\u00e1s afectado por las inundaciones, seg\u00fan [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1452231","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cientos de personas muertas por inundaciones en Nigeria y Sud\u00e1n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cientos de personas muertas por inundaciones en Nigeria y Sud\u00e1n - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Al menos 170 personas han muerto y m\u00e1s de 200.000 han sido desplazadas tras semanas de inundaciones en el pa\u00eds m\u00e1s poblado de \u00c1frica, dijo a CNN el martes un portavoz de la agencia de gesti\u00f3n de desastres de Nigeria. El norte de Nigeria ha sido el m\u00e1s afectado por las inundaciones, seg\u00fan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-28T15:03:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cientos de personas muertas por inundaciones en Nigeria y Sud\u00e1n\",\"datePublished\":\"2024-08-28T15:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/\"},\"wordCount\":944,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/\",\"name\":\"Cientos de personas muertas por inundaciones en Nigeria y Sud\u00e1n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-28T15:03:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cientos de personas muertas por inundaciones en Nigeria y Sud\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cientos de personas muertas por inundaciones en Nigeria y Sud\u00e1n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cientos de personas muertas por inundaciones en Nigeria y Sud\u00e1n - Noticias","og_description":"(CNN) &#8212; Al menos 170 personas han muerto y m\u00e1s de 200.000 han sido desplazadas tras semanas de inundaciones en el pa\u00eds m\u00e1s poblado de \u00c1frica, dijo a CNN el martes un portavoz de la agencia de gesti\u00f3n de desastres de Nigeria. El norte de Nigeria ha sido el m\u00e1s afectado por las inundaciones, seg\u00fan [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-28T15:03:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/"},"author":{"name":"","@id":""},"headline":"Cientos de personas muertas por inundaciones en Nigeria y Sud\u00e1n","datePublished":"2024-08-28T15:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/"},"wordCount":944,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/","name":"Cientos de personas muertas por inundaciones en Nigeria y Sud\u00e1n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-28T15:03:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cientos de personas muertas por inundaciones en Nigeria y Sud\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/phoenix\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cientos de personas muertas por inundaciones en Nigeria y Sud\u00e1n","url":"http:\/\/noticiasya.com\/phoenix\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/phoenix\/2024\/08\/28\/muertos-inundaciones-nigeria-sudan-africa-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-28T15:03:56Z","datePublished":"2024-08-28T15:03:56Z","dateModified":"2024-08-28T15:03:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cientos de personas muertas por inundaciones en Nigeria y Sud\\u00e1n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/phoenix\\\/2024\\\/08\\\/28\\\/muertos-inundaciones-nigeria-sudan-africa-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/phoenix\\\/2024\\\/08\\\/28\\\/muertos-inundaciones-nigeria-sudan-africa-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-28T15:03:56Z\",\"datePublished\":\"2024-08-28T15:03:56Z\",\"dateModified\":\"2024-08-28T15:03:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458800,"url":"https:\/\/noticiasya.com\/phoenix\/2025\/02\/16\/tormenta-este-inundaciones-trax\/","url_meta":{"origin":1452231,"position":0},"title":"Tormenta avanza en el este de EE.UU. con fuertes lluvias y amenazas de tornado, y obliga a realizar rescates acu\u00e1ticos","author":"","date":"febrero 16, 2025","format":false,"excerpt":"Equipos de rescate acu\u00e1tico nocturno fueron desplegados en \u00e1reas afectadas por las fuertes lluvias de una poderosa tormenta que avanza por el este de Estados Unidos a primera hora del domingo, con la posibilidad de inundaciones potencialmente mortales y tornados peligrosos.Im\u00e1genes de video capturadas en varios estados muestran \u00e1rboles derribados,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448712,"url":"https:\/\/noticiasya.com\/phoenix\/2024\/04\/30\/decenas-desaparecidos-fuertes-inundaciones-kenia-trax\/","url_meta":{"origin":1452231,"position":1},"title":"Decenas de desaparecidos por fuertes inundaciones en Kenya","author":"","date":"abril 30, 2024","format":false,"excerpt":"(CNN) -- Al menos 91 personas est\u00e1n desaparecidas tras las fuertes inundaciones en Nairobi, capital de Kenya, inform\u00f3 el gobierno este martes despu\u00e9s de semanas de fuertes lluvias que asolaron partes del pa\u00eds.Unas 76 personas est\u00e1n desaparecidas tras las inundaciones cerca de la localidad de Mai Mahiu, al noroeste de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448906,"url":"https:\/\/noticiasya.com\/phoenix\/2024\/05\/05\/kenianos-sin-hogar-buscan-seres-queridos-arrastrados-por-las-inundaciones-trax\/","url_meta":{"origin":1452231,"position":2},"title":"Kenianos que se quedaron sin hogar buscan a sus seres queridos arrastrados por las inundaciones","author":"","date":"mayo 5, 2024","format":false,"excerpt":"(CNN) -- Julia Wanjiku acost\u00f3 a su hijo Isaac el pasado domingo tras un d\u00eda celebrando su tercer cumplea\u00f1os. En la madrugada del lunes, Wanjiku se despert\u00f3 tras o\u00edr los gritos de sus vecinos. Un feroz r\u00edo de agua fangosa atraves\u00f3 un t\u00fanel bloqueado y se adentr\u00f3 en la localidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465027,"url":"https:\/\/noticiasya.com\/phoenix\/2025\/08\/01\/lluvias-washington-nueva-york-inundaciones-vuelos-trax\/","url_meta":{"origin":1452231,"position":3},"title":"Lluvias torrenciales afectan a Washington y Nueva York mientras inundaciones colapsan carreteras y afectan vuelos","author":"","date":"agosto 1, 2025","format":false,"excerpt":"Lluvias torrenciales e inundaciones repentinas azotaron el jueves la zona del Atl\u00e1ntico medio y el noreste, causando estragos a lo largo del corredor de la Interestatal 95 y provocando la muerte de un ni\u00f1o en Maryland. Se trata de otra grave inundaci\u00f3n en un verano que ha estado plagado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458823,"url":"https:\/\/noticiasya.com\/phoenix\/2025\/02\/17\/tormenta-nieve-vientos-inundaciones-kentucky-trax\/","url_meta":{"origin":1452231,"position":4},"title":"Persiste la amenaza de inundaciones en Kentucky, mientras el aire fr\u00edo potencialmente mortal se desplaza al centro de EE.UU.","author":"","date":"febrero 17, 2025","format":false,"excerpt":"Una tormenta invernal mortal de costa a costa, que barri\u00f3 Estados Unidos este fin de semana, sigue amenazando partes del sur, medio oeste y noreste con m\u00e1s inundaciones, mientras el aire fr\u00edo que pone en peligro la vida se mueve hacia el centro de Estados Unidos.El sistema meteorol\u00f3gico del fin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451282,"url":"https:\/\/noticiasya.com\/phoenix\/2024\/07\/20\/derrumbe-puente-china-12-muertos-desaparecidos-trax\/","url_meta":{"origin":1452231,"position":5},"title":"Se derrumba un puente en China: hay 12 muertos y m\u00e1s de 30 desaparecidos","author":"","date":"julio 20, 2024","format":false,"excerpt":"(CNN) -- Al menos 12 personas murieron y otras 31 est\u00e1n desaparecidas tras derrumbarse parcialmente un puente en la provincia de Shanxi, en el norte del pa\u00eds, seg\u00fan la cadena estatal CCTV.Las autoridades dijeron que una parte del puente del condado de Zhashui, en la ciudad de Shangluo, se derrumb\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/phoenix\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts\/1452231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/comments?post=1452231"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/posts\/1452231\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/media?parent=1452231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/categories?post=1452231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/phoenix\/wp-json\/wp\/v2\/tags?post=1452231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}