{"id":1436468,"date":"2023-01-10T14:40:52","date_gmt":"2023-01-10T22:40:52","guid":{"rendered":"https:\/\/noticiasya.com\/?p=1436468"},"modified":"2023-01-10T14:40:52","modified_gmt":"2023-01-10T22:40:52","slug":"cinco-momentos-clave-para-entender-el-caso-trevi-andrade","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/","title":{"rendered":"Cinco momentos clave para entender el caso Trevi-Andrade"},"content":{"rendered":"<p>Hace casi 20 a\u00f1os se escribi\u00f3 la historia de horror en la que se vieron implicados la cantante Gloria Trevi y el productor Sergio Andrade, al ser se\u00f1alados por haber cometido delitos de corrupci\u00f3n de menores y por los que fueron detenidos en Brasil para despu\u00e9s ser encarcelados.<\/p>\n<p>El esc\u00e1ndalo que se tra\u00edan estos dos conmocion\u00f3 al pa\u00eds, pues se trataba de una de las estrellas m\u00e1s populares de la m\u00fasica en M\u00e9xico, adem\u00e1s de que las acusaciones en su contra no eran algo para tomarse a la ligera.<\/p>\n<p>Y eso no es todo, recientemente salieron a la luz dos nuevas acusaciones en las que la cantante est\u00e1 implicada, pues se trata de dos v\u00edctimas que hasta el d\u00eda de hoy decidieron hablar al respecto y se\u00f1alar los actos despiadados que hicieron en su contra.<\/p>\n<p>Con todo esto y para entender un poco de qu\u00e9 se trat\u00f3 este famoso caso, vamos a enlistar cinco momentos clave que ocurrieron en aquel entonces y por los cuales fueron procesados ambas personalidades, as\u00ed como Mary Boquitas, quien tambi\u00e9n estuvo envuelta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1327374 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/01\/GettyImages-51972455.jpg?w=1024\" alt=\"\" width=\"1024\" height=\"661\" \/><\/p>\n<p><strong>El inicio del Clan Trevi-Andrade<\/strong><\/p>\n<p>A mitades de los a\u00f1os 80, Gloria Trevi comenzaba a hacer carrera y estaba siendo reconocida por su talento y carisma para componer m\u00fasica. Un hecho que adem\u00e1s de llamar la atenci\u00f3n del p\u00fablico, tambi\u00e9n llam\u00f3 la del productor y manejador de talentos, Sergio Andrade, quien era famoso por haber impulsado la carrera de artistas como Lucero o Yuri.<\/p>\n<p>Cuando solo ten\u00eda 15, Gloria ya era parte de los diferentes proyectos musicales que manejaba Andrade, por lo que naturalmente el siguiente paso era convertirse en su representante. A su equipo se sum\u00f3 Mary Boquitas, primero como corista y luego como cantante.<\/p>\n<p>Despu\u00e9s de trabajar un par de meses juntos, Trevi lanz\u00f3 su primer disco titulado Qu\u00e9 Hago Aqu\u00ed (1989), y su carrera fue impulsada con todo el m\u00fasculo que el productor pose\u00eda para crecer talento.<\/p>\n<p>En ese entonces, nadie se imaginaba lo que estaba pasando detr\u00e1s de c\u00e1maras.<\/p>\n<p><strong>Primera denuncia en contra de Sergio Andrade<\/strong><\/p>\n<p>Fue hasta el a\u00f1o 1997 que la primera demanda en contra de Andrade lleg\u00f3. Se trataba de una acusaci\u00f3n p\u00fablica que Aline Hern\u00e1ndez, su exesposa, revel\u00f3 e hizo que todo el caso explotara.<\/p>\n<p>Durante ese mismo a\u00f1o Aline public\u00f3 el libro autobiogr\u00e1fico &#171;La Gloria por el Infierno&#187;, en el cual narraba todo lo que hab\u00eda vivido al lado de productor hasta ese entonces.<\/p>\n<p>Mar\u00eda Raquenel, quien se cas\u00f3 con Andrade cuando solo ten\u00eda 15 a\u00f1os de edad, tambi\u00e9n lo denunci\u00f3 cuando las acusaciones comenzaron a surgir. Ella declar\u00f3 los abusos que sufri\u00f3 en la relaci\u00f3n y hasta hace solo un a\u00f1o, dijo estar lista para contar lo que vivi\u00f3 y ser\u00e1 a trav\u00e9s de un libro.<\/p>\n<p>Los padres de Karina Yapor acudieron al ministerio p\u00fablico pues sospechaban lo que estaba pasando con su hija y el clan en el que la hab\u00edan envuelto, por lo que esto fue el primer paso para dar con la captura de estos dos personajes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1327373 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/01\/GettyImages-2767551.jpg?w=1024\" alt=\"\" width=\"1024\" height=\"625\" \/><\/p>\n<p><strong>Acusan a Gloria Trevi<\/strong><\/p>\n<p>A inicios del a\u00f1o 2000, Trevi y Andrade fueron detenidos al aterrizar en Brasil, y despu\u00e9s de acumular distintas acusaciones en su contra, Andrade recibi\u00f3 una pena de siete a\u00f1os y 10 meses de c\u00e1rcel, por los delitos de secuestro, violaci\u00f3n agravada y corrupci\u00f3n de menores.<\/p>\n<p>Por su parte, Trevi recibi\u00f3 una sentencia de cuatro a\u00f1os y ocho meses de prisi\u00f3n junto a Raquenel Portillo quien fuera su &#171;c\u00f3mplice&#187; en dichos cr\u00edmenes.<\/p>\n<p>Durante todo lo que les estaba pasando, Trevi y Andrade se convirtieron en padres de Ana Dalay, su primera hija quien muri\u00f3 a solo unos d\u00edas de haber nacido y cuya causa de muerte se encuentra a\u00fan en inc\u00f3gnito.<\/p>\n<p>Mientras estaba en prisi\u00f3n, Trevi fue madre por segunda ocasi\u00f3n, esta vez de \u00c1ngel Gabriel, quien algunos han dicho que es hijo de Sergio Andrade y otros, que se trata del producto de una violaci\u00f3n que Gloria sufri\u00f3 dentro de la c\u00e1rcel.<\/p>\n<p><strong>Trevi sale de la c\u00e1rcel y retoma su carrera<\/strong><\/p>\n<p>Fue en septiembre del 2004 que la int\u00e9rprete de &#8216;Pelo Suelto&#8217; fue absuelta, por el juez que manejaba su caso en Chihuahua, y exonerada de los cargos de rapto y corrupci\u00f3n de menores en contra de Karina Alejandra Yapor.<\/p>\n<p>Luego de esto y de haber pagado su condena, la cantante le dio vuelta a la p\u00e1gina y sigui\u00f3 con su carrera, la cual despeg\u00f3 r\u00e1pidamente gracias a su disco La Trayectoria (2006), el cual recaba algunos de sus \u00e9xitos m\u00e1s importantes y un nuevo y controversial sencillo titulado &#8216;Todos Me Miran&#8217;.<\/p>\n<p>De a poco, la cantante consigui\u00f3 dejar en el pasado los a\u00f1os de abuso y cr\u00edmenes, conectando con sus fans con su m\u00fasica y dando una imagen positiva e inclusi\u00f3n al mundo.<\/p>\n<p>Gloria era una nueva persona y eso se notaba en su forma de afrontar el mundo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1327372 size-full\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/01\/GettyImages-52008115.jpg\" alt=\"Mexican Singer Gloria Trevi (c) And Her Son Angel\" width=\"1024\" height=\"672\" \/><\/p>\n<p><strong>Nuevas acusaciones en su contra<\/strong><\/p>\n<p>Se sabe poco de la vida actual de Sergio Andrade. Algunos dicen que para sobrevivir, tuvo que vender las propiedades que le quedaban a su nombre y que las regal\u00edas le siguen dando un porcentaje de capital mensual. Otros dicen que se retir\u00f3 de la vida p\u00fablica para terminar viviendo en Morelos, Cuernavaca, la Ciudad de la Eterna Primavera en M\u00e9xico.<\/p>\n<p>Lo que s\u00ed sabemos, es que actualmente tiene 67 a\u00f1os de edad y que termin\u00f3 su condena de casi ocho a\u00f1os recluido en uno de los penales m\u00e1s serios de M\u00e9xico, lo que no podemos creer, es el tiempo de condena que le dieron.<\/p>\n<p>De cualquier forma, seg\u00fan Rolling Stone, la cantante Gloria Trevi est\u00e1 siendo se\u00f1alada por dos testigos de sus cr\u00edmenes, quienes vivieron el abuso de aquellos a\u00f1os y que fueron afectadas a tal grado, que hasta el d\u00eda de hoy tienen el coraje de salir a hablar y denunciar a sus atacantes.<\/p>\n<p>Seg\u00fan la revista, Trevi enfrentar\u00e1 una acusaci\u00f3n en los pr\u00f3ximos meses y que se trata de una corte de la ciudad de Los \u00c1ngeles, la encargada de poner los puntos sobre las \u00edes.<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CnASV4EpW3e\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:500px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CnASV4EpW3e\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <\/p>\n<div style=\" display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p><\/a><\/p>\n<p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CnASV4EpW3e\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by El Bot\u00f3n (@elbotonradio)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><\/p>\n<p>Aunque no hay declaraciones oficiales de ninguna de las dos partes, este es un caso que ha levantado el inter\u00e9s de miles de curiosos a lo largo de los a\u00f1os, y del que cada vez se tienen m\u00e1s detalles que lo vuelven dif\u00edcil de ignorar.<\/p>\n<p>\u00bfQu\u00e9 pasar\u00e1 en los siguientes d\u00edas? Deja tu teor\u00eda en los comentarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace casi 20 a\u00f1os se escribi\u00f3 la historia de horror en la que se vieron implicados la cantante Gloria Trevi y el productor Sergio Andrade, al ser se\u00f1alados por haber cometido delitos de corrupci\u00f3n de menores y por los que fueron detenidos en Brasil para despu\u00e9s ser encarcelados. El esc\u00e1ndalo que se tra\u00edan estos dos [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1436470,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[51],"tags":[70,71,72,73,74,75],"class_list":["post-1436468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-gloria-trevi","tag-karina-yapor","tag-maria-requenel","tag-mary-boquitas","tag-sergio-andrade","tag-trevi-andrade","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cinco momentos clave para entender el caso Trevi-Andrade - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinco momentos clave para entender el caso Trevi-Andrade - Noticias\" \/>\n<meta property=\"og:description\" content=\"Hace casi 20 a\u00f1os se escribi\u00f3 la historia de horror en la que se vieron implicados la cantante Gloria Trevi y el productor Sergio Andrade, al ser se\u00f1alados por haber cometido delitos de corrupci\u00f3n de menores y por los que fueron detenidos en Brasil para despu\u00e9s ser encarcelados. El esc\u00e1ndalo que se tra\u00edan estos dos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-10T22:40:52+00:00\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Cinco momentos clave para entender el caso Trevi-Andrade\",\"datePublished\":\"2023-01-10T22:40:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/\"},\"wordCount\":1149,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Gloria Trevi\",\"Karina Yapor\",\"Mar\u00eda Requenel\",\"Mary Boquitas\",\"Sergio Andrade\",\"Trevi-andrade\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/\",\"url\":\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/\",\"name\":\"Cinco momentos clave para entender el caso Trevi-Andrade - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-01-10T22:40:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cinco momentos clave para entender el caso Trevi-Andrade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/noticiasya.com\/reno\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinco momentos clave para entender el caso Trevi-Andrade - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/","og_locale":"es_ES","og_type":"article","og_title":"Cinco momentos clave para entender el caso Trevi-Andrade - Noticias","og_description":"Hace casi 20 a\u00f1os se escribi\u00f3 la historia de horror en la que se vieron implicados la cantante Gloria Trevi y el productor Sergio Andrade, al ser se\u00f1alados por haber cometido delitos de corrupci\u00f3n de menores y por los que fueron detenidos en Brasil para despu\u00e9s ser encarcelados. El esc\u00e1ndalo que se tra\u00edan estos dos [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/","og_site_name":"Noticias","article_published_time":"2023-01-10T22:40:52+00:00","author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Cinco momentos clave para entender el caso Trevi-Andrade","datePublished":"2023-01-10T22:40:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/"},"wordCount":1149,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"image":{"@id":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#primaryimage"},"thumbnailUrl":"","keywords":["Gloria Trevi","Karina Yapor","Mar\u00eda Requenel","Mary Boquitas","Sergio Andrade","Trevi-andrade"],"articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/","url":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/","name":"Cinco momentos clave para entender el caso Trevi-Andrade - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#primaryimage"},"image":{"@id":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-01-10T22:40:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-valle\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cinco momentos clave para entender el caso Trevi-Andrade"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/noticiasya.com\/reno\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cinco momentos clave para entender el caso Trevi-Andrade","url":"http:\/\/noticiasya.com\/reno\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2023\/01\/10\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":["gloria trevi","karina yapor","mar\u00eda requenel","mary boquitas","sergio andrade","trevi-andrade"],"dateCreated":"2023-01-10T22:40:52Z","datePublished":"2023-01-10T22:40:52Z","dateModified":"2023-01-10T22:40:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cinco momentos clave para entender el caso Trevi-Andrade\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/01\\\/10\\\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/01\\\/10\\\/cinco-momentos-clave-para-entender-el-caso-trevi-andrade\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[\"gloria trevi\",\"karina yapor\",\"mar\\u00eda requenel\",\"mary boquitas\",\"sergio andrade\",\"trevi-andrade\"],\"dateCreated\":\"2023-01-10T22:40:52Z\",\"datePublished\":\"2023-01-10T22:40:52Z\",\"dateModified\":\"2023-01-10T22:40:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442887,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/30\/gloria-trevi-demanda-a-su-exmanager-y-productor-sergio-andrade-por-abuso-sexual-y-fisico\/","url_meta":{"origin":1436468,"position":0},"title":"Gloria Trevi demanda a su exm\u00e1nager y productor Sergio Andrade por abuso sexual y f\u00edsico","author":"Eduardo Salinas","date":"diciembre 30, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La cantante mexicana Gloria de los Angeles Trevi\u00f1o, mejor conocida como Gloria Trevi, demand\u00f3 por supuesto abuso sexual y f\u00edsico a Sergio Andrade, quien fue su m\u00e1nager y productor durante las d\u00e9cadas de los a\u00f1os 80 y 90. La int\u00e9rprete de \u201cPelo suelto\u201d dice que tras ser\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1439054,"url":"https:\/\/noticiasya.com\/reno\/2023\/05\/18\/gloria-trevi-exploto-en-show-porque-la-siguen-relacionando-con-sergio-andrade\/","url_meta":{"origin":1436468,"position":1},"title":"Gloria Trevi explot\u00f3 en show porque la siguen relacionando con Sergio Andrade","author":"Eduardo Salinas","date":"mayo 18, 2023","format":false,"excerpt":"Aunque no lo quiera, Gloria Trevi siempre ha sido relacionada al productor Sergio Andrade por todo aquello que pas\u00f3 hace muchos a\u00f1os y que la involucra directamente en uno de los esc\u00e1ndalos m\u00e1s grandes del mundo del entretenimiento. Por m\u00e1s que la cantante ha intentado zafarse del caso, tal parece\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/reno\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471742,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/27\/gloria-trevi-fiesta-latina-bmo-stadium-orix\/","url_meta":{"origin":1436468,"position":2},"title":"Gloria Trevi convierte su cumplea\u00f1os en una fiesta latina en el BMO Stadium de Los \u00c1ngeles","author":"Eduardo Salinas","date":"febrero 27, 2026","format":false,"excerpt":"Gloria Trevi pisar\u00e1 el escenario del BMO Stadium con la misma fuerza que la convirti\u00f3 en un \u00edcono de los 90. La cantante mexicana celebrar\u00e1 all\u00ed su cumplea\u00f1os el s\u00e1bado 28 de febrero de 2026, en la que ser\u00e1 su \u00fanica presentaci\u00f3n en Estados Unidos este a\u00f1o.\u201cHe pasado mi vida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470781,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/02\/fontana-di-trevi-dos-euros-lanzar-monedas-roma-trax\/","url_meta":{"origin":1436468,"position":3},"title":"Lanzar monedas a la Fontana di Trevi ahora cuesta 2 euros\u2026 y los turistas siguen ignorando las reglas","author":"","date":"febrero 2, 2026","format":false,"excerpt":"La leyenda dice que lanzar una moneda a la Fontana de Trevi en Roma garantiza un regreso a la \u201cCiudad Eterna\u201d. Dos monedas prometen encontrar el amor con alguien de Italia. Tres, casarse con un alguien que haya nacido en Italia.Sin embargo, a partir del 2 de febrero, hacer cualquiera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464031,"url":"https:\/\/noticiasya.com\/reno\/2025\/06\/28\/tiro-monedas-fontana-di-trevi-se-enamoro-trax\/","url_meta":{"origin":1436468,"position":4},"title":"Tir\u00f3 tres monedas a la Fontana di Trevi y se enamor\u00f3","author":"","date":"junio 28, 2025","format":false,"excerpt":"Catherine Tondelli estaba de pie bajo la Fontana di Trevi, en una tarde de verano en Roma, a punto de arrojar tres monedas a las aguas de la fuente.Al crecer en Estados Unidos, Catherine hab\u00eda visto pel\u00edculas rom\u00e1nticas ambientadas en Italia. Hab\u00eda le\u00eddo libros sobre Roma. Hab\u00eda o\u00eddo que la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451608,"url":"https:\/\/noticiasya.com\/reno\/2024\/08\/05\/rebeca-andrade-gimnasta-brasilena-derroto-simone-biles-trax\/","url_meta":{"origin":1436468,"position":5},"title":"Qui\u00e9n es Rebeca Andrade, la gimnasta brasile\u00f1a que derrot\u00f3 a Simone Biles","author":"","date":"agosto 5, 2024","format":false,"excerpt":"(CNN) -- Simone Biles, once veces medallista ol\u00edmpica, es dif\u00edcil de batir, pero no imposible.La gimnasta brasile\u00f1a Rebeca Andrade lo demostr\u00f3 al superar a su rival estadounidense en la final de suelo de los Juegos Ol\u00edmpicos de Par\u00eds. Biles se llev\u00f3 la medalla de plata.Fue un momento de catarsis para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1436468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1436468"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1436468\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1436468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1436468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1436468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}