{"id":1442428,"date":"2023-12-21T14:33:38","date_gmt":"2023-12-21T22:33:38","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442428"},"modified":"2023-12-21T14:33:38","modified_gmt":"2023-12-21T22:33:38","slug":"el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/","title":{"rendered":"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago"},"content":{"rendered":"<p>(CNN) &#8212; El gobernador de Texas, Greg Abbott, est\u00e1 subiendo la apuesta en sus esfuerzos por transportar inmigrantes a ciudades santuario, llev\u00e1ndolos en avi\u00f3n a Chicago, dijo a CNN el secretario de prensa del gobernador, Andrew Mahaleris.<\/p>\n<p>&#171;Hasta que el presidente Biden d\u00e9 un paso al frente y haga su trabajo para asegurar la frontera, Texas seguir\u00e1 tomando medidas hist\u00f3ricas para ayudar a nuestros socios locales a responder a esta crisis provocada por Biden&#187;, dijo Mahaleris.<\/p>\n<p>El primer vuelo parti\u00f3 de El Paso a Chicago con 120 pasajeros este martes, public\u00f3 Mahaleris en X. La publicaci\u00f3n incluye un video del primer vuelo que muestra a familias migrantes, incluidos ni\u00f1os, abordando el vuelo y el avi\u00f3n despegando.<\/p>\n<p>La nueva ley de inmigraci\u00f3n de Texas siembra confusi\u00f3n e incertidumbre a lo largo de la frontera<\/p>\n<p>Una fuente familiarizada con las operaciones en tierra le dijo a CNN que los migrantes firmaron una renuncia de consentimiento voluntaria que estuvo disponible en varios idiomas al abordar. CNN no tuvo la oportunidad de hablar con los migrantes para confirmar este detalle.<\/p>\n<p>La oficina del gobernador no respondi\u00f3 de inmediato a las preguntas sobre el costo del vuelo.<\/p>\n<p>La semana pasada, la ciudad de Chicago, que informa que ha recibido m\u00e1s de 25.000 inmigrantes de Texas en los \u00faltimos 16 meses, confisc\u00f3 su primer autob\u00fas que dejaba inmigrantes tras la aprobaci\u00f3n de una nueva ordenanza municipal que imped\u00eda a los autobuses dejar a personas en la ciudad sin un permiso.<\/p>\n<p>Abbott ha transportado en autob\u00fas a m\u00e1s de 80.000 inmigrantes a ciudades santuario en todo Estados Unidos desde abril de 2022, seg\u00fan la \u00faltima publicaci\u00f3n X del gobernador.<\/p>\n<p>Detalles del vuelo<\/p>\n<p>El vuelo de migrantes que lleg\u00f3 a Chicago desde El Paso, Texas, aterriz\u00f3 en el Aeropuerto Internacional O\u2019Hare aproximadamente a las 7:15 pm CT del martes por la noche, seg\u00fan un comunicado de la Oficina de Comunicaciones y Manejo de Emergencias de Chicago (OEMC).<\/p>\n<p>\u201cLa polic\u00eda del aeropuerto O\u2019Hare recibi\u00f3 una llamada indicando que un avi\u00f3n privado fletado por el Departamento de Manejo de Emergencias de Texas aterriz\u00f3 y dej\u00f3 aproximadamente a 100 solicitantes de asilo en Signature Flight. Seg\u00fan los informes, dos individuos no identificados que volaban con el avi\u00f3n salieron de Signature Flight y abandonaron la escena en un Uber antes de la llegada de la polic\u00eda\u201d, dijo la OEMC en el comunicado.<\/p>\n<p>AMLO critica al gobernador de Texas por controvertida ley de inmigraci\u00f3n<\/p>\n<p>Seg\u00fan la OEMC, la ciudad est\u00e1 trabajando actualmente para encontrar espacio en el sistema de refugios para todos los solicitantes de asilo que actualmente se encuentran en el aeropuerto O&#8217;Hare.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El gobernador de Texas, Greg Abbott, est\u00e1 subiendo la apuesta en sus esfuerzos por transportar inmigrantes a ciudades santuario, llev\u00e1ndolos en avi\u00f3n a Chicago, dijo a CNN el secretario de prensa del gobernador, Andrew Mahaleris. &#171;Hasta que el presidente Biden d\u00e9 un paso al frente y haga su trabajo para asegurar la frontera, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442428","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El gobernador de Texas, Greg Abbott, est\u00e1 subiendo la apuesta en sus esfuerzos por transportar inmigrantes a ciudades santuario, llev\u00e1ndolos en avi\u00f3n a Chicago, dijo a CNN el secretario de prensa del gobernador, Andrew Mahaleris. &#171;Hasta que el presidente Biden d\u00e9 un paso al frente y haga su trabajo para asegurar la frontera, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-21T22:33:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago\",\"datePublished\":\"2023-12-21T22:33:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/\"},\"wordCount\":477,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/\",\"name\":\"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-21T22:33:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/","og_locale":"es_ES","og_type":"article","og_title":"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago - Noticias","og_description":"(CNN) &#8212; El gobernador de Texas, Greg Abbott, est\u00e1 subiendo la apuesta en sus esfuerzos por transportar inmigrantes a ciudades santuario, llev\u00e1ndolos en avi\u00f3n a Chicago, dijo a CNN el secretario de prensa del gobernador, Andrew Mahaleris. &#171;Hasta que el presidente Biden d\u00e9 un paso al frente y haga su trabajo para asegurar la frontera, [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/","og_site_name":"Noticias","article_published_time":"2023-12-21T22:33:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/"},"author":{"name":"","@id":""},"headline":"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago","datePublished":"2023-12-21T22:33:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/"},"wordCount":477,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/","url":"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/","name":"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-21T22:33:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago","url":"http:\/\/noticiasya.com\/reno\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-21T22:33:38Z","datePublished":"2023-12-21T22:33:38Z","dateModified":"2023-12-21T22:33:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/21\\\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/21\\\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-21T22:33:38Z\",\"datePublished\":\"2023-12-21T22:33:38Z\",\"dateModified\":\"2023-12-21T22:33:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1443826,"url":"https:\/\/noticiasya.com\/reno\/2024\/01\/16\/chicago-se-esfuerza-por-albergar-a-migrantes-en-un-frio-extremo-mientras-el-gobernador-de-texas-se-niega-a-detener-los-envios-de-personas\/","url_meta":{"origin":1442428,"position":0},"title":"Chicago se esfuerza por albergar a migrantes en un fr\u00edo extremo mientras el gobernador de Texas se niega a detener los env\u00edos de personas","author":"","date":"enero 16, 2024","format":false,"excerpt":"(CNN) -- Con la esperanza de detener la llegada de migrantes mientras el tiempo invernal azota a Chicago, el gobernador dem\u00f3crata de Illinois advirti\u00f3 en una carta el viernes a su hom\u00f3logo republicano en Texas que enviar migrantes ahora a \u201cla ciudad de los vientos\u201d podr\u00eda costar vidas, lo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442443,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/21\/biden-aumenta-la-presion-sobre-lopez-obrador-mientras-el-alza-de-migrantes-en-la-frontera-aviva-un-viejo-problema-politico\/","url_meta":{"origin":1442428,"position":1},"title":"Biden aumenta la presi\u00f3n sobre L\u00f3pez Obrador mientras el alza de migrantes en la frontera aviva un viejo problema pol\u00edtico","author":"","date":"diciembre 21, 2023","format":false,"excerpt":"(CNN) --\u00a0El presidente de Estados Unidos, Joe Biden, aument\u00f3 la presi\u00f3n sobre su hom\u00f3logo de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, para atender la compleja situaci\u00f3n en la frontera que comparten los dos pa\u00edses por la cantidad sin precedentes de migrantes que han llegado. La gran oleada de personas\u00a0ha puesto en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442921,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/30\/texas-envia-solicitantes-de-asilo-a-las-principales-ciudades-en-autobus-sin-previo-aviso-estos-alcaldes-quieren-pisar-el-freno\/","url_meta":{"origin":1442428,"position":2},"title":"Texas env\u00eda solicitantes de asilo a las principales ciudades en autob\u00fas sin previo aviso. Estos alcaldes quieren pisar el freno","author":"","date":"diciembre 30, 2023","format":false,"excerpt":"(CNN) -- Frustrados por los \u201cautobuses deshonestos\u201d de Texas que dejan a miles de inmigrantes, los alcaldes de Nueva York, Chicago y Denver est\u00e1n tratando de frenar el aumento exigiendo a los operadores de autobuses que coordinen las llegadas bajo la amenaza de confiscaciones, multas e incluso penas de c\u00e1rcel.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446987,"url":"https:\/\/noticiasya.com\/reno\/2024\/03\/15\/texas-donaciones-migrantes-autobus-trax\/","url_meta":{"origin":1442428,"position":3},"title":"El gobernador de Texas predijo que las donaciones financiar\u00edan el env\u00edo de migrantes en autob\u00fas fuera del estado. Ha recaudado menos del 1% del costo","author":"","date":"marzo 15, 2024","format":false,"excerpt":"(CNN) -- El gobernador de Texas, Greg Abbott, se jact\u00f3 poco despu\u00e9s de comenzar a solicitar donaciones privadas para su controvertido programa de transporte de migrantes en autob\u00fas de que probablemente \"no habr\u00eda ning\u00fan costo para el Estado\", dada la avalancha de apoyo de ciudadanos preocupados en todo el pa\u00eds.Pero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443215,"url":"https:\/\/noticiasya.com\/reno\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas-2\/","url_meta":{"origin":1442428,"position":4},"title":"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas","author":"","date":"enero 5, 2024","format":false,"excerpt":"(CNN) -- Despu\u00e9s de intentar frenar a los \u201cautobuses rebeldes\u201d de Texas que dejan a miles de inmigrantes en la ciudad, el alcalde de Nueva York, Eric Adams, ha presentado una demanda contra una docena de empresas de autobuses ch\u00e1rter que transportaban inmigrantes.La demanda, que nombra a 17 compa\u00f1\u00edas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443210,"url":"https:\/\/noticiasya.com\/reno\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/","url_meta":{"origin":1442428,"position":5},"title":"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas","author":"","date":"enero 5, 2024","format":false,"excerpt":"(CNN) -- Despu\u00e9s de intentar frenar a los \u201cautobuses rebeldes\u201d de Texas que dejan a miles de inmigrantes en la ciudad, el alcalde de Nueva York, Eric Adams, ha presentado una demanda contra una docena de empresas de autobuses ch\u00e1rter que transportaban inmigrantes.La demanda, que nombra a 17 compa\u00f1\u00edas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1442428"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442428\/revisions"}],"predecessor-version":[{"id":1442457,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442428\/revisions\/1442457"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1442428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1442428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1442428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}