{"id":1442510,"date":"2023-12-22T21:33:36","date_gmt":"2023-12-23T05:33:36","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442510"},"modified":"2023-12-22T21:33:36","modified_gmt":"2023-12-23T05:33:36","slug":"ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/","title":{"rendered":"CEO de Wayfair dice que los empleados necesitan trabajar m\u00e1s horas"},"content":{"rendered":"<p>Nueva York (CNN)&#8211; El CEO de Wayfair tiene un mensaje de fin de a\u00f1o para los empleados de la empresa de muebles en l\u00ednea: no rehuyas a trabajar m\u00e1s horas y a mezclar tu trabajo con tu vida.<\/p>\n<p>&#171;Ganar requiere trabajo duro. Creo que la mayor\u00eda de nosotros, siendo individuos ambiciosos, encontramos la satisfacci\u00f3n en la alegr\u00eda de ver nuestros esfuerzos materializados en resultados tangibles&#187;, dijo el CEO Niraj Shah en una nota a los empleados a principios de este mes celebrando el reciente \u00e9xito de la compa\u00f1\u00eda, y que un portavoz de la empresa confirm\u00f3 a CNN. &#171;Trabajar muchas horas, ser receptivo, compaginar el trabajo y la vida, no es algo de lo que haya que huir. No hay muchos casos de pereza recompensada con \u00e9xito&#187;.<\/p>\n<p>\u00bfPoco compromiso de los empleados? As\u00ed es como las empresas pueden cambiar esto<\/p>\n<p>Shah tambi\u00e9n anim\u00f3 a los empleados de Wayfair a pensar en el dinero de la empresa que gastan como propio y a negociar los precios. En diciembre de 2022, Wayfair ten\u00eda alrededor de 15.000 empleados, seg\u00fan su presentaci\u00f3n m\u00e1s reciente.<\/p>\n<p>&#171;\u00bfGastar\u00edas dinero en eso, gastar\u00edas tanto dinero en esa cosa, ese precio te parece razonable y, por \u00faltimo, negociaste el precio?&#187;, dijo en un correo electr\u00f3nico a los empleados de Wayfair a principios de este mes. La nota fue obtenida por primera vez por Business Insider.<\/p>\n<p>El negocio de Wayfair se dispar\u00f3 a principios de la pandemia a medida que los compradores a domicilio ped\u00edan muebles, escritorios y art\u00edculos para el hogar en l\u00ednea.<\/p>\n<p>Pero la empresa tuvo problemas a partir de 2022, cuando la gente volvi\u00f3 a comprar en persona y cambi\u00f3 su gasto de bienes f\u00edsicos a experiencias.<\/p>\n<p>En 2022, Wayfair anunci\u00f3 que recortar\u00eda el 5% de su plantilla.<\/p>\n<p>Pero Shah dijo a los empleados en su correo electr\u00f3nico que la compa\u00f1\u00eda ha vuelto a ser rentable.<\/p>\n<p>&#171;Juntos podemos ganar mucho m\u00e1s r\u00e1pido de lo que estamos ganando ahora si remamos todos juntos en esta direcci\u00f3n&#187;, dijo. &#171;Seamos agresivos, pragm\u00e1ticos, frugales, \u00e1giles, orientados al cliente e inteligentes&#187;.<\/p>\n<p>Las oficinas estadounidenses est\u00e1n medio vac\u00edas. Este podr\u00eda ser el pr\u00f3ximo gran riesgo para los bancos<\/p>\n<p>Nicholas Bloom, profesor de Econom\u00eda, dijo a Richard Quest de CNN en una entrevista el jueves que &#171;si Wayfair quiere dirigir un negocio en el que la gente trabaje 80 horas a la semana, va a tener que subir sus salarios un 50% para pagarles por ello&#187;.<\/p>\n<p>&#171;No veo que esto funcione con el empleado t\u00edpico&#187;, dijo Bloom, se\u00f1alando que el mercado laboral es fuerte y los empleados tienen opciones.<\/p>\n<p>Un portavoz de la empresa no estaba disponible de inmediato para responder a las preguntas de CNN sobre la remuneraci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva York (CNN)&#8211; El CEO de Wayfair tiene un mensaje de fin de a\u00f1o para los empleados de la empresa de muebles en l\u00ednea: no rehuyas a trabajar m\u00e1s horas y a mezclar tu trabajo con tu vida. &#171;Ganar requiere trabajo duro. Creo que la mayor\u00eda de nosotros, siendo individuos ambiciosos, encontramos la satisfacci\u00f3n en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442510","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CEO de Wayfair dice que los empleados necesitan trabajar m\u00e1s horas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CEO de Wayfair dice que los empleados necesitan trabajar m\u00e1s horas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nueva York (CNN)&#8211; El CEO de Wayfair tiene un mensaje de fin de a\u00f1o para los empleados de la empresa de muebles en l\u00ednea: no rehuyas a trabajar m\u00e1s horas y a mezclar tu trabajo con tu vida. &#171;Ganar requiere trabajo duro. Creo que la mayor\u00eda de nosotros, siendo individuos ambiciosos, encontramos la satisfacci\u00f3n en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-23T05:33:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"CEO de Wayfair dice que los empleados necesitan trabajar m\u00e1s horas\",\"datePublished\":\"2023-12-23T05:33:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/\"},\"wordCount\":499,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/\",\"name\":\"CEO de Wayfair dice que los empleados necesitan trabajar m\u00e1s horas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-23T05:33:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CEO de Wayfair dice que los empleados necesitan trabajar m\u00e1s horas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CEO de Wayfair dice que los empleados necesitan trabajar m\u00e1s horas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/","og_locale":"es_ES","og_type":"article","og_title":"CEO de Wayfair dice que los empleados necesitan trabajar m\u00e1s horas - Noticias","og_description":"Nueva York (CNN)&#8211; El CEO de Wayfair tiene un mensaje de fin de a\u00f1o para los empleados de la empresa de muebles en l\u00ednea: no rehuyas a trabajar m\u00e1s horas y a mezclar tu trabajo con tu vida. &#171;Ganar requiere trabajo duro. Creo que la mayor\u00eda de nosotros, siendo individuos ambiciosos, encontramos la satisfacci\u00f3n en [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/","og_site_name":"Noticias","article_published_time":"2023-12-23T05:33:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/"},"author":{"name":"","@id":""},"headline":"CEO de Wayfair dice que los empleados necesitan trabajar m\u00e1s horas","datePublished":"2023-12-23T05:33:36+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/"},"wordCount":499,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/","url":"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/","name":"CEO de Wayfair dice que los empleados necesitan trabajar m\u00e1s horas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-23T05:33:36+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"CEO de Wayfair dice que los empleados necesitan trabajar m\u00e1s horas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"CEO de Wayfair dice que los empleados necesitan trabajar m\u00e1s horas","url":"http:\/\/noticiasya.com\/reno\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2023\/12\/22\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-23T05:33:36Z","datePublished":"2023-12-23T05:33:36Z","dateModified":"2023-12-23T05:33:36Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"CEO de Wayfair dice que los empleados necesitan trabajar m\\u00e1s horas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/22\\\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/22\\\/ceo-de-wayfair-dice-que-los-empleados-necesitan-trabajar-mas-horas\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-23T05:33:36Z\",\"datePublished\":\"2023-12-23T05:33:36Z\",\"dateModified\":\"2023-12-23T05:33:36Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455800,"url":"https:\/\/noticiasya.com\/reno\/2024\/11\/13\/condado-washington-semana-laboral-4-dias-trax\/","url_meta":{"origin":1442510,"position":0},"title":"Un condado de Washington cambi\u00f3 a una semana laboral de 4 d\u00edas. Podr\u00eda ser el futuro del trabajo","author":"","date":"noviembre 13, 2024","format":false,"excerpt":"(CNN) -- El verano pasado, Kristen y Eric Rezabek se sent\u00edan agobiados. Eric se estaba planteando aceptar un trayecto de cuatro horas por un trabajo mejor pagado, mientras que Kristen, que tiene dos empleos, planeaba a\u00f1adir una jornada completa a su horario de trabajo, que ya era a tiempo completo,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456055,"url":"https:\/\/noticiasya.com\/reno\/2024\/11\/24\/que-saber-empleados-federales-departamento-eficiencia-gubernamental-fin-trabajo-remoto-trax\/","url_meta":{"origin":1442510,"position":1},"title":"\u00bfBusca el &#171;Departamento de Eficiencia Gubernamental&#187; poner fin al trabajo remoto? Esto es lo que hay que saber","author":"","date":"noviembre 24, 2024","format":false,"excerpt":"(CNN) \u2014 Elon Musk y Vivek Ramaswamy est\u00e1n decididos a obligar a los empleados federales de Estados Unidos a regresar a la oficina con la esperanza de que algunos opten por renunciar en vez de eso.Ese esfuerzo afectar\u00e1 a algunas agencias \u2014y trabajadores\u2014 mucho m\u00e1s que a otras. El tiempo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448117,"url":"https:\/\/noticiasya.com\/reno\/2024\/04\/15\/semanas-laborales-4-dias-trax\/","url_meta":{"origin":1442510,"position":2},"title":"Las semanas laborales de 4 d\u00edas pueden estar a la vuelta de la esquina. Un tercio de las empresas estadounidenses las est\u00e1 considerando","author":"","date":"abril 15, 2024","format":false,"excerpt":"Nueva York (CNN) -- El burnout o agotamiento laboral es un problema tan grave para los trabajadores que algunos jefes se est\u00e1n planteando reducir la duraci\u00f3n de la semana laboral.Casi un tercio (30%) de las grandes empresas estadounidenses est\u00e1 explorando nuevos cambios en los horarios de trabajo, como semanas laborales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445951,"url":"https:\/\/noticiasya.com\/reno\/2024\/02\/23\/semana-laboral-cuatro-dias-reino-unido-trax-2\/","url_meta":{"origin":1442510,"position":3},"title":"Probaron la semana laboral de cuatro d\u00edas y tuvo tanto \u00e9xito que decidieron mantenerla","author":"","date":"febrero 23, 2024","format":false,"excerpt":"(CNN) -- Un a\u00f1o despu\u00e9s de que concluyera el mayor ensayo mundial de una semana laboral de cuatro d\u00edas, una gran mayor\u00eda de las empresas que participaron a\u00fan permit\u00edan a sus empleados trabajar una semana m\u00e1s corta y m\u00e1s de la mitad hab\u00edan hecho el cambio permanente.Durante seis meses, entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466202,"url":"https:\/\/noticiasya.com\/reno\/2025\/09\/06\/cato-nueva-york-redada-ice-detenidos-trax\/","url_meta":{"origin":1442510,"position":4},"title":"Redada del ICE en un negocio de Nueva York dej\u00f3 trabajadores aterrorizados y ralentiz\u00f3 la producci\u00f3n, dice copropietario","author":"","date":"septiembre 6, 2025","format":false,"excerpt":"Cuando Lenny Schmidt lleg\u00f3 a su negocio familiar de fabricaci\u00f3n de barras nutricionales en el norte del estado de Nueva York el jueves por la ma\u00f1ana, los agentes federales de inmigraci\u00f3n ya estaban all\u00ed.\u201cLos agentes hab\u00edan invadido la planta\u201d, dijo. \u201cProbablemente hab\u00eda m\u00e1s de 100 agentes, en veh\u00edculos de cuatro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473489,"url":"https:\/\/noticiasya.com\/reno\/2026\/04\/24\/microsoft-jubilacion-voluntaria-trax\/","url_meta":{"origin":1442510,"position":5},"title":"Microsoft busca reducir el tama\u00f1o de su plantilla con un programa in\u00e9dito de jubilaci\u00f3n anticipada","author":"","date":"abril 24, 2026","format":false,"excerpt":"Microsoft ofrece a cerca del 7 % de su plantilla en Estados Unidos la opci\u00f3n de jubilarse anticipadamente, el m\u00e1s reciente intento de una importante empresa tecnol\u00f3gica de reducir su tama\u00f1o mientras incrementa las inversiones en inteligencia artificial.El programa de jubilaci\u00f3n \u00fanica, pionera en la empresa, estar\u00e1 disponible para los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1442510"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442510\/revisions"}],"predecessor-version":[{"id":1442527,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442510\/revisions\/1442527"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1442510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1442510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1442510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}