{"id":1442600,"date":"2023-12-24T17:33:28","date_gmt":"2023-12-25T01:33:28","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442600"},"modified":"2023-12-24T17:33:28","modified_gmt":"2023-12-25T01:33:28","slug":"mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/","title":{"rendered":"Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas"},"content":{"rendered":"<p>(CNN) &#8212; Una mujer de Alabama que tiene dos \u00fateros (una extra\u00f1a condici\u00f3n) dio a luz a gemelos despu\u00e9s de quedar embarazada a principios de este a\u00f1o en ambos \u00fateros.<\/p>\n<p>Despu\u00e9s de 20 horas combinadas de trabajo de parto, Kelsey Hatcher dio a luz a su tercer y cuarto hijo, un par de gemelos inusuales, el martes y mi\u00e9rcoles de la semana pasada, seg\u00fan un comunicado de prensa del Hospital de Birmingham de la Universidad de Alabama.<\/p>\n<p>Hatcher fue inducida a las 39 semanas y durante todo el trabajo de parto tuvo el doble de seguimiento, el doble de registros y se le asignaron dos enfermeras de parto, seg\u00fan el comunicado.<\/p>\n<p>El consumo de marihuana durante el embarazo podr\u00eda ocasionar riesgos en la salud de los beb\u00e9s, seg\u00fan estudio<\/p>\n<p>La beb\u00e9 A, Roxi, naci\u00f3 por v\u00eda vaginal a las 7:45 p. m. del 19 de diciembre.<\/p>\n<p>&#171;Hubo una ovaci\u00f3n de todos en la sala cuando naci\u00f3 el primer beb\u00e9, pero quedaba otro beb\u00e9&#187;, dijo Shweta Patel, obstetra de Hatcher, en el comunicado de prensa. &#171;Kelsey estaba esencialmente trabajando en el \u00fatero izquierdo mientras simult\u00e1neamente se somet\u00eda a la cirug\u00eda de proceso posparto en el derecho\u201d.<\/p>\n<p>Mientras ten\u00eda contracciones con el beb\u00e9 B, Hatcher ya estaba amamantando al beb\u00e9 A, se\u00f1al\u00f3 Patel.<\/p>\n<p>Y casi 10 horas despu\u00e9s, Baby B, Rebel, naci\u00f3 por ces\u00e1rea a las 6:10 am del 20 de diciembre.<\/p>\n<p>\u201cDespu\u00e9s de un viaje tan largo y loco, signific\u00f3 mucho ver a mis dos hijas juntas por primera vez\u201d, dijo Hatcher.<\/p>\n<p>Dieta mediterr\u00e1nea en el embarazo mejora habilidades cognitivas del beb\u00e9<\/p>\n<p>Seg\u00fan los m\u00e9dicos, las ni\u00f1as son t\u00e9cnicamente gemelas a pesar de tener dos cumplea\u00f1os diferentes y estar en dos \u00fateros durante el embarazo.<\/p>\n<p>&#171;Creo que es seguro llamar a las ni\u00f1as gemelas fraternales&#187;, dijo Richard O. Davis, profesor de la Divisi\u00f3n de Medicina Materno-Fetal de la UAB y m\u00e9dico que cogestion\u00f3 el embarazo de Hatcher.<\/p>\n<p>Rebel y Roxi.<\/p>\n<p>\u201cAl final del d\u00eda, eran dos beb\u00e9s en un mismo vientre al mismo tiempo. Simplemente ten\u00edan apartamentos diferentes\u201d, a\u00f1adi\u00f3 Davis.<\/p>\n<p>Hatcher se enter\u00f3 de que naci\u00f3 con dos \u00fateros, una condici\u00f3n llamada didelfo uterino, cuando ten\u00eda 17 a\u00f1os y unas semanas despu\u00e9s de este embarazo fue cuando descubri\u00f3 que estaba embarazada en ambos \u00fateros, dice el comunicado.<\/p>\n<p>Los estudios de casos estiman que las posibilidades de un embarazo como este (una mujer con dos \u00fateros que lleva un beb\u00e9 en cada uno al mismo tiempo) son de alrededor de 1 entre 2.000 millones en la poblaci\u00f3n general, aunque es imposible saberlo con certeza con algo tan poco frecuente.<\/p>\n<p>&#171;Nunca en nuestros sue\u00f1os m\u00e1s locos podr\u00edamos haber planeado un embarazo y un parto como este, pero traer a nuestras dos ni\u00f1as sanas a este mundo de manera segura siempre fue el objetivo, y la UAB nos ayud\u00f3 a lograrlo&#187;, dijo Hatcher, &#171;Parece apropiado que tengan dos cumplea\u00f1os. Ambas ten\u00edan sus propias \u201ccasas\u201d y ahora ambas tienen sus propias historias de nacimiento \u00fanicas\u201d.<\/p>\n<p>Carma Hassan de CNN contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Una mujer de Alabama que tiene dos \u00fateros (una extra\u00f1a condici\u00f3n) dio a luz a gemelos despu\u00e9s de quedar embarazada a principios de este a\u00f1o en ambos \u00fateros. Despu\u00e9s de 20 horas combinadas de trabajo de parto, Kelsey Hatcher dio a luz a su tercer y cuarto hijo, un par de gemelos inusuales, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442600","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Una mujer de Alabama que tiene dos \u00fateros (una extra\u00f1a condici\u00f3n) dio a luz a gemelos despu\u00e9s de quedar embarazada a principios de este a\u00f1o en ambos \u00fateros. Despu\u00e9s de 20 horas combinadas de trabajo de parto, Kelsey Hatcher dio a luz a su tercer y cuarto hijo, un par de gemelos inusuales, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-25T01:33:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas\",\"datePublished\":\"2023-12-25T01:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/\"},\"wordCount\":563,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/\",\"name\":\"Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-25T01:33:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/","og_locale":"es_ES","og_type":"article","og_title":"Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas - Noticias","og_description":"(CNN) &#8212; Una mujer de Alabama que tiene dos \u00fateros (una extra\u00f1a condici\u00f3n) dio a luz a gemelos despu\u00e9s de quedar embarazada a principios de este a\u00f1o en ambos \u00fateros. Despu\u00e9s de 20 horas combinadas de trabajo de parto, Kelsey Hatcher dio a luz a su tercer y cuarto hijo, un par de gemelos inusuales, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/","og_site_name":"Noticias","article_published_time":"2023-12-25T01:33:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/"},"author":{"name":"","@id":""},"headline":"Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas","datePublished":"2023-12-25T01:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/"},"wordCount":563,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/","url":"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/","name":"Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-25T01:33:28+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas","url":"http:\/\/noticiasya.com\/reno\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-25T01:33:28Z","datePublished":"2023-12-25T01:33:28Z","dateModified":"2023-12-25T01:33:28Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mujer que estaba embarazada en cada uno de sus dos \\u00fateros da a luz a gemelas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/24\\\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/24\\\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-25T01:33:28Z\",\"datePublished\":\"2023-12-25T01:33:28Z\",\"dateModified\":\"2023-12-25T01:33:28Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1442598,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/24\/mujer-que-estaba-embarazada-en-cada-uno-de-sus-dos-uteros-da-a-luz-a-gemelas\/","url_meta":{"origin":1442600,"position":0},"title":"Mujer que estaba embarazada en cada uno de sus dos \u00fateros da a luz a gemelas","author":"","date":"diciembre 24, 2023","format":false,"excerpt":"(CNN) -- Una mujer de Alabama que tiene dos \u00fateros (una extra\u00f1a condici\u00f3n) dio a luz a gemelos despu\u00e9s de quedar embarazada a principios de este a\u00f1o en ambos \u00fateros.Despu\u00e9s de 20 horas combinadas de trabajo de parto, Kelsey Hatcher dio a luz a su tercer y cuarto hijo, un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1425804,"url":"https:\/\/noticiasya.com\/reno\/2022\/09\/12\/dos-jovenes-madres-dan-a-luz-en-sus-vehiculos-en-menos-de-24-horas-policia-asiste-partos\/","url_meta":{"origin":1442600,"position":1},"title":"Dos jovenes madres dan a luz en sus veh\u00edculos en menos de 24 horas; polic\u00eda asiste partos","author":"agomez","date":"septiembre 12, 2022","format":false,"excerpt":"\u00a1En los dos casos nacieron ni\u00f1as y ambas se encuentran sanas!","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/reno\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445036,"url":"https:\/\/noticiasya.com\/reno\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia\/","url_meta":{"origin":1442600,"position":2},"title":"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia","author":"agomez","date":"febrero 7, 2024","format":false,"excerpt":"(CNN) -- Un m\u00e9dico forense dio a conocer este martes la forma de la muerte de un beb\u00e9 cuya madre acus\u00f3 a un hospital de Georgia y a otros de decapitarlo durante el parto, calific\u00e1ndolo de homicidio.La oficina del m\u00e9dico forense del condado de Clayton, Georgia, dijo que el beb\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445038,"url":"https:\/\/noticiasya.com\/reno\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/","url_meta":{"origin":1442600,"position":3},"title":"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia","author":"","date":"febrero 7, 2024","format":false,"excerpt":"(CNN) -- Un m\u00e9dico forense dio a conocer este martes la forma de la muerte de un beb\u00e9 cuya madre acus\u00f3 a un hospital de Georgia y a otros de decapitarlo durante el parto, calific\u00e1ndolo de homicidio.La oficina del m\u00e9dico forense del condado de Clayton, Georgia, dijo que el beb\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457943,"url":"https:\/\/noticiasya.com\/reno\/2025\/01\/28\/guerra-israel-peligro-mortal-embarazadas-ninas-gaza-trax\/","url_meta":{"origin":1442600,"position":4},"title":"La guerra de Israel supuso un &#171;peligro mortal&#187; para las mujeres embarazadas y las ni\u00f1as en Gaza, afirma Human Rights Watch","author":"","date":"enero 28, 2025","format":false,"excerpt":"Human Rights Watch acus\u00f3 a Israel de infligir \u201cpeligros graves y a veces potencialmente mortales\u201d a mujeres y ni\u00f1as embarazadas y en posparto en Gaza, en un informe publicado este martes.El informe de 50 p\u00e1ginas, \u201cCinco beb\u00e9s en una incubadora: Violaciones de los derechos de las mujeres embarazadas en medio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469914,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/08\/nacimiento-inusual-gemelos-gorila-congo-trax\/","url_meta":{"origin":1442600,"position":5},"title":"Se registra el inusual nacimiento de gemelos de gorila de monta\u00f1a en un parque del Congo","author":"","date":"enero 8, 2026","format":false,"excerpt":"Una gorila de monta\u00f1a dio a luz a gemelos en el este del Congo, una zona afectada por la guerra, inform\u00f3 un parque nacional el mi\u00e9rcoles, calificando el hecho como \u201cun acontecimiento importante\u201d para esta subespecie en peligro de extinci\u00f3n.El nacimiento de los dos gorilas machos, hijos de una madre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1442600"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442600\/revisions"}],"predecessor-version":[{"id":1442616,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442600\/revisions\/1442616"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1442600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1442600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1442600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}