{"id":1442744,"date":"2023-12-27T14:33:42","date_gmt":"2023-12-27T22:33:42","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442744"},"modified":"2023-12-27T14:33:42","modified_gmt":"2023-12-27T22:33:42","slug":"blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/","title":{"rendered":"Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0 Altos funcionarios estadounidenses viajar\u00e1n a M\u00e9xico este mi\u00e9rcoles para buscar m\u00e1s ayuda de sus hom\u00f3logos para reducir los cruces fronterizos mientras el presidente Joe Biden enfrenta una presi\u00f3n cada vez mayor sobre el manejo de la frontera sur de Estados Unidos.<\/p>\n<p>La inmigraci\u00f3n ha sido una vulnerabilidad pol\u00edtica para Biden, en medio de fuertes cr\u00edticas de los republicanos y algunos miembros de su propio partido por la situaci\u00f3n en la frontera entre Estados Unidos y M\u00e9xico. Este mes, el tema pas\u00f3 al centro de la agenda de pol\u00edtica exterior del presidente, mientras la Casa Blanca presionaba para obtener ayuda para Ucrania e Israel en medio de sus esfuerzos b\u00e9licos. La falta de consenso sobre los cambios en la pol\u00edtica fronteriza finalmente impidi\u00f3 que Biden consiguiera miles de millones de d\u00f3lares en fondos para Ucrania, Israel y la frontera antes de fin de a\u00f1o.<\/p>\n<p>Antes de la reuni\u00f3n de estemi\u00e9rcoles, los funcionarios de Seguridad Nacional discutieron una serie de formas en que M\u00e9xico puede ayudar a reducir el n\u00famero de personas en la frontera con Estados Unidos que estar\u00e1n entre sus peticiones, incluido el traslado de migrantes al sur, el control de los ferrocarriles que utilizan los migrantes para trasladarse al norte y la provisi\u00f3n de incentivos para no viajar a la frontera como visas.<\/p>\n<p>El secretario de Estado, Antony Blinken, el secretario de Seguridad Nacional, Alejandro Mayorkas, y la asesora de Seguridad Nacional de la Casa Blanca, Liz Sherwood-Randall, asistir\u00e1n a la reuni\u00f3n, que cierra un a\u00f1o que comenz\u00f3 con la migraci\u00f3n como tema clave.<\/p>\n<p>El secretario de Estado Anthony Blinken habla durante una conferencia de prensa el mi\u00e9rcoles 20 de diciembre en el Departamento de Estado en Washington. (Roberto Schmidt\/AFP\/Getty Images)<\/p>\n<p>En enero, Biden se reuni\u00f3 con el presidente mexicano, Andr\u00e9s Manuel L\u00f3pez Obrador, en la Ciudad de M\u00e9xico para la Cumbre de L\u00edderes de Am\u00e9rica del Norte, donde, junto con el primer ministro canadiense, Justin Trudeau, abordaron los flujos migratorios en la regi\u00f3n.<\/p>\n<p>Casi un a\u00f1o despu\u00e9s \u2013y a pesar de una serie de medidas destinadas a disuadir la migraci\u00f3n irregular\u2013 el n\u00famero r\u00e9cord de migrantes que se desplazan por el hemisferio occidental sigue siendo un desaf\u00edo apremiante para Estados Unidos y M\u00e9xico.<\/p>\n<p>La migraci\u00f3n a menudo tiene altibajos, pero en las \u00faltimas semanas, una nueva oleada de migrantes que huyen del deterioro de las condiciones en sus pa\u00edses de origen desbord\u00f3 los ya escasos recursos federales y estatales. Antiguos y actuales funcionarios de Seguridad Nacional advirtieron que la frontera se acerca a un \u201cpunto de ruptura\u201d.<\/p>\n<p>La semana pasada, Biden llam\u00f3 a su hom\u00f3logo mexicano cuando empeoraba la situaci\u00f3n en la frontera sur de Estados Unidos. Durante la llamada, los dos l\u00edderes coincidieron en que se \u201cnecesitaban urgentemente\u201d medidas coercitivas adicionales para que se pudieran reabrir los puertos de entrada clave, que hab\u00edan sido suspendidos para redirigir al personal para ayudar a procesar a los migrantes.<\/p>\n<p>Hist\u00f3ricamente, Estados Unidos se ha apoyado en M\u00e9xico para frenar el flujo de migrantes que viajan hacia la frontera sur de Estados Unidos. Pero M\u00e9xico, al igual que Estados Unidos, enfrenta dificultades similares a medida que el n\u00famero de migrantes que cruzan hacia su pa\u00eds supera sus limitados recursos.<br \/>\n&#171;Los mexicanos todav\u00eda tienen una capacidad relativamente limitada&#187;, dijo Earl Anthony Wayne, ex embajador de Estados Unidos en M\u00e9xico y miembro de pol\u00edticas p\u00fablicas del Wilson Center.<\/p>\n<p>El secretario de Seguridad Nacional Alejandro Mayorkas es visto en la Sala de Prensa James S. Brady de la Casa Blanca el 11 de mayo de 2023 en Washington.<\/p>\n<p>\u201cSu fuerza de inmigraci\u00f3n no cuenta con fondos suficientes y es peque\u00f1a. Adem\u00e1s, ocasionalmente utilizan a la Guardia Nacional para detener a las personas, pero eso solo sirve para detener a las personas por per\u00edodos cortos de tiempo y no parece funcionar muy bien. Y todav\u00eda hay redes de contrabandistas\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Actualmente, las autoridades mexicanas est\u00e1n lidiando con miles de migrantes que abandonaron Tapachula, ubicada en el sur de M\u00e9xico, el domingo, en un largo viaje a pie hacia Estados Unidos.<\/p>\n<p>Muchos de los migrantes son de Am\u00e9rica Central y del Sur, as\u00ed como del Caribe, Cuba y Hait\u00ed. Las caravanas, como la que parti\u00f3 el fin de semana, a menudo se dividen en las semanas que tardan en llegar a la frontera sur de Estados Unidos, por lo que no est\u00e1 claro cu\u00e1ntos migrantes llegar\u00e1n a la frontera entre Estados Unidos y M\u00e9xico.<\/p>\n<p>El n\u00famero de inmigrantes que llegan tambi\u00e9n ha sido dif\u00edcil de gestionar para las autoridades estadounidenses porque no hay suficiente espacio de detenci\u00f3n o vuelos de repatriaci\u00f3n para aquellos que no califican para asilo.<\/p>\n<p>Ya en el norte de M\u00e9xico, m\u00e1s de 11.000 migrantes contin\u00faan esperando en refugios y campamentos para cruzar a Estados Unidos, seg\u00fan l\u00edderes comunitarios. Muchos de esos migrantes esperan ingresar a Estados Unidos a trav\u00e9s de v\u00edas legales establecidas por la administraci\u00f3n Biden, como la aplicaci\u00f3n CBP One, que automatiza la programaci\u00f3n de citas para solicitar asilo con las autoridades fronterizas, dijeron.<\/p>\n<p>Rosa Flores de CNN contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0 Altos funcionarios estadounidenses viajar\u00e1n a M\u00e9xico este mi\u00e9rcoles para buscar m\u00e1s ayuda de sus hom\u00f3logos para reducir los cruces fronterizos mientras el presidente Joe Biden enfrenta una presi\u00f3n cada vez mayor sobre el manejo de la frontera sur de Estados Unidos. La inmigraci\u00f3n ha sido una vulnerabilidad pol\u00edtica para Biden, en medio de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442744","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0 Altos funcionarios estadounidenses viajar\u00e1n a M\u00e9xico este mi\u00e9rcoles para buscar m\u00e1s ayuda de sus hom\u00f3logos para reducir los cruces fronterizos mientras el presidente Joe Biden enfrenta una presi\u00f3n cada vez mayor sobre el manejo de la frontera sur de Estados Unidos. La inmigraci\u00f3n ha sido una vulnerabilidad pol\u00edtica para Biden, en medio de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-27T22:33:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor\",\"datePublished\":\"2023-12-27T22:33:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/\"},\"wordCount\":953,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/\",\"name\":\"Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-27T22:33:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/","og_locale":"es_ES","og_type":"article","og_title":"Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor - Noticias","og_description":"(CNN) &#8212;\u00a0 Altos funcionarios estadounidenses viajar\u00e1n a M\u00e9xico este mi\u00e9rcoles para buscar m\u00e1s ayuda de sus hom\u00f3logos para reducir los cruces fronterizos mientras el presidente Joe Biden enfrenta una presi\u00f3n cada vez mayor sobre el manejo de la frontera sur de Estados Unidos. La inmigraci\u00f3n ha sido una vulnerabilidad pol\u00edtica para Biden, en medio de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/","og_site_name":"Noticias","article_published_time":"2023-12-27T22:33:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/"},"author":{"name":"","@id":""},"headline":"Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor","datePublished":"2023-12-27T22:33:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/"},"wordCount":953,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/","url":"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/","name":"Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-27T22:33:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor","url":"http:\/\/noticiasya.com\/reno\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-27T22:33:42Z","datePublished":"2023-12-27T22:33:42Z","dateModified":"2023-12-27T22:33:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Blinken y Mayorkas presionar\\u00e1n a sus hom\\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\\u00f3n cada vez mayor\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/27\\\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/27\\\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-27T22:33:42Z\",\"datePublished\":\"2023-12-27T22:33:42Z\",\"dateModified\":\"2023-12-27T22:33:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442740,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/27\/blinken-y-mayorkas-presionaran-a-sus-homologos-mexicanos-para-que-reduzcan-los-cruces-fronterizos-mientras-biden-enfrenta-una-presion-cada-vez-mayor\/","url_meta":{"origin":1442744,"position":0},"title":"Blinken y Mayorkas presionar\u00e1n a sus hom\u00f3logos mexicanos para que reduzcan los cruces fronterizos mientras Biden enfrenta una presi\u00f3n cada vez mayor","author":"","date":"diciembre 27, 2023","format":false,"excerpt":"(CNN) --\u00a0 Altos funcionarios estadounidenses viajar\u00e1n a M\u00e9xico este mi\u00e9rcoles para buscar m\u00e1s ayuda de sus hom\u00f3logos para reducir los cruces fronterizos mientras el presidente Joe Biden enfrenta una presi\u00f3n cada vez mayor sobre el manejo de la frontera sur de Estados Unidos.La inmigraci\u00f3n ha sido una vulnerabilidad pol\u00edtica para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442781,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/28\/blinken-y-mayorkas-sostuvieron-reunion-muy-productiva-con-pares-mexicanos\/","url_meta":{"origin":1442744,"position":1},"title":"Blinken y Mayorkas sostuvieron \u201creuni\u00f3n muy productiva\u201d con pares mexicanos","author":"","date":"diciembre 28, 2023","format":false,"excerpt":"(CNN) --\u00a0 El secretario de Seguridad Nacional, Alejandro Mayorkas, dijo que tuvo una \"reuni\u00f3n muy productiva\" con el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, y su gabinete en una publicaci\u00f3n este mi\u00e9rcoles a trav\u00e9s de X.El encuentro de este mi\u00e9rcoles se produce mientras Estados Unidos busca ayuda de M\u00e9xico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442786,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/28\/blinken-y-mayorkas-sostuvieron-reunion-muy-productiva-con-pares-mexicanos-2\/","url_meta":{"origin":1442744,"position":2},"title":"Blinken y Mayorkas sostuvieron \u201creuni\u00f3n muy productiva\u201d con pares mexicanos","author":"","date":"diciembre 28, 2023","format":false,"excerpt":"(CNN) --\u00a0 El secretario de Seguridad Nacional, Alejandro Mayorkas, dijo que tuvo una \"reuni\u00f3n muy productiva\" con el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, y su gabinete en una publicaci\u00f3n este mi\u00e9rcoles a trav\u00e9s de X.El encuentro de este mi\u00e9rcoles se produce mientras Estados Unidos busca ayuda de M\u00e9xico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444542,"url":"https:\/\/noticiasya.com\/reno\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/","url_meta":{"origin":1442744,"position":3},"title":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump","author":"","date":"enero 28, 2024","format":false,"excerpt":"(CNN) -- El presidente de Estados Unidos, Joe Biden, est\u00e1 adoptando medidas fronterizas m\u00e1s duras, incluido el cierre de la frontera entre Estados Unidos y M\u00e9xico, lo que marca un marcado cambio con respecto a sus primeros d\u00edas en el cargo mientras intenta defenderse de los ataques del expresidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444544,"url":"https:\/\/noticiasya.com\/reno\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump-2\/","url_meta":{"origin":1442744,"position":4},"title":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump","author":"","date":"enero 28, 2024","format":false,"excerpt":"(CNN) -- El presidente de Estados Unidos, Joe Biden, est\u00e1 adoptando medidas fronterizas m\u00e1s duras, incluido el cierre de la frontera entre Estados Unidos y M\u00e9xico, lo que marca un marcado cambio con respecto a sus primeros d\u00edas en el cargo mientras intenta defenderse de los ataques del expresidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444545,"url":"https:\/\/noticiasya.com\/reno\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump-3\/","url_meta":{"origin":1442744,"position":5},"title":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump","author":"","date":"enero 28, 2024","format":false,"excerpt":"(CNN) -- El presidente de Estados Unidos, Joe Biden, est\u00e1 adoptando medidas fronterizas m\u00e1s duras, incluido el cierre de la frontera entre Estados Unidos y M\u00e9xico, lo que marca un marcado cambio con respecto a sus primeros d\u00edas en el cargo mientras intenta defenderse de los ataques del expresidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1442744"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442744\/revisions"}],"predecessor-version":[{"id":1442760,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442744\/revisions\/1442760"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1442744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1442744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1442744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}