{"id":1442747,"date":"2023-12-27T16:33:34","date_gmt":"2023-12-28T00:33:34","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442747"},"modified":"2023-12-27T16:33:34","modified_gmt":"2023-12-28T00:33:34","slug":"quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/","title":{"rendered":"\u00bfQui\u00e9n mat\u00f3 a Canserbero? Fiscal\u00eda venezolana afirma que se trat\u00f3 de un doble homicidio, en un giro inesperado en el caso"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La Fiscal\u00eda General de Venezuela afirm\u00f3 este martes que el cantante de rap y hip-hop Tirone Gonz\u00e1lez, mejor conocido como Canserbero, y su amigo Carlos Molnar, bajista del grupo Zion TLP, fueron v\u00edctimas de un doble homicidio en enero de 2015 y no de un homicidio-suicidio como se anunci\u00f3 originalmente.<\/p>\n<p>Al presentar los resultados de la investigaci\u00f3n, el fiscal general Tarek William Saab mostr\u00f3 un video con una confesi\u00f3n de Natalia Am\u00e9stica, pareja de Molnar por 10 a\u00f1os y m\u00e1nager de Canserbero, quien asegur\u00f3 que les proporcion\u00f3 una alta dosis de calmantes a Molnar y a Gonz\u00e1lez de forma oculta en un t\u00e9. Agreg\u00f3 que cuando se quedaron dormidos, apu\u00f1al\u00f3 a ambos m\u00faltiples veces, primero a Molnar y luego a Gonz\u00e1lez.<\/p>\n<p>CNN ha intentado comunicarse con la defensa de Am\u00e9stica sin hasta ahora haber obtenido respuesta.<\/p>\n<p>En la narraci\u00f3n de Am\u00e9stica, que, seg\u00fan la Fiscal\u00eda, fue ratificada por la confesi\u00f3n de su hermano Guillermo, ella lo llam\u00f3 para que la ayudara a modificar la escena del crimen, con ayuda de tres funcionarios del Servicio Bolivariano de Inteligencia (Sebin) que supuestamente cobraron un dinero por armar la escena del \u201chomicidio-suicidio\u201d. CNN contact\u00f3 al Sebin para obtener una respuesta a las acusaciones, pero no ha obtenido respuesta a\u00fan.<\/p>\n<p>Los pescadores que investigaban algo brillante llevaron al rescate &#171;milagroso&#187; de un hombre de Indiana atrapado en un cami\u00f3n accidentado durante d\u00edas, dice la polic\u00eda<\/p>\n<p>Entre las alteraciones descritas por la Fiscal\u00eda est\u00e1n m\u00e1s pu\u00f1aladas y golpes a ambas v\u00edctimas para simular una ri\u00f1a, incluida uno en el rostro que le habr\u00eda desfigurado la cara a Tirone Gonz\u00e1lez. Tambi\u00e9n la creaci\u00f3n de huellas del supuesto recorrido de Gonz\u00e1lez hacia la ventana donde se simular\u00eda el suicidio al lanzar el cuerpo desde un d\u00e9cimo piso. Pero las huellas se correspond\u00edan con una medida de calzado de 37,5 cm y no con la huella plantar de Cancerbero, quien seg\u00fan se inform\u00f3 en dicha conferencia era talla 41, siempre seg\u00fan el relato de la Fiscal\u00eda.<\/p>\n<p>Saab asegur\u00f3 que durante el 18 y 19 de este mes particip\u00f3 de forma directa en las entrevistas a los imputados en procesos que, asegur\u00f3, \u201cse realizaron ajustados a la Constituci\u00f3n venezolana\u201d. En la medianoche del 19 de diciembre, ambos solicitaron hablar con el fiscal \u201cpara confesar lo ocurrido ese d\u00eda\u201d, dijo Saab. Los videos fueron transmitidos en la rueda de prensa y a trav\u00e9s del canal del Estado.<\/p>\n<p>Al describir los motivos del homicidio de Molnar, en el video mostrado por el Ministerio p\u00fablico, Natalia Am\u00e9stica asegur\u00f3 que \u00e9ste no le hab\u00eda pagado el dinero que hab\u00edan invertido en una gira realizada en diciembre de 2014 por Chile y Argentina. Con respecto a Canserbero, asegur\u00f3 que \u00e9l manten\u00eda una actitud indiferente hacia ella y que no quer\u00eda ser su amigo.<\/p>\n<p>El jefe del Ministerio Publico asegur\u00f3 que de momento suman seis personas las detenidas y que solicitaron \u00f3rdenes de aprehensi\u00f3n contra al menos cuatro de los primeros funcionarios que abordaron el sitio del suceso por, seg\u00fan se\u00f1al\u00f3, haber actuado de manera negligente al encubrir el hecho.<\/p>\n<p>Youtuber lleva a las autoridades a los restos humanos que se cree pertenecen a un hombre desaparecido desde 2013<\/p>\n<p>Asegur\u00f3 adem\u00e1s que en la reanudaci\u00f3n de la pesquisa participaron dos fiscales nacionales, tres directores, 33 expertos y 13 funcionarios del Comando Nacional Antiextorsi\u00f3n y secuestro (Conas) y de otros dos cuerpos auxiliares de seguridad, adem\u00e1s de la participaci\u00f3n directa del fiscal general. Precisaron que la nueva fase incluy\u00f3 110 diligencias de investigaci\u00f3n y 13 viajes a Maracay para recabar nueva evidencia.<\/p>\n<p>View this post on Instagram<\/p>\n<p>A post shared by Chamo Gonz\u00e1lez (@elcanserbero)<\/p>\n<p>\u00bfQui\u00e9n fue Canserbero?<\/p>\n<p>Tirone Jos\u00e9 Gonz\u00e1lez fue un cantante venezolano de hip hop y rap que utiliz\u00f3 el alias de Canserbero en el mundo de la m\u00fasica y que inclu\u00eda iron\u00eda y cr\u00edtica social en sus mensajes. Naci\u00f3 el 11 de marzo de 1988 en Maracay, estado Aragua, en el centro norte de Venezuela.<\/p>\n<p>Canserbero public\u00f3 tres \u00e1lbumes:<\/p>\n<p>Vida (2010)<\/p>\n<p>Muerte (2012)<\/p>\n<p>Apa y Can (2013) en conjunto con el rapero Apache<\/p>\n<p>En octubre de 2023, la revista Rolling Stone nombr\u00f3 a Canserbero como el mejor exponente del rap en espa\u00f1ol, entre 50 artistas del g\u00e9nero. En el texto destacan que \u201ccon letras profundas, una voz inconfundible y una actitud de s\u00f3lida autenticidad, Canserbero necesit\u00f3 poco tiempo para convertirse en una de las figuras emblem\u00e1ticas del rap en Am\u00e9rica Latina\u201d.<\/p>\n<p>El 19 de enero de 2015, cuando fue hallado muerto, ten\u00eda 26 a\u00f1os. Sus restos fueron sepultados en el Cementerio Metropolitano de Maraca y seg\u00fan la versi\u00f3n inicial, Canserbero hab\u00eda asesinado a Molnar para luego suicidarse. Los familiares y amigos del cantante no creyeron nunca esa versi\u00f3n y solicitaron que se reanudara la investigaci\u00f3n.<\/p>\n<p>Saab asegur\u00f3 que en noviembre, tras reunirse con los familiares y con la novia de Canserbero, decidieron reabrir la investigaci\u00f3n y practicar la exhumaci\u00f3n del cuerpo de Tirone Gonz\u00e1lez.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La Fiscal\u00eda General de Venezuela afirm\u00f3 este martes que el cantante de rap y hip-hop Tirone Gonz\u00e1lez, mejor conocido como Canserbero, y su amigo Carlos Molnar, bajista del grupo Zion TLP, fueron v\u00edctimas de un doble homicidio en enero de 2015 y no de un homicidio-suicidio como se anunci\u00f3 originalmente. Al presentar [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442747","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQui\u00e9n mat\u00f3 a Canserbero? Fiscal\u00eda venezolana afirma que se trat\u00f3 de un doble homicidio, en un giro inesperado en el caso - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n mat\u00f3 a Canserbero? Fiscal\u00eda venezolana afirma que se trat\u00f3 de un doble homicidio, en un giro inesperado en el caso - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La Fiscal\u00eda General de Venezuela afirm\u00f3 este martes que el cantante de rap y hip-hop Tirone Gonz\u00e1lez, mejor conocido como Canserbero, y su amigo Carlos Molnar, bajista del grupo Zion TLP, fueron v\u00edctimas de un doble homicidio en enero de 2015 y no de un homicidio-suicidio como se anunci\u00f3 originalmente. Al presentar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-28T00:33:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQui\u00e9n mat\u00f3 a Canserbero? Fiscal\u00eda venezolana afirma que se trat\u00f3 de un doble homicidio, en un giro inesperado en el caso\",\"datePublished\":\"2023-12-28T00:33:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/\"},\"wordCount\":908,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/\",\"name\":\"\u00bfQui\u00e9n mat\u00f3 a Canserbero? Fiscal\u00eda venezolana afirma que se trat\u00f3 de un doble homicidio, en un giro inesperado en el caso - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-28T00:33:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9n mat\u00f3 a Canserbero? Fiscal\u00eda venezolana afirma que se trat\u00f3 de un doble homicidio, en un giro inesperado en el caso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n mat\u00f3 a Canserbero? Fiscal\u00eda venezolana afirma que se trat\u00f3 de un doble homicidio, en un giro inesperado en el caso - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n mat\u00f3 a Canserbero? Fiscal\u00eda venezolana afirma que se trat\u00f3 de un doble homicidio, en un giro inesperado en el caso - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La Fiscal\u00eda General de Venezuela afirm\u00f3 este martes que el cantante de rap y hip-hop Tirone Gonz\u00e1lez, mejor conocido como Canserbero, y su amigo Carlos Molnar, bajista del grupo Zion TLP, fueron v\u00edctimas de un doble homicidio en enero de 2015 y no de un homicidio-suicidio como se anunci\u00f3 originalmente. Al presentar [&hellip;]","og_url":"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/","og_site_name":"Noticias","article_published_time":"2023-12-28T00:33:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/"},"author":{"name":"","@id":""},"headline":"\u00bfQui\u00e9n mat\u00f3 a Canserbero? Fiscal\u00eda venezolana afirma que se trat\u00f3 de un doble homicidio, en un giro inesperado en el caso","datePublished":"2023-12-28T00:33:34+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/"},"wordCount":908,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/","url":"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/","name":"\u00bfQui\u00e9n mat\u00f3 a Canserbero? Fiscal\u00eda venezolana afirma que se trat\u00f3 de un doble homicidio, en un giro inesperado en el caso - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-28T00:33:34+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9n mat\u00f3 a Canserbero? Fiscal\u00eda venezolana afirma que se trat\u00f3 de un doble homicidio, en un giro inesperado en el caso"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQui\u00e9n mat\u00f3 a Canserbero? Fiscal\u00eda venezolana afirma que se trat\u00f3 de un doble homicidio, en un giro inesperado en el caso","url":"http:\/\/noticiasya.com\/reno\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2023\/12\/27\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-28T00:33:34Z","datePublished":"2023-12-28T00:33:34Z","dateModified":"2023-12-28T00:33:34Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQui\\u00e9n mat\\u00f3 a Canserbero? Fiscal\\u00eda venezolana afirma que se trat\\u00f3 de un doble homicidio, en un giro inesperado en el caso\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/27\\\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/27\\\/quien-mato-a-canserbero-fiscalia-venezolana-afirma-que-se-trato-de-un-doble-homicidio-en-un-giro-inesperado-en-el-caso\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-28T00:33:34Z\",\"datePublished\":\"2023-12-28T00:33:34Z\",\"dateModified\":\"2023-12-28T00:33:34Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444186,"url":"https:\/\/noticiasya.com\/reno\/2024\/01\/20\/se-cumplen-9-anos-de-la-muerte-del-rapero-venezolano-canserbero-fiscal-y-familiares-sostienen-disputa\/","url_meta":{"origin":1442747,"position":0},"title":"Se cumplen 9 a\u00f1os de la muerte del rapero venezolano Canserbero: fiscal y familiares sostienen disputa","author":"","date":"enero 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Al cumplirse nueve a\u00f1os de la muerte del rapero venezolano Tyrone Gonz\u00e1lez, mejor conocido como \u201cCanserbero\u201d, que fue considerado por la revista Rolling Stone como el artista m\u00e1s influyente del mundo en ese g\u00e9nero musical, el Fiscal general de Venezuela, Tarek William Saab anunci\u00f3 este viernes en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444246,"url":"https:\/\/noticiasya.com\/reno\/2024\/01\/22\/se-cumplen-9-anos-de-la-muerte-del-rapero-venezolano-canserbero-fiscal-y-familiares-sostienen-disputa-2\/","url_meta":{"origin":1442747,"position":1},"title":"Se cumplen 9 a\u00f1os de la muerte del rapero venezolano Canserbero: fiscal y familiares sostienen disputa","author":"","date":"enero 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Al cumplirse nueve a\u00f1os de la muerte del rapero venezolano Tyrone Gonz\u00e1lez, mejor conocido como \"Canserbero\" -que fue considerado por la revista Rolling Stone como el artista m\u00e1s influyente del mundo en ese g\u00e9nero musical-, el Fiscal general de Venezuela, Tarek William Saab, anunci\u00f3 este viernes en sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465259,"url":"https:\/\/noticiasya.com\/reno\/2025\/08\/08\/detienen-sospechoso-homicidio-delegado-tamaulipas-fiscalia-orix\/","url_meta":{"origin":1442747,"position":2},"title":"Detienen a sospechoso del homicidio del delegado en Tamaulipas de la Fiscal\u00eda General de M\u00e9xico","author":"","date":"agosto 8, 2025","format":false,"excerpt":"Uno de los presuntos responsables del homicidio del delegado en Tamaulipas de la Fiscal\u00eda General de la Rep\u00fablica (FGR), Ernesto V\u00e1squez Reyna, fue detenido este viernes en la ciudad fronteriza de Reynosa, inform\u00f3 la propia Fiscal\u00eda de M\u00e9xico en un comunicado. Est\u00e1 previsto que pronto comparezca ante un juez.La Fiscal\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457876,"url":"https:\/\/noticiasya.com\/reno\/2025\/01\/25\/homicidio-periodista-alejandro-gallegos-leon-orix\/","url_meta":{"origin":1442747,"position":3},"title":"Fiscal\u00eda investiga desaparici\u00f3n y homicidio de periodista Alejandro Gallegos Le\u00f3n en Tabasco","author":"","date":"enero 25, 2025","format":false,"excerpt":"La Fiscal\u00eda General del estado de Tabasco, en el sur de M\u00e9xico, inform\u00f3 este s\u00e1bado que inici\u00f3 una investigaci\u00f3n por la desaparici\u00f3n y homicidio del periodista y profesor Alejandro Gallegos Le\u00f3n, de acuerdo con un comunicado de prensa.Seg\u00fan la entidad, Gallegos hab\u00eda sido reportado como desaparecido el viernes y su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463598,"url":"https:\/\/noticiasya.com\/reno\/2025\/06\/16\/quienes-son-detenidos-atentado-miguel-uribe-turbay-orix\/","url_meta":{"origin":1442747,"position":4},"title":"\u00bfQui\u00e9nes son los detenidos por el atentado contra Miguel Uribe Turbay?","author":"","date":"junio 16, 2025","format":false,"excerpt":"Tres personas han sido detenidas en Colombia por el atentado el 7 de junio al senador y precandidato presidencial Miguel Uribe Turbay. El presunto autor material \u2014un menor de edad\u2014 as\u00ed como un hombre y una mujer est\u00e1n bajo custodia de las autoridades, se\u00f1alados de haber participado en el ataque.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468239,"url":"https:\/\/noticiasya.com\/reno\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/","url_meta":{"origin":1442747,"position":5},"title":"Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo","author":"","date":"noviembre 11, 2025","format":false,"excerpt":"Autoridades de Michoac\u00e1n, en el suroeste de M\u00e9xico, investigan en qu\u00e9 circunstancias fue abatido el joven se\u00f1alado como el presunto autor del homicidio del alcalde de Uruapan, Carlos Manzo, ocurrido la noche del 1 de noviembre, dijeron el gobernador de Michoac\u00e1n, Alfredo Ram\u00edrez Bedolla, y el secretario de Seguridad federal,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1442747"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442747\/revisions"}],"predecessor-version":[{"id":1442765,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442747\/revisions\/1442765"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1442747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1442747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1442747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}