{"id":1442775,"date":"2023-12-28T05:33:45","date_gmt":"2023-12-28T13:33:45","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442775"},"modified":"2023-12-28T05:33:45","modified_gmt":"2023-12-28T13:33:45","slug":"analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/","title":{"rendered":"An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Se esperaba que la econom\u00eda china se recuperara r\u00e1pidamente en 2023 y retomara su papel de motor indiscutible del crecimiento mundial. En cambio, se estanc\u00f3 hasta el punto de que el Fondo Monetario Internacional (FMI), entre otros, lo llama un \u201clastre\u201d para la producci\u00f3n mundial. A pesar de sus muchos problemas (una crisis inmobiliaria, un gasto d\u00e9bil y un alto desempleo juvenil), la mayor\u00eda de los economistas creen que la segunda econom\u00eda m\u00e1s grande del mundo alcanzar\u00e1 su objetivo oficial de crecimiento de alrededor del 5% este a\u00f1o. Pero eso todav\u00eda est\u00e1 por debajo del crecimiento anual promedio de m\u00e1s del 6% en la d\u00e9cada anterior a la pandemia de covid 19, y 2024 parece cada vez m\u00e1s siniestro, dijeron. Es posible que el pa\u00eds se enfrente a d\u00e9cadas de estancamiento a partir de entonces.<\/p>\n<p>\u201cEl desaf\u00edo para la econom\u00eda china en 2024 no ser\u00e1 el crecimiento del PBI, que probablemente ser\u00e1 superior al 4,5%\u201d, dijo Derek Scissors, investigador principal del American Enterprise Institute, un grupo de expertos de centro derecha. &#171;El desaf\u00edo ser\u00e1 que la \u00fanica direcci\u00f3n desde all\u00ed es hacia abajo&#187;.<\/p>\n<p>Sin reformas de mercado importantes, el pa\u00eds podr\u00eda quedar atrapado en lo que los economistas llaman \u201cla trampa del ingreso medio\u201d, advirti\u00f3, refiri\u00e9ndose a la noci\u00f3n de que las econom\u00edas emergentes salen r\u00e1pidamente de la pobreza para quedar atrapadas antes de alcanzar el estatus de ingresos altos.<\/p>\n<p>Durante d\u00e9cadas, desde que China se reabri\u00f3 al mundo en 1978, fue una de las principales econom\u00edas de m\u00e1s r\u00e1pido crecimiento del planeta. Entre 1991 y 2011 creci\u00f3 un 10,5% anual. Despu\u00e9s de 2012, cuando Xi Jinping asumi\u00f3 la presidencia, la expansi\u00f3n se desaceler\u00f3, pero todav\u00eda promediaba el 6,7% en la d\u00e9cada hasta 2021.<\/p>\n<p>&#171;La segunda mitad de la d\u00e9cada de 2020&#8230; ver\u00e1 una desaceleraci\u00f3n del crecimiento&#187;, dijo Scissors, citando una correcci\u00f3n en el problem\u00e1tico sector inmobiliario junto con una disminuci\u00f3n demogr\u00e1fica.<\/p>\n<p>El FMI tambi\u00e9n se ha vuelto m\u00e1s pesimista respecto de las perspectivas a largo plazo. En noviembre, dijo que esperaba que la tasa de crecimiento de China alcanzara el 5,4% en 2023 y disminuyera gradualmente hasta el 3,5% en 2028 en medio de vientos en contra que van desde una productividad d\u00e9bil hasta el envejecimiento de la poblaci\u00f3n.<\/p>\n<p>\u00bfQue ha cambiado?<\/p>\n<p>La econom\u00eda china, que est\u00e1 plagada de una letan\u00eda de desaf\u00edos, no lleg\u00f3 a esta posici\u00f3n de la noche a la ma\u00f1ana.<\/p>\n<p>Scissors dijo que la anterior administraci\u00f3n del presidente Hu Jintao hab\u00eda inundado la econom\u00eda con liquidez en 2009 durante lo m\u00e1s profundo de la crisis financiera mundial para impulsar el crecimiento. El gobierno de Xi se mostr\u00f3 reacio a frenar el endeudamiento despu\u00e9s de llegar al poder en 2012, lo que provoc\u00f3 que se acumularan problemas estructurales.<\/p>\n<p>Logan Wright, director de investigaci\u00f3n de mercados de China en Rhodium Group, estuvo de acuerdo y dijo: &#171;La desaceleraci\u00f3n de la econom\u00eda de China es estructural, causada por el fin de una expansi\u00f3n sin precedentes del cr\u00e9dito y la inversi\u00f3n durante la \u00faltima d\u00e9cada&#187;.<\/p>\n<p>El sistema financiero del pa\u00eds simplemente no podr\u00e1 generar los mismos niveles de crecimiento crediticio que tuvo en a\u00f1os anteriores, dijo, por lo que Beijing tendr\u00e1 mucho menos control sobre la direcci\u00f3n de su econom\u00eda que en el pasado.<\/p>\n<p>Lo que empeor\u00f3 las cosas fue la obstinada adopci\u00f3n por parte de Beijing de una pol\u00edtica de cero Covid de estrictos bloqueos y su amplia represi\u00f3n contra la empresa privada, que da\u00f1\u00f3 profundamente la confianza y golpe\u00f3 la parte m\u00e1s vibrante de la econom\u00eda.<\/p>\n<p>Las consecuencias de estas pol\u00edticas se pueden ver en la desaceleraci\u00f3n de este a\u00f1o. Los precios al consumidor fueron d\u00e9biles durante la mayor parte de 2023 debido a la escasa demanda y existe el riesgo de una espiral deflacionaria.<\/p>\n<p>La crisis inmobiliaria se profundiz\u00f3. La ca\u00edda de las ventas de viviendas llev\u00f3 a algunos promotores saludables como Country Garden al borde del colapso. La crisis se extendi\u00f3 al enorme sector bancario paralelo, provocando impagos y provocando protestas en todo el pa\u00eds.<\/p>\n<p>Los gobiernos locales est\u00e1n luchando contra dificultades financieras despu\u00e9s de tres a\u00f1os de gasto de Covid y disminuci\u00f3n de las ventas de tierras. Algunas ciudades no pueden pagar sus deudas y han tenido que recortar servicios b\u00e1sicos o reducir los beneficios m\u00e9dicos para las personas mayores.<\/p>\n<p>El desempleo juvenil ha llegado a ser tan grave que el gobierno dej\u00f3 de publicar los datos .<\/p>\n<p>Las empresas extranjeras se han vuelto cautelosas ante el creciente escrutinio de Beijing y se est\u00e1n retirando del pa\u00eds . En el tercer trimestre, una medida de la inversi\u00f3n extranjera directa (IED) en China se volvi\u00f3 negativa por primera vez desde 1998.<\/p>\n<p>Una encuesta de septiembre realizada por la C\u00e1mara de Comercio Estadounidense en Shanghai mostr\u00f3 que solo el 52% de los encuestados eran optimistas sobre sus perspectivas comerciales a cinco a\u00f1os, el nivel m\u00e1s bajo desde que comenz\u00f3 la encuesta en 1999.<\/p>\n<p>\u00bfSe convertir\u00e1 China en Jap\u00f3n?<\/p>\n<p>A medida que el crecimiento de China se desacelera, algunos economistas hicieron comparaciones con Jap\u00f3n, que experiment\u00f3 dos \u201cd\u00e9cadas perdidas\u201d de crecimiento estancado y deflaci\u00f3n despu\u00e9s del estallido de su burbuja inmobiliaria a principios de los a\u00f1os noventa.<\/p>\n<p>Pero Scissors no cree que las cosas vayan as\u00ed, al menos no de inmediato.<\/p>\n<p>&#171;El resto de la d\u00e9cada de 2020 no parecer\u00e1 una d\u00e9cada perdida: el crecimiento del PIB chino se mantendr\u00e1 muy por encima de cero&#187;, afirm\u00f3.<\/p>\n<p>Sin embargo, a largo plazo, el mayor problema econ\u00f3mico podr\u00eda ser la demograf\u00eda. El a\u00f1o pasado, la poblaci\u00f3n de China cay\u00f3 a 1.411 millones de habitantes , lo que marc\u00f3 su primer descenso desde 1961.<\/p>\n<p>Su tasa total de fertilidad, el n\u00famero promedio de beb\u00e9s que una mujer tendr\u00e1 a lo largo de su vida, tambi\u00e9n cay\u00f3 a un m\u00ednimo hist\u00f3rico de 1,09 el a\u00f1o pasado desde 1,30 apenas dos a\u00f1os antes. Eso significa que la tasa de fertilidad de China es ahora incluso m\u00e1s baja que la de Jap\u00f3n, un pa\u00eds conocido desde hace mucho tiempo por su sociedad envejecida.<\/p>\n<p>Una enfermera cuida a un reci\u00e9n nacido en el Hospital de Mujeres y Ni\u00f1os de la ciudad de Fuyang, provincia de Anhui, el 8 de agosto de 2022. CFOTO\/Future Publishing\/Getty Images<\/p>\n<p>La demograf\u00eda puede tener un impacto significativo en el potencial de crecimiento de una econom\u00eda. Una disminuci\u00f3n de la oferta laboral y un aumento del gasto social y sanitario podr\u00edan conducir a un d\u00e9ficit fiscal m\u00e1s amplio y una mayor carga de deuda.<\/p>\n<p>Una fuerza laboral m\u00e1s peque\u00f1a tambi\u00e9n podr\u00eda erosionar los ahorros, lo que resultar\u00eda en tasas de inter\u00e9s m\u00e1s altas y una disminuci\u00f3n de la inversi\u00f3n. La demanda de vivienda, por ejemplo, puede caer en el largo plazo.<\/p>\n<p>&#171;En la d\u00e9cada de 2040, la contracci\u00f3n de la poblaci\u00f3n har\u00e1 imposible el crecimiento agregado&#187;, dijo Scissors. &#171;Sin cambios dr\u00e1sticos en las pol\u00edticas, no habr\u00e1 recuperaci\u00f3n para China: la d\u00e9cada de 2030 ser\u00e1 peor que la de 2020&#187;.<\/p>\n<p>\u00bfPuede Xi establecer un nuevo rumbo?<\/p>\n<p>Los l\u00edderes de China, que se reunieron este mes para discutir objetivos y pol\u00edticas econ\u00f3micas para el pr\u00f3ximo a\u00f1o, dijeron que aumentar\u00e1n el apoyo fiscal y monetario a la econom\u00eda. Los funcionarios incluso prometieron fortalecer la \u201cpropaganda econ\u00f3mica\u201d y la \u201corientaci\u00f3n de la opini\u00f3n p\u00fablica\u201d en un intento por aumentar la confianza.<\/p>\n<p>Los medios informaron que el gobierno podr\u00eda volver a fijar el objetivo econ\u00f3mico para el pr\u00f3ximo a\u00f1o en alrededor del 5%, lo que parece ambicioso en comparaci\u00f3n con las previsiones independientes. El objetivo oficial se anunciar\u00e1 en marzo, cuando China celebre sus reuniones legislativas anuales.<\/p>\n<p>Pero no es probable que las medidas ayuden a solucionar los problemas estructurales.<\/p>\n<p>&#171;Los formuladores de pol\u00edticas parecen creer que con un poco de est\u00edmulo y un cambio en el sentimiento, la econom\u00eda puede retomar un camino m\u00e1s s\u00f3lido&#187;, dijo Julian Evans-Pritchard, jefe de Econom\u00eda de China en Capital Economics. Dijo que los funcionarios tambi\u00e9n parecen tener la esperanza de que establecer un objetivo de crecimiento ambicioso pueda ayudar a impulsar la confianza.<\/p>\n<p>&#171;Si bien hay algo de verdad en esto, creemos que los funcionarios est\u00e1n subestimando hasta qu\u00e9 punto la desaceleraci\u00f3n de China es de naturaleza estructural y no ser\u00e1 revertida tan f\u00e1cilmente&#187;.<\/p>\n<p>&#171;La mayor parte de la desaceleraci\u00f3n refleja una disminuci\u00f3n estructural de la productividad y el crecimiento de los ingresos, m\u00e1s que una debilidad c\u00edclica que pueda abordarse mediante est\u00edmulos del lado de la demanda u otras medidas que impulsen la confianza&#187;, dijo.<\/p>\n<p>Si Beijing recurre a su viejo manual, como un mayor endeudamiento, a\u00fan podr\u00eda estimular el crecimiento en 2024, pero s\u00f3lo como \u201cun analg\u00e9sico econ\u00f3mico, no una cura\u201d, seg\u00fan Scissors.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Se esperaba que la econom\u00eda china se recuperara r\u00e1pidamente en 2023 y retomara su papel de motor indiscutible del crecimiento mundial. En cambio, se estanc\u00f3 hasta el punto de que el Fondo Monetario Internacional (FMI), entre otros, lo llama un \u201clastre\u201d para la producci\u00f3n mundial. A pesar de sus muchos problemas (una crisis inmobiliaria, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442775","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Se esperaba que la econom\u00eda china se recuperara r\u00e1pidamente en 2023 y retomara su papel de motor indiscutible del crecimiento mundial. En cambio, se estanc\u00f3 hasta el punto de que el Fondo Monetario Internacional (FMI), entre otros, lo llama un \u201clastre\u201d para la producci\u00f3n mundial. A pesar de sus muchos problemas (una crisis inmobiliaria, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-28T13:33:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor\",\"datePublished\":\"2023-12-28T13:33:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/\"},\"wordCount\":1583,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/\",\"name\":\"An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-28T13:33:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/","og_locale":"es_ES","og_type":"article","og_title":"An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor - Noticias","og_description":"(CNN) &#8212;\u00a0Se esperaba que la econom\u00eda china se recuperara r\u00e1pidamente en 2023 y retomara su papel de motor indiscutible del crecimiento mundial. En cambio, se estanc\u00f3 hasta el punto de que el Fondo Monetario Internacional (FMI), entre otros, lo llama un \u201clastre\u201d para la producci\u00f3n mundial. A pesar de sus muchos problemas (una crisis inmobiliaria, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/","og_site_name":"Noticias","article_published_time":"2023-12-28T13:33:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/"},"author":{"name":"","@id":""},"headline":"An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor","datePublished":"2023-12-28T13:33:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/"},"wordCount":1583,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/","url":"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/","name":"An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-28T13:33:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor","url":"http:\/\/noticiasya.com\/reno\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-28T13:33:45Z","datePublished":"2023-12-28T13:33:45Z","dateModified":"2023-12-28T13:33:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"An\\u00e1lisis: la econom\\u00eda de China tuvo un a\\u00f1o miserable. 2024 podr\\u00eda ser a\\u00fan peor\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/28\\\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/28\\\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-28T13:33:45Z\",\"datePublished\":\"2023-12-28T13:33:45Z\",\"dateModified\":\"2023-12-28T13:33:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1461296,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/17\/aranceles-omc-comercio-global-economia-trax\/","url_meta":{"origin":1442775,"position":0},"title":"La guerra comercial global da\u00f1ar\u00e1 gravemente a EE.UU. y a las econom\u00edas globales, seg\u00fan la OMC","author":"","date":"abril 17, 2025","format":false,"excerpt":"La guerra comercial global del presidente Donald Trump perjudicar\u00e1 a las econom\u00edas de todo el mundo este a\u00f1o, incluyendo a la de EE.UU., seg\u00fan un nuevo informe de la Organizaci\u00f3n Mundial del Comercio (OMC).La OMC proyecta que las econom\u00edas globales crecer\u00e1n a un ritmo m\u00e1s lento que sin aranceles, especialmente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463417,"url":"https:\/\/noticiasya.com\/reno\/2025\/06\/10\/global-peor-decada-desde-1960-banco-mundial-trax\/","url_meta":{"origin":1442775,"position":1},"title":"La econom\u00eda global se encamina hacia la peor d\u00e9cada desde la de 1960, advierte el Banco Mundial","author":"","date":"junio 10, 2025","format":false,"excerpt":"El crecimiento econ\u00f3mico en el mundo se encamina hacia su d\u00e9cada m\u00e1s d\u00e9bil desde la de 1960, seg\u00fan un nuevo an\u00e1lisis del Banco Mundial, que se\u00f1ala la guerra comercial del presidente Donald Trump como un factor clave que afecta a las econom\u00edas de todo el mundo.El Banco Mundial prev\u00e9 que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463133,"url":"https:\/\/noticiasya.com\/reno\/2025\/06\/03\/consecuencias-aranceles-trump-peores-ocde-trax\/","url_meta":{"origin":1442775,"position":2},"title":"Las consecuencias de los aranceles de Trump son peores de lo que pens\u00e1bamos, afirma la OCDE","author":"","date":"junio 3, 2025","format":false,"excerpt":"La guerra comercial del presidente Donald Trump causar\u00e1 un da\u00f1o econ\u00f3mico mayor al esperado, tanto en Estados Unidos como en el resto del mundo, seg\u00fan nuevas previsiones de la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3mico (OCDE).En un informe publicado el martes, el grupo de 38 naciones, en su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461246,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/16\/china-crecimiento-economico-inesperado-trax\/","url_meta":{"origin":1442775,"position":3},"title":"China registra un crecimiento econ\u00f3mico inesperadamente fuerte antes de la entrada en vigor de los aranceles","author":"","date":"abril 16, 2025","format":false,"excerpt":"China registr\u00f3 un crecimiento econ\u00f3mico inesperadamente fuerte en el primer trimestre de 2025, antes de que entraran en vigor los aranceles del presidente de Estados Unidos, Donald Trump.El crecimiento de su producto interior bruto (PIB) alcanz\u00f3 el 5,4 % en el primer trimestre, seg\u00fan inform\u00f3 el mi\u00e9rcoles la Oficina Nacional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447376,"url":"https:\/\/noticiasya.com\/reno\/2024\/03\/26\/economia-salario-amlo-orix\/","url_meta":{"origin":1442775,"position":4},"title":"As\u00ed han evolucionado la econom\u00eda y los salarios de M\u00e9xico con AMLO","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El desempe\u00f1o de la econom\u00eda en M\u00e9xico durante los cinco a\u00f1os que lleva el gobierno del presidente de M\u00e9xico Andr\u00e9s Manuel L\u00f3pez Obrador ha sido de claroscuros: el Producto Interno Bruto (PIB) cay\u00f3 8,5% en 2020, en medio de la pandemia de covid-19, pero de all\u00ed ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459513,"url":"https:\/\/noticiasya.com\/reno\/2025\/03\/05\/china-guerra-comercial-trump-crecimiento-trax\/","url_meta":{"origin":1442775,"position":5},"title":"China desaf\u00eda guerra comercial de Trump al fijar objetivo de crecimiento del 5% y promete &#171;superar cualquier dificultad&#187;","author":"","date":"marzo 5, 2025","format":false,"excerpt":"China fij\u00f3 un ambicioso objetivo de crecimiento de \u201calrededor del 5%\u201d para 2025, en una desafiante muestra de confianza mientras se prepara para las consecuencias de la escalada de aranceles estadounidenses sobre su econom\u00eda impulsada por las exportaciones.El objetivo \u201csubraya nuestra determinaci\u00f3n de afrontar las dificultades de frente y esforzarnos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1442775"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442775\/revisions"}],"predecessor-version":[{"id":1442791,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442775\/revisions\/1442791"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1442775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1442775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1442775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}