{"id":1442777,"date":"2023-12-28T06:33:41","date_gmt":"2023-12-28T14:33:41","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442777"},"modified":"2023-12-28T06:33:41","modified_gmt":"2023-12-28T14:33:41","slug":"caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/","title":{"rendered":"Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado &#171;\u00c9xodo de la pobreza&#187;"},"content":{"rendered":"<p>(CNN) &#8212; La Oficina de Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos (CBP) est\u00e1 monitoreando los informes de una caravana de miles de migrantes que se ha formado en el sur de M\u00e9xico y advierte que estos grupos generalmente se mueven lentamente y luego se fragmentan antes de llegar a la frontera sur de Estados Unidos, dijo la agencia en un comunicado a CNN.<\/p>\n<p>Canciller de M\u00e9xico dice que reuni\u00f3n con EE.UU. fue \u201cexcelente\u201d e insin\u00faa acuerdos sobre la frontera<\/p>\n<p>Migrantes caminan como parte de la caravana que ha sido llamada &#171;El \u00e9xodo de la pobreza&#187;. (STR\/AFP via Getty Images)<\/p>\n<p>&#171;La CBP continuar\u00e1 monitoreando los acontecimientos en coordinaci\u00f3n con nuestras contrapartes extranjeras e interinstitucionales, como lo hemos hecho con movilizaciones anteriores de migrantes&#187;, dijo la CBP.<\/p>\n<p>\u00bfC\u00f3mo es y d\u00f3nde queda Eagle Pass? Esta es la realidad de una de las ciudades fronterizas donde se agolpan inmigrantes en EE.UU.<\/p>\n<p>La administraci\u00f3n de Biden ha estado lidiando con un elevado n\u00famero de cruces de migrantes que han agotado los recursos locales, estatales y federales durante varias semanas. CBP ha aumentado los recursos a la frontera y suspendido temporalmente las operaciones en varios puertos de entrada para redirigir al personal a procesar a los migrantes.<\/p>\n<p>Seg\u00fan la CBP, los encuentros con migrantes contin\u00faan fluctuando, ya que los traficantes y otros criminales difunden informaci\u00f3n err\u00f3nea para atraer a los migrantes a cruzar ilegalmente. Pero la agencia advierte que cualquier persona sin base legal en Estados Unidos podr\u00eda estar sujeta a expulsi\u00f3n.<\/p>\n<p>\u00bfDe d\u00f3nde vienen los miles de migrantes que integran la caravana el &#171;\u00c9xodo de la pobreza&#187;?<\/p>\n<p>Este domingo 24 de diciembre, miles de migrantes abandonaron Tapachula, en el sur de M\u00e9xico, para realizar un largo viaje a pie hacia Estados Unidos. Los organizadores llaman a la caravana el &#171;\u00c9xodo de la pobreza&#187;.<\/p>\n<p>Uno de los organizadores, Luis Villagr\u00e1n, dijo a los periodistas que est\u00e1n huyendo de lo &#171;inhumano&#187; y que &#171;la \u00fanica esperanza de esta gente es salir, llamar la atenci\u00f3n y decir que estamos vivos. Lo \u00fanico que queremos es trabajar&#187;. Lo \u00fanico que queremos son documentos para salir adelante&#187;, a\u00f1adi\u00f3 Villagr\u00e1n.<\/p>\n<p>\u00bfDe d\u00f3nde provienen los migrantes?<\/p>\n<p>Muchos de los migrantes son de Am\u00e9rica Central y del Sur, as\u00ed como del Caribe, Cuba y Hait\u00ed.<\/p>\n<p>Benigno S\u00e1nchez, un migrante cubano, dijo a CNN: &#171;Tenemos miedo de hablar&#8230; Tenemos necesidades econ\u00f3micas. Tenemos un sue\u00f1o, trabajar honestamente. \u00bfQu\u00e9 les puedo decir? Desafortunadamente, vivimos en un gobierno corrupto&#187;.<\/p>\n<p>En medio de su caminata, Aida Pe\u00f1a, salvadore\u00f1a, dijo a CNN que como recompensa por el sacrificio que est\u00e1n haciendo espera que &#171;Dios les d\u00e9 el milagro de cruzar&#187; a Estados Unidos.<\/p>\n<p>M\u00e1s de 11.000 migrantes esperan en el norte de M\u00e9xico<\/p>\n<p>\u00bfCu\u00e1ntos integran el llamado &#171;\u00c9xodo de la pobreza&#187;?<\/p>\n<p>( STR\/AFP via Getty Images)<\/p>\n<p>Unos 7.000 migrantes, seg\u00fan los organizadores del contingente, partieron en la v\u00edspera de Navidad desde el sur de M\u00e9xico hacia la frontera norte.<\/p>\n<p>Sin embargo, el n\u00famero de migrantes ha disminuido a medida que los migrantes se han dispersado a aproximadamente 3.000, seg\u00fan estimaciones de la agencia de la ONU para los refugiados compartidas con CNN.<\/p>\n<p>Los migrantes han estado tratando de presionar a las autoridades mexicanas para que proporcionen documentos, que anteriormente permit\u00edan a las personas que cruzaban hacia M\u00e9xico moverse por todo el pa\u00eds.<\/p>\n<p>La falta de documentos parece haber influido en la decisi\u00f3n de los migrantes, incluidos los que podr\u00edan haber querido presentar una solicitud de asilo o quedarse en M\u00e9xico, de continuar dirigi\u00e9ndose a Estados Unidos, alimentando la actual caravana que avanza por M\u00e9xico, seg\u00fan entrevistas en el terreno por parte de las ONG.<\/p>\n<p>Entre las solicitudes sobre la mesa de Estados Unidos de cara a la reuni\u00f3n del mi\u00e9rcoles en M\u00e9xico est\u00e1 la de que el gobierno mexicano proporcione incentivos, como visas, para que los migrantes permanezcan en el pa\u00eds y eviten migrar irregularmente, dijeron funcionarios a CNN.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La Oficina de Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos (CBP) est\u00e1 monitoreando los informes de una caravana de miles de migrantes que se ha formado en el sur de M\u00e9xico y advierte que estos grupos generalmente se mueven lentamente y luego se fragmentan antes de llegar a la frontera sur de Estados [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442777","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado &quot;\u00c9xodo de la pobreza&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado &quot;\u00c9xodo de la pobreza&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La Oficina de Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos (CBP) est\u00e1 monitoreando los informes de una caravana de miles de migrantes que se ha formado en el sur de M\u00e9xico y advierte que estos grupos generalmente se mueven lentamente y luego se fragmentan antes de llegar a la frontera sur de Estados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-28T14:33:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado &#171;\u00c9xodo de la pobreza&#187;\",\"datePublished\":\"2023-12-28T14:33:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/\"},\"wordCount\":735,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/\",\"name\":\"Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado \\\"\u00c9xodo de la pobreza\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-28T14:33:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado &#171;\u00c9xodo de la pobreza&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado \"\u00c9xodo de la pobreza\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/","og_locale":"es_ES","og_type":"article","og_title":"Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado \"\u00c9xodo de la pobreza\" - Noticias","og_description":"(CNN) &#8212; La Oficina de Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos (CBP) est\u00e1 monitoreando los informes de una caravana de miles de migrantes que se ha formado en el sur de M\u00e9xico y advierte que estos grupos generalmente se mueven lentamente y luego se fragmentan antes de llegar a la frontera sur de Estados [&hellip;]","og_url":"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/","og_site_name":"Noticias","article_published_time":"2023-12-28T14:33:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/"},"author":{"name":"","@id":""},"headline":"Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado &#171;\u00c9xodo de la pobreza&#187;","datePublished":"2023-12-28T14:33:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/"},"wordCount":735,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/","url":"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/","name":"Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado \"\u00c9xodo de la pobreza\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-28T14:33:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado &#171;\u00c9xodo de la pobreza&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado &#171;\u00c9xodo de la pobreza&#187;","url":"http:\/\/noticiasya.com\/reno\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-28T14:33:41Z","datePublished":"2023-12-28T14:33:41Z","dateModified":"2023-12-28T14:33:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Caravana de migrantes de M\\u00e9xico hacia EE.UU.: de d\\u00f3nde provienen, hacia d\\u00f3nde se dirigen, y cu\\u00e1ntos integran el llamado &#171;\\u00c9xodo de la pobreza&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/28\\\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/28\\\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-28T14:33:41Z\",\"datePublished\":\"2023-12-28T14:33:41Z\",\"dateModified\":\"2023-12-28T14:33:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442768,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/28\/caravana-de-migrantes-de-mexico-hacia-ee-uu-de-donde-provienen-hacia-donde-se-dirigen-y-cuantos-integran-el-llamado-exodo-de-la-pobreza\/","url_meta":{"origin":1442777,"position":0},"title":"Caravana de migrantes de M\u00e9xico hacia EE.UU.: de d\u00f3nde provienen, hacia d\u00f3nde se dirigen, y cu\u00e1ntos integran el llamado &#171;\u00c9xodo de la pobreza&#187;","author":"","date":"diciembre 28, 2023","format":false,"excerpt":"(CNN) -- La Oficina de Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos (CBP) est\u00e1 monitoreando los informes de una caravana de miles de migrantes que se ha formado en el sur de M\u00e9xico y advierte que estos grupos generalmente se mueven lentamente y luego se fragmentan antes de llegar a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442636,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/25\/miles-de-migrantes-se-suman-a-caravana-rumbo-a-ee-uu\/","url_meta":{"origin":1442777,"position":1},"title":"Miles de migrantes se suman a caravana rumbo a EE.UU.","author":"","date":"diciembre 25, 2023","format":false,"excerpt":"(CNN) -- Miles de migrantes abandonaron Tapachula, en el sur de M\u00e9xico, este domingo, realizando un largo viaje a pie hacia Estados Unidos. Los organizadores llaman a la caravana el \"\u00c9xodo de la pobreza\".Muchos de los migrantes son de Am\u00e9rica Central y del Sur, as\u00ed como del Caribe, Cuba y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442752,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/27\/blinken-aterriza-en-mexico-para-conversaciones-complejas-con-amlo-y-mas-funcionarios-sobre-migracion\/","url_meta":{"origin":1442777,"position":2},"title":"Blinken aterriza en M\u00e9xico para &#8216;conversaciones complejas&#8217; con AMLO y m\u00e1s funcionarios sobre migraci\u00f3n","author":"","date":"diciembre 27, 2023","format":false,"excerpt":"(CNN) -- El secretario de Estado, Antony Blinken, aterriz\u00f3 en la Ciudad de M\u00e9xico, junto con otros altos funcionarios estadounidenses, seg\u00fan el grupo, para lo que la Casa Blanca describe como \u201cconversaciones complejas\u201d.En un comunicado, la Casa Blanca dijo que M\u00e9xico es \u201cuno de nuestros socios m\u00e1s fuertes en materia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467021,"url":"https:\/\/noticiasya.com\/reno\/2025\/10\/01\/caravana-migrantes-mexico-no-eeuu-orix\/","url_meta":{"origin":1442777,"position":3},"title":"&#171;No queremos ir a EE.UU.&#187;: caravana de migrantes busca establecerse en M\u00e9xico, pero la burocracia le pone otro muro","author":"","date":"octubre 1, 2025","format":false,"excerpt":"Vladimir Ortiz Cassola, un cubano de 24 a\u00f1os, se uni\u00f3 a la caravana de m\u00e1s de 580 migrantes que sali\u00f3 este mi\u00e9rcoles desde Tapachula, Chiapas, en el sur de M\u00e9xico, hasta la Ciudad de M\u00e9xico. No buscan cruzar la frontera norte. No quieren llegar a Estados Unidos. Lo que piden,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442771,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/28\/canciller-de-mexico-dice-que-reunion-con-ee-uu-fue-excelente-e-insinua-acuerdos-sobre-la-frontera\/","url_meta":{"origin":1442777,"position":4},"title":"Canciller de M\u00e9xico dice que reuni\u00f3n con EE.UU. fue \u201cexcelente\u201d e insin\u00faa acuerdos sobre la frontera","author":"","date":"diciembre 28, 2023","format":false,"excerpt":"(CNN) -- Alicia B\u00e1rcena, m\u00e1xima diplom\u00e1tica de M\u00e9xico, calific\u00f3 la reuni\u00f3n con altos funcionarios estadounidenses sobre la crisis migratoria como un \u201cexcelente\u201d encuentro que reafirm\u00f3 la amistad y el trabajo conjunto entre ambos pa\u00edses, seg\u00fan una grabaci\u00f3n de audio de un grupo con medios mexicanos proporcionada a CNN por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442781,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/28\/blinken-y-mayorkas-sostuvieron-reunion-muy-productiva-con-pares-mexicanos\/","url_meta":{"origin":1442777,"position":5},"title":"Blinken y Mayorkas sostuvieron \u201creuni\u00f3n muy productiva\u201d con pares mexicanos","author":"","date":"diciembre 28, 2023","format":false,"excerpt":"(CNN) --\u00a0 El secretario de Seguridad Nacional, Alejandro Mayorkas, dijo que tuvo una \"reuni\u00f3n muy productiva\" con el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, y su gabinete en una publicaci\u00f3n este mi\u00e9rcoles a trav\u00e9s de X.El encuentro de este mi\u00e9rcoles se produce mientras Estados Unidos busca ayuda de M\u00e9xico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1442777"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442777\/revisions"}],"predecessor-version":[{"id":1442793,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442777\/revisions\/1442793"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1442777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1442777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1442777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}