{"id":1442785,"date":"2023-12-28T10:33:44","date_gmt":"2023-12-28T18:33:44","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442785"},"modified":"2023-12-28T10:33:44","modified_gmt":"2023-12-28T18:33:44","slug":"5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/","title":{"rendered":"5 claves del megaproyecto de ley de Javier Milei en Argentina"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El Gobierno del presidente de Argentina, Javier Milei, present\u00f3 este mi\u00e9rcoles un megaproyecto de ley que plantea una profunda reforma del Estado.<\/p>\n<p>Los 5 puntos m\u00e1s pol\u00e9micos del megadecreto del presidente Javier Milei<\/p>\n<p>La iniciativa Ley de Bases y Puntos de Partida para La Libertad de los Argentinos, como se titula, tiene una extensi\u00f3n de 183 p\u00e1ginas con m\u00e1s de 664 art\u00edculos, entre ellos, el megadecreto de Necesidad y Urgencia (DNU), que gener\u00f3 diversas reacciones desde su anuncio, siete d\u00edas atr\u00e1s.<\/p>\n<p>Tambi\u00e9n incluye la reglamentaci\u00f3n del protocolo antibloqueos presentado por la ministra de Seguridad, Patricia Bullrich, en el que se endurecen las sanciones a quienes participen y\/o convoquen u organicen cortes a la circulaci\u00f3n en calles.<\/p>\n<p>\u00bfEs constitucional el decreto de necesidad y urgencia del presidente Javier Milei en Argentina?<\/p>\n<p>\u201cPromovemos estas reformas en nombre de la Revoluci\u00f3n de Mayo de 1810 (inicio de la independencia nacional) y en defensa de la vida, la libertad y la propiedad de los argentinos\u201d, dice el mensaje publicado en la cuenta en X de la Oficina del presidente Javier Milei, que incluye la foto del legajo de la ley envuelto con una cinta con los colores de la bandera argentina.<\/p>\n<p>El Presidente Javier Milei envi\u00f3 al Congreso de la Naci\u00f3n la Ley de Bases y Puntos de Partida para La Libertad de los Argentinos.<br \/>\nCon el esp\u00edritu de restituir el orden econ\u00f3mico y social basado en la doctrina liberal plasmada en la Constituci\u00f3n Nacional de 1853, presentamos al\u2026 pic.twitter.com\/5yYSBYA751<br \/>\n\u2014 Oficina del Presidente Javier Milei (@OPEArg) December 27, 2023<\/p>\n<p>Lo que tienes que saber<\/p>\n<p>Estado de Emergencia<\/p>\n<p>Reforzando el sentido de urgencia que Milei proclama en sus discursos, y que se plasma tambi\u00e9n en el DNU, el proyecto de ley declara \u201cla emergencia p\u00fablica en materia econ\u00f3mica, financiera, fiscal, previsional, de seguridad, defensa, tarifaria, energ\u00e9tica, sanitaria, administrativa y social hasta el 31 de diciembre de 2025\u201d.<\/p>\n<p>\u00bfC\u00f3mo impactar\u00e1 en la econom\u00eda el megadecreto de necesidad y urgencia de Milei?<\/p>\n<p>Este punto otorgar\u00eda la potestad al Poder Ejecutivo de tomar decisiones legislativas en todas esas materias durante los pr\u00f3ximos dos a\u00f1os, con la posibilidad de prorrogarlo por dos a\u00f1os m\u00e1s, hasta 2027, es decir, la totalidad del mandato en curso.<\/p>\n<p>Reformas al sistema electoral<\/p>\n<p>Se propone la eliminaci\u00f3n de las elecciones primarias, abiertas, simult\u00e1neas y obligatorias (PASO), proceso en el que se dirimen las internas partidarias que fue sancionado en 2009, cuyo costo y utilidad han sido cuestionados por distintos partidos a lo largo de los a\u00f1os.<\/p>\n<p>Adem\u00e1s, se plantea incorporar la boleta \u00fanica y modificar la elecci\u00f3n de los miembros de la C\u00e1mara de Diputados por un nuevo sistema de circunscripciones que cambiar\u00eda sustancialmente la composici\u00f3n de la asamblea legislativa y dificultar\u00eda la posibilidad de que las fuerzas minoritarias ganen bancas.<\/p>\n<p>Privatizaci\u00f3n de empresas p\u00fablicas<\/p>\n<p>La normativa propuesta enlista empresas \u201cde propiedad total o mayoritaria estatal\u201d sujetas a privatizaciones. Entre estas se incluyen la aerol\u00ednea de bandera Aerol\u00edneas Argentinas, la petrolera YPF, medios de comunicaci\u00f3n estatales como la agencia de noticias T\u00e9lam, la Televisi\u00f3n P\u00fablica y Radio Nacional.<\/p>\n<p>\u201cSe constituir\u00e1n sociedades an\u00f3nimas, en las cuales el Poder Ejecutivo nacional podr\u00e1 conservar una acci\u00f3n con derecho a veto en las decisiones que impliquen el cierre de la actividad\u201d, dice el texto.<\/p>\n<p>Jubilaciones<\/p>\n<p>Se suspende la f\u00f3rmula de movilidad jubilatoria. Esto significa que las actualizaciones de las pensiones para la tercera edad ser\u00e1n discrecionales, &#171;hasta tanto se establezca una forma autom\u00e1tica&#187;.<\/p>\n<p>Mientras no se defina esa f\u00f3rmula, que no est\u00e1 prevista en el texto de esta ley, los aumentos para este sector de la sociedad quedan en manos del Poder Ejecutivo.<\/p>\n<p>\u201cEl Poder Ejecutivo nacional podr\u00e1 realizar aumentos peri\u00f3dicos atendiendo prioritariamente a los beneficiarios de m\u00e1s bajos ingresos&#187;, dice la nueva normativa.<\/p>\n<p>Regularizaci\u00f3n de bienes no declarados<\/p>\n<p>Se establece un mecanismo de regularizaci\u00f3n de bienes no declarados, incluido dinero en efectivo, participaciones accionarias, inmuebles, t\u00edtulos valores (bonos, acciones, etc.) y bienes intangibles con al\u00edcuotas que van del 5% al 15%.<\/p>\n<p>El plazo para acceder a este beneficio ser\u00eda hasta el 30 de noviembre de 2024 y estar\u00edan excluidos los funcionarios p\u00fablicos con cargos hasta el 30 de diciembre.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El Gobierno del presidente de Argentina, Javier Milei, present\u00f3 este mi\u00e9rcoles un megaproyecto de ley que plantea una profunda reforma del Estado. Los 5 puntos m\u00e1s pol\u00e9micos del megadecreto del presidente Javier Milei La iniciativa Ley de Bases y Puntos de Partida para La Libertad de los Argentinos, como se titula, tiene [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442785","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5 claves del megaproyecto de ley de Javier Milei en Argentina - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 claves del megaproyecto de ley de Javier Milei en Argentina - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El Gobierno del presidente de Argentina, Javier Milei, present\u00f3 este mi\u00e9rcoles un megaproyecto de ley que plantea una profunda reforma del Estado. Los 5 puntos m\u00e1s pol\u00e9micos del megadecreto del presidente Javier Milei La iniciativa Ley de Bases y Puntos de Partida para La Libertad de los Argentinos, como se titula, tiene [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-28T18:33:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"5 claves del megaproyecto de ley de Javier Milei en Argentina\",\"datePublished\":\"2023-12-28T18:33:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/\"},\"wordCount\":759,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/\",\"url\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/\",\"name\":\"5 claves del megaproyecto de ley de Javier Milei en Argentina - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-28T18:33:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 claves del megaproyecto de ley de Javier Milei en Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 claves del megaproyecto de ley de Javier Milei en Argentina - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/","og_locale":"es_ES","og_type":"article","og_title":"5 claves del megaproyecto de ley de Javier Milei en Argentina - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El Gobierno del presidente de Argentina, Javier Milei, present\u00f3 este mi\u00e9rcoles un megaproyecto de ley que plantea una profunda reforma del Estado. Los 5 puntos m\u00e1s pol\u00e9micos del megadecreto del presidente Javier Milei La iniciativa Ley de Bases y Puntos de Partida para La Libertad de los Argentinos, como se titula, tiene [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/","og_site_name":"Noticias","article_published_time":"2023-12-28T18:33:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/"},"author":{"name":"","@id":""},"headline":"5 claves del megaproyecto de ley de Javier Milei en Argentina","datePublished":"2023-12-28T18:33:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/"},"wordCount":759,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/","url":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/","name":"5 claves del megaproyecto de ley de Javier Milei en Argentina - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-28T18:33:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"5 claves del megaproyecto de ley de Javier Milei en Argentina"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"5 claves del megaproyecto de ley de Javier Milei en Argentina","url":"http:\/\/noticiasya.com\/reno\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2023\/12\/28\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-28T18:33:44Z","datePublished":"2023-12-28T18:33:44Z","dateModified":"2023-12-28T18:33:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"5 claves del megaproyecto de ley de Javier Milei en Argentina\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/28\\\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2023\\\/12\\\/28\\\/5-claves-del-megaproyecto-de-ley-de-javier-milei-en-argentina\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-28T18:33:44Z\",\"datePublished\":\"2023-12-28T18:33:44Z\",\"dateModified\":\"2023-12-28T18:33:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442496,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/22\/los-cinco-puntos-mas-polemicos-del-megadecreto-del-presidente-milei-en-argentina\/","url_meta":{"origin":1442785,"position":0},"title":"Los cinco puntos m\u00e1s pol\u00e9micos del megadecreto del presidente Milei en Argentina","author":"","date":"diciembre 22, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Argentina, Javier Milei, firm\u00f3 un extenso decreto de 366 art\u00edculos que busca desregular la econom\u00eda. Esto incluye la derogaci\u00f3n parcial y total, y la modificaci\u00f3n de cientos de leyes de distintos \u00e1mbitos de aplicaci\u00f3n: trabajo, salud, precios, deporte, tarjetas de cr\u00e9dito, entre otros.\u00bfEs constitucional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442498,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/22\/los-cinco-puntos-mas-polemicos-del-megadecreto-del-presidente-milei-en-argentina-2\/","url_meta":{"origin":1442785,"position":1},"title":"Los cinco puntos m\u00e1s pol\u00e9micos del megadecreto del presidente Milei en Argentina","author":"","date":"diciembre 22, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Argentina, Javier Milei, firm\u00f3 un extenso decreto de 366 art\u00edculos que busca desregular la econom\u00eda. Esto incluye la derogaci\u00f3n parcial y total, y la modificaci\u00f3n de cientos de leyes de distintos \u00e1mbitos de aplicaci\u00f3n: trabajo, salud, precios, deporte, tarjetas de cr\u00e9dito, entre otros.\u00bfEs constitucional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442506,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/22\/los-cinco-puntos-mas-polemicos-del-megadecreto-del-presidente-milei-en-argentina-3\/","url_meta":{"origin":1442785,"position":2},"title":"Los cinco puntos m\u00e1s pol\u00e9micos del megadecreto del presidente Milei en Argentina","author":"","date":"diciembre 22, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Argentina, Javier Milei, firm\u00f3 un extenso decreto de 366 art\u00edculos que busca desregular la econom\u00eda. Esto incluye la derogaci\u00f3n parcial y total, y la modificaci\u00f3n de cientos de leyes de distintos \u00e1mbitos de aplicaci\u00f3n: trabajo, salud, precios, deporte, tarjetas de cr\u00e9dito, entre otros.\u00bfEs constitucional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442839,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/29\/la-principal-federacion-sindical-de-argentina-convoca-a-paro-nacional-en-enero\/","url_meta":{"origin":1442785,"position":3},"title":"La principal federaci\u00f3n sindical de Argentina convoca a paro nacional en enero","author":"","date":"diciembre 29, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La Confederaci\u00f3n General del Trabajo (CGT) de Argentina, la mayor central sindical del pa\u00eds, convoc\u00f3 este jueves a un paro nacional previsto para el pr\u00f3ximo 24 de enero, en rechazo a los decretos anunciados la semana pasada por el presidente Javier Milei.5 claves del megaproyecto de ley\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442840,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/29\/la-principal-federacion-sindical-de-argentina-convoca-a-paro-nacional-en-enero-2\/","url_meta":{"origin":1442785,"position":4},"title":"La principal federaci\u00f3n sindical de Argentina convoca a paro nacional en enero","author":"","date":"diciembre 29, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La Confederaci\u00f3n General del Trabajo (CGT) de Argentina, la mayor central sindical del pa\u00eds, convoc\u00f3 este jueves a un paro nacional previsto para el pr\u00f3ximo 24 de enero, en rechazo a los decretos anunciados la semana pasada por el presidente Javier Milei.5 claves del megaproyecto de ley\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442513,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/22\/los-cinco-puntos-mas-polemicos-del-megadecreto-del-presidente-milei-en-argentina-4\/","url_meta":{"origin":1442785,"position":5},"title":"Los cinco puntos m\u00e1s pol\u00e9micos del megadecreto del presidente Milei en Argentina","author":"","date":"diciembre 22, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Argentina, Javier Milei, firm\u00f3 este mi\u00e9rcoles un extenso decreto de 366 art\u00edculos que busca desregular la econom\u00eda. Esto incluye la derogaci\u00f3n parcial o total, y la modificaci\u00f3n de cientos de leyes de distintos \u00e1mbitos de aplicaci\u00f3n: trabajo, salud, precios, deporte, tarjetas de cr\u00e9dito, entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1442785"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442785\/revisions"}],"predecessor-version":[{"id":1442802,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1442785\/revisions\/1442802"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1442785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1442785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1442785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}