{"id":1447564,"date":"2024-03-30T19:03:39","date_gmt":"2024-03-31T02:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/"},"modified":"2024-03-30T19:03:39","modified_gmt":"2024-03-31T02:03:39","slug":"fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/","title":{"rendered":"Fiscal\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0Las ocho personas cuyos cuerpos fueron encontrados en Oxaca, M\u00e9xico, eran migrantes de China que murieron en el mar, inform\u00f3 este s\u00e1bado la Fiscal\u00eda General del estado en un comunicado.<\/p>\n<p>Seg\u00fan la entidad, las v\u00edctimas &#171;viajaban a bordo de una embarcaci\u00f3n que era guiada por un hombre originario de M\u00e9xico, la cual sali\u00f3 de Tapachula, en el estado de Chiapas, el jueves 28 de marzo de 2024&#187;.<\/p>\n<p>&#171;De pronto, la embarcaci\u00f3n se volte\u00f3, por lo que quedaron varados en el mar donde fallecieron las ocho v\u00edctimas, siendo que solo sobrevivi\u00f3 uno de los migrantes, accidente que ocurri\u00f3 el 29 de marzo&#187;, se agreg\u00f3.<\/p>\n<p>Investigan la muerte de ocho personas encontradas en la costa de Oaxaca, en el sur de M\u00e9xico<\/p>\n<p>Seg\u00fan la Fiscal\u00eda, el sobreviviente es un hombre de China y no se dieron detalles sobre qu\u00e9 habr\u00eda pasado con el gu\u00eda mexicano.<\/p>\n<p>En el comunicado se agreg\u00f3 que &#171;las v\u00edctimas a\u00fan no han sido identificadas de manera oficial, por lo que la Fiscal\u00eda de Oaxaca realiza los trabajos interinstitucionales con diferentes instancias federales, adem\u00e1s que se efect\u00faan las labores para trabajar con la embajada de China en M\u00e9xico&#187;.<\/p>\n<p>Un mensaje enviado por CNN a la Embajada de China en M\u00e9xico este s\u00e1bado en busca de m\u00e1s informaci\u00f3n no fue respondido de inmediato.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0Las ocho personas cuyos cuerpos fueron encontrados en Oxaca, M\u00e9xico, eran migrantes de China que murieron en el mar, inform\u00f3 este s\u00e1bado la Fiscal\u00eda General del estado en un comunicado. Seg\u00fan la entidad, las v\u00edctimas &#171;viajaban a bordo de una embarcaci\u00f3n que era guiada por un hombre originario de M\u00e9xico, la cual sali\u00f3 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447564","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0Las ocho personas cuyos cuerpos fueron encontrados en Oxaca, M\u00e9xico, eran migrantes de China que murieron en el mar, inform\u00f3 este s\u00e1bado la Fiscal\u00eda General del estado en un comunicado. Seg\u00fan la entidad, las v\u00edctimas &#171;viajaban a bordo de una embarcaci\u00f3n que era guiada por un hombre originario de M\u00e9xico, la cual sali\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-31T02:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fiscal\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar\",\"datePublished\":\"2024-03-31T02:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/\"},\"wordCount\":272,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/\",\"name\":\"Fiscal\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-31T02:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0Las ocho personas cuyos cuerpos fueron encontrados en Oxaca, M\u00e9xico, eran migrantes de China que murieron en el mar, inform\u00f3 este s\u00e1bado la Fiscal\u00eda General del estado en un comunicado. Seg\u00fan la entidad, las v\u00edctimas &#171;viajaban a bordo de una embarcaci\u00f3n que era guiada por un hombre originario de M\u00e9xico, la cual sali\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-31T02:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/"},"author":{"name":"","@id":""},"headline":"Fiscal\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar","datePublished":"2024-03-31T02:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/"},"wordCount":272,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/","name":"Fiscal\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-31T02:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Fiscal\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fiscal\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar","url":"http:\/\/noticiasya.com\/reno\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2024\/03\/30\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-31T02:03:39Z","datePublished":"2024-03-31T02:03:39Z","dateModified":"2024-03-31T02:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Fiscal\\u00eda confirma que personas encontradas muertas en Oaxaca eran migrantes de China que murieron en el mar\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/03\\\/30\\\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/03\\\/30\\\/fiscalia-confirma-personas-muertas-oaxaca-migrantes-china-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-31T02:03:39Z\",\"datePublished\":\"2024-03-31T02:03:39Z\",\"dateModified\":\"2024-03-31T02:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447549,"url":"https:\/\/noticiasya.com\/reno\/2024\/03\/29\/investigan-muerte-ocho-personas-oaxaca-mexico-orix\/","url_meta":{"origin":1447564,"position":0},"title":"Investigan la muerte de ocho personas encontradas en la costa de Oaxaca, en el sur de M\u00e9xico","author":"","date":"marzo 29, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Los cuerpos de ocho personas fueron localizados este viernes en las costas de Oaxaca, en el sur de M\u00e9xico, inform\u00f3 la Fiscal\u00eda General del estado a trav\u00e9s de un comunicado. La instituci\u00f3n agreg\u00f3 que los datos preliminares indican que los fallecidos eran migrantes.La Fiscal\u00eda detall\u00f3 que el hallazgo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455701,"url":"https:\/\/noticiasya.com\/reno\/2024\/11\/09\/hallan-71-migrantes-retenidos-oaxaca-mexico-orix\/","url_meta":{"origin":1447564,"position":1},"title":"Autoridades hallan a 71 migrantes retenidos en una casa en Oaxaca, en el sureste de M\u00e9xico","author":"","date":"noviembre 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Fiscal\u00eda General de Oaxaca, en el sureste de M\u00e9xico, inform\u00f3 este viernes del hallazgo de 71 migrantes de varias nacionalidades, entre ellos 19 menores de edad, que estaban hacinados en el interior de una vivienda.En el operativo, que fue realizado el jueves, las autoridades encontraron 32\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464468,"url":"https:\/\/noticiasya.com\/reno\/2025\/07\/12\/localizan-rancho-guanajuato-personas-victimas-trata-orix\/","url_meta":{"origin":1447564,"position":2},"title":"Localizan en un rancho de Guanajuato, M\u00e9xico, a unas 700 personas que posiblemente eran v\u00edctimas de trata","author":"","date":"julio 12, 2025","format":false,"excerpt":"Cerca de 700 personas que posiblemente eran v\u00edctimas de trata con fines de explotaci\u00f3n laboral fueron localizadas en un rancho de Guanajuato, en el centro de M\u00e9xico, inform\u00f3 la Fiscal\u00eda local este s\u00e1bado en un comunicado.El hallazgo ocurri\u00f3 en el municipio de Dolores Hidalgo, donde autoridades de varias instituciones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445891,"url":"https:\/\/noticiasya.com\/reno\/2024\/02\/21\/tres-migrantes-muertos-ataque-armado-sonora-orix\/","url_meta":{"origin":1447564,"position":3},"title":"Fiscal\u00eda de Sonora confirma la muerte de tres migrantes tras ataque armado; dos mujeres y un menor de edad","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El fiscal general de Sonora, Gustavo Salas, confirm\u00f3 este lunes que dos mujeres y un menor de edad migrantes murieron en un ataque armado perpetrado el jueves pasado contra los veh\u00edculos en los que viajaban en la localidad de S\u00e1ric, cuando buscaban llegar a la frontera entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450917,"url":"https:\/\/noticiasya.com\/reno\/2024\/07\/05\/localizan-mujeres-colombianas-victimas-trata-personas-yucatan-mexico-orix\/","url_meta":{"origin":1447564,"position":4},"title":"Autoridades de M\u00e9xico localizan a ocho mujeres colombianas consideradas v\u00edctimas de trata de personas en Yucat\u00e1n","author":"","date":"julio 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Autoridades de M\u00e9xico localizaron a ocho mujeres de nacionalidad colombiana que, de acuerdo con investigaciones ministeriales, eran v\u00edctimas de trata de personas en la ciudad de M\u00e9rida, capital del estado de Yucat\u00e1n, inform\u00f3 la Fiscal\u00eda General de la Rep\u00fablica (FGR) en un comunicado publicado este viernes.Las mujeres fueron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462009,"url":"https:\/\/noticiasya.com\/reno\/2025\/05\/05\/muertos-volcamiento-lancha-san-diego-investigan-migrantes-trax\/","url_meta":{"origin":1447564,"position":5},"title":"Al menos tres muertos tras volcamiento de lancha frente a San Diego; autoridades investigan si son migrantes","author":"","date":"mayo 5, 2025","format":false,"excerpt":"Una peque\u00f1a embarcaci\u00f3n se volc\u00f3 el lunes en el oc\u00e9ano cerca de San Diego. El incidente caus\u00f3 la muerte de tres personas, dej\u00f3 cuatro heridos y nueve desaparecidos, seg\u00fan la Guardia Costera de EE.UU.La Guardia Costera inform\u00f3 en X que busca a nueve personas desaparecidas en el agua a unos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1447564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1447564"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1447564\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1447564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1447564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1447564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}