{"id":1448040,"date":"2024-04-12T16:03:41","date_gmt":"2024-04-12T23:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/"},"modified":"2024-04-12T16:03:41","modified_gmt":"2024-04-12T23:03:41","slug":"amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/","title":{"rendered":"L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0El presidente Andr\u00e9s Manuel L\u00f3pez Obrador incluy\u00f3 entre los 100 compromisos de su gobierno establecer un sistema de salud de primer nivel, universal, gratuito y de calidad, con atenci\u00f3n m\u00e9dica y medicamentos gratuitos, con m\u00e9dicos generales y especialistas suficientes, con estudios diagn\u00f3sticos en los centros de salud y equipos completos para hacerlos, y todos los f\u00e1rmacos que se necesiten, esto tanto para poblaci\u00f3n sin seguridad social como para los que tienen acceso a esta.<\/p>\n<p>A pocos meses de terminar el sexenio, especialistas consultados por CNN en Espa\u00f1ol dicen que en el balance de este compromiso se pueden se\u00f1alar avances, pero tambi\u00e9n diversos pendientes y fallas. De hecho, el propio presidente reconoci\u00f3 el martes 9 de abril en conferencia de prensa que a\u00fan no se ha logrado ese sistema de salud de primer nivel que prometi\u00f3, pero asegur\u00f3 que estar\u00e1 listo para el fin de su mandato.<\/p>\n<p>Aciertos de la gesti\u00f3n<\/p>\n<p>Gustavo Leal Fern\u00e1ndez, profesor investigador de tiempo completo de la Universidad Aut\u00f3noma Metropolitana Xochimilco (UAM-Xochimilco) y dedicado durante muchos a\u00f1os al an\u00e1lisis de la pol\u00edtica de salud y seguridad social en M\u00e9xico y el mundo, dice que a L\u00f3pez Obrador se le debe reconocer que implement\u00f3 \u201cuna suerte de pol\u00edtica de contenci\u00f3n&#187; para detener una &#171;inercia neoliberal sobre el sistema de salud&#187;\u00a0que, a su juicio, lo estaba encaminando a la privatizaci\u00f3n.<\/p>\n<p>Uno de los principales cambios fue el modelo para atender a la poblaci\u00f3n sin seguridad social. El presidente elimin\u00f3 el Seguro Popular vigente desde 2003, durante la presidencia de Vicente Fox, y lo sustituy\u00f3, primero, por el Instituto Nacional de Salud para el Bienestar (Insabi), y despu\u00e9s, por el Organismo P\u00fablico Descentralizado (OPD) IMSS Bienestar.<\/p>\n<p>AMLO sustituir\u00e1 el Seguro Popular en M\u00e9xico por un nuevo sistema de salud<\/p>\n<p>Con el Insabi, los ciudadanos ya no necesitaron afiliarse, como se hac\u00eda con el Seguro Popular. Todo el que no tuviera cobertura de seguridad social y requiriera atenci\u00f3n la recibir\u00eda. Tampoco habr\u00eda cobros en servicios ni medicamentos, como pasaba antes, ni se le pagar\u00eda a privados por la atenci\u00f3n a los pacientes.<\/p>\n<p>Andr\u00e9s Casta\u00f1eda, especialista en pol\u00edticas de salud y coordinador de Cero Desabasto, un colectivo de organizaciones que promueven el acceso a la salud, opina que el cambio tuvo sus claroscuros.<\/p>\n<p>Se\u00f1ala que el viejo modelo del Seguro Popular para atender a la poblaci\u00f3n sin seguridad social \u201cacarreaba grandes inequidades a las que no se hab\u00edan logrado hacerles frente&#187;. Por ejemplo, para la atenci\u00f3n de las enfermedades con gastos catastr\u00f3ficos solo se cubr\u00eda a ni\u00f1os hasta los cinco a\u00f1os y algunos casos de c\u00e1ncer, cuando &#171;a las personas con seguridad social se les cubre todo\u201d, indic\u00f3 Casta\u00f1eda.<\/p>\n<p>Y agrega que \u201csolamente se estaban agudizando las brechas en la calidad de los servicios que se ofertaban y los servicios colectivos de salud (prevenci\u00f3n y promoci\u00f3n) cada vez se iban desdibujando, m\u00e1s por una falta de rector\u00eda de las autoridades federales\u201d.<\/p>\n<p>Juan Manuel Lira, doctorado en Gobernabilidad y Gesti\u00f3n P\u00fablica, y extitular de la Unidad de Atenci\u00f3n M\u00e9dica del Instituto Mexicano de Seguridad Social (IMSS), tambi\u00e9n considera positivo el cambio que se hizo al desaparecer el Seguro Popular.<\/p>\n<p>Sostiene que en un estudio del Instituto Nacional de Salud P\u00fablica, de la doctora Arantxa Colchero, que incluy\u00f3 la revisi\u00f3n a art\u00edculos cient\u00edficos se estableci\u00f3 que\u00a0no existe evidencia sobre el impacto que el Seguro Popular tuvo en la salud o la mortalidad durante su vigencia.<\/p>\n<p>Sin embargo, los entrevistados coinciden en que la implementaci\u00f3n del Insabi se hizo de forma desordenada, sin conocimiento y que, adem\u00e1s, tuvo que enfrentar una pandemia.<\/p>\n<p>(Foto de ALFREDO ESTRELLA\/AFP v\u00eda Getty Images)<\/p>\n<p>\u201cA diferencia de otras \u00e1reas de la administraci\u00f3n de L\u00f3pez Obrador, como la energ\u00e9tica, donde el gobierno entr\u00f3 con una agenda m\u00e1s perfilada para definir lo que iban a hacer, eso no sucedi\u00f3 en el sector salud\u201d, dijo Leal Fern\u00e1ndez.<\/p>\n<p>Agreg\u00f3 que \u201ccuando toman las riendas del poder, lo que empiezan a hacer es una serie de improvisaciones para proponer alternativas de pol\u00edticas. Los equipos que entran a dirigir, tanto la Secretar\u00eda de Salud, como el IMSS o el ISSSTE, no tra\u00edan una propuesta espec\u00edfica\u201d.<\/p>\n<p>Leal Fern\u00e1ndez a\u00f1ade que las autoridades de salud propusieron en ese entonces se enfoc\u00f3 m\u00e1s en las personas sin seguridad social, defendieron que no existiera el Seguro Popular, con el que se cobraban las atenciones y los medicamentos, y quer\u00edan impulsar un sistema de salud que se ocupara tambi\u00e9n de la prevenci\u00f3n, con promotores comunitarios, y no solo de la atenci\u00f3n para curar las enfermedades, pero no tra\u00edan una propuesta espec\u00edfica ni desarrollada para crear el Insabi.<\/p>\n<p>An\u00e1lisis |\u00bfHay una crisis en el sistema de salud p\u00fablica en M\u00e9xico? 6:03<\/p>\n<p>A eso habr\u00eda que agregarle, contin\u00faa, que \u201chab\u00eda diferencias en los equipos de alto nivel de las instituciones&#187;, lo que provoc\u00f3 cambios abruptos en algunos liderazgos institucionales.<\/p>\n<p>Leal Fern\u00e1ndez dijo que esto llev\u00f3 a que fuera el\u00a0propio presidente el que fuera\u00a0construyendo la agenda del sector, \u201cy eso en t\u00e9rminos de la administraci\u00f3n p\u00fablica tiene la ventaja de que es la voz presidencial, pero en t\u00e9rminos de lo que deber\u00eda ser el dise\u00f1o de una pol\u00edtica, el presidente no est\u00e1 tan informado como un equipo competente que debi\u00f3 trabajar el tema desde antes de que se tomara el poder\u201d.<\/p>\n<p>El impacto de la pandemia<\/p>\n<p>La pandemia de covid-19 fue otro gran impacto para la construcci\u00f3n del nuevo sistema de salud, por el par\u00f3n econ\u00f3mico de la vida social y la necesidad del sector de volcarse a la atenci\u00f3n de esta enfermedad, coincidieron los expertos.<\/p>\n<p>\u201cEl sector se integra de manera f\u00e1ctica para atender la pandemia y eso pospone la agenda del cambio en el sector salud hasta la constituci\u00f3n (el 31 de agosto de 2022) del OPD IMSS-Bienestar\u201d, dijo\u00a0Leal Fern\u00e1ndez.<\/p>\n<p>Miembros de una brigada de salud en Ciudad de M\u00e9xico realizan visitas casa por casa para hacer pruebas de covid-19. (Photo by PEDRO PARDO\/AFP via Getty Images)<\/p>\n<p>Por su parte,\u00a0Casta\u00f1eda se\u00f1ala que \u201cquiz\u00e1 el presidente y su equipo se hubieran dado cuenta antes de que el Insabi no funcionaba si no los hubiera distra\u00eddo el tema de la pandemia\u201d, y agrega al punto que esa transici\u00f3n, ese cambio que se estaba viviendo no ayud\u00f3, a su vez, a la respuesta a la crisis sanitaria porque no permiti\u00f3 usar el modelo que ya se ten\u00eda antes (el Seguro Popular) y que ya ten\u00eda, aun con sus errores, estabilidad y estructura financiera.<\/p>\n<p>De hecho, el Insabi desapareci\u00f3 despu\u00e9s de la pandemia y se cre\u00f3 entonces el Organismo P\u00fablico Descentralizado (OPD) IMSS-Bienestar, diferente del programa que ya operaba desde la d\u00e9cada de los 70, el IMSS-Bienestar, pero en el que el presidente L\u00f3pez Obrador se inspir\u00f3 para construir la nueva alternativa. Y as\u00ed como para atenderse en el Insabi ya no se necesita afiliaci\u00f3n, tampoco para el OPD IMSS-Bienestar, en el que solo se requiere\u00a0presentar una identificaci\u00f3n oficial y el comprobante de no estar inscrito en alguna instituci\u00f3n de seguridad social.<\/p>\n<p>CNN solicit\u00f3 una entrevista con la Secretar\u00eda de Salud para conocer su punto de vista respecto a la gesti\u00f3n del sector en esta administraci\u00f3n, pero hasta la publicaci\u00f3n de este art\u00edculo no hubo respuesta.<\/p>\n<p>A tres a\u00f1os del primer caso de covid-19 en M\u00e9xico, \u00bfafect\u00f3 la interferencia pol\u00edtica en la pandemia?<\/p>\n<p>Pero el OPD IMSS-Bienestar ya se ha implementado en 23 estados del pa\u00eds, todos gobernados por el partido Morena, el mismo de L\u00f3pez Obrador. Y aunque al principio solo inclu\u00eda un primer nivel de atenci\u00f3n (el primer contacto con el paciente que incluye centro de salud, consultorios generales y unidades de medicina familiar) y el segundo nivel (que ofrece ya servicios de atenci\u00f3n ambulatoria, especializada y de hospitalizaci\u00f3n), ya se han transferido al IMSS-Bienestar los hospitales de alta especialidad, de tercer nivel.<\/p>\n<p>El martes 9 de abril, en la conferencia de prensa de L\u00f3pez Obrador, el secretario de Salud, Jorge Alcocer Varela, dijo que se brinda atenci\u00f3n a 53.244.970 habitantes en esos 23 estados, que forman parte de este instituto y que est\u00e1 garantizado para ellos la atenci\u00f3n m\u00e9dica gratuita, universal y de calidad.<\/p>\n<p>El IMSS-Bienestar, dijo Alcocer, cuenta con &#171;11.913 centros de salud en los 23 estados para poder llevar a cabo las acciones de promoci\u00f3n de la salud, acciones deportivas, la prevenci\u00f3n de la enfermedad, la recuperaci\u00f3n y la rehabilitaci\u00f3n. En estos centros de salud, que son la entrada al sistema de salud, se cuenta con el equipamiento y medicamentos necesarios, el personal capacitado: m\u00e9dicos, enfermeras, trabajadoras sociales, sic\u00f3logos&#187;.<\/p>\n<p>En la misma conferencia, Zoe Robledo, director del IMSS y del OPD IMSS-Bienestar, dijo que la cobertura en esos estados beneficia al &#171;84.8 por ciento de quienes no tienen seguridad social a un sistema que es p\u00fablico, que es gratuito y que adem\u00e1s es uniforme\u201d.<\/p>\n<p>&#171;El IMSS-Bienestar es una buena soluci\u00f3n, por lo menos ya pensada, con estructura. No se ha terminado de implementar porque es ambiciosa, pero es una mucho mejor propuesta que el Insabi, con cambios de paradigma importantes, como dividir la promoci\u00f3n, la prevenci\u00f3n y la atenci\u00f3n de la salud, y darle un empleo estable y con prestaciones al personal de salud, que en muchos casos ten\u00eda sueldos muy dispares y empleos mal pagados\u201d, dice Casta\u00f1eda.<\/p>\n<p>Al respecto, L\u00f3pez Obrador\u00a0declar\u00f3 en la conferencia de prensa de este martes que \u201cse ha venido trabajando para garantizar al pueblo de M\u00e9xico el derecho a la salud, como lo establece el art\u00edculo 4\u00ba de nuestra Constituci\u00f3n. Es todo un desaf\u00edo y decidimos aceptar el reto. Hemos sostenido, hemos dicho, que antes de terminar nuestro mandato, esto es antes de que concluya septiembre, vamos a tener en M\u00e9xico el mejor sistema de salud p\u00fablica del mundo, aunque parezca ut\u00f3pico, incre\u00edble, fantasioso; nada de eso\u201d.<\/p>\n<p>Los puntos m\u00e1s controversiales<\/p>\n<p>Sin duda, uno de los temas m\u00e1s controversiales de este sexenio fue la eliminaci\u00f3n del Fideicomiso del Sistema de Protecci\u00f3n Social en Salud, del que depend\u00eda el Fondo de Protecci\u00f3n Contra Gastos Catastr\u00f3ficos (hoy Fondo de Salud para el Bienestar), con el que se atend\u00edan las enfermedades para la poblaci\u00f3n sin seguridad social en tiempos del Seguro Popular.<\/p>\n<p>El Fondo de Protecci\u00f3n contra Gastos Catastr\u00f3ficos \u201cproporcionaba recursos monetarios, a trav\u00e9s del fideicomiso, a los prestadores de servicios acreditados (muchos de ellos privados) y con convenios firmados con las 32 entidades federativas para la atenci\u00f3n de 66 enfermedades, entre las que destacan c\u00e1ncer o VIH\/SIDA\u201d, seg\u00fan un documento del Senado mexicano.<\/p>\n<p>Pero con el enfoque del gobierno de L\u00f3pez Obrador de no pagar a privados por los servicios de salud, se dej\u00f3 de utilizar en exclusiva este fondo para pagar la atenci\u00f3n de enfermedades de alta especialidad.<\/p>\n<p>Jorge Cano, investigador del Programa de Gasto P\u00fablico y Rendici\u00f3n de Cuentas de la organizaci\u00f3n M\u00e9xico Eval\u00faa, que monitorea, analiza\u00a0y formula recomendaciones para mejorar la gesti\u00f3n p\u00fablica, dice que en 2022 se gastaron solo 58 millones de pesos (m\u00e1s de US$ 3,5 millones al cambio actual) de este fondo para esas atenciones, 99% menos al promedio del sexenio pasado.<\/p>\n<p>AMLO y su salud: lo que no pudo ocultar el mandatario mexicano durante sus casi seis a\u00f1os de gobierno<\/p>\n<p>Cano dice que es probable que estas enfermedades se est\u00e9n atendiendo con el gasto corriente del Insabi, hoy IMSS-Bienestar. Sin embargo, esto no se puede saber porque se cambi\u00f3 la Ley de Salud y la Ley de Ingresos de la Federaci\u00f3n para permitir que la mayor parte de los recursos del fondo que no se usan se pasen a la Tesorer\u00eda de la Federaci\u00f3n (Tesofe), donde no es posible seguirles el rastro.<\/p>\n<p>Otra cuesti\u00f3n que analistas y especialistas cuestionan de\u00a0esta administraci\u00f3n es que abog\u00f3 por modificar el modelo de atenci\u00f3n para la poblaci\u00f3n sin seguridad social y no se busc\u00f3 mejorar el de la poblaci\u00f3n que est\u00e1 afiliada a una instituci\u00f3n de seguridad social como el IMSS o el Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (ISSSTE).<\/p>\n<p>\u201cUna cr\u00edtica que se le puede hacer a esta administraci\u00f3n es que se enfoc\u00f3 en implementar este IMSS-Bienestar para la gente que no tiene seguridad social, y ha dejado un poco atr\u00e1s al sistema que depende de la seguridad social, como es el IMSS y el ISSSTE, donde s\u00ed ha habido retrocesos, ha bajado la calidad de la atenci\u00f3n m\u00e9dica, hay desabasto de medicamentos, el trato a los pacientes no es el m\u00e1s adecuado y hasta la limpieza de las instalaciones es cuestionable\u201d, subraya Lira.<\/p>\n<p>(Foto: PEDRO PARDO\/AFP via Getty Images)<\/p>\n<p>Lira basa sus cuestionamientos en la Encuesta Nacional de Calidad e Impacto Gubernamental (ENCIG) del INEGI, seg\u00fan la cual la satisfacci\u00f3n con los servicios del IMSS pas\u00f3 de 52% en 2021 a 48,7% en 2023; en el ISSSTE pas\u00f3 de 51,8% en 2021 a 49,3% en 2023 y en el Insabi-IMSS Bienestar de 54,5% a 58,1%.<\/p>\n<p>Otro punto a destacar es que pese al enfoque en la poblaci\u00f3n no asegurada no se lograron acortar las brechas en cuanto a presupuesto. Judith Senyacen M\u00e9ndez, directora adjunta de Investigaci\u00f3n y especialista en salud y finanzas del Centro de Investigaci\u00f3n Econ\u00f3mica y Presupuestaria (CIEP), precisa que el \u201cgasto per c\u00e1pita para los afiliados a PEMEX es de US$ 1.944 anuales en 2024, en el ISSTE es de US$ 675, en el IMSS de US$ 562 y en IMSS-Bienestar de US$ 249\u201d. Las brechas son enormes.<\/p>\n<p>Los analistas dicen que tampoco se logr\u00f3 incrementar significativamente el presupuesto que se dedica a la salud. En 2024 aument\u00f3 5,9% en t\u00e9rminos reales respecto al monto aprobado para 2023, seg\u00fan Senyacen M\u00e9ndez. Este incremento equivale a unos US$ 3.361 millones. Tres cuartas partes de ese aumento, precisa la analista, se destinan al IMSS y una cuarta parte a la poblaci\u00f3n sin seguridad social.<\/p>\n<p>Para este \u00faltimo sector, dice M\u00e9ndez, el presupuesto total para 2024 representa apenas el 0,83% del Producto Interno Bruto (PIB), mientras que para 2016 representaba un 1,28%.<\/p>\n<p>\u201cDe acuerdo con las recomendaciones de la OCDE (Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3mico), el gasto total en salud deber\u00eda ser de 6% del PIB, as\u00ed que para la poblaci\u00f3n sin seguridad social deber\u00eda rondar al menos el 3%. Estamos muy lejos de eso\u201d, dice M\u00e9ndez.<\/p>\n<p>Aun y se usar\u00e1n los montos recomendados por la OCDE, M\u00e9xico estar\u00eda lejos del gasto de salud que hace Dinamarca, usualmente usado como referente por el presidente L\u00f3pez Obrador, y que es de 9.5% del PIB al a\u00f1o, entre los m\u00e1s altos en el mundo.<\/p>\n<p>Seg\u00fan Cano, para alcanzar el nivel que recomienda la OCDE \u201ctendr\u00edamos que estar llegando a un gasto adicional de 1,5 billones de pesos (US$ 699.334 millones) y eso se ve muy complicado ante la situaci\u00f3n de las finanzas p\u00fablicas que han estado muy debilitadas\u201d.<\/p>\n<p>N\u00fameros con claroscuros<\/p>\n<p>De acuerdo con los diversos indicadores, el balance general en el sistema de salud no es del todo positivo, por estos virajes en los modelos de atenci\u00f3n, el centrarse en la poblaci\u00f3n sin seguridad social y la pandemia de covid-19, que signific\u00f3 un reto para todos los gobiernos del mundo.<\/p>\n<p>Consultas<\/p>\n<p>De acuerdo con datos de la Direcci\u00f3n General de Informaci\u00f3n en Salud, en 2018 (antes de la llegada de L\u00f3pez Obrador a la presidencia) hubo m\u00e1s de 97,6 millones consultas externas en la Secretar\u00eda de Salud. En 2020, en plena pandemia, el n\u00famero cay\u00f3 hasta menos de la mitad, a 45,7 millones. Y para 2022, \u00faltimo dato disponible, ese n\u00famero subi\u00f3 a 51 millones, lejos a\u00fan de los datos prepandemia, con una ca\u00edda de 47,6% respecto al \u00faltimo a\u00f1o de la administraci\u00f3n anterior.<\/p>\n<p>En tanto que en el IMSS hubo casi 130 millones de consultas en 2018, de acuerdo con el reporte Radiograf\u00eda del Desabasto en M\u00e9xico 2022, de la organizaci\u00f3n Cero Desabasto. En 2020 fueron unas 90,7 millones y para 2022 se logr\u00f3 una recuperaci\u00f3n, al superar las 132,3 millones. Sin embargo, de acuerdo con la Encuesta Nacional de Calidad e Impacto Gubernamental (Encig), las consultas pueden estarse dando, pero el servicio no ser\u00eda el m\u00e1s adecuado en todos los casos.<\/p>\n<p>Seg\u00fan el colectivo, su Radiogaf\u00eda se realiz\u00f3 con base a informaci\u00f3n recopilada de pacientes, familiares y profesionales de la salud mediante plataformas propias digitales y a partir de datos p\u00fablicos obtenidos a trav\u00e9s de la Plataforma Nacional de Transparencia.<\/p>\n<p>Cirug\u00edas<\/p>\n<p>En 2018 hubo m\u00e1s de 1,3 millones de cirug\u00edas realizadas en hospitales de la Secretar\u00eda de Salud. Ese n\u00famero baj\u00f3 a 916.101 en 2020 y volvi\u00f3 a subir por arriba de los 1,1 millones en 2022, lo que muestra que aqu\u00ed tampoco hubo una recuperaci\u00f3n para la poblaci\u00f3n sin seguridad social. S\u00ed la hubo en el IMSS, donde se registraron 1,4 millones en 2018, 877.500 en 2020 y 1,8 millones en 2022.<\/p>\n<p>Medicamentos<\/p>\n<p>En cuanto al abastecimiento de medicamentos, no se ha logrado tener el 100%. Seg\u00fan el reporte de la organizaci\u00f3n Cero Desabasto, en el IMSS el n\u00famero de recetas no surtidas efectivamente (es decir negadas o parcialmente surtidas) fue de 1,4 millones en 2018, 15,8 millones en 2020 y 12,5 millones en 2022, lo que muestra que el problema no solo no se ha resuelto, sino que se fue agudizando.<\/p>\n<p>Lira matiza que\u00a0la Organizaci\u00f3n Mundial de la Salud (OMS) ha publicado reportes sobre desabastecimiento de medicamentos a nivel global. \u201cDe hecho, hoy estamos en lo que los cient\u00edficos llaman la era de la escasez de los medicamentos. Eso derivado, en gran medida, por la pandemia de covid-19, por la que se tuvieron que desviar todas las l\u00edneas de producci\u00f3n y la planeaci\u00f3n y distribuci\u00f3n de f\u00e1rmacos, lo que hasta hoy no se ha superado\u201d, dice el especialista.<\/p>\n<p>Vacunaci\u00f3n<\/p>\n<p>La cobertura de vacunaci\u00f3n tambi\u00e9n ha ca\u00eddo. De acuerdo con la Encuesta Nacional de Salud y Nutrici\u00f3n Continua (Ensanut-Continua 2022), solo el 42,6% de los ni\u00f1os y ni\u00f1as estaba con esquema completo de vacunaci\u00f3n al a\u00f1o de edad, mientras que a los dos a\u00f1os de edad eran solo el 26,6%. Aunque en este punto hay que aclarar que las coberturas en vacunaci\u00f3n han ca\u00eddo de forma importante en M\u00e9xico desde el sexenio pasado.<\/p>\n<p>Un trabajador de la salud prepara una dosis de la vacuna contra el covid-19. (Foto de PEDRO PARDO\/AFP v\u00eda Getty Images)<\/p>\n<p>De 2012 a 2018, las coberturas de vacunaci\u00f3n en ni\u00f1os de hasta un a\u00f1o cayeron de 74,2% a 19,9% y en menores de hasta 2 a\u00f1os pasaron de 77,9% a 35,3%. Sin embargo, estas coberturas tampoco han logrado recuperarse durante este sexenio.<\/p>\n<p>Ahora, a solo meses que L\u00f3pez Obrador deje la presidencisa, se reconoce que hubo avances, pero el reto que queda para la siguiente administraci\u00f3n de consolidar o reformar el nuevo sistema de salud, de acuerdo a quien gane la presidencia, es, coinciden los entrevistados, muy grande.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0El presidente Andr\u00e9s Manuel L\u00f3pez Obrador incluy\u00f3 entre los 100 compromisos de su gobierno establecer un sistema de salud de primer nivel, universal, gratuito y de calidad, con atenci\u00f3n m\u00e9dica y medicamentos gratuitos, con m\u00e9dicos generales y especialistas suficientes, con estudios diagn\u00f3sticos en los centros de salud y equipos completos para hacerlos, y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448040","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0El presidente Andr\u00e9s Manuel L\u00f3pez Obrador incluy\u00f3 entre los 100 compromisos de su gobierno establecer un sistema de salud de primer nivel, universal, gratuito y de calidad, con atenci\u00f3n m\u00e9dica y medicamentos gratuitos, con m\u00e9dicos generales y especialistas suficientes, con estudios diagn\u00f3sticos en los centros de salud y equipos completos para hacerlos, y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-12T23:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1\",\"datePublished\":\"2024-04-12T23:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/\"},\"wordCount\":3336,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/\",\"name\":\"L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-12T23:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/","og_locale":"es_ES","og_type":"article","og_title":"L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1 - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0El presidente Andr\u00e9s Manuel L\u00f3pez Obrador incluy\u00f3 entre los 100 compromisos de su gobierno establecer un sistema de salud de primer nivel, universal, gratuito y de calidad, con atenci\u00f3n m\u00e9dica y medicamentos gratuitos, con m\u00e9dicos generales y especialistas suficientes, con estudios diagn\u00f3sticos en los centros de salud y equipos completos para hacerlos, y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-12T23:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/"},"author":{"name":"","@id":""},"headline":"L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1","datePublished":"2024-04-12T23:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/"},"wordCount":3336,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/","name":"L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-12T23:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1","url":"http:\/\/noticiasya.com\/reno\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-12T23:03:41Z","datePublished":"2024-04-12T23:03:41Z","dateModified":"2024-04-12T23:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"L\\u00f3pez Obrador prometi\\u00f3 que dejar\\u00eda en M\\u00e9xico \\u201cel mejor sistema de salud p\\u00fablica del mundo\\u201d; algunos dudan si cumplir\\u00e1\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/12\\\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/12\\\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-12T23:03:41Z\",\"datePublished\":\"2024-04-12T23:03:41Z\",\"dateModified\":\"2024-04-12T23:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442736,"url":"https:\/\/noticiasya.com\/reno\/2023\/12\/27\/el-gobierno-de-lopez-obrador-alista-su-megafarmacia-un-plan-que-genera-dudas-entre-especialistas\/","url_meta":{"origin":1448040,"position":0},"title":"El Gobierno de L\u00f3pez Obrador alista su \u201cmegafarmacia\u201d, un plan que genera dudas entre especialistas","author":"","date":"diciembre 27, 2023","format":false,"excerpt":"(CNN en Espa\u00f1ol) --\u00a0El Gobierno de M\u00e9xico se prepara para inaugurar una \u201cmegafarmacia\u201d que, seg\u00fan el presidente Andr\u00e9s Manuel L\u00f3pez Obrador, contar\u00e1 con todos los medicamentos existentes y podr\u00e1 surtir en 24 horas a las instituciones p\u00fablicas de salud que lo requieran. Sin embargo, el plan genera dudas entre especialistas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453151,"url":"https:\/\/noticiasya.com\/reno\/2024\/09\/27\/como-esta-mexico-lopez-obrador-indicadores-balance-orix\/","url_meta":{"origin":1448040,"position":1},"title":"AN\u00c1LISIS | \u00bfMejor\u00f3 M\u00e9xico con L\u00f3pez Obrador? Estos indicadores sugieren resultados mixtos","author":"","date":"septiembre 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Est\u00e1 por concluir el Gobierno del presidente Andr\u00e9s Manuel L\u00f3pez Obrador en M\u00e9xico. Se trata de un pol\u00edtico que busc\u00f3 el cargo en tres ocasiones \u20142006, 2012 y 2018 (cuando finalmente gan\u00f3)\u2014 y una de las figuras p\u00fablicas m\u00e1s relevantes en la historia reciente del pa\u00eds.L\u00f3pez Obrador\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448009,"url":"https:\/\/noticiasya.com\/reno\/2024\/04\/11\/propuestas-de-xochitl-galvez-en-materia-de-salud-como-candidata-a-presidenta-de-mexico-orix\/","url_meta":{"origin":1448040,"position":2},"title":"Las principales propuestas de X\u00f3chitl G\u00e1lvez en materia de salud como candidata a presidenta de M\u00e9xico","author":"","date":"abril 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \u00a0X\u00f3chitl G\u00e1lvez, candidata presidencial de la coalici\u00f3n Fuerza y Coraz\u00f3n por M\u00e9xico, integrada por los partidos Revolucionario Institucional (PRI), Acci\u00f3n Nacional (PAN) y el de la Revoluci\u00f3n Democr\u00e1tica (PRD), plantea como parte de su campa\u00f1a nueve ejes en materia de salud.G\u00e1lvez afirma en uno de sus spots\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447504,"url":"https:\/\/noticiasya.com\/reno\/2024\/03\/28\/amlo-lopez-obrador-argentinos-orix\/","url_meta":{"origin":1448040,"position":3},"title":"AMLO &#171;abraza&#187; a Petro y ataca a Milei: &#171;No comprendo c\u00f3mo los argentinos votaron por alguien que desprecia al pueblo&#187;","author":"","date":"marzo 28, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La respuesta del presidente de M\u00e9xico, Andres Manuel L\u00f3pez Obrador, al mandatario argentino, Javier Milei, luego de que este lo llamara \"ignorante\" en una entrevista con CNN en Espa\u00f1ol no tard\u00f3 en llegar.A falta de su conferencia de prensa matutina habitual, L\u00f3pez Obrador recurri\u00f3 a publicar en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447643,"url":"https:\/\/noticiasya.com\/reno\/2024\/04\/02\/controversias-periodismo-amlo-arremete-presentador-cnn-entrevisto-milei-orix\/","url_meta":{"origin":1448040,"position":4},"title":"En medio de sus controversias con el periodismo, AMLO arremete contra presentador de CNN que entrevist\u00f3 a Milei","author":"","date":"abril 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 Despu\u00e9s de las m\u00faltiples controversias y choques que tuvo con periodistas y medios, este lunes el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, arremeti\u00f3 contra Andr\u00e9s Oppenheimer, presentador de CNN, por la pol\u00e9mica que se abri\u00f3 tras las cr\u00edticas que le dedic\u00f3 su par de Argentina, Javier\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447498,"url":"https:\/\/noticiasya.com\/reno\/2024\/03\/28\/milei-amlo-xochitl-galvez-claudia-sheinbaum-orix\/","url_meta":{"origin":1448040,"position":5},"title":"X\u00f3chitl G\u00e1lvez y Claudia Sheinbaum responden a Milei luego de que llamara &#171;ignorante&#187; a AMLO","author":"","date":"marzo 28, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, fue objeto de duras palabras del mandatario de Argentina, Javier Milei. En entrevista con Andr\u00e9s Oppenheimer para CNN, el gobernante argentino llam\u00f3 a su hom\u00f3logo mexicano un \"ignorante\". El tema lleg\u00f3 a la campa\u00f1a presidencial: tanto la candidata oficialista\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1448040"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448040\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1448040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1448040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1448040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}