{"id":1448044,"date":"2024-04-12T18:03:43","date_gmt":"2024-04-13T01:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/"},"modified":"2024-04-12T18:03:43","modified_gmt":"2024-04-13T01:03:43","slug":"javier-milei-elon-musk-intereses-detras-encuentro-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/","title":{"rendered":"Javier Milei y Elon Musk cara a cara: los intereses detr\u00e1s el encuentro"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0Javier Milei y Elon Musk tuvieron finalmente su selfie time en la f\u00e1brica de Tesla, en Austin, Texas, este viernes durante la gira del presidente argentino en Estados Unidos, donde tambi\u00e9n recibi\u00f3 la distinci\u00f3n de la comunidad jud\u00eda de \u201cEmbajador internacional de la luz\u201d.<\/p>\n<p>\u201c\u00a1Por un futuro apasionante e inspirador!\u201d, tuite\u00f3 el magnate sobre una foto de ambos, los pulgares arriba, la futurista Giga Tesla espejada detr\u00e1s.<\/p>\n<p>Si bien es la primera vez que se ven cara a cara, Milei y Musk vienen coqueteando hace rato entre tweets, likes, retweets y alguna llamada telef\u00f3nica en la que se prometieron esta cita.<\/p>\n<p>El presidente de Argentina, Javier Milei, se re\u00fane con Elon Musk en Texas; hablaron sobre la necesidad del libre mercado<\/p>\n<p>Durante la visita, que tambi\u00e9n tuvo su momento de reuni\u00f3n en una mesa de trabajo, el mandatario argentino estuvo acompa\u00f1ado por su hermana Karina Milei, tambi\u00e9n secretaria de la Presidencia, el embajador argentino en EE.UU. Gerardo Werthein, el rabino y gu\u00eda espiritual Axel Wanish y el emprendedor Patricio Fuks.<\/p>\n<p>Seg\u00fan el comunicado de prensa que difundieron desde la presidencia de Argentina, Milei y Musk conversaron de \u201cla necesidad de liberar los mercados y defender las ideas de la libertad\u201d, as\u00ed como tambi\u00e9n \u201celiminar trabas burocr\u00e1ticas que alejan a los inversores\u201d.<\/p>\n<p>Por su parte, el presidente argentino reconoci\u00f3 el rol de los emprendedores y el empresario manifest\u00f3 su compromiso con las ideas de la libertad y los gobiernos promercados.<\/p>\n<p>Adem\u00e1s, siempre seg\u00fan la informaci\u00f3n oficial, Musk hizo \u201chincapi\u00e9 en fomentar la tasa de natalidad en el mundo, haciendo \u00e9nfasis en que la falta de crecimiento de la poblaci\u00f3n puede ser terminal para nuestra civilizaci\u00f3n\u201d.<\/p>\n<p>VIVA LA LIBERTAD CARAJO pic.twitter.com\/uNt7LIs3ja<br \/>\n\u2014 Javier Milei (@JMilei) April 12, 2024<\/p>\n<p>El desembarco de Starlink<\/p>\n<p>En febrero de 2024, el Ente Nacional de Comunicaciones (Enacom) autoriz\u00f3 la llegada de Starlink a Argentina y desde abril el servicio comenz\u00f3 a comercializarse en el pa\u00eds.<\/p>\n<p>Meses atr\u00e1s, en uno de sus primeros anuncios como presidente, el l\u00edder de La Libertad Avanza le hizo su primer gran gui\u00f1o al empresario multimillonario al mencionar a Starlink como una empresa favorecida por las desregulaciones que se propon\u00edan en su gesti\u00f3n.<\/p>\n<p>Sin embargo, la compa\u00f1\u00eda de internet satelital ya ten\u00eda habilitaci\u00f3n para operar desde el a\u00f1o 2020. De hecho, en 2022 se inscribi\u00f3 como sociedad ante la Inspecci\u00f3n General de Justicia (IGJ).<\/p>\n<p>El hecho de que Milei nombrara a la compa\u00f1\u00eda, que no se encontraba en la letra del decreto al que se hac\u00eda referencia entonces, llam\u00f3 la atenci\u00f3n. Algunos analistas coinciden en que pudo haber sido una maniobra de distracci\u00f3n o incluso publicitaria.<\/p>\n<p>\u00bfPor qu\u00e9 Elon Musk apoya a Javier Milei en Argentina? Simpat\u00eda por la ultraderecha y\u00a0litio para bater\u00edas, hip\u00f3tesis de especialistas<\/p>\n<p>La cuesti\u00f3n del oro blanco<\/p>\n<p>Argentina tiene grandes reservas de litio, un mineral clave en el futuro de Tesla. De hecho, esa es una de las hip\u00f3tesis de los analistas que comentan la cercan\u00eda ente Musk y Milei.<\/p>\n<p>Junto a sus vecinos Bolivia y Chile, Argentina conforma el famoso \u201ctri\u00e1ngulo del litio\u201d, una regi\u00f3n que contiene m\u00e1s del 50% de las provisiones globales de este recurso, seg\u00fan un informe reciente del Centro Nacional de Informaci\u00f3n sobre Minerales del Servicio Geol\u00f3gico de Estados Unidos.<\/p>\n<p>Solo Argentina tiene 20 millones de toneladas de oro blanco -como se le llama al mineral- y su legislaci\u00f3n en materia de extracci\u00f3n es la m\u00e1s laxa para capitales extranjeros que la de sus pa\u00edses vecinos.<\/p>\n<p>Tesla, la compa\u00f1\u00eda de autos el\u00e9ctricos de Elon Musk, ha expresado su inter\u00e9s por este recurso preciado para la fabricaci\u00f3n de bater\u00edas. De hecho, en mayo de 2023 la empresa anunci\u00f3 el inicio de la construcci\u00f3n de una refiner\u00eda interna para procesar esa materia prima.<\/p>\n<p>Si bien no hubo ning\u00fan anuncio tras el encuentro en la Giga Tesla, tanto el presidente argentino como el due\u00f1o de \u201cX\u201d coincidieron en \u201cla importancia del desarrollo tecnol\u00f3gico para el progreso de la humanidad y en la necesidad de establecer reglas de juego claras y estables para poder traer empresas que fomenten este desarrollo\u201d.<\/p>\n<p>Una afinidad atravesada por la misma narrativa pol\u00edtica<\/p>\n<p>La afinidad entre Javier Milei y Elon Musk va m\u00e1s all\u00e1 del internet satelital, el litio y cualquier otra alianza econ\u00f3mica que puedan trazar.<\/p>\n<p>Ambos tienen un idioma com\u00fan. Aunque Milei no hable ingl\u00e9s ni Musk castellano, el ida y vuelta entre ellos fluye naturalmente en \u201cX\u201d, antes Twitter.<\/p>\n<p>Adem\u00e1s, los dos predican lo que llaman \u201clas ideas de la libertad\u201d y comparten el rechazo al progresismo y la izquierda.<\/p>\n<p>Tambi\u00e9n comparten proximidad con algunos l\u00edderes globales como Donald Trump, a quien Musk devolvi\u00f3 su usuario de \u201cX\u201d cuando se convirti\u00f3 en due\u00f1o de la red social, cuenta que hab\u00eda sido inhabilitada por violar las normas contra la incitaci\u00f3n a la violencia en el marco del atentado al Capitolio de Estados Unidos en 2021.<\/p>\n<p>En ese mismo espacio, el due\u00f1o de SpaceX celebr\u00f3 la victoria electoral del entonces candidato Milei como la llegada de \u201cla prosperidad para Argentina\u201d. Tambi\u00e9n, apoy\u00f3 su disertaci\u00f3n en el foro Davos con una imagen de contenido sexual expl\u00edcito ilustrando el placer de Musk al escuchar a Milei frente a empresarios del mundo. Ese Tweet fue a la vez retuiteado por el hijo de Trump.<\/p>\n<p>Milei invit\u00f3 a Musk a su asunci\u00f3n. Pero aunque el due\u00f1o de Tesla no pudo asistir, le prometi\u00f3 al mandatario argentino visitar Argentina este a\u00f1o, seg\u00fan dijo Milei en ese entonces.<\/p>\n<p>Despu\u00e9s del encuentro de este viernes, seg\u00fan el comunicado de la presidencia, Milei y Musk \u201cacordaron realizar pr\u00f3ximamente un gran evento en la Argentina para fomentar las ideas de la libertad\u201d.<\/p>\n<p>Con informaci\u00f3n de Sof\u00eda Benavides, Gonzalo Zegarra, Iv\u00e1n P\u00e9rez Sarmenti y Aleja P\u00e1ez<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0Javier Milei y Elon Musk tuvieron finalmente su selfie time en la f\u00e1brica de Tesla, en Austin, Texas, este viernes durante la gira del presidente argentino en Estados Unidos, donde tambi\u00e9n recibi\u00f3 la distinci\u00f3n de la comunidad jud\u00eda de \u201cEmbajador internacional de la luz\u201d. \u201c\u00a1Por un futuro apasionante e inspirador!\u201d, tuite\u00f3 el magnate [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448044","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Javier Milei y Elon Musk cara a cara: los intereses detr\u00e1s el encuentro - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Javier Milei y Elon Musk cara a cara: los intereses detr\u00e1s el encuentro - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0Javier Milei y Elon Musk tuvieron finalmente su selfie time en la f\u00e1brica de Tesla, en Austin, Texas, este viernes durante la gira del presidente argentino en Estados Unidos, donde tambi\u00e9n recibi\u00f3 la distinci\u00f3n de la comunidad jud\u00eda de \u201cEmbajador internacional de la luz\u201d. \u201c\u00a1Por un futuro apasionante e inspirador!\u201d, tuite\u00f3 el magnate [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-13T01:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Javier Milei y Elon Musk cara a cara: los intereses detr\u00e1s el encuentro\",\"datePublished\":\"2024-04-13T01:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/\"},\"wordCount\":1063,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/\",\"name\":\"Javier Milei y Elon Musk cara a cara: los intereses detr\u00e1s el encuentro - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-13T01:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Javier Milei y Elon Musk cara a cara: los intereses detr\u00e1s el encuentro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Javier Milei y Elon Musk cara a cara: los intereses detr\u00e1s el encuentro - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Javier Milei y Elon Musk cara a cara: los intereses detr\u00e1s el encuentro - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0Javier Milei y Elon Musk tuvieron finalmente su selfie time en la f\u00e1brica de Tesla, en Austin, Texas, este viernes durante la gira del presidente argentino en Estados Unidos, donde tambi\u00e9n recibi\u00f3 la distinci\u00f3n de la comunidad jud\u00eda de \u201cEmbajador internacional de la luz\u201d. \u201c\u00a1Por un futuro apasionante e inspirador!\u201d, tuite\u00f3 el magnate [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-13T01:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/"},"author":{"name":"","@id":""},"headline":"Javier Milei y Elon Musk cara a cara: los intereses detr\u00e1s el encuentro","datePublished":"2024-04-13T01:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/"},"wordCount":1063,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/","name":"Javier Milei y Elon Musk cara a cara: los intereses detr\u00e1s el encuentro - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-13T01:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Javier Milei y Elon Musk cara a cara: los intereses detr\u00e1s el encuentro"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Javier Milei y Elon Musk cara a cara: los intereses detr\u00e1s el encuentro","url":"http:\/\/noticiasya.com\/reno\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2024\/04\/12\/javier-milei-elon-musk-intereses-detras-encuentro-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-13T01:03:43Z","datePublished":"2024-04-13T01:03:43Z","dateModified":"2024-04-13T01:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Javier Milei y Elon Musk cara a cara: los intereses detr\\u00e1s el encuentro\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/12\\\/javier-milei-elon-musk-intereses-detras-encuentro-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/12\\\/javier-milei-elon-musk-intereses-detras-encuentro-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-13T01:03:43Z\",\"datePublished\":\"2024-04-13T01:03:43Z\",\"dateModified\":\"2024-04-13T01:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448039,"url":"https:\/\/noticiasya.com\/reno\/2024\/04\/12\/javier-milei-argentina-reune-elon-musk-orix\/","url_meta":{"origin":1448044,"position":0},"title":"El presidente de Argentina, Javier Milei, se re\u00fane con Elon Musk en Texas","author":"","date":"abril 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 Tras haberse reunido con el empresario Elon Musk en Austin, Texas, el presidente de Argentina, Javier Milei, comparti\u00f3 este viernes una imagen con el due\u00f1o de Tesla.Tanto Milei como Musk compartieron las im\u00e1genes en sus respectivos perfiles de X, la red social cuyo due\u00f1o es el multimillonario\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458875,"url":"https:\/\/noticiasya.com\/reno\/2025\/02\/18\/javier-milei-reunion-elon-musk-esta-semana-trax\/","url_meta":{"origin":1448044,"position":1},"title":"Javier Milei se reunir\u00e1 con Elon Musk esta semana","author":"","date":"febrero 18, 2025","format":false,"excerpt":"El presidente de Argentina, Javier Milei, se reunir\u00e1 con Elon Musk en Washington el jueves, seg\u00fan el portavoz de Milei, Manuel Adorni.El mandatario argentino tambi\u00e9n se reunir\u00e1 con la directora gerente del Fondo Monetario Internacional (FMI), Kristalina Georgieva, y el s\u00e1bado se espera que asista a la Conferencia de Acci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449827,"url":"https:\/\/noticiasya.com\/reno\/2024\/05\/29\/milei-openai-encuentros-gigantes-tecnologicas-ee-uu-orix\/","url_meta":{"origin":1448044,"position":2},"title":"Milei inaugura con OpenAI una serie de encuentros con gigantes tecnol\u00f3gicas de EE.UU.","author":"","date":"mayo 29, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Argentina, Javier Milei, inici\u00f3 este martes durante su viaje a Estados Unidos una serie de encuentros que esta semana sostendr\u00e1 con directivos de gigantes tecnol\u00f3gicas.La primera reuni\u00f3n fue con el CEO de OpenAI, Sam Altman, con quien Milei dijo en su cuenta de X\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459129,"url":"https:\/\/noticiasya.com\/reno\/2025\/02\/24\/elon-musk-trump-y-el-fmi-lo-que-dejo-el-viaje-de-milei-a-los-estados-unidos\/","url_meta":{"origin":1448044,"position":3},"title":"Elon Musk, Trump y el FMI: lo que dej\u00f3 el viaje de Milei a Estados Unidos","author":"","date":"febrero 24, 2025","format":false,"excerpt":"Jaime Rosemberg, columnista y periodista de CNN Radio Argentina, convers\u00f3 este lunes con el equipo de Los Primeros de la Tarde sobre las repercusiones del viaje del presidente Javier Milei y la comitiva oficial a los Estados Unidos en medio del esc\u00e1ndalo del gobierno con la cripto $LIBRA.\u201cTuvo el respaldo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458081,"url":"https:\/\/noticiasya.com\/reno\/2025\/01\/31\/julio-burdman-politologo-la-popularidad-de-milei-esta-robusta\/","url_meta":{"origin":1448044,"position":4},"title":"Julio Burdman, polit\u00f3logo: &#171;La popularidad de Milei est\u00e1 robusta&#187;","author":"","date":"enero 31, 2025","format":false,"excerpt":"El polit\u00f3logo Julio Burdman, director del Observatorio Electoral, habl\u00f3 este viernes en CNN Radio del impacto del informe de su consultora realizado entre el 19 de febrero y el 25 de enero sobre la imagen y popularidad de Javier Milei, Donald Trump y el empresario Elon Musk.Seg\u00fan arroja el informe,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452509,"url":"https:\/\/noticiasya.com\/reno\/2024\/09\/07\/cuales-son-intereses-elon-musk-america-latina-orix\/","url_meta":{"origin":1448044,"position":5},"title":"\u00bfCu\u00e1les son los intereses de Elon Musk en Am\u00e9rica Latina?","author":"","date":"septiembre 7, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El multimillonario Elon Musk, due\u00f1o de X y otras empresas, dedica buena parte de su actividad en redes sociales a lo que sucede en Am\u00e9rica Latina. En los \u00faltimos d\u00edas ha publicado varios mensajes sobre la suspensi\u00f3n de la red social de su propiedad en Brasil, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1448044"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448044\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1448044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1448044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1448044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}