{"id":1448139,"date":"2024-04-15T17:03:46","date_gmt":"2024-04-16T00:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/"},"modified":"2024-04-15T17:03:46","modified_gmt":"2024-04-16T00:03:46","slug":"encuentran-20-cuerpos-descomposicion-barco-brasil-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/","title":{"rendered":"Encuentran al menos 20 cuerpos en descomposici\u00f3n en un barco frente a las costas de Brasil"},"content":{"rendered":"<p>(CNN) \u2013\u2013 Al menos 20 cuerpos en grave estado de descomposici\u00f3n se encontraron en un barco frente a la costa del noreste de Brasil, informaron las autoridades.<\/p>\n<p>La embarcaci\u00f3n fue hallada en la costa de Bragan\u00e7a, al noreste de Par\u00e1, el 13 de abril, asegur\u00f3 el domingo el Ministerio P\u00fablico Federal de Brasil.<\/p>\n<p>Desde entonces se han abierto dos investigaciones.<\/p>\n<p>Las autoridades explicaron que se hab\u00edan encontrado al menos 20 cuerpos en el barco, pero debido a la descomposici\u00f3n de los restos se desconoce cu\u00e1ntos murieron en la embarcaci\u00f3n.<\/p>\n<p>Se cree que los fallecidos no son de Brasil sino posiblemente del Caribe, dijeron los investigadores a CNN Brasil.<\/p>\n<p>Las autoridades locales aseguran que no ha habido informes recientes de brasile\u00f1os desaparecidos.<\/p>\n<p>La polic\u00eda se despleg\u00f3 en el puerto de Vila do Castelo en Braganca, Brasil, el 14 de abril, despu\u00e9s de que los pescadores informaron haber visto un barco cargado con cad\u00e1veres en descomposici\u00f3n frente a la costa del estado de Par\u00e1 el s\u00e1bado. (Raimundo Pacco\/AP)<\/p>\n<p>Noticia en desarrollo&#8230;<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 Al menos 20 cuerpos en grave estado de descomposici\u00f3n se encontraron en un barco frente a la costa del noreste de Brasil, informaron las autoridades. La embarcaci\u00f3n fue hallada en la costa de Bragan\u00e7a, al noreste de Par\u00e1, el 13 de abril, asegur\u00f3 el domingo el Ministerio P\u00fablico Federal de Brasil. Desde entonces [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448139","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Encuentran al menos 20 cuerpos en descomposici\u00f3n en un barco frente a las costas de Brasil - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encuentran al menos 20 cuerpos en descomposici\u00f3n en un barco frente a las costas de Brasil - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 Al menos 20 cuerpos en grave estado de descomposici\u00f3n se encontraron en un barco frente a la costa del noreste de Brasil, informaron las autoridades. La embarcaci\u00f3n fue hallada en la costa de Bragan\u00e7a, al noreste de Par\u00e1, el 13 de abril, asegur\u00f3 el domingo el Ministerio P\u00fablico Federal de Brasil. Desde entonces [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T00:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Encuentran al menos 20 cuerpos en descomposici\u00f3n en un barco frente a las costas de Brasil\",\"datePublished\":\"2024-04-16T00:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/\"},\"wordCount\":211,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/\",\"name\":\"Encuentran al menos 20 cuerpos en descomposici\u00f3n en un barco frente a las costas de Brasil - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-16T00:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encuentran al menos 20 cuerpos en descomposici\u00f3n en un barco frente a las costas de Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encuentran al menos 20 cuerpos en descomposici\u00f3n en un barco frente a las costas de Brasil - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Encuentran al menos 20 cuerpos en descomposici\u00f3n en un barco frente a las costas de Brasil - Noticias","og_description":"(CNN) \u2013\u2013 Al menos 20 cuerpos en grave estado de descomposici\u00f3n se encontraron en un barco frente a la costa del noreste de Brasil, informaron las autoridades. La embarcaci\u00f3n fue hallada en la costa de Bragan\u00e7a, al noreste de Par\u00e1, el 13 de abril, asegur\u00f3 el domingo el Ministerio P\u00fablico Federal de Brasil. Desde entonces [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-16T00:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/"},"author":{"name":"","@id":""},"headline":"Encuentran al menos 20 cuerpos en descomposici\u00f3n en un barco frente a las costas de Brasil","datePublished":"2024-04-16T00:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/"},"wordCount":211,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/","name":"Encuentran al menos 20 cuerpos en descomposici\u00f3n en un barco frente a las costas de Brasil - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-16T00:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Encuentran al menos 20 cuerpos en descomposici\u00f3n en un barco frente a las costas de Brasil"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Encuentran al menos 20 cuerpos en descomposici\u00f3n en un barco frente a las costas de Brasil","url":"http:\/\/noticiasya.com\/reno\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2024\/04\/15\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-16T00:03:46Z","datePublished":"2024-04-16T00:03:46Z","dateModified":"2024-04-16T00:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Encuentran al menos 20 cuerpos en descomposici\\u00f3n en un barco frente a las costas de Brasil\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/15\\\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/15\\\/encuentran-20-cuerpos-descomposicion-barco-brasil-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-16T00:03:46Z\",\"datePublished\":\"2024-04-16T00:03:46Z\",\"dateModified\":\"2024-04-16T00:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448208,"url":"https:\/\/noticiasya.com\/reno\/2024\/04\/17\/policia-brasil-mujer-hombre-muerto-banco-retirar-prestamo-trax\/","url_meta":{"origin":1448139,"position":0},"title":"La polic\u00eda de Brasil detiene a una mujer sospechosa de llevar a un hombre muerto al banco para retirar un pr\u00e9stamo","author":"","date":"abril 17, 2024","format":false,"excerpt":"(CNN) -- La polic\u00eda de Brasil detuvo a una mujer sospechosa de llevar a un banco a un hombre muerto, que seg\u00fan ella era su t\u00edo, para retirar un pr\u00e9stamo de cuatro cifras.Las im\u00e1genes del encuentro de la mujer con el banco causaron un debate nacional en Brasil tras hacerse\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450887,"url":"https:\/\/noticiasya.com\/reno\/2024\/07\/04\/89-muertos-naufragio-migrantes-mauritania-trax\/","url_meta":{"origin":1448139,"position":1},"title":"Al menos 89 personas mueren tras naufragio con migrantes en la costa de Mauritania","author":"","date":"julio 4, 2024","format":false,"excerpt":"(CNN) -- Al menos 89 inmigrantes murieron cuando su barco naufrag\u00f3 frente a las costas de Mauritania el lunes, inform\u00f3 este jueves la agencia de noticias estatal mauritana.Los guardacostas mauritanos recuperaron los cuerpos de los migrantes que se encontraban a bordo de un gran barco pesquero tradicional cuando volc\u00f3, seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449785,"url":"https:\/\/noticiasya.com\/reno\/2024\/05\/27\/recuperan-cuerpos-ejercito-guerrillas-caqueta-colombia-orix\/","url_meta":{"origin":1448139,"position":2},"title":"Gobernador del Caquet\u00e1, Colombia, afirma que han recuperado al menos 11 cad\u00e1veres por enfrentamientos entre el Ej\u00e9rcito colombiano y disidencias de la guerrilla","author":"","date":"mayo 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El gobernador del departamento del Caquet\u00e1, Colombia, Luis Francisco Ruiz Aguilar, dijo este lunes en una entrevista con Noticias Caracol que las autoridades han recuperado al menos 11 cad\u00e1veres debido a los enfrentamientos este fin de semana en la regi\u00f3n entre el Ej\u00e9rcito colombiano y presuntas disidencias de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452037,"url":"https:\/\/noticiasya.com\/reno\/2024\/08\/21\/localizan-cuatro-cuerpos-busqueda-desaparecidos-superyate-bayesian-hundido-trax\/","url_meta":{"origin":1448139,"position":3},"title":"Localizan cuatro cuerpos en la b\u00fasqueda de los desaparecidos del superyate Bayesian hundido en Sicilia","author":"","date":"agosto 21, 2024","format":false,"excerpt":"Porticello, Italia (CNN) -- Cuatro cuerpos fueron encontrados por buzos el mi\u00e9rcoles mientras los rescatistas buscan a los desaparecidos del superyate \"Bayesian\", que se hundi\u00f3 frente a la costa de Sicilia a principios de esta semana.Un equipo de CNN sobre el terreno vio el mi\u00e9rcoles a las autoridades italianas trasladar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448525,"url":"https:\/\/noticiasya.com\/reno\/2024\/04\/25\/casi-400-cadaveres-fosas-hospital-nasser-gaza-khan-younis-trax\/","url_meta":{"origin":1448139,"position":4},"title":"Casi 400 cad\u00e1veres fueron encontrados en la fosa com\u00fan de un hospital de Gaza, dice la Defensa Civil Palestina","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN) -- Las autoridades de Gaza concluyeron su b\u00fasqueda de fosas comunes en un hospital en el sur de Gaza y dijeron que descubrieron un total de 392 cad\u00e1veres, incluidos algunos que todav\u00eda llevaban batas quir\u00fargicas.En una conferencia de prensa el jueves, un funcionario de la Defensa Civil Palestina en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447835,"url":"https:\/\/noticiasya.com\/reno\/2024\/04\/07\/bahamas-intercepta-barco-inmigrantes-haitianos-trax\/","url_meta":{"origin":1448139,"position":5},"title":"Bahamas intercept\u00f3 barco con 257 inmigrantes haitianos","author":"","date":"abril 7, 2024","format":false,"excerpt":"(CNN) -- Las Fuerzas Reales de Defensa de las Bahamas (RBDF, por sus siglas en ingl\u00e9s) detuvieron este domingo a 257 inmigrantes haitianos que viajaban en barco, en lo que las autoridades llamaron una \"operaci\u00f3n de tr\u00e1fico de inmigrantes a gran escala\", seg\u00fan un comunicado.El barco fue interceptado a 39\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1448139"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448139\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1448139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1448139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1448139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}