{"id":1448140,"date":"2024-04-15T17:03:46","date_gmt":"2024-04-16T00:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/"},"modified":"2024-04-15T17:03:46","modified_gmt":"2024-04-16T00:03:46","slug":"ventas-iphone-caen-razon-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/","title":{"rendered":"Las ventas de iPhone est\u00e1n cayendo. Esta es la raz\u00f3n"},"content":{"rendered":"<p>(CNN) &#8212; Las ventas de tel\u00e9fonos inteligentes de Apple cayeron un 10% el \u00faltimo trimestre, seg\u00fan la firma de investigaci\u00f3n de mercado IDC, ya que las ventas en China cayeron dr\u00e1sticamente.<\/p>\n<p>La compa\u00f1\u00eda ha perdido impulso en China debido a que el nacionalismo, una econom\u00eda dif\u00edcil y una mayor competencia han perjudicado a Apple en los \u00faltimos meses.<\/p>\n<p>&#171;Es una ca\u00edda pronunciada para Apple, pero si piensas en d\u00f3nde hemos estado en los \u00faltimos cuatro a\u00f1os, Apple probablemente ha sido la marca m\u00e1s resistente, ya que super\u00f3 problemas de la cadena de suministro y desaf\u00edos macroecon\u00f3micos, m\u00e1s que otras marcas&#187;, dijo Nabila Popal, directora de investigaci\u00f3n de IDC, a CNN.<\/p>\n<p>Samsung ha sido el principal fabricante de smartphones durante los \u00faltimos 12 a\u00f1os. Apple se llev\u00f3 la corona el a\u00f1o pasado, pero solo durante un trimestre, ya que Samsung recuper\u00f3 el lugar.<\/p>\n<p>El Departamento de Justicia de EE.UU. demanda a Apple. Estas son las razones<\/p>\n<p>&#171;Tambi\u00e9n es muy significativo que Samsung haya vuelto a estar en la cima&#187;, afirm\u00f3 Popal. &#171;Este a\u00f1o, esperamos que Android crezca al doble del ritmo de iOS&#187;. (Android es el sistema operativo utilizado por los sistemas Samsung, mientras que los iPhone usan iOS).<\/p>\n<p>Esto se debe a que Android tuvo un fuerte declive en los \u00faltimos a\u00f1os, por lo que ahora tiene m\u00e1s espacio para crecer. Tanto Apple como Samsung no respondieron a una solicitud de comentarios.<\/p>\n<p>En general, IDC dijo que los env\u00edos mundiales de tel\u00e9fonos inteligentes aumentaron un 7,8% a\u00f1o tras a\u00f1o a aproximadamente 289 millones de dispositivos en el primer trimestre de 2024, lo que indica que el mercado de tel\u00e9fonos inteligentes est\u00e1 resurgiendo despu\u00e9s de dos a\u00f1os de desaf\u00edos macroecon\u00f3micos.<\/p>\n<p>Apple enfrenta la competencia de Huawei en China<\/p>\n<p>Samsung ocup\u00f3 aproximadamente el 20,8% de la participaci\u00f3n de mercado (o 60,1 millones de env\u00edos) durante el trimestre, seguido de Apple con el 17,3% (50,1 millones de env\u00edos). El fabricante chino Xiaomi represent\u00f3 el 14,1% (40,8 millones de env\u00edos).<\/p>\n<p>En diciembre, Apple super\u00f3 a Samsung como empresa de mayor desempe\u00f1o en la categor\u00eda de tel\u00e9fonos inteligentes, y le puso fin a los 12 a\u00f1os de trayectoria de Samsung en la cima, con una participaci\u00f3n de mercado del 20% (en comparaci\u00f3n con la participaci\u00f3n de mercado del 19,4% de Samsung).<\/p>\n<p>Los nuevos tel\u00e9fonos modelo Galaxy S24 Ultra de Samsung que ofrecen funciones de inteligencia artificial exhibidos en el evento Galaxy Unpacked en San Jos\u00e9, California, EE.UU., el 17 de enero de 2024. Cr\u00e9dito: Loren Elliott\/Reuters.<\/p>\n<p>Aunque IDC dijo en su \u00faltimo informe que espera que Apple y Samsung mantengan su control en el mercado, es probable que contin\u00fae el resurgimiento de Huawei y otras empresas en China, incluidas Xiaomi y OPPO\/OnePlus. Los consumidores chinos que alguna vez habr\u00edan considerado a Apple ahora est\u00e1n recurriendo a marcas nacionales en China.<\/p>\n<p>China sigue siendo un mercado importante para Apple, ya que es el mercado m\u00e1s grande detr\u00e1s de Estados Unidos. La empresa sigue ofreciendo descuentos en China para ayudar a impulsar las ventas.<\/p>\n<p>El a\u00f1o pasado, el popular tel\u00e9fono inteligente Mate 60 de Huawei fue noticia cuando el gobierno de EE.UU. busc\u00f3 m\u00e1s informaci\u00f3n sobre el modelo Pro, que inclu\u00eda un procesador sofisticado. Su debut sorprendi\u00f3 a los expertos de la industria que cuestionaron c\u00f3mo la compa\u00f1\u00eda podr\u00eda fabricar un chip de este tipo luego de los amplios esfuerzos de Estados Unidos para restringir el acceso de China a la tecnolog\u00eda extranjera de chips debido a lo que percib\u00edan como preocupaciones de seguridad nacional.<\/p>\n<p>Samsung o Apple, \u00bfcu\u00e1l es el mejor tel\u00e9fono m\u00f3vil para 2024?<\/p>\n<p>Popal tambi\u00e9n se\u00f1al\u00f3 que Apple no ha articulado un mensaje contundente sobre la inteligencia artificial, en un momento en que muchas empresas de tecnolog\u00eda est\u00e1n aplicando estrategias y caracter\u00edsticas relacionadas.<\/p>\n<p>&#171;Esperamos escuchar algunos mensajes sobre esto en su conferencia de desarrolladores de junio&#187;, dijo. &#171;Tenemos la esperanza de que, si realmente ofrecen algo a los consumidores&#8230; deber\u00edan generar m\u00e1s inter\u00e9s que el que han visto en los desaf\u00edos&#187;.<\/p>\n<p>Samsung, sin embargo, ya ha apostado por la Inteligencia Artificial. Para su l\u00ednea insignia m\u00e1s reciente, el Galaxy S24, que se anunci\u00f3 en enero, la compa\u00f1\u00eda enfatiz\u00f3 en incorporar avances de inteligencia artificial a sus mensajes, fotos y juegos.<\/p>\n<p>&#171;A medida que el mercado general de tel\u00e9fonos inteligentes se recupera este a\u00f1o, con un fuerte enfoque en la IA, Samsung est\u00e1 en buena posici\u00f3n para seguir creciendo este a\u00f1o&#187;, a\u00f1adi\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Las ventas de tel\u00e9fonos inteligentes de Apple cayeron un 10% el \u00faltimo trimestre, seg\u00fan la firma de investigaci\u00f3n de mercado IDC, ya que las ventas en China cayeron dr\u00e1sticamente. La compa\u00f1\u00eda ha perdido impulso en China debido a que el nacionalismo, una econom\u00eda dif\u00edcil y una mayor competencia han perjudicado a Apple en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448140","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las ventas de iPhone est\u00e1n cayendo. Esta es la raz\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las ventas de iPhone est\u00e1n cayendo. Esta es la raz\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Las ventas de tel\u00e9fonos inteligentes de Apple cayeron un 10% el \u00faltimo trimestre, seg\u00fan la firma de investigaci\u00f3n de mercado IDC, ya que las ventas en China cayeron dr\u00e1sticamente. La compa\u00f1\u00eda ha perdido impulso en China debido a que el nacionalismo, una econom\u00eda dif\u00edcil y una mayor competencia han perjudicado a Apple en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T00:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las ventas de iPhone est\u00e1n cayendo. Esta es la raz\u00f3n\",\"datePublished\":\"2024-04-16T00:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/\"},\"wordCount\":820,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/\",\"name\":\"Las ventas de iPhone est\u00e1n cayendo. Esta es la raz\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-16T00:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las ventas de iPhone est\u00e1n cayendo. Esta es la raz\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las ventas de iPhone est\u00e1n cayendo. Esta es la raz\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Las ventas de iPhone est\u00e1n cayendo. Esta es la raz\u00f3n - Noticias","og_description":"(CNN) &#8212; Las ventas de tel\u00e9fonos inteligentes de Apple cayeron un 10% el \u00faltimo trimestre, seg\u00fan la firma de investigaci\u00f3n de mercado IDC, ya que las ventas en China cayeron dr\u00e1sticamente. La compa\u00f1\u00eda ha perdido impulso en China debido a que el nacionalismo, una econom\u00eda dif\u00edcil y una mayor competencia han perjudicado a Apple en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-16T00:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/"},"author":{"name":"","@id":""},"headline":"Las ventas de iPhone est\u00e1n cayendo. Esta es la raz\u00f3n","datePublished":"2024-04-16T00:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/"},"wordCount":820,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/","name":"Las ventas de iPhone est\u00e1n cayendo. Esta es la raz\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-16T00:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las ventas de iPhone est\u00e1n cayendo. Esta es la raz\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las ventas de iPhone est\u00e1n cayendo. Esta es la raz\u00f3n","url":"http:\/\/noticiasya.com\/reno\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2024\/04\/15\/ventas-iphone-caen-razon-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-16T00:03:46Z","datePublished":"2024-04-16T00:03:46Z","dateModified":"2024-04-16T00:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las ventas de iPhone est\\u00e1n cayendo. Esta es la raz\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/15\\\/ventas-iphone-caen-razon-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/15\\\/ventas-iphone-caen-razon-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-16T00:03:46Z\",\"datePublished\":\"2024-04-16T00:03:46Z\",\"dateModified\":\"2024-04-16T00:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448261,"url":"https:\/\/noticiasya.com\/reno\/2024\/04\/19\/apple-elimina-whatsapp-threads-tienda-aplicaciones-china-orden-beijing-trax\/","url_meta":{"origin":1448140,"position":0},"title":"Apple elimina WhatsApp y Threads de su tienda de aplicaciones en China por orden de Beijing","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN) -- Apple elimin\u00f3 WhatsApp y Threads de su tienda de aplicaciones en China, siguiendo una orden del organismo de control de Internet del pa\u00eds, que aleg\u00f3 problemas de seguridad nacional.\"Estamos obligados a cumplir las leyes de los pa\u00edses en los que operamos, incluso cuando no estamos de acuerdo\", dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449823,"url":"https:\/\/noticiasya.com\/reno\/2024\/05\/29\/apple-recorto-precios-iphone-en-china-las-ventas-se-estan-recuperando-trax\/","url_meta":{"origin":1448140,"position":1},"title":"Apple recort\u00f3 los precios del iPhone en China. Las ventas se est\u00e1n recuperando","author":"","date":"mayo 29, 2024","format":false,"excerpt":"(CNN) -- El repunte de las ventas del iPhone de Apple en China est\u00e1 cobrando impulso, despu\u00e9s de que la compa\u00f1\u00eda redujera agresivamente los precios en su mayor mercado extranjero para atraer a los consumidores que buscaban activamente gangas en una econom\u00eda d\u00e9bil.Los env\u00edos de tel\u00e9fonos celulares de marcas extranjeras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461950,"url":"https:\/\/noticiasya.com\/reno\/2025\/05\/04\/aranceles-trump-apple-900-millones-tim-cook-trax\/","url_meta":{"origin":1448140,"position":2},"title":"Los aranceles de Trump podr\u00edan costarle a Apple US$ 900 millones este trimestre, dice el CEO Tim Cook","author":"","date":"mayo 4, 2025","format":false,"excerpt":"Los aranceles podr\u00edan sumar US$ 900 millones a los costos de Apple este trimestre, dijo el jueves el CEO de Apple, Tim Cook, al revelar que el gigante tecnol\u00f3gico estaba trasladando la producci\u00f3n de iPhones vendidos en Estados Unidos de China a la India.\u201cSuponiendo que las tasas, pol\u00edticas y aplicaciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466330,"url":"https:\/\/noticiasya.com\/reno\/2025\/09\/10\/iphone-air-apple-telefonos-inteligentes-emocionantes-trax\/","url_meta":{"origin":1448140,"position":3},"title":"iPhone Air: el \u00faltimo intento de Apple por hacer que los tel\u00e9fonos inteligentes vuelvan a ser emocionantes","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"Durante buena parte de la \u00faltima d\u00e9cada, las c\u00e1maras m\u00e1s n\u00edtidas, las pantallas m\u00e1s grandes y la mayor duraci\u00f3n de la bater\u00eda han definido las actualizaciones anuales de los tel\u00e9fonos inteligentes.Pero eso puede que ya no sea suficiente para deslumbrar a los consumidores, al menos en opini\u00f3n de Apple.La compa\u00f1\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460746,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/02\/tesla-ventas-desploman-caida-trax\/","url_meta":{"origin":1448140,"position":4},"title":"Las ventas de Tesla se desploman: la empresa registra la mayor ca\u00edda de su historia","author":"","date":"abril 2, 2025","format":false,"excerpt":"Las ventas de Tesla se desplomaron un 13% en los tres primeros meses de este a\u00f1o, en medio de reacciones negativas contra el CEO Elon Musk y de la creciente competencia de veh\u00edculos el\u00e9ctricos de otros fabricantes.Tesla inform\u00f3 que entreg\u00f3 336.681 autos en el primer trimestre de 2025, en comparaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464791,"url":"https:\/\/noticiasya.com\/reno\/2025\/07\/23\/tesla-malas-ventas-trax\/","url_meta":{"origin":1448140,"position":5},"title":"Prep\u00e1rate para m\u00e1s malas noticias de Tesla","author":"","date":"julio 23, 2025","format":false,"excerpt":"La ca\u00edda en las ventas de Tesla durante los \u00faltimos 18 meses ha sido un giro sorprendente para una empresa que solo hab\u00eda registrado una disminuci\u00f3n trimestral interanual de ventas antes de 2024. Y la compa\u00f1\u00eda enfrenta problemas significativos por delante.Los inversionistas ya saben que las ventas del segundo trimestre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1448140"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448140\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1448140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1448140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1448140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}