{"id":1448148,"date":"2024-04-15T20:03:42","date_gmt":"2024-04-16T03:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/"},"modified":"2024-04-15T20:03:42","modified_gmt":"2024-04-16T03:03:42","slug":"canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/","title":{"rendered":"Canciller de M\u00e9xico anuncia rescate de cuerpo de trabajador v\u00edctima del accidente del puente de Baltimore"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0Alicia B\u00e1rcena, Canciller de M\u00e9xico, anunci\u00f3 este lunes que fue recuperado el cuerpo de Carlos Daniel Hern\u00e1ndez, trabajador mexicano que muri\u00f3 tras el accidente en el puente Francis Scott Key.<\/p>\n<p>\u201cFue recuperado el cuerpo de Carlos Daniel Hern\u00e1ndez, mexicano que trabajaba en el puente de Key Brige en Baltimore, que colaps\u00f3 el 26 de marzo. Carlos Daniel representa a nuestros trabajadores mexicanos en EUA. Nuestro m\u00e1s sentido p\u00e9same y acompa\u00f1amiento consular a su familia.\u201d<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0Alicia B\u00e1rcena, Canciller de M\u00e9xico, anunci\u00f3 este lunes que fue recuperado el cuerpo de Carlos Daniel Hern\u00e1ndez, trabajador mexicano que muri\u00f3 tras el accidente en el puente Francis Scott Key. \u201cFue recuperado el cuerpo de Carlos Daniel Hern\u00e1ndez, mexicano que trabajaba en el puente de Key Brige en Baltimore, que colaps\u00f3 el 26 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448148","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Canciller de M\u00e9xico anuncia rescate de cuerpo de trabajador v\u00edctima del accidente del puente de Baltimore - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canciller de M\u00e9xico anuncia rescate de cuerpo de trabajador v\u00edctima del accidente del puente de Baltimore - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0Alicia B\u00e1rcena, Canciller de M\u00e9xico, anunci\u00f3 este lunes que fue recuperado el cuerpo de Carlos Daniel Hern\u00e1ndez, trabajador mexicano que muri\u00f3 tras el accidente en el puente Francis Scott Key. \u201cFue recuperado el cuerpo de Carlos Daniel Hern\u00e1ndez, mexicano que trabajaba en el puente de Key Brige en Baltimore, que colaps\u00f3 el 26 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T03:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Canciller de M\u00e9xico anuncia rescate de cuerpo de trabajador v\u00edctima del accidente del puente de Baltimore\",\"datePublished\":\"2024-04-16T03:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/\"},\"wordCount\":118,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/\",\"name\":\"Canciller de M\u00e9xico anuncia rescate de cuerpo de trabajador v\u00edctima del accidente del puente de Baltimore - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-16T03:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canciller de M\u00e9xico anuncia rescate de cuerpo de trabajador v\u00edctima del accidente del puente de Baltimore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canciller de M\u00e9xico anuncia rescate de cuerpo de trabajador v\u00edctima del accidente del puente de Baltimore - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Canciller de M\u00e9xico anuncia rescate de cuerpo de trabajador v\u00edctima del accidente del puente de Baltimore - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0Alicia B\u00e1rcena, Canciller de M\u00e9xico, anunci\u00f3 este lunes que fue recuperado el cuerpo de Carlos Daniel Hern\u00e1ndez, trabajador mexicano que muri\u00f3 tras el accidente en el puente Francis Scott Key. \u201cFue recuperado el cuerpo de Carlos Daniel Hern\u00e1ndez, mexicano que trabajaba en el puente de Key Brige en Baltimore, que colaps\u00f3 el 26 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-16T03:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/"},"author":{"name":"","@id":""},"headline":"Canciller de M\u00e9xico anuncia rescate de cuerpo de trabajador v\u00edctima del accidente del puente de Baltimore","datePublished":"2024-04-16T03:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/"},"wordCount":118,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/","name":"Canciller de M\u00e9xico anuncia rescate de cuerpo de trabajador v\u00edctima del accidente del puente de Baltimore - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-16T03:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Canciller de M\u00e9xico anuncia rescate de cuerpo de trabajador v\u00edctima del accidente del puente de Baltimore"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Canciller de M\u00e9xico anuncia rescate de cuerpo de trabajador v\u00edctima del accidente del puente de Baltimore","url":"http:\/\/noticiasya.com\/reno\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2024\/04\/15\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-16T03:03:42Z","datePublished":"2024-04-16T03:03:42Z","dateModified":"2024-04-16T03:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Canciller de M\\u00e9xico anuncia rescate de cuerpo de trabajador v\\u00edctima del accidente del puente de Baltimore\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/15\\\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/15\\\/canciller-mexico-anuncia-rescate-cuerpo-trabajador-puente-baltimore-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-16T03:03:42Z\",\"datePublished\":\"2024-04-16T03:03:42Z\",\"dateModified\":\"2024-04-16T03:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447789,"url":"https:\/\/noticiasya.com\/reno\/2024\/04\/05\/cuerpo-baltimore-victima-maynor-suazo-sandoval-trax\/","url_meta":{"origin":1448148,"position":0},"title":"Recuperan el cuerpo de Maynor Suazo Sandoval, v\u00edctima del colapso del puente en Baltimore","author":"","date":"abril 5, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El cuerpo de Maynor Yasir Suazo-Sandoval, una de las v\u00edctimas del colapso del puente Francis Scott Key en Baltimore, fue recuperado este mi\u00e9rcoles, inform\u00f3 un comunicado del Centro de Informaci\u00f3n Conjunta del Puente Key.\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore?La agencia explic\u00f3 que sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449277,"url":"https:\/\/noticiasya.com\/reno\/2024\/05\/08\/guatemala-confirma-hallazgo-cuerpo-trabajador-muerto-puente-baltimore-orix\/","url_meta":{"origin":1448148,"position":1},"title":"Canciller\u00eda de Guatemala confirma localizaci\u00f3n del cuerpo de trabajador que muri\u00f3 en puente Francis Scott en Baltimore","author":"","date":"mayo 8, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El consulado de Guatemala en Maryland, Estados Unidos, confirm\u00f3 el martes que est\u00e1 en contacto con los familiares del trabajador guatemalteco fallecido en el colapso del puente Francis Scott Key en Baltimore el pasado 26 de marzo, seg\u00fan un comunicado de la canciller\u00eda del pa\u00eds centroamericano.De acuerdo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447525,"url":"https:\/\/noticiasya.com\/reno\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/","url_meta":{"origin":1448148,"position":2},"title":"\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas?","author":"","date":"marzo 29, 2024","format":false,"excerpt":"(CNN) -- Trabajaban durante el turno de la noche arreglando baches en el famoso puente Francis Scott Key de Baltimore, en el que 30.000 habitantes de Maryland confiaban cada d\u00eda. Pero su labor result\u00f3 en tragedia la madrugada del martes, cuando un barco de carga de m\u00e1s de 96.600 toneladas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447413,"url":"https:\/\/noticiasya.com\/reno\/2024\/03\/26\/victimas-colapso-puente-baltimore-mexicanos-guatemaltecos-trax\/","url_meta":{"origin":1448148,"position":3},"title":"Las v\u00edctimas del colapso del puente de Baltimore incluyen ciudadanos mexicanos y guatemaltecos, dicen las autoridades","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Las seis personas que a\u00fan est\u00e1n desaparecidas tras el colapso del puente Francis Scott Key en Baltimore incluyen ciudadanos mexicanos, seg\u00fan Rafael Laveaga, jefe de la Secci\u00f3n Consular de la Embajada de M\u00e9xico en Washington, quien habl\u00f3 con los periodistas cerca del lugar el martes.La Guardia Costera de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473720,"url":"https:\/\/noticiasya.com\/reno\/2026\/05\/01\/tragedia-colapso-puente-baltimore-madre-deportacion-hija-riesgo-orix\/","url_meta":{"origin":1448148,"position":4},"title":"Tras la tragedia del colapso del puente en Baltimore, una madre enfrenta la deportaci\u00f3n y su hija el riesgo de otra p\u00e9rdida","author":"","date":"mayo 1, 2026","format":false,"excerpt":"La fotograf\u00eda de Jos\u00e9 Mynor L\u00f3pez descansa entre flores y veladoras en un memorial improvisado cerca del Key Bridge, en Baltimore. Desde su muerte, la madre de su hija, Zoila Guerra Sandoval, le ha repetido a la peque\u00f1a de siete a\u00f1os que todo estar\u00e1 bien. Pero hay algo que a\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447386,"url":"https:\/\/noticiasya.com\/reno\/2024\/03\/26\/que-paso-por-que-colapso-puente-baltimore-victimas-fotos-trax\/","url_meta":{"origin":1448148,"position":5},"title":"\u00bfPor qu\u00e9 colaps\u00f3 el puente de Baltimore, cu\u00e1ntas v\u00edctimas hay y qu\u00e9 sabemos del accidente?","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Un enorme buque de carga se estrell\u00f3 contra el puente Francis Scott Key de Baltimore la madrugada del martes, causando que el puente de 2,5 kil\u00f3metros se desmoronara con autom\u00f3viles y personas al agua helada.Esto es lo que sabemos sobre la cat\u00e1strofe:\u00bfPor qu\u00e9 se derrumb\u00f3 el puente?Poco antes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1448148"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448148\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1448148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1448148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1448148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}