{"id":1448167,"date":"2024-04-16T16:03:38","date_gmt":"2024-04-16T23:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/"},"modified":"2024-04-16T16:03:38","modified_gmt":"2024-04-16T23:03:38","slug":"zelensky-ley-reclutamiento-ucrania-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/","title":{"rendered":"Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania"},"content":{"rendered":"<p>(CNN) &#8212; El presidente de Ucrania, Volodymyr Zelensky, promulg\u00f3 una ley clave que reforma las reglas de reclutamiento del pa\u00eds.<\/p>\n<p>La legislaci\u00f3n impone un nuevo requisito a todos los hombres entre 18 y 60 a\u00f1os de registrarse en el ej\u00e9rcito de Ucrania y llevar consigo sus documentos de registro en todo momento. El objetivo es hacer que los procesos de reclutamiento sean m\u00e1s eficientes y transparentes, afirma el Gobierno.<\/p>\n<p>Los hombres en edad de servicio que viven en el extranjero no podr\u00e1n renovar sus pasaportes en los consulados ucranianos sin presentar los documentos de registro actualizados.<\/p>\n<p>La nueva ley no cubre ning\u00fan aumento potencial en el n\u00famero de personas que podr\u00edan ser llamadas a filas.<\/p>\n<p>Tampoco contiene disposiciones para desmovilizar a los soldados que han pasado largos per\u00edodos luchando. Los legisladores ucranianos debatieron durante meses si permitir a los soldados ucranianos con m\u00e1s a\u00f1os de servicio la oportunidad de regresar a casa en rotaci\u00f3n, o si las renovadas ofensivas de Rusia significaban que no pod\u00edan permitirse el lujo de permitir que los soldados exhaustos descansaran.<\/p>\n<p>Ucrania &#171;se qued\u00f3 sin misiles&#187; para frustrar el ataque ruso a una central el\u00e9ctrica, dice Zelensky<\/p>\n<p>El proyecto de ley fue modificado m\u00e1s de 4.000 veces desde que se present\u00f3 por primera vez, una medida de lo pol\u00edticamente dif\u00edcil que ha sido elaborar la legislaci\u00f3n. El parlamento de Ucrania finalmente elimin\u00f3 los planes de desmovilizaci\u00f3n para mantener la mayor cantidad posible de soldados en el frente, decepcionando a muchas familias que esperaban que la nueva ley tambi\u00e9n consagrara un per\u00edodo fijo de tres a\u00f1os de servicio activo.<\/p>\n<p>El parlamento de Ucrania aprob\u00f3 la ley la semana pasada y Zelensky dio la aprobaci\u00f3n presidencial el martes.<\/p>\n<p>Un militar ucraniano dispara un ob\u00fas hacia los soldados rusos en la regi\u00f3n de Jers\u00f3n, Ucrania, en marzo. Serhii Nuzhnenko\/Reuters<\/p>\n<p>A finales del a\u00f1o pasado, el l\u00edder de la facci\u00f3n Siervos del Pueblo de Zelensky en el parlamento dijo que el ej\u00e9rcito buscaba medio mill\u00f3n de hombres y mujeres en servicio adicionales. Pero el comandante en jefe de Ucrania, Oleksandr Syrsyki, dijo recientemente que cualquier aumento en las cifras probablemente ser\u00eda significativamente menor.<\/p>\n<p>La firma de la ley por parte de Zelensky ocurre poco despu\u00e9s de que el comandante de Ucrania en el frente oriental advirtiera que los soldados rusos superaban en n\u00famero a las suyas hasta 10 veces.<\/p>\n<p>Despu\u00e9s de que se aprobara la ley la semana pasada, decenas de esposas y familiares de militares se reunieron frente al parlamento de Ucrania para protestar y exigir que se incluyeran plazos para el servicio.<\/p>\n<p>Anastasia Bulba, cuyo esposo Vitalii se ofreci\u00f3 como voluntario para unirse al ej\u00e9rcito inmediatamente despu\u00e9s de que Rusia lanzara su invasi\u00f3n a gran escala en febrero de 2022, dijo a CNN que los soldados de Ucrania \u201cse han quedado sin t\u00e9rminos de servicio y sin idea de cu\u00e1ndo podr\u00e1n regresar a sus familias\u201d.<\/p>\n<p>&#171;Los defensores del pa\u00eds, en quienes descansa la independencia de todo el pa\u00eds, fueron enga\u00f1ados&#187;, afirm\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El presidente de Ucrania, Volodymyr Zelensky, promulg\u00f3 una ley clave que reforma las reglas de reclutamiento del pa\u00eds. La legislaci\u00f3n impone un nuevo requisito a todos los hombres entre 18 y 60 a\u00f1os de registrarse en el ej\u00e9rcito de Ucrania y llevar consigo sus documentos de registro en todo momento. El objetivo es [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448167","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El presidente de Ucrania, Volodymyr Zelensky, promulg\u00f3 una ley clave que reforma las reglas de reclutamiento del pa\u00eds. La legislaci\u00f3n impone un nuevo requisito a todos los hombres entre 18 y 60 a\u00f1os de registrarse en el ej\u00e9rcito de Ucrania y llevar consigo sus documentos de registro en todo momento. El objetivo es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T23:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania\",\"datePublished\":\"2024-04-16T23:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/\"},\"wordCount\":562,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/\",\"name\":\"Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-16T23:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania - Noticias","og_description":"(CNN) &#8212; El presidente de Ucrania, Volodymyr Zelensky, promulg\u00f3 una ley clave que reforma las reglas de reclutamiento del pa\u00eds. La legislaci\u00f3n impone un nuevo requisito a todos los hombres entre 18 y 60 a\u00f1os de registrarse en el ej\u00e9rcito de Ucrania y llevar consigo sus documentos de registro en todo momento. El objetivo es [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-16T23:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/"},"author":{"name":"","@id":""},"headline":"Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania","datePublished":"2024-04-16T23:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/"},"wordCount":562,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/","name":"Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-16T23:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania","url":"http:\/\/noticiasya.com\/reno\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2024\/04\/16\/zelensky-ley-reclutamiento-ucrania-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-16T23:03:38Z","datePublished":"2024-04-16T23:03:38Z","dateModified":"2024-04-16T23:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Zelensky firma una ley que reforma las reglas de reclutamiento de Ucrania\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/16\\\/zelensky-ley-reclutamiento-ucrania-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/16\\\/zelensky-ley-reclutamiento-ucrania-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-16T23:03:38Z\",\"datePublished\":\"2024-04-16T23:03:38Z\",\"dateModified\":\"2024-04-16T23:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448455,"url":"https:\/\/noticiasya.com\/reno\/2024\/04\/23\/ucrania-hombres-edad-militar-en-el-extranjero-suspendiendo-servicios-consulares-trax\/","url_meta":{"origin":1448167,"position":0},"title":"Ucrania presiona a hombres en edad militar en el extranjero suspendiendo sus servicios consulares","author":"","date":"abril 23, 2024","format":false,"excerpt":"(CNN) -- Ucrania est\u00e1 aumentando la presi\u00f3n sobre los hombres en edad de ser llamados a filas que viven en el extranjero suspendiendo sus servicios consulares, en medio de una revisi\u00f3n m\u00e1s amplia de las reglas de movilizaci\u00f3n del pa\u00eds destinadas a reforzar sus defensas contra la invasi\u00f3n rusa .El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460742,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/02\/putin-ejercito-ruso-reclutamiento-guerra-ucrania-trax\/","url_meta":{"origin":1448167,"position":1},"title":"Putin llama a 160.000 hombres al Ej\u00e9rcito en la \u00faltima campa\u00f1a de reclutamiento, en un momento crucial en guerra en Ucrania","author":"","date":"abril 2, 2025","format":false,"excerpt":"Est\u00e1 en marcha una de las mayores rondas de reclutamiento en el Ej\u00e9rcito ruso en varios a\u00f1os, mientras el presidente Vladimir Putin impulsa una expansi\u00f3n de las tropas del pa\u00eds en un momento crucial de la guerra en Ucrania.Putin firm\u00f3 un decreto que autoriza la \u00faltima fase del reclutamiento semestral\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473020,"url":"https:\/\/noticiasya.com\/reno\/2026\/04\/09\/registro-automatico-servicio-militar-asi-funcionara-trax\/","url_meta":{"origin":1448167,"position":2},"title":"\u00bfC\u00f3mo funcionar\u00e1 el registro autom\u00e1tico para el servicio militar obligatorio que entrar\u00e1 en vigor en diciembre?","author":"","date":"abril 9, 2026","format":false,"excerpt":"Los hombres j\u00f3venes y elegibles ser\u00e1n inscritos autom\u00e1ticamente en el registro del Servicio Selectivo a partir de diciembre, como parte de una medida incluida en el proyecto de ley anual de pol\u00edtica de defensa que el Congreso promulg\u00f3 a finales del a\u00f1o pasado.Los hombres de 18 a 26 a\u00f1os ya\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451906,"url":"https:\/\/noticiasya.com\/reno\/2024\/08\/16\/rusia-putin-guerra-ucrania-trax\/","url_meta":{"origin":1448167,"position":3},"title":"Putin prometi\u00f3 que los reclutas mal entrenados no ser\u00edan enviados a la guerra. Ahora el frente ha llegado a ellos","author":"","date":"agosto 16, 2024","format":false,"excerpt":"(CNN) -- El presidente de Rusia, Vladimir Putin, hizo una gran promesa cuando lanz\u00f3 su guerra contra Ucrania: los reclutas no participar\u00edan en combate. Pero mientras Mosc\u00fa lucha por contener los avances ucranianos en su territorio, las familias de los j\u00f3venes soldados desplegados en la zona est\u00e1n dando la voz\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467187,"url":"https:\/\/noticiasya.com\/reno\/2025\/10\/07\/regiones-rusas-bonos-reclutamiento-guerra-ucrania-trax\/","url_meta":{"origin":1448167,"position":4},"title":"Regiones rusas aumentan el pago de los bonos militares para atraer a m\u00e1s reclutas para la guerra en Ucrania","author":"","date":"octubre 7, 2025","format":false,"excerpt":"Las regiones rusas est\u00e1n aumentando de forma dr\u00e1stica las sumas que pagan a los nuevos reclutas militares, en un contexto en el que, seg\u00fan analistas, las campa\u00f1as de reclutamiento \u201cideol\u00f3gicas\u201d ya no bastan para motivar a la poblaci\u00f3n a combatir en Ucrania.En los \u00faltimos d\u00edas, varias regiones anunciaron que hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450332,"url":"https:\/\/noticiasya.com\/reno\/2024\/06\/13\/ucrania-presos-soldados-ejercito-guerra-trax\/","url_meta":{"origin":1448167,"position":5},"title":"De la c\u00e1rcel a las trincheras: el intento de Ucrania de convertir a los presos en soldados","author":"","date":"junio 13, 2024","format":false,"excerpt":"Ucrania Central (CNN) -- El comandante del batall\u00f3n, Dmytro Kukharchuk, habla en voz baja pero con firmeza. Con sus manos tatuadas tras la espalda, cuenta a los hombres, todos convictos, su experiencia luchando por Ucrania en Bakhmut y Avdiivka.Kukharchuk, de 34 a\u00f1os, est\u00e1 en una prisi\u00f3n del centro de Ucrania,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1448167"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448167\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1448167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1448167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1448167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}