{"id":1448177,"date":"2024-04-17T00:03:43","date_gmt":"2024-04-17T07:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/"},"modified":"2024-04-17T00:03:43","modified_gmt":"2024-04-17T07:03:43","slug":"cien-muertos-pakistan-afganistan-fuertes-lluvias-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/","title":{"rendered":"M\u00e1s de cien muertos en Pakist\u00e1n y Afganist\u00e1n debido a las fuertes lluvias"},"content":{"rendered":"<p>(CNN) &#8212; M\u00e1s de cien personas han muerto en Pakist\u00e1n y Afganist\u00e1n en los \u00faltimos d\u00edas cuando las fuertes lluvias azotaron a los dos pa\u00edses. La Oficina Meteorol\u00f3gica de Pakist\u00e1n advirti\u00f3 que se avecinan m\u00e1s precipitaciones.<\/p>\n<p>En Afganist\u00e1n, las fuertes lluvias e inundaciones en 23 provincias mataron a 66 personas e hirieron a otras 36, seg\u00fan informes preliminares del mul\u00e1 Janan Sayeq, portavoz del Ministerio afgano de Gesti\u00f3n de Desastres.<\/p>\n<p>Sayeq a\u00f1adi\u00f3 que 600 animales murieron y m\u00e1s de 1.200 casas quedaron total o parcialmente destruidas.<\/p>\n<p>Este martes se celebr\u00f3 en Kabul una reuni\u00f3n de emergencia para coordinar y entregar asistencia humanitaria de emergencia a las zonas afectadas, dijo Sayeq, y a\u00f1adi\u00f3 que asistieron funcionarios del Ministerio afgano de Gesti\u00f3n de Desastres, agencias de la ONU y otras ONG.<\/p>\n<p>En Pakist\u00e1n, 32 personas murieron, entre ellas 15 ni\u00f1os y 6 mujeres, y 41 resultaron heridas en la provincia noroccidental de Khyber Pakhtunkhwa, seg\u00fan un informe publicado por la autoridad provincial de gesti\u00f3n de cat\u00e1strofes (PDMA). Ocho personas m\u00e1s murieron en la provincia suroccidental de Baluchist\u00e1n, seg\u00fan el PDMA de la provincia. En total, casi 170 casas quedaron completamente destruidas y m\u00e1s de 1.250 sufrieron da\u00f1os parciales.<\/p>\n<p>La Oficina Meteorol\u00f3gica de Pakist\u00e1n advirti\u00f3 sobre m\u00e1s lluvias a partir de este martes por la noche y es probable que afecten a la mayor parte de Baluchist\u00e1n el mi\u00e9rcoles y se extiendan al resto de Pakist\u00e1n este jueves.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; M\u00e1s de cien personas han muerto en Pakist\u00e1n y Afganist\u00e1n en los \u00faltimos d\u00edas cuando las fuertes lluvias azotaron a los dos pa\u00edses. La Oficina Meteorol\u00f3gica de Pakist\u00e1n advirti\u00f3 que se avecinan m\u00e1s precipitaciones. En Afganist\u00e1n, las fuertes lluvias e inundaciones en 23 provincias mataron a 66 personas e hirieron a otras 36, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448177","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e1s de cien muertos en Pakist\u00e1n y Afganist\u00e1n debido a las fuertes lluvias - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de cien muertos en Pakist\u00e1n y Afganist\u00e1n debido a las fuertes lluvias - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; M\u00e1s de cien personas han muerto en Pakist\u00e1n y Afganist\u00e1n en los \u00faltimos d\u00edas cuando las fuertes lluvias azotaron a los dos pa\u00edses. La Oficina Meteorol\u00f3gica de Pakist\u00e1n advirti\u00f3 que se avecinan m\u00e1s precipitaciones. En Afganist\u00e1n, las fuertes lluvias e inundaciones en 23 provincias mataron a 66 personas e hirieron a otras 36, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-17T07:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"M\u00e1s de cien muertos en Pakist\u00e1n y Afganist\u00e1n debido a las fuertes lluvias\",\"datePublished\":\"2024-04-17T07:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/\"},\"wordCount\":288,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/\",\"name\":\"M\u00e1s de cien muertos en Pakist\u00e1n y Afganist\u00e1n debido a las fuertes lluvias - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-17T07:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de cien muertos en Pakist\u00e1n y Afganist\u00e1n debido a las fuertes lluvias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de cien muertos en Pakist\u00e1n y Afganist\u00e1n debido a las fuertes lluvias - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de cien muertos en Pakist\u00e1n y Afganist\u00e1n debido a las fuertes lluvias - Noticias","og_description":"(CNN) &#8212; M\u00e1s de cien personas han muerto en Pakist\u00e1n y Afganist\u00e1n en los \u00faltimos d\u00edas cuando las fuertes lluvias azotaron a los dos pa\u00edses. La Oficina Meteorol\u00f3gica de Pakist\u00e1n advirti\u00f3 que se avecinan m\u00e1s precipitaciones. En Afganist\u00e1n, las fuertes lluvias e inundaciones en 23 provincias mataron a 66 personas e hirieron a otras 36, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-17T07:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/"},"author":{"name":"","@id":""},"headline":"M\u00e1s de cien muertos en Pakist\u00e1n y Afganist\u00e1n debido a las fuertes lluvias","datePublished":"2024-04-17T07:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/"},"wordCount":288,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/","name":"M\u00e1s de cien muertos en Pakist\u00e1n y Afganist\u00e1n debido a las fuertes lluvias - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-17T07:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de cien muertos en Pakist\u00e1n y Afganist\u00e1n debido a las fuertes lluvias"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"M\u00e1s de cien muertos en Pakist\u00e1n y Afganist\u00e1n debido a las fuertes lluvias","url":"http:\/\/noticiasya.com\/reno\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2024\/04\/17\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-17T07:03:43Z","datePublished":"2024-04-17T07:03:43Z","dateModified":"2024-04-17T07:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"M\\u00e1s de cien muertos en Pakist\\u00e1n y Afganist\\u00e1n debido a las fuertes lluvias\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/17\\\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/04\\\/17\\\/cien-muertos-pakistan-afganistan-fuertes-lluvias-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-17T07:03:43Z\",\"datePublished\":\"2024-04-17T07:03:43Z\",\"dateModified\":\"2024-04-17T07:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466075,"url":"https:\/\/noticiasya.com\/reno\/2025\/09\/02\/terremoto-afganistan-donde-afectados-trax\/","url_meta":{"origin":1448177,"position":0},"title":"\u00bfD\u00f3nde tuvo lugar el terremoto de Afganist\u00e1n y a cu\u00e1nta gente afect\u00f3? Todo lo que sabemos","author":"","date":"septiembre 2, 2025","format":false,"excerpt":"Los gobernantes talibanes de Afganist\u00e1n han pedido ayuda internacional despu\u00e9s de que un enorme terremoto mat\u00f3 a cientos de personas y arras\u00f3 aldeas enteras, a\u00f1adiendo m\u00e1s miseria a un pa\u00eds devastado por la guerra que ya estaba lidiando con la escasez de alimentos y los recortes en la ayuda extranjera.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467378,"url":"https:\/\/noticiasya.com\/reno\/2025\/10\/15\/afganistan-pakistan-intercambian-ataques-mortales-trax\/","url_meta":{"origin":1448177,"position":1},"title":"Afganist\u00e1n y Pakist\u00e1n protagonizan sus ataques m\u00e1s mortales en a\u00f1os: qu\u00e9 hay detr\u00e1s de la escalada","author":"","date":"octubre 15, 2025","format":false,"excerpt":"Las tensiones entre Afganist\u00e1n y Pakist\u00e1n han aumentado en los \u00faltimos d\u00edas con el intercambio de disparos mortales entre estos dos vecinos, lo que ha avivado los temores de un conflicto m\u00e1s amplio.Los combates se produjeron tras los ataques del jueves pasado en la capital afgana, Kabul, y en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472275,"url":"https:\/\/noticiasya.com\/reno\/2026\/03\/17\/afganistan-denuncia-ataque-hospital-pakistan-reux\/","url_meta":{"origin":1448177,"position":2},"title":"Afganist\u00e1n dice que m\u00e1s de 400 personas murieron en ataque paquistan\u00ed contra un hospital en Kabul; Islamabad niega acusaci\u00f3n","author":"","date":"marzo 17, 2026","format":false,"excerpt":"M\u00e1s de 400 personas murieron y 265 resultaron heridas en un ataque a\u00e9reo perpetrado por Pakist\u00e1n contra un hospital de rehabilitaci\u00f3n para usuarios de drogas en Kabul, declar\u00f3 este martes un portavoz del gobierno talib\u00e1n afgano, lo que representa una marcada escalada en el conflicto entre ambos pa\u00edses vecinos.Pakist\u00e1n rechaz\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465553,"url":"https:\/\/noticiasya.com\/reno\/2025\/08\/16\/mueren-400-personas-inundaciones-pakistan-cachemira-nepal-trax\/","url_meta":{"origin":1448177,"position":3},"title":"Mueren m\u00e1s de 400 personas por inundaciones repentinas en Pakist\u00e1n, Cachemira administrada por India y Nepal","author":"","date":"agosto 16, 2025","format":false,"excerpt":"Las inundaciones repentinas como consecuencias de las fuertes lluvias han provocado m\u00e1s de 400 muertos en partes de Pakist\u00e1n, Cachemira administrada por la India y Nepal, mientras decenas de personas siguen desaparecidas, seg\u00fan dijeron las autoridades.En el noroeste de Pakist\u00e1n, al menos 321 personas murieron en 48 horas, informaron este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449560,"url":"https:\/\/noticiasya.com\/reno\/2024\/05\/17\/mueren-europeos-espanoles-tiroteo-afganistan-orix\/","url_meta":{"origin":1448177,"position":4},"title":"Mueren tres espa\u00f1oles en un tiroteo en Afganist\u00e1n","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN) -- Tres ciudadanos espa\u00f1oles murieron y al menos uno result\u00f3 herido en un tiroteo en el centro de Afganist\u00e1n el viernes, dijo a CNN una fuente diplom\u00e1tica espa\u00f1ola.Anteriormente, el portavoz del Ministerio del Interior de Afganist\u00e1n dijo que los tres extranjeros muertos y cuatro de los heridos en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471717,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/27\/guerra-abierta-talibanes-pakistan-trax\/","url_meta":{"origin":1448177,"position":5},"title":"El ministro de Defensa de Pakist\u00e1n habla de una &#171;guerra abierta&#187; con los talibanes de Afganist\u00e1n. \u00bfQu\u00e9 est\u00e1 pasando?","author":"","date":"febrero 27, 2026","format":false,"excerpt":"Afganist\u00e1n y Pakist\u00e1n se enfrentan de nuevo con mort\u00edferos bombardeos y fuego de mortero a trav\u00e9s de su escarpada frontera. El ministro de Defensa de Islamabad afirm\u00f3 que la paciencia de su pa\u00eds se hab\u00eda \u201cagotado\u201d y declar\u00f3 una \u201cguerra abierta\u201d contra su vecino, gobernado por los talibanes.Se trata del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1448177"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1448177\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1448177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1448177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1448177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}