{"id":1452941,"date":"2024-09-22T15:03:38","date_gmt":"2024-09-22T22:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/"},"modified":"2024-09-22T15:03:38","modified_gmt":"2024-09-22T22:03:38","slug":"japon-terremoto-lluvias-inundaciones-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/","title":{"rendered":"Esta regi\u00f3n de Jap\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles"},"content":{"rendered":"<p>(CNN) \u2013\u2013 Una persona muri\u00f3 y varias est\u00e1n desaparecidas despu\u00e9s de que lluvias r\u00e9cord causaran inundaciones y deslizamientos de tierra en la costa de Jap\u00f3n, en la misma regi\u00f3n que fue golpeada por un gran terremoto el d\u00eda de A\u00f1o Nuevo, dijeron las autoridades locales.<\/p>\n<p>La agencia meteorol\u00f3gica japonesa emiti\u00f3 el s\u00e1bado su m\u00e1xima alerta de emergencia para la prefectura de Ishikawa, e inst\u00f3 a los residentes a extremar las precauciones ante lo que, seg\u00fan dijo, es la lluvia m\u00e1s intensa que ha sufrido la regi\u00f3n en su historia. La alerta fue rebajada el domingo por la ma\u00f1ana, pero la agencia meteorol\u00f3gica pidi\u00f3 a los residentes que permanecieran en alerta m\u00e1xima.<\/p>\n<p>La fuerte lluvia caus\u00f3 que 16 r\u00edos de la zona se desbordaran, seg\u00fan inform\u00f3 la emisora \u200b\u200bp\u00fablica japonesa NHK.<\/p>\n<p>Una persona muri\u00f3 en la ciudad de Suzu despu\u00e9s de que su casa fuera tragada por un deslizamiento de tierra, inform\u00f3 NHK. Al menos seis personas est\u00e1n desaparecidas, dijeron las autoridades de Ishikawa, y decenas de miles se vieron obligadas a evacuar, seg\u00fan NHK.<\/p>\n<p>La tormenta dej\u00f3 sin electricidad a m\u00e1s de 6.200 hogares, dijeron las autoridades.<\/p>\n<p>Trabajadores se refugian debajo de sus mesas: as\u00ed se vivi\u00f3 el sismo de Jap\u00f3n de magnitud 7,1 en una oficina<\/p>\n<p>Es una regi\u00f3n que ya ha sufrido destrucci\u00f3n y miseria este a\u00f1o.<\/p>\n<p>El 1 de enero, un poderoso terremoto de magnitud 7,5 sacudi\u00f3 la pen\u00ednsula de Noto en Ishikawa, mat\u00f3 a cientos de personas y caus\u00f3 una destrucci\u00f3n generalizada de la que la regi\u00f3n a\u00fan se est\u00e1 recuperando.<\/p>\n<p>Las viviendas temporales construidas para las personas que perdieron sus hogares en el terremoto est\u00e1n rodeadas por varios centr\u00edmetros de agua turbia, seg\u00fan se puede ver en las fotograf\u00edas.<\/p>\n<p>Seg\u00fan el Ministerio de Tierras, Infraestructura, Transporte y Turismo, cuatro trabajadores que realizaban trabajos de restauraci\u00f3n tras el terremoto en la ciudad de Wajima desaparecieron. El ministerio afirma que es posible que hayan quedado atrapados en un deslizamiento de tierra.<\/p>\n<p>Los terremotos hacen que el suelo sea inestable y propenso a m\u00e1s deslizamientos de tierra, especialmente despu\u00e9s de fuertes lluvias.<\/p>\n<p>Personas retiran el barro para desalojar un autom\u00f3vil luego de las inundaciones en la ciudad de Wajima, el 22 de septiembre de 2024. Cr\u00e9dito: Yuichi Yamazaki\/AFP\/Getty Images.<\/p>\n<p>Un puente se derrumb\u00f3 despu\u00e9s de una fuerte lluvia en la ciudad de Wajima, el 22 de septiembre de 2024. Cr\u00e9dito: Yuichi Yamazaki\/AFP\/Getty Images.<\/p>\n<p>Las viviendas temporales, construidas para las personas que perdieron sus hogares durante el terremoto del 1 de enero de 2024, est\u00e1n rodeadas por las aguas de la inundaci\u00f3n despu\u00e9s de que las fuertes lluvias azotaran la ciudad de Wajima, el 22 de septiembre de 2024. Cr\u00e9dito: JIJI Press\/AFP\/Getty Images.<\/p>\n<p>Un hombre empuja su bicicleta por una acera fangosa luego de una fuerte lluvia en la ciudad de Wajima, el 22 de septiembre de 2024. Cr\u00e9dito: Yuichi Yamazaki\/AFP\/Getty Images.<\/p>\n<p>\u2013\u2013 Hanako Montgomery de CNN contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 Una persona muri\u00f3 y varias est\u00e1n desaparecidas despu\u00e9s de que lluvias r\u00e9cord causaran inundaciones y deslizamientos de tierra en la costa de Jap\u00f3n, en la misma regi\u00f3n que fue golpeada por un gran terremoto el d\u00eda de A\u00f1o Nuevo, dijeron las autoridades locales. La agencia meteorol\u00f3gica japonesa emiti\u00f3 el s\u00e1bado su m\u00e1xima alerta [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1452941","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esta regi\u00f3n de Jap\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esta regi\u00f3n de Jap\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 Una persona muri\u00f3 y varias est\u00e1n desaparecidas despu\u00e9s de que lluvias r\u00e9cord causaran inundaciones y deslizamientos de tierra en la costa de Jap\u00f3n, en la misma regi\u00f3n que fue golpeada por un gran terremoto el d\u00eda de A\u00f1o Nuevo, dijeron las autoridades locales. La agencia meteorol\u00f3gica japonesa emiti\u00f3 el s\u00e1bado su m\u00e1xima alerta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-22T22:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Esta regi\u00f3n de Jap\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles\",\"datePublished\":\"2024-09-22T22:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/\"},\"wordCount\":555,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/\",\"name\":\"Esta regi\u00f3n de Jap\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-09-22T22:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esta regi\u00f3n de Jap\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esta regi\u00f3n de Jap\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Esta regi\u00f3n de Jap\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles - Noticias","og_description":"(CNN) \u2013\u2013 Una persona muri\u00f3 y varias est\u00e1n desaparecidas despu\u00e9s de que lluvias r\u00e9cord causaran inundaciones y deslizamientos de tierra en la costa de Jap\u00f3n, en la misma regi\u00f3n que fue golpeada por un gran terremoto el d\u00eda de A\u00f1o Nuevo, dijeron las autoridades locales. La agencia meteorol\u00f3gica japonesa emiti\u00f3 el s\u00e1bado su m\u00e1xima alerta [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/","og_site_name":"Noticias","article_published_time":"2024-09-22T22:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/"},"author":{"name":"","@id":""},"headline":"Esta regi\u00f3n de Jap\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles","datePublished":"2024-09-22T22:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/"},"wordCount":555,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/","url":"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/","name":"Esta regi\u00f3n de Jap\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-09-22T22:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Esta regi\u00f3n de Jap\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Esta regi\u00f3n de Jap\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles","url":"http:\/\/noticiasya.com\/reno\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2024\/09\/22\/japon-terremoto-lluvias-inundaciones-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-09-22T22:03:38Z","datePublished":"2024-09-22T22:03:38Z","dateModified":"2024-09-22T22:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Esta regi\\u00f3n de Jap\\u00f3n se recuperaba de un terremoto mortal cuando lluvias torrenciales inundaron sus calles\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/09\\\/22\\\/japon-terremoto-lluvias-inundaciones-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2024\\\/09\\\/22\\\/japon-terremoto-lluvias-inundaciones-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-09-22T22:03:38Z\",\"datePublished\":\"2024-09-22T22:03:38Z\",\"dateModified\":\"2024-09-22T22:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1442995,"url":"https:\/\/noticiasya.com\/reno\/2024\/01\/01\/un-terremoto-de-magnitud-75-sacude-el-oeste-de-japon-y-genera-alerta-de-tsunami\/","url_meta":{"origin":1452941,"position":0},"title":"Un terremoto de magnitud 7,5 sacude el oeste de Jap\u00f3n y genera alerta de tsunami","author":"","date":"enero 1, 2024","format":false,"excerpt":"(CNN) --\u00a0 Un terremoto de magnitud 7,5 sacudi\u00f3 el oeste de Jap\u00f3n este lunes por la tarde, lo que provoc\u00f3 una alerta de tsunami, seg\u00fan el Servicio Geol\u00f3gico de Estados Unidos y la Agencia Meteorol\u00f3gica de Jap\u00f3n.El terremoto, que tuvo una profundidad de 10 kil\u00f3metros, se produjo a las 4:10\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464960,"url":"https:\/\/noticiasya.com\/reno\/2025\/07\/29\/alertas-tsunami-terremoto-costa-oriental-rusia-trax\/","url_meta":{"origin":1452941,"position":1},"title":"Activan alertas de tsunami para partes de Rusia y Jap\u00f3n tras un fuerte sismo","author":"","date":"julio 29, 2025","format":false,"excerpt":"Se emitieron alertas de tsunami para partes de Rusia y Jap\u00f3n tras un enorme terremoto de magnitud 8,7 que sacudi\u00f3 el mi\u00e9rcoles la remota y escasamente poblada costa oriental de Rusia.El sismo ocurri\u00f3 a unos 136 kil\u00f3metros de Petropavlovsk-Kamchatsky, Rusia, a una profundidad de 19 kil\u00f3metros, de acuerdo con el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452262,"url":"https:\/\/noticiasya.com\/reno\/2024\/08\/29\/japon-4-millones-personas-evacuar-tifon-shanshan-amenaza-hasta-metro-lluvia-trax\/","url_meta":{"origin":1452941,"position":2},"title":"Jap\u00f3n insta a 4 millones de personas a evacuar mientras el tif\u00f3n Shanshan amenaza el sur con hasta un metro de lluvia","author":"","date":"agosto 29, 2024","format":false,"excerpt":"(CNN) -- Se inst\u00f3 a evacuar a casi 4 millones de personas en el sur de Jap\u00f3n luego de que el tif\u00f3n Shanshan toc\u00f3 tierra este jueves, dejando a miles de residentes sin electricidad y azotando la isla de Kyushu con r\u00e1fagas de viento, lluvias torrenciales y peligrosas marejadas cicl\u00f3nicas.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455461,"url":"https:\/\/noticiasya.com\/reno\/2024\/10\/30\/hubo-fallos-prevision-y-alerta-dana-tragedia-espana-orix\/","url_meta":{"origin":1452941,"position":3},"title":"Los factores alrededor de la devastaci\u00f3n por la DANA &#171;sin precedentes&#187; en Espa\u00f1a: sorpresa, cambio clim\u00e1tico y el papel de los mensajes de alerta","author":"","date":"octubre 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Varias localidades del sur y este de Espa\u00f1a fueron golpeadas con hasta 30 cm de lluvia en solo unas pocas horas el martes, en lo que marc\u00f3 la peor lluvia en Valencia en 28 a\u00f1os, seg\u00fan la Agencia Estatal de Meteorolog\u00eda, AEMET. La magnitud del fen\u00f3meno tom\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468344,"url":"https:\/\/noticiasya.com\/reno\/2025\/11\/14\/california-tormenta-inundaciones-trax\/","url_meta":{"origin":1452941,"position":4},"title":"Tormenta en el sur de California: aumenta el riesgo de inundaciones y deslizamientos de tierra","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"Una fuerte tormenta del Pac\u00edfico est\u00e1 provocando intensas lluvias en el sur de California, lo que aumenta el riesgo de inundaciones, deslizamientos de tierra y flujos de escombros potencialmente mortales, en especial cerca de las zonas afectadas por incendios en el \u00e1rea de Los \u00c1ngeles.Una combinaci\u00f3n de fuertes lluvias y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445599,"url":"https:\/\/noticiasya.com\/reno\/2024\/02\/18\/california-ya-empapada-se-prepara-para-la-proxima-ronda-de-lluvias-con-alertas-de-inundaciones-y-evacuaciones\/","url_meta":{"origin":1452941,"position":5},"title":"California, ya empapada, se prepara para la pr\u00f3xima ronda de lluvias con alertas de inundaciones y evacuaciones","author":"","date":"febrero 18, 2024","format":false,"excerpt":"(CNN) --\u00a0 Las alertas de inundaciones se extienden a lo largo de gran parte de la costa de California y se han ordenado algunas advertencias de evacuaci\u00f3n a medida que otra ronda de fuertes lluvias llega al estado ya empapado y crece la amenaza de inundaciones y deslizamientos de tierra.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1452941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1452941"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1452941\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1452941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1452941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1452941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}