{"id":1461465,"date":"2025-04-21T16:03:40","date_gmt":"2025-04-21T23:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/"},"modified":"2025-04-21T16:03:40","modified_gmt":"2025-04-21T23:03:40","slug":"deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/","title":{"rendered":"C\u00f3mo la deportaci\u00f3n de \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de inflexi\u00f3n en la historia de Estados Unidos"},"content":{"rendered":"<p>La <a href=\"https:\/\/www.cnn.com\/2025\/04\/14\/politics\/what-to-know-about-the-kilmar-armando-abrego-garcia-case\/index.html\">saga de Kilmar \u00c1brego Garc\u00eda<\/a> se ha convertido en la historia de m\u00e1s de un inmigrante indocumentado en una c\u00e1rcel salvadore\u00f1a y ahora es uno de esos casos raros que resuenan en la historia y dictan el car\u00e1cter de Estados Unidos.<\/p>\n<p>El destino del residente de Maryland deportado se est\u00e1 convirtiendo en una prueba decisiva del programa de deportaciones masivas de <a href=\"https:\/\/www.cnn.com\/politics\/president-donald-trump-47\">Donald Trump<\/a> y de la capacidad de los dem\u00f3cratas de formular un argumento opuesto sobre el tema pol\u00edticamente complicado de la inmigraci\u00f3n, que normalmente favorece al presidente y su partido.<\/p>\n<p>El caso de \u00c1brego Garc\u00eda y asuntos relacionados podr\u00edan ser el catalizador de una colisi\u00f3n constitucional entre una administraci\u00f3n que no admite restricciones a su poder y la autoridad del poder judicial para hacer contrapeso a un presidente sin restricciones.<\/p>\n<p>El resultado final de esta cr\u00edtica batalla legal podr\u00eda depender de si la mayor\u00eda conservadora de la Corte Suprema est\u00e1 dispuesta a correr el riesgo de un enfrentamiento con el presidente, algo que parece estar dispuesta a evitar.<\/p>\n<p>La administraci\u00f3n admiti\u00f3 ante el tribunal que \u00c1brego Garc\u00eda fue deportado por un error administrativo, ignorando la decisi\u00f3n de un juez que imped\u00eda su regreso a su natal El Salvador, donde su vida podr\u00eda correr peligro. Sin embargo, las autoridades se <a href=\"https:\/\/www.cnn.com\/2025\/04\/14\/politics\/trump-nayib-bukele-white-house-immigration\/index.html\">niegan a devolver<\/a> a \u00c1brego Garc\u00eda a Estados Unidos, argumentando que carecen de la facultad para obligar a El Salvador a hacerlo.<\/p>\n<p>Los funcionarios tambi\u00e9n optan por interpretar el fallo de la Corte Suprema, que exige que la administraci\u00f3n de Trump <a href=\"https:\/\/www.cnn.com\/2025\/04\/10\/politics\/supreme-court-abrego-garcia\/index.html\">\u201cfacilite\u201d su regreso,<\/a> como un respaldo un\u00e1nime a la postura de la administraci\u00f3n. Argumentan que, dado que \u00c1brego Garc\u00eda se encuentra bajo custodia de un gobierno extranjero, no tienen la facultad de devolverlo.<\/p>\n<p>La Casa Blanca insiste en que \u00c1brego Garc\u00eda es un terrorista, miembro de la notoria pandilla MS-13, y que jam\u00e1s ser\u00e1 devuelto a Estados Unidos. Sin embargo, no ha presentado pruebas definitivas que demuestren estas afirmaciones. <a href=\"https:\/\/www.cnn.com\/2025\/04\/19\/politics\/abrego-garcia-trump-administration-violent-gang-member\/index.html\">En cambio, ha difamado<\/a> la reputaci\u00f3n de \u00c1brego Garc\u00eda al destacar una disputa dom\u00e9stica con su esposa, nacida en Estados Unidos y una acusaci\u00f3n de su participaci\u00f3n en la trata de personas. Sin embargo, \u00c1brego Garc\u00eda no fue procesado en ninguno de los dos casos, y su esposa ha desestimado las acusaciones en su contra.<\/p>\n<p>El senador de Maryland, Chris Van Hollen, <a href=\"https:\/\/www.cnn.com\/2025\/04\/18\/politics\/chris-van-hollen-kilmar-abrego-garcia-cecot-el-salvador\/index.html\">visit\u00f3 El Salvador la semana pasada<\/a>. \u00c1brego Garc\u00eda fue liberado para reunirse con \u00e9l, vestido de civil, en una sesi\u00f3n de fotos aparentemente organizada por el gobierno aliado de Trump para avergonzar al dem\u00f3crata visitante.<\/p>\n<p>\u201cEl tema en cuesti\u00f3n es que \u00e9l y su administraci\u00f3n est\u00e1n desafiando una orden judicial que le otorga a \u00c1brego Garc\u00eda el derecho al debido proceso\u201d, <a href=\"https:\/\/www.cnn.com\/2025\/04\/20\/politics\/chris-van-hollen-kilmar-abrego-garcia\/index.html\">declar\u00f3 Van Hollen a Dana Bash de CNN<\/a> en \u201cState of the Union\u201d el domingo. \u201cTienen que aguantar o callarse en los tribunales\u201d. El senador argument\u00f3 que el caso demuestra que Estados Unidos tiene un \u201cpresidente sin ley que ignora la orden de la Corte Suprema de Estados Unidos de facilitar su regreso\u201d.<\/p>\n<p>Los dem\u00f3cratas, afectados por la prolongada negativa del expresidente Joe Biden a admitir una crisis en la frontera sur, han tenido dificultades recientemente para gestionar la pol\u00edtica migratoria. Y la administraci\u00f3n de Trump ha intentado explotar el caso de \u00c1brego Garc\u00eda para obligar a sus defensores a oponerse a su postura de l\u00ednea dura, que considera pol\u00edticamente beneficiosa.<\/p>\n<p>Pero Van Hollen afirm\u00f3 que los problemas van mucho m\u00e1s all\u00e1 de la dif\u00edcil situaci\u00f3n de un solo individuo y llegan a la cuesti\u00f3n fundamental del poder presidencial, donde Trump est\u00e1 forzando y potencialmente excediendo los l\u00edmites legales en temas que van m\u00e1s all\u00e1 de la inmigraci\u00f3n. Van Hollen argument\u00f3 que el presidente est\u00e1 utilizando el flagelo de la violencia de pandillas para justificar la elusi\u00f3n de las salvaguardias legales.<\/p>\n<p>Cuando Bash le pregunt\u00f3 si aceptar\u00eda que \u00c1brego Garc\u00eda fuera finalmente deportado, dada su situaci\u00f3n de indocumentado, Van Hollen respondi\u00f3: \u201cEstoy conforme con lo que dicte la ley\u201d.<\/p>\n<p>Van Hollen ha sido duramente criticado por Trump y la Casa Blanca por su visita. El presidente lo llam\u00f3 \u201ctonto\u201d y el caso ha llevado a algunos dem\u00f3cratas, incluido el gobernador de California, Gavin Newsom, a sugerir que al partido le convendr\u00eda atacar duramente a Trump en el tema econ\u00f3mico, un tema que podr\u00eda ser m\u00e1s importante para los votantes. Pero Van Hollen defendi\u00f3 su postura. Declar\u00f3 a Bash, de CNN: \u201cNo creo que est\u00e9 mal luchar por los derechos constitucionales de una persona, porque si renunciamos a los derechos de una persona, amenazamos los derechos de todos\u201d.<\/p>\n<p>Sin embargo, el zar de la frontera del Gobierno de Trump, Tom Homan, se neg\u00f3 a ceder en el caso, que se ha convertido en una prueba de fuego para el enfoque migratorio general de la administraci\u00f3n. Despu\u00e9s de todo, si \u00c1brego Garc\u00eda es devuelto, se cuestionar\u00e1 la situaci\u00f3n de cientos de otros inmigrantes indocumentados que, seg\u00fan la administraci\u00f3n, son terroristas y pandilleros que fueron <a href=\"https:\/\/www.cnn.com\/2025\/04\/08\/americas\/el-salvador-cecot-prison-deportees\/index.html\">enviados a una prisi\u00f3n de mala reputaci\u00f3n en El Salvador<\/a>. Y la administraci\u00f3n de Trump estar\u00eda admitiendo t\u00e1citamente que los tribunales ten\u00edan jurisdicci\u00f3n sobre su conducta.<\/p>\n<p>\u201cEliminamos una amenaza a la seguridad p\u00fablica, una amenaza a la seguridad nacional, un miembro de una pandilla violenta de Estados Unidos\u201d, dijo Homan el domingo en el programa \u201cThis Week\u201d de ABC News.<\/p>\n<p>\u201cLa inteligencia del ICE dice que es miembro de la MS-13. La informaci\u00f3n confidencial dice que es miembro de la MS-13. El Salvador dice que es miembro de la MS-13. Creo que est\u00e1 justo donde debe estar\u201d, a\u00f1adi\u00f3.<\/p>\n<p>El programa de deportaci\u00f3n masiva de la administraci\u00f3n de Trump, una pieza central de la campa\u00f1a electoral del presidente para 2024, ahora est\u00e1 envuelto en m\u00faltiples desaf\u00edos legales.<\/p>\n<p>Parece inevitable que las pol\u00edticas que ya han llegado a la Corte Suprema regresen all\u00ed para su decisi\u00f3n final en un momento de importancia hist\u00f3rica.<\/p>\n<p>En la madrugada del s\u00e1bado, por ejemplo, la mayor\u00eda del <a href=\"https:\/\/www.cnn.com\/2025\/04\/19\/politics\/supreme-court-alien-enemies-act-order\/index.html\">Tribunal Supremo impidi\u00f3 temporalmente que<\/a> la administraci\u00f3n deportara a un grupo de inmigrantes en Texas en virtud de la Ley de Enemigos Extranjeros de 1798. El juez Samuel Alito, quien discrep\u00f3 junto con su colega conservador Clarence Thomas, critic\u00f3 duramente la decisi\u00f3n, calific\u00e1ndola de \u201csin precedentes y legalmente cuestionable\u201d. Se espera que el tribunal emita un fallo m\u00e1s formal sobre si la Casa Blanca puede seguir adelante en los pr\u00f3ximos d\u00edas.<\/p>\n<p>El uso de la Ley de Enemigos Extranjeros es controvertido por varias razones. En primer lugar, es una de las leyes m\u00e1s infames de la historia de Estados Unidos y sirvi\u00f3 de base para el internamiento de estadounidenses de origen japon\u00e9s durante la Segunda Guerra Mundial, un cap\u00edtulo oscuro de la historia estadounidense. En segundo lugar, la ley est\u00e1 dise\u00f1ada para utilizarse en tiempos de guerra con el fin de detener y deportar a civiles. A pesar de la afirmaci\u00f3n de Trump de que Estados Unidos sufre una invasi\u00f3n migratoria, el pa\u00eds no se encuentra en estado de guerra.<\/p>\n<p>En otro caso relacionado con la ley, el juez federal de distrito James Boasberg <a href=\"https:\/\/www.cnn.com\/2025\/04\/16\/politics\/boasberg-contempt-deportation-flights\/index.html\">dictamin\u00f3 el mi\u00e9rcoles<\/a> que la administraci\u00f3n mostr\u00f3 una \u201cignorancia deliberada\u201d de su orden de mediados de marzo que suspend\u00eda los vuelos de deportaci\u00f3n en medio de una disputa sobre la legalidad de las expulsiones. Fue el primer juez en determinar que existe causa probable para declarar a funcionarios de la administraci\u00f3n en desacato penal.<\/p>\n<p>Las principales preocupaciones sobre el uso de la Ley de Enemigos Extranjeros se reducen a la falta de oportunidades para que los detenidos impugnen la acci\u00f3n en su contra ante los tribunales. Esta impresi\u00f3n (de que se est\u00e1n violando derechos constitucionales b\u00e1sicos y procedimientos legales que sustentan la rep\u00fablica) se materializa en el caso de \u00c1brego Garc\u00eda y es la raz\u00f3n por la que opositores de Trump como Van Hollen lo consideran tan crucial.<\/p>\n<p>En un giro clave del drama de la semana pasada, un tribunal federal de apelaciones rechaz\u00f3 la solicitud del gobierno de anular la decisi\u00f3n de la jueza federal de Maryland, <a href=\"https:\/\/www.cnn.com\/2025\/04\/17\/politics\/paula-xinis-judge-kilmar-abrego-garcia\/index.html\">Paula Xinis<\/a>, en el caso de \u00c1brego Garc\u00eda. Xinis est\u00e1 cada vez m\u00e1s frustrada con las t\u00e1cticas dilatorias y la actitud desafiante del gobierno tras ordenarle seguir las instrucciones de la Corte Suprema y facilitar su regreso.<\/p>\n<p>En un fallo emitido el jueves, la Corte de Apelaciones de Estados Unidos para el Cuarto Circuito deneg\u00f3 la solicitud de emergencia del gobierno para suspender la orden de Xinis en espera de la apelaci\u00f3n. En representaci\u00f3n de la corte de apelaciones, el juez Harvie Wilkinson afirm\u00f3 que la afirmaci\u00f3n de la administraci\u00f3n de \u201cun derecho a recluir a residentes de este pa\u00eds en prisiones extranjeras sin el debido proceso\u201d deber\u00eda ser \u201cimpactante no solo para los jueces, sino tambi\u00e9n para el sentido intuitivo de libertad que los estadounidenses, lejos de los tribunales, a\u00fan aprecian\u201d.<\/p>\n<p>Wilkinson, designado por el expresidente Ronald Reagan, advirti\u00f3 sobre una situaci\u00f3n en la que dos ramas del gobierno estaban \u201cenfrent\u00e1ndose irrevocablemente entre s\u00ed en un conflicto que promete debilitarlas a ambas\u201d.<\/p>\n<p>\u201cSi hoy el Ejecutivo se arroga el derecho a deportar sin el debido proceso y sin acatar las \u00f3rdenes judiciales, \u00bfqu\u00e9 garant\u00eda habr\u00e1 ma\u00f1ana de que no deporte a ciudadanos estadounidenses y luego se desentendi\u00f3 de su responsabilidad de traerlos de vuelta a casa?\u201d, pregunt\u00f3 Wilkinson. \u201c\u00bfY qu\u00e9 garant\u00eda habr\u00e1 de que el Ejecutivo no utilice sus amplios poderes discrecionales contra sus enemigos pol\u00edticos?\u201d<\/p>\n<p>El fallo encapsul\u00f3 este momento peligroso en la historia estadounidense y la cuesti\u00f3n de si el poder judicial \u2014uno de los \u00faltimos contrapesos efectivos del poder de Trump\u2014 restringir\u00e1 o facilitar\u00e1 el camino a un presidente que ve pocos l\u00edmites a su autoridad.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La saga de Kilmar \u00c1brego Garc\u00eda se ha convertido en la historia de m\u00e1s de un inmigrante indocumentado en una c\u00e1rcel salvadore\u00f1a y ahora es uno de esos casos raros que resuenan en la historia y dictan el car\u00e1cter de Estados Unidos. El destino del residente de Maryland deportado se est\u00e1 convirtiendo en una prueba [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1461465","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo la deportaci\u00f3n de \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de inflexi\u00f3n en la historia de Estados Unidos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo la deportaci\u00f3n de \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de inflexi\u00f3n en la historia de Estados Unidos - Noticias\" \/>\n<meta property=\"og:description\" content=\"La saga de Kilmar \u00c1brego Garc\u00eda se ha convertido en la historia de m\u00e1s de un inmigrante indocumentado en una c\u00e1rcel salvadore\u00f1a y ahora es uno de esos casos raros que resuenan en la historia y dictan el car\u00e1cter de Estados Unidos. El destino del residente de Maryland deportado se est\u00e1 convirtiendo en una prueba [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-21T23:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3mo la deportaci\u00f3n de \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de inflexi\u00f3n en la historia de Estados Unidos\",\"datePublished\":\"2025-04-21T23:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/\"},\"wordCount\":1760,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/\",\"name\":\"C\u00f3mo la deportaci\u00f3n de \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de inflexi\u00f3n en la historia de Estados Unidos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-21T23:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo la deportaci\u00f3n de \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de inflexi\u00f3n en la historia de Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo la deportaci\u00f3n de \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de inflexi\u00f3n en la historia de Estados Unidos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo la deportaci\u00f3n de \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de inflexi\u00f3n en la historia de Estados Unidos - Noticias","og_description":"La saga de Kilmar \u00c1brego Garc\u00eda se ha convertido en la historia de m\u00e1s de un inmigrante indocumentado en una c\u00e1rcel salvadore\u00f1a y ahora es uno de esos casos raros que resuenan en la historia y dictan el car\u00e1cter de Estados Unidos. El destino del residente de Maryland deportado se est\u00e1 convirtiendo en una prueba [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/","og_site_name":"Noticias","article_published_time":"2025-04-21T23:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/"},"author":{"name":"","@id":""},"headline":"C\u00f3mo la deportaci\u00f3n de \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de inflexi\u00f3n en la historia de Estados Unidos","datePublished":"2025-04-21T23:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/"},"wordCount":1760,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/","url":"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/","name":"C\u00f3mo la deportaci\u00f3n de \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de inflexi\u00f3n en la historia de Estados Unidos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-21T23:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo la deportaci\u00f3n de \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de inflexi\u00f3n en la historia de Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3mo la deportaci\u00f3n de \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de inflexi\u00f3n en la historia de Estados Unidos","url":"http:\/\/noticiasya.com\/reno\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2025\/04\/21\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-21T23:03:40Z","datePublished":"2025-04-21T23:03:40Z","dateModified":"2025-04-21T23:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3mo la deportaci\\u00f3n de \\u00c1brego Garc\\u00eda se convirti\\u00f3 en un punto de inflexi\\u00f3n en la historia de Estados Unidos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/21\\\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/21\\\/deportacion-salvadoreno-punto-inflexion-historia-estados-unidos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-21T23:03:40Z\",\"datePublished\":\"2025-04-21T23:03:40Z\",\"dateModified\":\"2025-04-21T23:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465772,"url":"https:\/\/noticiasya.com\/reno\/2025\/08\/22\/historia-kilmar-abrego-deportacion-liberacion-trax\/","url_meta":{"origin":1461465,"position":0},"title":"El caso de Kilmar \u00c1brego Garc\u00eda: desde su deportaci\u00f3n por error a El Salvador hasta su liberaci\u00f3n de custodia criminal","author":"","date":"agosto 22, 2025","format":false,"excerpt":"La pesadilla de Kilmar \u00c1brego Garc\u00eda comenz\u00f3 en marzo pasado, cuando fue deportado por un \u201cerror administrativo\u201d a El Salvador y encarcelado en una prisi\u00f3n de m\u00e1xima seguridad del pa\u00eds. Su caso fue motivo de una prolongada batalla pol\u00edtica y legal del Gobierno de Donald Trump contra los jueces que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463302,"url":"https:\/\/noticiasya.com\/reno\/2025\/06\/07\/caso-abrego-garcia-conflicto-politico-trax\/","url_meta":{"origin":1461465,"position":1},"title":"C\u00f3mo el caso de Kilmar \u00c1brego Garc\u00eda se convirti\u00f3 en un punto de conflicto pol\u00edtico","author":"","date":"junio 7, 2025","format":false,"excerpt":"El caso de Kilmar \u00c1brego Garc\u00eda comenz\u00f3 discretamente, reduci\u00e9ndose a un error administrativo que lo elev\u00f3 en la lista para abordar un vuelo de deportaci\u00f3n con destino a El Salvador en marzo. Posteriormente, un documento judicial del Departamento de Justicia de Trump que reconoc\u00eda el error lo puso en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463317,"url":"https:\/\/noticiasya.com\/reno\/2025\/06\/07\/trump-decision-abrego-garcia-trax\/","url_meta":{"origin":1461465,"position":2},"title":"Trump se refiri\u00f3 al regreso de \u00c1brego Garc\u00eda a EE.UU. tras su deportaci\u00f3n por error a El Salvador: &#171;No fue mi decisi\u00f3n&#187;","author":"","date":"junio 7, 2025","format":false,"excerpt":"El presidente Donald Trump afirm\u00f3 que no fue decisi\u00f3n suya traer a Kilmar \u00c1brego Garc\u00eda de vuelta a Estados Unidos para que se enfrentara a cargos penales federales, sino del Departamento de Justicia.\u201cEl Departamento de Justicia decidi\u00f3 hacerlo as\u00ed, y est\u00e1 bien\u201d, dijo Trump en una entrevista telef\u00f3nica con NBC.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461776,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/30\/trump-traer-abrego-garcia-el-salvador-trax\/","url_meta":{"origin":1461465,"position":3},"title":"Trump dice que &#171;podr\u00eda&#187; traer de vuelta a \u00c1brego Garc\u00eda desde El Salvador, pero no lo har\u00e1","author":"","date":"abril 30, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, reconoci\u00f3 este martes que podr\u00eda lograr el regreso de Kilmar Armando \u00c1brego Garc\u00eda, un hombre de Maryland que fue deportado injustamente a El Salvador el mes pasado, pero se niega a hacerlo.Los comentarios parecen contradecir declaraciones previas hechas por \u00e9l y sus principales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464170,"url":"https:\/\/noticiasya.com\/reno\/2025\/07\/03\/abogados-kilmar-abrego-el-salvador-trax\/","url_meta":{"origin":1461465,"position":4},"title":"Abogados de Kilmar \u00c1brego Garc\u00eda detallan torturas y malos tratos en la megac\u00e1rcel de El Salvador","author":"","date":"julio 3, 2025","format":false,"excerpt":"Los abogados de Kilmar \u00c1brego Garc\u00eda continuaron el mi\u00e9rcoles su esfuerzo para mantener vivo su caso civil contra la administraci\u00f3n Trump, solicitando enmendar la demanda para incluir lo que describen como la \u201ctortura y maltrato\u201d que experiment\u00f3 en la notoria megaprisi\u00f3n de El Salvador, adonde fue deportado injustamente y retenido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460934,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/07\/kilmar-abrego-que-paso-salvadoreno-deportado-error-trax\/","url_meta":{"origin":1461465,"position":5},"title":"Qu\u00e9 pas\u00f3 con Kilmar \u00c1brego, el salvadore\u00f1o deportado de EE.UU. por error, y en qu\u00e9 va su caso","author":"","date":"abril 7, 2025","format":false,"excerpt":"Kilmar Armando \u00c1brego Garc\u00eda es un padre de tres hijos que viv\u00eda en Maryland a quien el Gobierno de Donald Trump afirm\u00f3 haber deportado por error a El Salvador.Seg\u00fan sus abogados, \u00c1brego Garc\u00eda huy\u00f3 de la violencia de pandillas en El Salvador hace m\u00e1s de una d\u00e9cada. Fue identificado por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1461465"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461465\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1461465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1461465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1461465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}