{"id":1461479,"date":"2025-04-22T06:03:43","date_gmt":"2025-04-22T13:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/"},"modified":"2025-04-22T06:03:43","modified_gmt":"2025-04-22T13:03:43","slug":"fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/","title":{"rendered":"Fernando S\u00e1nchez, candidato de CC: Si Macri y Bullrich &#171;no solucionan el problema de seguridad es por una disputa de poder&#187;"},"content":{"rendered":"<p>Fernando S\u00e1nchez, candidato a legislador porte\u00f1o por la Coalici\u00f3n C\u00edvica (CC), visit\u00f3 los estudios de CNN Radio para analizar las elecciones legislativas en la ciudad de Buenos Aires, que se realizar\u00e1n el 18 d emayo.<\/p>\n<p>En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201ces una campa\u00f1a que hay que percibir el \u00e1nimo de la sociedad, que quiere que las cosas vayan bien pero que no quiere que se desordene en otros\u201d.<\/p>\n<p>Remarc\u00f3 que <strong>\u201cal electorado porte\u00f1o no le gusta que se le grite, no le gusta el agravio. En la calle hay un enojo enorme pero todas las charlas terminan en saber c\u00f3mo le vas a solucionar el problema del entorno\u201d<\/strong>.<\/p>\n<p>En este sentido, asegur\u00f3 que <strong>\u201cdesaparecieron los debates sobre el cambio ambiental, la diversidad, hay que hablar de lo que importa y no lo que est\u00e1 de moda\u201d<\/strong>.<\/p>\n<p>No obstante, remarc\u00f3 que \u201ctodos hablan de seguridad y hacen hincapi\u00e9 en las fugas de las comisarias, porque la crisis no fue resuelta. Hay que ver que se puede hacer con la gente en situaci\u00f3n de calle, con problemas mentales, con consumo problem\u00e1tico, y las situaciones de vivienda\u201d.<\/p>\n<p>El candidato a legislador por la CC, detall\u00f3 que hay <strong>\u201c17 opciones electorales es un mont\u00f3n. La mayor\u00eda de los partidos en los que est\u00e1bamos en alianza est\u00e1n en internas y nosotros tenemos el partido ordenado. No estamos para ordenar las internas de otros. As\u00ed que queremos dar nuestras propuestas\u201d<\/strong>.<\/p>\n<p>Adem\u00e1s, detall\u00f3 que <strong>\u201cqueremos revisar los contratos de la basura, ayudar a resolver el problema de las c\u00e1rceles con la Naci\u00f3n porque si el jefe de gobierno y la ministra de Seguridad, que se conocen, no pueden solucionar el problema es por la disputa de poder\u201d<\/strong>.<\/p>\n<p>Por otro lado, Fernando S\u00e1nchez afirm\u00f3 que <strong>\u201cla CC tuvo la responsabilidad de pensar en un grupo vulnerable como son los jubilados.<br \/>Los que jubilados perdieron 8% en el cambio de la f\u00f3rmula de Alberto Fern\u00e1ndez a Javier Milei\u201d<\/strong>.<\/p>\n<p>Y asegur\u00f3 que \u201cpiensa en resolver el problema, con responsabilidad fiscal, eso es lo que hizo mi partido\u201d.<\/p>\n<p>En este sentido, explic\u00f3 que \u201c<strong>gran arte de la poblaci\u00f3n de la ciudad es mayor de 60 a\u00f1os, la mayor\u00eda vulnerable<\/strong>. Llevamos proyectos para favorecer el pago de ABL, la seguridad alimentaria para ir con una ayuda m\u00e1s fuerte y darle programas para que las personas cuando salen en la vida laboral se reinserten en la vida social y cultural\u201d.<\/p>\n<p>El postulante de la CC concluy\u00f3 que esos programas necesitan bajos recursos y no rompen la responsabilidad fiscal y consider\u00f3 que <strong>\u201chay que ser un poco de Milei con alma\u201d<\/strong>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fernando S\u00e1nchez, candidato a legislador porte\u00f1o por la Coalici\u00f3n C\u00edvica (CC), visit\u00f3 los estudios de CNN Radio para analizar las elecciones legislativas en la ciudad de Buenos Aires, que se realizar\u00e1n el 18 d emayo. En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201ces una campa\u00f1a que hay que percibir el \u00e1nimo de la sociedad, que quiere [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1461479","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fernando S\u00e1nchez, candidato de CC: Si Macri y Bullrich &quot;no solucionan el problema de seguridad es por una disputa de poder&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fernando S\u00e1nchez, candidato de CC: Si Macri y Bullrich &quot;no solucionan el problema de seguridad es por una disputa de poder&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Fernando S\u00e1nchez, candidato a legislador porte\u00f1o por la Coalici\u00f3n C\u00edvica (CC), visit\u00f3 los estudios de CNN Radio para analizar las elecciones legislativas en la ciudad de Buenos Aires, que se realizar\u00e1n el 18 d emayo. En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201ces una campa\u00f1a que hay que percibir el \u00e1nimo de la sociedad, que quiere [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-22T13:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fernando S\u00e1nchez, candidato de CC: Si Macri y Bullrich &#171;no solucionan el problema de seguridad es por una disputa de poder&#187;\",\"datePublished\":\"2025-04-22T13:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/\"},\"wordCount\":487,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/\",\"name\":\"Fernando S\u00e1nchez, candidato de CC: Si Macri y Bullrich \\\"no solucionan el problema de seguridad es por una disputa de poder\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-22T13:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fernando S\u00e1nchez, candidato de CC: Si Macri y Bullrich &#171;no solucionan el problema de seguridad es por una disputa de poder&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fernando S\u00e1nchez, candidato de CC: Si Macri y Bullrich \"no solucionan el problema de seguridad es por una disputa de poder\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/","og_locale":"es_ES","og_type":"article","og_title":"Fernando S\u00e1nchez, candidato de CC: Si Macri y Bullrich \"no solucionan el problema de seguridad es por una disputa de poder\" - Noticias","og_description":"Fernando S\u00e1nchez, candidato a legislador porte\u00f1o por la Coalici\u00f3n C\u00edvica (CC), visit\u00f3 los estudios de CNN Radio para analizar las elecciones legislativas en la ciudad de Buenos Aires, que se realizar\u00e1n el 18 d emayo. En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201ces una campa\u00f1a que hay que percibir el \u00e1nimo de la sociedad, que quiere [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/","og_site_name":"Noticias","article_published_time":"2025-04-22T13:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/"},"author":{"name":"","@id":""},"headline":"Fernando S\u00e1nchez, candidato de CC: Si Macri y Bullrich &#171;no solucionan el problema de seguridad es por una disputa de poder&#187;","datePublished":"2025-04-22T13:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/"},"wordCount":487,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/","url":"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/","name":"Fernando S\u00e1nchez, candidato de CC: Si Macri y Bullrich \"no solucionan el problema de seguridad es por una disputa de poder\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-22T13:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Fernando S\u00e1nchez, candidato de CC: Si Macri y Bullrich &#171;no solucionan el problema de seguridad es por una disputa de poder&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fernando S\u00e1nchez, candidato de CC: Si Macri y Bullrich &#171;no solucionan el problema de seguridad es por una disputa de poder&#187;","url":"http:\/\/noticiasya.com\/reno\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2025\/04\/22\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-22T13:03:43Z","datePublished":"2025-04-22T13:03:43Z","dateModified":"2025-04-22T13:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Fernando S\\u00e1nchez, candidato de CC: Si Macri y Bullrich &#171;no solucionan el problema de seguridad es por una disputa de poder&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/22\\\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/22\\\/fernando-sanchez-candidato-de-cc-si-macri-y-bullrich-no-solucionan-el-problema-de-seguridad-es-por-una-disputa-de-poder\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-22T13:03:43Z\",\"datePublished\":\"2025-04-22T13:03:43Z\",\"dateModified\":\"2025-04-22T13:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461708,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/28\/alejandro-kim-candidato-porteno-de-principios-y-valores-la-gente-se-va-a-encontrar-con-un-peronismo-con-sentido-comun\/","url_meta":{"origin":1461479,"position":0},"title":"Alejandro Kim, candidato porte\u00f1o de Principios y Valores: &#171;La gente se va a encontrar con un peronismo con sentido com\u00fan&#187;","author":"","date":"abril 28, 2025","format":false,"excerpt":"Alejandro Kim, candidato a legislador porte\u00f1o por Principios y Valores, el partido de Guillermo Moreno, visit\u00f3 los estudios de CNN Radio para analizar las elecciones del pr\u00f3ximo 18 de mayo en la ciudad de Buenos Aires.En CNN Primera Ma\u00f1ana, afirm\u00f3 que en el \u201ccontacto con la gente veo dos cosas.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461796,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/30\/laura-alonso-los-libertarios-no-conocen-la-ciudad-y-no-les-importa\/","url_meta":{"origin":1461479,"position":1},"title":"Laura Alonso: &#171;Los libertarios no conocen la ciudad y no les importa&#187;","author":"","date":"abril 30, 2025","format":false,"excerpt":"Laura Alonso, vocera del Gobierno de la Ciudad de Buenos Aires y candidata a legisladora porte\u00f1a, visit\u00f3 los estudios de CNN para conversar con Nacho Gir\u00f3n y su equipo sobre las elecciones legislativas.En La Ma\u00f1ana de CNN afirm\u00f3 que \u201cSilvia Lospennato gan\u00f3 el debate porte\u00f1o de punta a punta. Es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462127,"url":"https:\/\/noticiasya.com\/reno\/2025\/05\/08\/que-la-izquierda-este-dividida-es-responsabilidad-del-fit\/","url_meta":{"origin":1461479,"position":2},"title":"Federico Winokur: &#171;Que la Izquierda est\u00e9 dividida es responsabilidad del FIT&#187;","author":"","date":"mayo 8, 2025","format":false,"excerpt":"Federico Winokur, candidato a legislador de \u201cLa Izquierda en la Ciudad\u201d, visit\u00f3 este jueves los estudios de CNN Radio para conversar con Nacho Gir\u00f3n y el equipo de La Ma\u00f1ana de CNN sobre las principales propuestas de su espacio para el \u00e1mbito parlamentario porte\u00f1o y cuestion\u00f3 la gesti\u00f3n del PRO\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460652,"url":"https:\/\/noticiasya.com\/reno\/2025\/03\/31\/ramiro-marra-candidato-a-legislador-porteno-hay-que-recuperar-la-via-publica\/","url_meta":{"origin":1461479,"position":3},"title":"Ramiro Marra, candidato a legislador porte\u00f1o: &#171;Hay que recuperar la v\u00eda p\u00fablica&#187;","author":"","date":"marzo 31, 2025","format":false,"excerpt":"Ramiro Marra, candidato a legislador porte\u00f1o por la UCeD\u00e9, convers\u00f3 con Pepe Gil Vidal y Mariana Arias en Regreso CNN sobre sus principales propuestas para la Ciudad de Buenos Aires, su alejamiento de La Libertad Avanza y su acompa\u00f1amiento al Gobierno de Javier Milei.\u201cLas ideas est\u00e1n basadas en recuperar la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460707,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/01\/waldo-wolf-candidato-a-legislador-hay-un-sector-del-oficialismo-que-quiere-ir-por-el-pro\/","url_meta":{"origin":1461479,"position":4},"title":"Waldo Wolf, candidato a legislador: &#171;Hay un sector del oficialismo que quiere ir por el PRO&#187;","author":"","date":"abril 1, 2025","format":false,"excerpt":"Waldo Wolfff, candidato a legislador en la lista del PRO, visit\u00f3 los estudios de CNN Radio para hablar de su postulaci\u00f3n en la Ciudad de Buenos Aires y le dej\u00f3 un mensaje a La Libertad Avanza: \u201cHay intenci\u00f3n pol\u00edtica de destruir al PRO\u201d.\u201cLlev\u00e9 el cargo (de ministro de Seguridad porte\u00f1o)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461306,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/17\/caruso-lombardi-no-se-cuantos-candidatos-pueden-caminar-entre-la-gente\/","url_meta":{"origin":1461479,"position":5},"title":"Caruso Lombardi: &#171;No s\u00e9 cu\u00e1ntos candidatos pueden caminar entre la gente&#187;","author":"","date":"abril 17, 2025","format":false,"excerpt":"Ricardo Caruso Lombardi, candidato a legislador porte\u00f1o por el MID, visit\u00f3 los estudios de CNN Radio para hablar de su postulaci\u00f3n.En CNN Primera Ma\u00f1ana, afirm\u00f3 que est\u00e1 \u201centusiasmado. No lo pensaba. A la hora de ganar un partido yo le meto. Soy competidor. Creo que hay que comprometerse. Yo hice\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1461479"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461479\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1461479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1461479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1461479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}