{"id":1461481,"date":"2025-04-22T07:03:42","date_gmt":"2025-04-22T14:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/"},"modified":"2025-04-22T07:03:42","modified_gmt":"2025-04-22T14:03:42","slug":"migrantes-venezolanos-trump-orden-corte-suprema-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/","title":{"rendered":"Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema"},"content":{"rendered":"<p>Un grupo de inmigrantes venezolanos que la administraci\u00f3n Trump <a href=\"https:\/\/www.cnn.com\/2025\/04\/19\/politics\/supreme-court-alien-enemies-act-order\/index.html\">ten\u00eda en la mira para su deportaci\u00f3n bajo una amplia autoridad en tiempos de guerra<\/a> dijo a la Corte Suprema que el aviso que les dieron los funcionarios de inmigraci\u00f3n sobre su inminente deportaci\u00f3n no cumple con una orden anterior del tribunal superior.<\/p>\n<p>\u201cNo se puede decir en ning\u00fan caso que los avisos en ingl\u00e9s proporcionados menos de 24 horas antes de una deportaci\u00f3n seg\u00fan la Ley de Enemigos Extranjeros cumplan con la orden de este tribunal de que el aviso debe ser suficiente para permitir que las personas realmente soliciten una revisi\u00f3n de h\u00e1beas corpus\u201d, dijo la Uni\u00f3n Estadounidense por las Libertades Civiles (ACLU, por sus siglas en ingl\u00e9s), que representa a los migrantes, en un escrito presentado el lunes.<\/p>\n<p>Esto hace referencia a una orden poco transparente que la Corte Suprema dict\u00f3 el 7 de abril en un caso separado, pero relacionado, de la AEA. En dicha orden, los nueve jueces coincidieron en que la administraci\u00f3n Trump debe proporcionar a las personas a las que se dirig\u00eda la ley un aviso suficiente para que puedan impugnar sus deportaciones. Sin embargo, los jueces no aclararon con qu\u00e9 antelaci\u00f3n es suficiente, y la administraci\u00f3n Trump, deseosa de reanudar las deportaciones, adopt\u00f3 una visi\u00f3n minimalista de lo que deb\u00eda hacer.<\/p>\n<p>La ACLU tambi\u00e9n solicit\u00f3 a la Corte Suprema, en su \u00faltimo escrito, que escuchara los argumentos sobre su solicitud de impedir que funcionarios de Trump realicen m\u00e1s deportaciones bajo la ley mientras contin\u00faa el litigio subyacente. En una orden emitida la madrugada del s\u00e1bado, el tribunal suspendi\u00f3 por ahora las deportaciones bajo la ley mientras revisa la solicitud de la ACLU.<\/p>\n<p>En una rara orden nocturna, una mayor\u00eda de jueces bloque\u00f3 a la administraci\u00f3n Trump de deportar a un grupo de inmigrantes en Texas este s\u00e1bado. Dos conservadores, los jueces Clarence Thomas y Samuel Alito, disintieron de la decisi\u00f3n.<\/p>\n<p>El breve fallo de la corte no explic\u00f3 su razonamiento. Los magistardos ordenaron a la administraci\u00f3n Trump responder a la apelaci\u00f3n de emergencia \u201clo antes posible\u201d, lo cual hizo m\u00e1s tarde el s\u00e1bado. Mientras tanto, la corte dijo: \u201cSe ordena al gobierno que no remueva a ning\u00fan miembro de la clase putativa de detenidos de los Estados Unidos hasta nueva orden de esta corte\u201d.<\/p>\n<p>La administraci\u00f3n Trump respondi\u00f3 m\u00e1s tarde el mismo s\u00e1bado, diciendo a la Corte Suprema que quiere la autoridad para remover a los venezolanos detenidos en Texas bajo leyes distintas a la controvertida Ley de Enemigos Extranjeros mientras contin\u00faa el litigio sobre sus posibles deportaciones.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de inmigrantes venezolanos que la administraci\u00f3n Trump ten\u00eda en la mira para su deportaci\u00f3n bajo una amplia autoridad en tiempos de guerra dijo a la Corte Suprema que el aviso que les dieron los funcionarios de inmigraci\u00f3n sobre su inminente deportaci\u00f3n no cumple con una orden anterior del tribunal superior. \u201cNo se puede [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1461481","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un grupo de inmigrantes venezolanos que la administraci\u00f3n Trump ten\u00eda en la mira para su deportaci\u00f3n bajo una amplia autoridad en tiempos de guerra dijo a la Corte Suprema que el aviso que les dieron los funcionarios de inmigraci\u00f3n sobre su inminente deportaci\u00f3n no cumple con una orden anterior del tribunal superior. \u201cNo se puede [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-22T14:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema\",\"datePublished\":\"2025-04-22T14:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/\"},\"wordCount\":492,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/\",\"name\":\"Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-22T14:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema - Noticias","og_description":"Un grupo de inmigrantes venezolanos que la administraci\u00f3n Trump ten\u00eda en la mira para su deportaci\u00f3n bajo una amplia autoridad en tiempos de guerra dijo a la Corte Suprema que el aviso que les dieron los funcionarios de inmigraci\u00f3n sobre su inminente deportaci\u00f3n no cumple con una orden anterior del tribunal superior. \u201cNo se puede [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/","og_site_name":"Noticias","article_published_time":"2025-04-22T14:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/"},"author":{"name":"","@id":""},"headline":"Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema","datePublished":"2025-04-22T14:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/"},"wordCount":492,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/","url":"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/","name":"Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-22T14:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema","url":"http:\/\/noticiasya.com\/reno\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-22T14:03:42Z","datePublished":"2025-04-22T14:03:42Z","dateModified":"2025-04-22T14:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Migrantes venezolanos afirman que la administraci\\u00f3n Trump no cumple con la orden de la Corte Suprema\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/22\\\/migrantes-venezolanos-trump-orden-corte-suprema-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/22\\\/migrantes-venezolanos-trump-orden-corte-suprema-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-22T14:03:42Z\",\"datePublished\":\"2025-04-22T14:03:42Z\",\"dateModified\":\"2025-04-22T14:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461369,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/18\/migrantes-venezolanos-texas-detener-deportacion-ley-enemigos-extranjeros-trax\/","url_meta":{"origin":1461481,"position":0},"title":"Migrantes venezolanos en Texas piden a la Corte Suprema que detenga su deportaci\u00f3n bajo la Ley de Enemigos Extranjeros","author":"","date":"abril 18, 2025","format":false,"excerpt":"Un grupo de migrantes venezolanos en Texas pidi\u00f3 este viernes a la Corte Suprema que detenga su deportaci\u00f3n bajo la Ley de Enemigos Extranjeros.La apelaci\u00f3n de emergencia es la segunda vez que el uso de Trump de la amplia autoridad de tiempos de guerra del siglo XVIII llega al alto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461407,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/20\/orden-corte-suprema-sobre-la-ley-de-enemigos-extranjeros-trax\/","url_meta":{"origin":1461481,"position":1},"title":"Qu\u00e9 hay que saber de la orden de la Corte Suprema de Justicia de EE.UU. sobre la Ley de Enemigos Extranjeros","author":"","date":"abril 20, 2025","format":false,"excerpt":"Menos de dos semanas despu\u00e9s de que la Corte Suprema de Justicia de EE.UU. permiti\u00f3 al presidente Donald Trump usar una controvertida autoridad de tiempos de guerra del siglo XVIII para acelerar las deportaciones, el tema ha vuelto a los jueces en una segunda apelaci\u00f3n de corta duraci\u00f3n con enormes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461857,"url":"https:\/\/noticiasya.com\/reno\/2025\/05\/01\/trump-pide-corte-suprema-terminar-tps-venezolanos-eeuu-trax\/","url_meta":{"origin":1461481,"position":2},"title":"Trump pide a la Corte Suprema que termine con las protecciones de deportaci\u00f3n TPS para venezolanos en EE.UU.","author":"","date":"mayo 1, 2025","format":false,"excerpt":"El Gobierno del presidente Donald Trump inst\u00f3 a la Corte Suprema el jueves a deshacer las protecciones de deportaci\u00f3n para cientos de miles de venezolanos que han sido mantenidas temporalmente por un tribunal federal inferior.En cuesti\u00f3n est\u00e1 una decisi\u00f3n de principios de este a\u00f1o de la secretaria de Seguridad Nacional,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463876,"url":"https:\/\/noticiasya.com\/reno\/2025\/06\/23\/corte-suprema-permite-trump-deportar-migrantes-sudan-del-sur-trax\/","url_meta":{"origin":1461481,"position":3},"title":"La Corte Suprema de EE.UU. permite a Trump deportar migrantes a Sud\u00e1n del Sur y otros pa\u00edses en crisis","author":"","date":"junio 23, 2025","format":false,"excerpt":"La Corte Suprema de EE.UU. concedi\u00f3 este lunes la solicitud de emergencia del presidente Donald Trump para reanudar la deportaci\u00f3n de migrantes a pa\u00edses distintos de su lugar de origen, incluidos lugares como Sud\u00e1n del Sur, con un aviso m\u00ednimo.La decisi\u00f3n representa una victoria significativa para el Gobierno de Trump,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462871,"url":"https:\/\/noticiasya.com\/reno\/2025\/05\/27\/trump-pide-corte-suprema-facilita-deportacion-inmigrantes-sudan-del-sur-trax\/","url_meta":{"origin":1461481,"position":4},"title":"Trump pide a la Corte Suprema facilitar la deportaci\u00f3n de migrantes a Sud\u00e1n del Sur y otros &#171;terceros&#187; pa\u00edses","author":"","date":"mayo 27, 2025","format":false,"excerpt":"El presidente Donald Trump pidi\u00f3 este martes a la Corte Suprema que facilite a su administraci\u00f3n la deportaci\u00f3n de personas a Sud\u00e1n del Sur y otros pa\u00edses que no son su pa\u00eds de origen, la m\u00e1s reciente de una serie de pol\u00edticas migratorias controversiales que su Gobierno ha presentado ante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467091,"url":"https:\/\/noticiasya.com\/reno\/2025\/10\/03\/corte-suprema-trump-poner-fin-tps-venezolanos-trax\/","url_meta":{"origin":1461481,"position":5},"title":"La Corte Suprema permite a Trump poner fin a las protecciones contra la deportaci\u00f3n para 300.000 venezolanos","author":"","date":"octubre 3, 2025","format":false,"excerpt":"Este viernes, la Corte Suprema permiti\u00f3 por segunda vez al presidente Donald Trump retirar las protecciones temporales contra la deportaci\u00f3n de 300.000 venezolanos.En una breve orden, y con la disidencia de los tres jueces progresistas de la Corte, la mayor\u00eda de los magistrados dictamin\u00f3 que el Gobierno pod\u00eda seguir adelante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1461481"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461481\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1461481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1461481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1461481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}