{"id":1461487,"date":"2025-04-22T09:03:50","date_gmt":"2025-04-22T16:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/"},"modified":"2025-04-22T09:03:50","modified_gmt":"2025-04-22T16:03:50","slug":"acciones-estadounidenses-oro-maximo-historico-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/","title":{"rendered":"Las acciones estadounidenses se recuperan mientras el oro alcanza un m\u00e1ximo hist\u00f3rico"},"content":{"rendered":"<p>Las acciones estadounidenses subieron el martes por la ma\u00f1ana a medida que los inversores ingresaban al mercado despu\u00e9s de una fuerte liquidaci\u00f3n el lunes.<\/p>\n<p>El Dow Jones gan\u00f3 600 puntos, o un 1,58 %. El S&#038;P 500, en general, avanz\u00f3 un 1,57 %. El Nasdaq Composite, con un fuerte componente tecnol\u00f3gico, subi\u00f3 un 1,9 %.<\/p>\n<p>Los inversores han estado nerviosos debido a la persistente incertidumbre sobre las negociaciones comerciales y al aumento de las cr\u00edticas del presidente Donald Trump al presidente de la Reserva Federal, Jerome Powell.<\/p>\n<p>El Nasdaq y el Dow Jones buscan romper una racha de cuatro d\u00edas de p\u00e9rdidas. Los tres \u00edndices principales se encaminan a su peor mes desde 2022 y el Dow Jones va camino de su peor abril desde 1932, seg\u00fan datos de FactSet.<\/p>\n<p>Las acciones vienen de una jornada marcadamente en rojo, ya que los inversores evaluaron la continua diatriba de Trump contra Powell por no recortar las tasas de inter\u00e9s, una queja que ha presentado en repetidas ocasiones. La independencia de la Reserva Federal (Fed, por sus siglas en ingl\u00e9s) es un sello distintivo del banco central, y los analistas del mercado se han mostrado inquietos por los continuos ataques verbales del presidente contra el presidente de la Fed.<\/p>\n<p>\u201cUna guerra comercial en m\u00faltiples frentes es en s\u00ed misma demasiado para que las acciones la manejen, por lo que agregarle una crisis de independencia de la Fed encima tiene a los mercados comprensiblemente nerviosos\u201d, dijo Jeff Buchbinder, estratega jefe de acciones de LPL Financial, en una nota del lunes.<\/p>\n<p>Si bien muchos expertos dicen que el presidente en realidad no tiene el poder de despedir al jefe de la Reserva Federal solo por diferencias pol\u00edticas, Trump ha dejado en claro que est\u00e1 dispuesto a romper con las normas y los precedentes.<\/p>\n<p>Mohit Kumar, economista jefe y estratega para Europa de Jefferies, dijo en una nota del martes que \u201cser\u00e1 casi imposible para Trump destituir a Powell sin motivo\u201d y es poco probable que Trump tenga un apoyo pol\u00edtico m\u00e1s amplio para expulsar a Powell antes de que finalice su mandato en 2026.<\/p>\n<p>\u201cAdem\u00e1s, como han demostrado los acontecimientos recientes, el mercado de bonos es el punto de presi\u00f3n para Trump\u201d, dijo Kumar. \u201cCualquier intento de socavar la independencia de la Fed se enfrentar\u00e1 a una fuerte reacci\u00f3n negativa en el mercado de bonos y Trump tendr\u00e1 que ceder\u201d.<\/p>\n<p>Las acciones estadounidenses, los bonos del gobierno y el d\u00f3lar sufrieron una fuerte ca\u00edda el lunes, continuando una tendencia que ha inquietado a Wall Street. Normalmente, cuando las acciones se desploman en momentos de incertidumbre, los inversores buscan refugio en activos refugio como los bonos del Tesoro y el d\u00f3lar. Sin embargo, esta creencia popular se ha desmoronado este mes durante las oleadas de ventas en las tres clases de activos estadounidenses.<\/p>\n<p>El rendimiento de los bonos del Tesoro a 10 a\u00f1os baj\u00f3 ligeramente y el d\u00f3lar estadounidense gan\u00f3 ligeramente el martes por la ma\u00f1ana, lo que indica una relativa calma despu\u00e9s de la venta masiva del lunes.<\/p>\n<p>El oro alcanz\u00f3 el martes un nuevo <a href=\"https:\/\/www.cnn.com\/2025\/04\/22\/business\/gold-price-surge-trump-powell-attacks-stocks-hnk-intl\/index.html\">r\u00e9cord hist\u00f3rico<\/a> por encima de los US$ 3.500 a onza troy. El metal precioso se ha disparado m\u00e1s de un 30 % este a\u00f1o, superando su ganancia del 27 % del a\u00f1o pasado. Los inversores han acudido en masa al oro ante la incertidumbre generalizada sobre las perspectivas de la econom\u00eda mundial.<\/p>\n<p>Los aranceles de Trump y las contramedidas impuestas por los socios comerciales de Estados Unidos probablemente supondr\u00e1n un duro golpe al crecimiento econ\u00f3mico mundial, y la prosperidad estadounidense se ver\u00e1 especialmente afectada, seg\u00fan el Fondo Monetario Internacional (FMI).<\/p>\n<p>Se espera que el crecimiento econ\u00f3mico mundial se desacelere al 2,8 % este a\u00f1o, desde el 3,3 % del a\u00f1o pasado y significativamente por debajo del promedio hist\u00f3rico, seg\u00fan pronostic\u00f3 el FMI en sus Perspectivas de la Econom\u00eda Mundial el martes. La desaceleraci\u00f3n prevista en Estados Unidos es a\u00fan m\u00e1s pronunciada, ya que su econom\u00eda probablemente crecer\u00e1 solo un 1,8 %, en comparaci\u00f3n con el 2,8 % en 2024.<\/p>\n<p>Esta semana Wall Street estar\u00e1 atento a posibles se\u00f1ales de progreso en las negociaciones comerciales, pero tambi\u00e9n se centrar\u00e1 en una serie de resultados de ganancias para el primer trimestre.<\/p>\n<p>Los inversores probablemente estar\u00e1n atentos hoy a los resultados de Tesla (<a href=\"https:\/\/www.cnn.com\/markets\/stocks\/TSLA\">TSLA<\/a>), que se publicar\u00e1n despu\u00e9s del cierre del mercado. La compa\u00f1\u00eda de veh\u00edculos el\u00e9ctricos de Elon Musk ha desplomado su valor de mercado este a\u00f1o, con una ca\u00edda de sus acciones de m\u00e1s del 40 %. Esta ca\u00edda de las acciones de Tesla se produce en medio de <a href=\"https:\/\/www.cnn.com\/2025\/03\/22\/business\/musk-doge-tesla-demonstrations\/index.html\">las cr\u00edticas<\/a> contra el papel de Musk en el gobierno estadounidense y la ca\u00edda de las ventas en Europa.<\/p>\n<p>El \u201cmiedo extremo\u201d fue el sentimiento que impuls\u00f3 los mercados el martes, seg\u00fan <a href=\"https:\/\/www.cnn.com\/markets\/fear-and-greed\">el \u00edndice de Miedo y Avaricia de CNN<\/a>. Este \u00edndice se ha mantenido firme en \u201cmiedo extremo\u201d este mes.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las acciones estadounidenses subieron el martes por la ma\u00f1ana a medida que los inversores ingresaban al mercado despu\u00e9s de una fuerte liquidaci\u00f3n el lunes. El Dow Jones gan\u00f3 600 puntos, o un 1,58 %. El S&#038;P 500, en general, avanz\u00f3 un 1,57 %. El Nasdaq Composite, con un fuerte componente tecnol\u00f3gico, subi\u00f3 un 1,9 %. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1461487","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las acciones estadounidenses se recuperan mientras el oro alcanza un m\u00e1ximo hist\u00f3rico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las acciones estadounidenses se recuperan mientras el oro alcanza un m\u00e1ximo hist\u00f3rico - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las acciones estadounidenses subieron el martes por la ma\u00f1ana a medida que los inversores ingresaban al mercado despu\u00e9s de una fuerte liquidaci\u00f3n el lunes. El Dow Jones gan\u00f3 600 puntos, o un 1,58 %. El S&#038;P 500, en general, avanz\u00f3 un 1,57 %. El Nasdaq Composite, con un fuerte componente tecnol\u00f3gico, subi\u00f3 un 1,9 %. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-22T16:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las acciones estadounidenses se recuperan mientras el oro alcanza un m\u00e1ximo hist\u00f3rico\",\"datePublished\":\"2025-04-22T16:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/\"},\"wordCount\":872,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/\",\"name\":\"Las acciones estadounidenses se recuperan mientras el oro alcanza un m\u00e1ximo hist\u00f3rico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-22T16:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las acciones estadounidenses se recuperan mientras el oro alcanza un m\u00e1ximo hist\u00f3rico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las acciones estadounidenses se recuperan mientras el oro alcanza un m\u00e1ximo hist\u00f3rico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Las acciones estadounidenses se recuperan mientras el oro alcanza un m\u00e1ximo hist\u00f3rico - Noticias","og_description":"Las acciones estadounidenses subieron el martes por la ma\u00f1ana a medida que los inversores ingresaban al mercado despu\u00e9s de una fuerte liquidaci\u00f3n el lunes. El Dow Jones gan\u00f3 600 puntos, o un 1,58 %. El S&#038;P 500, en general, avanz\u00f3 un 1,57 %. El Nasdaq Composite, con un fuerte componente tecnol\u00f3gico, subi\u00f3 un 1,9 %. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/","og_site_name":"Noticias","article_published_time":"2025-04-22T16:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/"},"author":{"name":"","@id":""},"headline":"Las acciones estadounidenses se recuperan mientras el oro alcanza un m\u00e1ximo hist\u00f3rico","datePublished":"2025-04-22T16:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/"},"wordCount":872,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/","url":"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/","name":"Las acciones estadounidenses se recuperan mientras el oro alcanza un m\u00e1ximo hist\u00f3rico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-22T16:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las acciones estadounidenses se recuperan mientras el oro alcanza un m\u00e1ximo hist\u00f3rico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las acciones estadounidenses se recuperan mientras el oro alcanza un m\u00e1ximo hist\u00f3rico","url":"http:\/\/noticiasya.com\/reno\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2025\/04\/22\/acciones-estadounidenses-oro-maximo-historico-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-22T16:03:50Z","datePublished":"2025-04-22T16:03:50Z","dateModified":"2025-04-22T16:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las acciones estadounidenses se recuperan mientras el oro alcanza un m\\u00e1ximo hist\\u00f3rico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/22\\\/acciones-estadounidenses-oro-maximo-historico-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/22\\\/acciones-estadounidenses-oro-maximo-historico-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-22T16:03:50Z\",\"datePublished\":\"2025-04-22T16:03:50Z\",\"dateModified\":\"2025-04-22T16:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465532,"url":"https:\/\/noticiasya.com\/reno\/2025\/08\/15\/dow-jones-abre-territorio-record-tasas-trax\/","url_meta":{"origin":1461487,"position":0},"title":"El Dow Jones abre en territorio r\u00e9cord, en medio del entusiasmo de Wall Street por una posible bajada de las tasas de inter\u00e9s","author":"","date":"agosto 15, 2025","format":false,"excerpt":"El Dow Jones se encamina este viernes a registrar un m\u00e1ximo hist\u00f3rico del a\u00f1o, lo que refleja el optimismo sostenido en Wall Street a pesar de los signos de turbulencias subyacentes en la econom\u00eda.Las acciones estadounidenses abrieron mixtas el viernes por la ma\u00f1ana. El Dow Jones subi\u00f3 268 puntos, o\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473199,"url":"https:\/\/noticiasya.com\/reno\/2026\/04\/15\/wall-street-guerra-iran-repunte-trax\/","url_meta":{"origin":1461487,"position":1},"title":"Wall Street se desplom\u00f3 por la guerra con Ir\u00e1n, pero ahora est\u00e1 repuntando. Esta es la raz\u00f3n","author":"","date":"abril 15, 2026","format":false,"excerpt":"En las \u00faltimas dos semanas, las acciones estadounidenses han experimentado un repunte que ha ayudado al S&P 500 y al Nasdaq a borrar todas las p\u00e9rdidas derivadas del estallido de la guerra con Ir\u00e1n.El S&P 500 ha subido en nueve de las \u00faltimas diez sesiones burs\u00e1tiles, acumulando una ganancia del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460901,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/06\/futuros-dow-jones-caen-1-500-puntos-mercado-trax\/","url_meta":{"origin":1461487,"position":2},"title":"Los futuros del Dow Jones caen m\u00e1s de 1.500 puntos","author":"","date":"abril 6, 2025","format":false,"excerpt":"El caos del mercado inducido por los aranceles del Gobierno de Trump a\u00fan no ha terminado.Los futuros de acciones estadounidenses cayeron dr\u00e1sticamente el domingo por la noche despu\u00e9s de dos sesiones de ventas que borraron m\u00e1s de US$ 5,4 billones en valor de mercado. Las acciones estaban listas para abrir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457099,"url":"https:\/\/noticiasya.com\/reno\/2024\/12\/31\/mercados-estados-unidos-acciones-2024-trax\/","url_meta":{"origin":1461487,"position":3},"title":"Los mercados en EE.UU. est\u00e1n listos para hacer algo que no han hecho en casi tres d\u00e9cadas","author":"","date":"diciembre 31, 2024","format":false,"excerpt":"Las acciones estadounidenses est\u00e1n a punto de lograr una haza\u00f1a tan poco com\u00fan que solo ha sucedido unas pocas veces en la historia.Se prev\u00e9 que el S&P 500 gane m\u00e1s del 20% este a\u00f1o despu\u00e9s de haber subido un 24% en 2023. Unas ganancias consecutivas de m\u00e1s del 20% ser\u00edan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472622,"url":"https:\/\/noticiasya.com\/reno\/2026\/03\/27\/dow-correccion-s-p-petroleo-guerra-iran-trax\/","url_meta":{"origin":1461487,"position":4},"title":"Dow cierra en correcci\u00f3n, S&#038;P con racha de p\u00e9rdidas y precios del petr\u00f3leo en su m\u00e1ximo desde que inici\u00f3 la guerra en Ir\u00e1n","author":"","date":"marzo 27, 2026","format":false,"excerpt":"Las acciones estadounidenses cayeron y el Dow cerr\u00f3 en correcci\u00f3n este viernes, ya que la incertidumbre sobre la duraci\u00f3n de la guerra con Ir\u00e1n y los nervios por la inflaci\u00f3n energ\u00e9tica siguieron pesando sobre los mercados.El Dow cay\u00f3 793 puntos, o un 1,73 %, y cerr\u00f3 en 45.167, un 10\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472393,"url":"https:\/\/noticiasya.com\/reno\/2026\/03\/20\/acciones-bonos-oro-se-desploman-guerra-con-iran-trax\/","url_meta":{"origin":1461487,"position":5},"title":"Las acciones, los bonos y el oro se desploman mientras se extiende la guerra con Ir\u00e1n","author":"","date":"marzo 20, 2026","format":false,"excerpt":"Las acciones y los bonos de Estados Unidos cayeron, los precios del petr\u00f3leo subieron y el oro tuvo su peor semana en cuatro d\u00e9cadas mientras la guerra con Ir\u00e1n contin\u00faa repercutiendo en los mercados financieros.El Russell 2000, un \u00edndice de empresas m\u00e1s peque\u00f1as m\u00e1s sensibles a las tasas de inter\u00e9s,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1461487"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461487\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1461487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1461487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1461487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}