{"id":1461510,"date":"2025-04-22T17:03:47","date_gmt":"2025-04-23T00:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/"},"modified":"2025-04-22T17:03:47","modified_gmt":"2025-04-23T00:03:47","slug":"burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/","title":{"rendered":"Burdman: &#171;Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos rinden bien en las pr\u00f3ximas elecciones&#187;"},"content":{"rendered":"<p><strong>(CNN Radio Argentina) \u2014 Julio Burdman, <\/strong>analista pol\u00edtico, analiz\u00f3 este martes en <em>CNN Econom\u00eda y Actualidad<\/em> la coyuntura pol\u00edtica de cara a las elecciones legislativas, el panorama que enfrenta el oficialismo y los desaf\u00edos tanto nacionales como provinciales para los distintos espacios.<\/p>\n<p>\u201cNo veo un escenario de ca\u00edda del gobierno porque siempre se mantuvo arriba del 50%\u201d, asegur\u00f3 el polit\u00f3logo al ser consultado sobre la estabilidad del presidente Javier Milei.<\/p>\n<p>Sin embargo, advirti\u00f3 sobre un factor clave que podr\u00eda complicar su proyecci\u00f3n: <strong>\u201cTras la salida del cepo, lo m\u00e1s delicado del proceso es si Milei va a enfrentar varios meses de inflaci\u00f3n superior a la prevista, que limen un poco su confianza dom\u00e9stica\u201d.<\/strong><\/p>\n<p>Para Burdman, lo esencial del proceso pol\u00edtico ser\u00e1 c\u00f3mo se comporten los armados electorales de La Libertad Avanza: \u201c<strong>Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos van a rendir bien en las pr\u00f3ximas elecciones. Hay que mirar con atenci\u00f3n c\u00f3mo vienen los desempe\u00f1os electorales del oficialismo en los pr\u00f3ximos meses\u201d.<\/strong><\/p>\n<p>Burdman puntualiz\u00f3 que uno de los principales problemas del oficialismo son las diferencias entre los escenarios provinciales y el armado nacional. <strong>\u201cLa Libertad Avanza enfrenta en las elecciones los escenarios locales de cada provincia, porque est\u00e1n tratando de diferenciarse de las nacionales\u201d.<\/strong><\/p>\n<p>En ese sentido, mencion\u00f3 que en la Ciudad de Buenos Aires prev\u00e9 una elecci\u00f3n fragmentada: \u201cImagino una fragmentaci\u00f3n. <strong>La campa\u00f1a de Leandro Santoro parece estar liderando porque ha logrado separarse y que no se lo asocie con Cristina Kirchner\u201d.<\/strong><\/p>\n<p>Sobre <strong>la provincia de Buenos Aires, <\/strong>explic\u00f3 que el panorama a\u00fan est\u00e1 en desarrollo: \u201cLo que se est\u00e1 definiendo es c\u00f3mo va a ser la oferta electoral entre la de septiembre y la de octubre\u201d.<\/p>\n<p>El analista se refiri\u00f3 al peronismo y sus estrategias: \u201cEn la oposici\u00f3n, lo que queda definir en esta elecci\u00f3n son las alianzas. En cuanto al peronismo, va a ir junto para octubre y separados en una elecci\u00f3n provincializada en septiembre. Eso es lo que creo el d\u00eda de hoy\u201d.<\/p>\n<p>Para Burdman, <strong>\u201cla gran apuesta del gobierno es lograr un buen sector electoral que le permite estar cerca del quorum propio en alianza con el PRO en la C\u00e1mara de Diputados\u201d.<\/strong><\/p>\n<p>Seg\u00fan explic\u00f3, el pont\u00edfice \u201cse cuid\u00f3 de llevar el mensaje de la Iglesia a otros lugares y no hacer latinoamericanismo, como se lo acusaba\u201d. Y agreg\u00f3: \u201cM\u00e1s all\u00e1 de alg\u00fan impacto que pudo haber tenido antes de su muerte, la imagen de \u00e9l hab\u00eda sido medida hace unos cuantos a\u00f1os: al principio med\u00eda muy alto, pero despu\u00e9s hubo una ca\u00edda, sobre todo en el marco de la grieta\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Radio Argentina) \u2014 Julio Burdman, analista pol\u00edtico, analiz\u00f3 este martes en CNN Econom\u00eda y Actualidad la coyuntura pol\u00edtica de cara a las elecciones legislativas, el panorama que enfrenta el oficialismo y los desaf\u00edos tanto nacionales como provinciales para los distintos espacios. \u201cNo veo un escenario de ca\u00edda del gobierno porque siempre se mantuvo arriba [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1461510","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Burdman: &quot;Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos rinden bien en las pr\u00f3ximas elecciones&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Burdman: &quot;Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos rinden bien en las pr\u00f3ximas elecciones&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Radio Argentina) \u2014 Julio Burdman, analista pol\u00edtico, analiz\u00f3 este martes en CNN Econom\u00eda y Actualidad la coyuntura pol\u00edtica de cara a las elecciones legislativas, el panorama que enfrenta el oficialismo y los desaf\u00edos tanto nacionales como provinciales para los distintos espacios. \u201cNo veo un escenario de ca\u00edda del gobierno porque siempre se mantuvo arriba [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-23T00:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Burdman: &#171;Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos rinden bien en las pr\u00f3ximas elecciones&#187;\",\"datePublished\":\"2025-04-23T00:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/\"},\"wordCount\":503,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/\",\"name\":\"Burdman: \\\"Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos rinden bien en las pr\u00f3ximas elecciones\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-23T00:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Burdman: &#171;Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos rinden bien en las pr\u00f3ximas elecciones&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Burdman: \"Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos rinden bien en las pr\u00f3ximas elecciones\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/","og_locale":"es_ES","og_type":"article","og_title":"Burdman: \"Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos rinden bien en las pr\u00f3ximas elecciones\" - Noticias","og_description":"(CNN Radio Argentina) \u2014 Julio Burdman, analista pol\u00edtico, analiz\u00f3 este martes en CNN Econom\u00eda y Actualidad la coyuntura pol\u00edtica de cara a las elecciones legislativas, el panorama que enfrenta el oficialismo y los desaf\u00edos tanto nacionales como provinciales para los distintos espacios. \u201cNo veo un escenario de ca\u00edda del gobierno porque siempre se mantuvo arriba [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/","og_site_name":"Noticias","article_published_time":"2025-04-23T00:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/"},"author":{"name":"","@id":""},"headline":"Burdman: &#171;Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos rinden bien en las pr\u00f3ximas elecciones&#187;","datePublished":"2025-04-23T00:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/"},"wordCount":503,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/","url":"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/","name":"Burdman: \"Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos rinden bien en las pr\u00f3ximas elecciones\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-23T00:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Burdman: &#171;Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos rinden bien en las pr\u00f3ximas elecciones&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Burdman: &#171;Lo esencial del fen\u00f3meno Milei es si sus armados pol\u00edticos rinden bien en las pr\u00f3ximas elecciones&#187;","url":"http:\/\/noticiasya.com\/reno\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2025\/04\/22\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-23T00:03:47Z","datePublished":"2025-04-23T00:03:47Z","dateModified":"2025-04-23T00:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Burdman: &#171;Lo esencial del fen\\u00f3meno Milei es si sus armados pol\\u00edticos rinden bien en las pr\\u00f3ximas elecciones&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/22\\\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/22\\\/burdman-lo-esencial-del-fenomeno-milei-es-si-sus-armados-politicos-rinden-bien-en-las-proximas-elecciones\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-23T00:03:47Z\",\"datePublished\":\"2025-04-23T00:03:47Z\",\"dateModified\":\"2025-04-23T00:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461635,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/25\/julio-burdman-el-fmi-le-esta-pidiendo-al-gobierno-tener-apoyo-politico-para-respaldar-el-plan-reformista\/","url_meta":{"origin":1461510,"position":0},"title":"Julio Burdman: &#171;El FMI le est\u00e1 pidiendo al Gobierno tener apoyo pol\u00edtico para respaldar el plan reformista&#187;","author":"","date":"abril 25, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2014 El analista pol\u00edtico Julio Burdman convers\u00f3 este viernes con Regreso CNN, el programa conducido por Mariana Arias y Pepe Gil Vidal, sobre las declaraciones de Kristalina Georgieva respecto a la situaci\u00f3n econ\u00f3mica argentina, el panorama electoral de cara a octubre y los recientes cruces entre el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458081,"url":"https:\/\/noticiasya.com\/reno\/2025\/01\/31\/julio-burdman-politologo-la-popularidad-de-milei-esta-robusta\/","url_meta":{"origin":1461510,"position":1},"title":"Julio Burdman, polit\u00f3logo: &#171;La popularidad de Milei est\u00e1 robusta&#187;","author":"","date":"enero 31, 2025","format":false,"excerpt":"El polit\u00f3logo Julio Burdman, director del Observatorio Electoral, habl\u00f3 este viernes en CNN Radio del impacto del informe de su consultora realizado entre el 19 de febrero y el 25 de enero sobre la imagen y popularidad de Javier Milei, Donald Trump y el empresario Elon Musk.Seg\u00fan arroja el informe,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461007,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/09\/julio-burdman-trump-esta-en-el-barro-tratando-de-resurgir-a-estados-unidos\/","url_meta":{"origin":1461510,"position":2},"title":"Julio Burdman: &#171;Trump est\u00e1 en el barro tratando de resurgir a Estados Unidos&#187;","author":"","date":"abril 9, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Julio Burdman, profesor de Geopol\u00edtica de la UBA, analiz\u00f3 este mi\u00e9rcoles en Regreso CNN con Mariana Arias y Pepe Gil Vidal las nuevas pol\u00edticas arancelarias impulsadas por el presidente Donald Trump y su impacto en la escena global. Seg\u00fan el especialista, detr\u00e1s de las decisiones del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462398,"url":"https:\/\/noticiasya.com\/reno\/2025\/05\/15\/panorama-electoral-en-caba-adorni-y-santoro-van-a-tener-discursos-para-sentirse-victoriosos\/","url_meta":{"origin":1461510,"position":3},"title":"Panorama electoral en CABA: &#171;Adorni y Santoro van a tener discursos para sentirse victoriosos&#187;","author":"","date":"mayo 15, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Viviana Isasi, analista pol\u00edtica, consultora y encuestadora de la agencia Isasi-Burdman, analiz\u00f3 este jueves en Regreso CNN el panorama electoral de la Ciudad Aut\u00f3noma de Buenos Aires de cara a las elecciones del domingo, y destac\u00f3 que la disputa principal se centra entre Manuel Adorni y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447158,"url":"https:\/\/noticiasya.com\/reno\/2024\/03\/20\/milei-mirtha-gaumont-orix\/","url_meta":{"origin":1461510,"position":4},"title":"Milei vs. Mirtha Legrand: el presidente vuelve a enfrentar a una artista argentina","author":"","date":"marzo 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 Un poco de contexto para empezar.Mirtha \u201cLa Chiqui\u201d Legrand es una pr\u00f3cer de la televisi\u00f3n argentina. Si no es la figura m\u00e1s importante, pocos le compiten.Su programa, \u201cAlmorzando con Mirtha Legrand\u201d, acompa\u00f1\u00f3 durante d\u00e9cadas los mediod\u00edas de las familias argentinas. En su mesa se sentaron presidentes, actores,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466223,"url":"https:\/\/noticiasya.com\/reno\/2025\/09\/07\/denuncias-corrupcion-karina-milei-previo-elecciones-buenos-aires-orix\/","url_meta":{"origin":1461510,"position":5},"title":"Denuncias de corrupci\u00f3n salpican a Karina Milei previo a elecciones cruciales en la provincia de Buenos Aires","author":"","date":"septiembre 7, 2025","format":false,"excerpt":"Una canci\u00f3n sobre la hermana del presidente Javier Milei se volvi\u00f3 viral en Argentina. Se escucha en videos de redes sociales, programas de radio e incluso en el Congreso de la Naci\u00f3n. La parodia utiliza la melod\u00eda de la reconocida canci\u00f3n cubana \u201cGuantanamera\u201d, pero con una nueva letra con tono\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1461510"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461510\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1461510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1461510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1461510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}