{"id":1461515,"date":"2025-04-22T22:03:50","date_gmt":"2025-04-23T05:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/"},"modified":"2025-04-22T22:03:50","modified_gmt":"2025-04-23T05:03:50","slug":"vaticano-papa-francisco-argentina-historia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/","title":{"rendered":"C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano"},"content":{"rendered":"<p>El 13 de marzo de 2013, Oscar Crespo estaba viendo la televisi\u00f3n en su natal Buenos Aires cuando vio el humo blanco apareciendo sobre la Capilla Sixtina en el Vaticano: se hab\u00eda elegido un nuevo papa.<\/p>\n<p>Al igual que millones de cat\u00f3licos en Latinoam\u00e9rica, ten\u00eda curiosidad por saber qui\u00e9n suceder\u00eda al papa Benedicto XVI. Para su sorpresa, escuch\u00f3 el nombre Bergoglio, el apellido de su amigo de la infancia, y se sinti\u00f3 inmediatamente abrumado por la emoci\u00f3n, record\u00f3.<\/p>\n<p>\u201c\u00a1Bergoglio, papa! \u00a1No lo pod\u00eda creer! Y en ese momento, mi tel\u00e9fono comenz\u00f3 a sonar\u201d, dijo Crespo a CNN desde Buenos Aires, explicando c\u00f3mo recibi\u00f3 una avalancha de llamadas de personas que sab\u00edan de su amistad. Poco despu\u00e9s, Crespo vio aparecer al cardenal Jorge Bergoglio en el balc\u00f3n de la Bas\u00edlica de San Pedro, convirti\u00e9ndose en el primer papa latinoamericano.<\/p>\n<p>Su elecci\u00f3n tom\u00f3 por sorpresa a Crespo y a toda Argentina, mientras que el resto del mundo se preguntaba qui\u00e9n era Jorge Bergoglio.<\/p>\n<p>En los meses siguientes, el Gobierno local incluso organiz\u00f3 un <a href=\"https:\/\/archive.ph\/o\/3AwER\/https:\/\/buenosaires.gob.ar\/noticias\/el-circuito-papal-visitara-los-lugares-claves-en-la-historia-de-francisco-0\">recorrido especial<\/a>, \u201cel circuito papal\u201d, para que los turistas y peregrinos pudieran vislumbrar los primeros a\u00f1os de Bergoglio en su natal Buenos Aires.<\/p>\n<p>Jorge Bergoglio naci\u00f3 en la capital de Argentina, Buenos Aires, el 17 de diciembre de 1936. Hijo de inmigrantes italianos, Mario y Regina, era el mayor de cinco hermanos.<\/p>\n<p>Pas\u00f3 su infancia y adolescencia en la casa de su familia en el coraz\u00f3n del barrio de clase media de Flores. Una placa fuera de su antiguo hogar, en la calle Membrillar 531, ahora anuncia con orgullo: \u201cAqu\u00ed vivi\u00f3 el papa Francisco\u201d.<\/p>\n<p>Como muchos ni\u00f1os sudamericanos, Bergoglio jugaba f\u00fatbol con amigos en su vecindario. Una placa en el suelo de la plaza Herminia Brumana en Flores dice: \u201cEn esta plaza sol\u00edan reunirse los ni\u00f1os del barrio. Aqu\u00ed, Jorge M. Bergoglio corr\u00eda tras la pelota con sus amigos. Tardes de juegos y amistad\u201d.<\/p>\n<p>El joven Bergoglio se convirti\u00f3 en un gran aficionado al f\u00fatbol, apoyando al equipo argentino San Lorenzo. Su amor por el deporte y por su equipo nunca disminuy\u00f3 como papa, con Francisco a menudo visto sosteniendo la camiseta de San Lorenzo y recibiendo equipos de f\u00fatbol en el Vaticano.<\/p>\n<p>\u201cLe encantaba la m\u00fasica, bailar y el f\u00fatbol. Fuimos a ver muchos partidos de f\u00fatbol\u201d, dijo Crespo. \u00c9l y Bergoglio se hicieron amigos cuando ten\u00edan 13 a\u00f1os, un v\u00ednculo que perdur\u00f3 cuando el \u00faltimo se convirti\u00f3 en el papa Francisco, aunque nunca regres\u00f3 a su tierra natal.<\/p>\n<p>Bergoglio creci\u00f3 aprendiendo sobre literatura y qu\u00edmica, entre otras materias, y disfrut\u00f3 de todo lo t\u00edpico de un adolescente, dice Crespo.<\/p>\n<p>Cuando ten\u00eda 12 a\u00f1os, el argentino incluso tuvo una novia que, d\u00e9cadas despu\u00e9s, fue perseguida por la prensa tras su elecci\u00f3n al papado.<\/p>\n<p>Amalia Damonte dijo a los periodistas en 2013 que el nuevo papa le envi\u00f3 una carta cuando ambos eran ni\u00f1os. \u201cMe dijo: \u2018Si no me caso contigo, me har\u00e9 sacerdote\u2019\u201d, record\u00f3.<\/p>\n<p>Pasaron los a\u00f1os y Bergoglio, de hecho, opt\u00f3 por el sacerdocio. Su profundo esp\u00edritu de servicio lo llev\u00f3 a elegir la Iglesia, seg\u00fan Crespo. Bergoglio <a href=\"https:\/\/archive.ph\/o\/3AwER\/https:\/\/www.cnn.com\/interactive\/2015\/09\/specials\/pope-dark-night-of-the-soul\/\">ingres\u00f3 a la orden religiosa jesuita<\/a> como novicio en 1958, fue ordenado en 1969 y se convirti\u00f3 en el \u00fanico arzobispo de su natal Buenos Aires en 1998.<\/p>\n<p>Fue <a href=\"https:\/\/archive.ph\/o\/3AwER\/https:\/\/www.cnn.com\/2013\/03\/13\/world\/europe\/vatican-pope-bergoglio-profile\/index.html\">nombrado cardenal en 2001<\/a> y se desempe\u00f1\u00f3 como presidente de la Conferencia Episcopal Argentina desde 2005 hasta 2011.<\/p>\n<p>Rechaz\u00f3 vivir en el palacio arzobispal, eligiendo en su lugar vivir en un apartamento sencillo. Tambi\u00e9n se neg\u00f3 a usar una limusina con chofer, prefiriendo tomar el autob\u00fas con la gente com\u00fan, y cocinaba sus propias comidas.<\/p>\n<p>Como jesuita viviendo bajo un voto de pobreza, Bergoglio llev\u00f3 una vida humilde y austera, renunciando incluso a los m\u00e1s m\u00ednimos lujos. Su rechazo a las apariencias de estatus una vez que se convirti\u00f3 en arzobispo dio al mundo <a href=\"https:\/\/archive.ph\/o\/3AwER\/https:\/\/www.cnn.com\/2013\/03\/27\/world\/europe\/vatican-pope\">una pista de c\u00f3mo se desarrollar\u00eda su papado<\/a> a\u00f1os despu\u00e9s.<\/p>\n<p>\u201cNunca tuvo un autom\u00f3vil, esa era la realidad. Sol\u00eda viajar con \u00e9l en transporte p\u00fablico. Y cuando compr\u00e9 un autom\u00f3vil, sol\u00eda llevarlo\u201d, dijo Crespo.<\/p>\n<p>Los viajes con el arzobispo Bergoglio inclu\u00edan visitas a las \u201cvillas\u201d, barrios marginales en las afueras de la capital, donde se convirti\u00f3 en una cara familiar.<\/p>\n<p>\u201cIba a las villas para ver a qui\u00e9n pod\u00eda ayudar. Me hab\u00eda dicho claramente: \u2018Mira, voy a ser sacerdote porque mi objetivo es estar al servicio de la gente. Para eso, voy a las villas, voy a ir al coraz\u00f3n del pa\u00eds\u2019\u201d, record\u00f3 Crespo.<\/p>\n<p>La austeridad y simplicidad de su vida, junto con una profunda necesidad de estar cerca de los pobres y marginados, lo definieron como sacerdote y como futuro papa, explic\u00f3 la periodista argentina Elisabetta Piqu\u00e9, autora de \u201cPapa Francisco: Vida y revoluci\u00f3n\u201d.<\/p>\n<p>\u201cEra considerado un arzobispo moderado\u2026 Era conocido como un arzobispo que sol\u00eda ir a las villas y que sol\u00eda tener una vida muy, muy simple\u201d, dijo Piqu\u00e9 a CNN.<\/p>\n<p>Piqu\u00e9 conoci\u00f3 a Bergoglio por primera vez en 2001 para una entrevista en Roma, un encuentro que dio lugar a una amistad que dur\u00f3 d\u00e9cadas. En ese momento, lo describi\u00f3 como un hombre t\u00edmido que la sorprendi\u00f3.<\/p>\n<p>\u201cEra realmente un sacerdote de mente abierta con quien pod\u00edas hablar de todo\u201d, dijo Piqu\u00e9.<\/p>\n<p>Un d\u00eda despu\u00e9s de que el cardenal Bergoglio se convirtiera en el papa Francisco, el 14 de marzo de 2013, llam\u00f3 a Piqu\u00e9 y le pregunt\u00f3 sobre la reacci\u00f3n en su natal Argentina.<\/p>\n<p>El nuevo papa mencion\u00f3 que hab\u00eda ido a rezar a la bas\u00edlica de Santa Mar\u00eda la Mayor en Roma, donde a\u00f1os despu\u00e9s solicitar\u00eda ser enterrado, y luego fue en persona a pagar su factura de alojamiento en el hotel Paulus VI donde se hosped\u00f3 durante el c\u00f3nclave, un gesto que sorprendi\u00f3 a todos.<\/p>\n<p>M\u00e1s tarde ese mes, la decisi\u00f3n de Francisco de no vivir en el apartamento papal en el \u00faltimo piso del Palacio Apost\u00f3lico, sino en la Casa Santa Marta, la residencia de la Ciudad del Vaticano donde se alojan los cardenales durante el c\u00f3nclave, fue inesperada y considerada un acto revolucionario por el nuevo papa, explic\u00f3 Piqu\u00e9.<\/p>\n<p>Como arzobispo en Buenos Aires, Bergoglio celebraba misa en una prisi\u00f3n, un hospital o un hospicio, tratando de llegar a los marginados y abrir la iglesia a todos, una tradici\u00f3n que continu\u00f3 durante su papado y se convirti\u00f3 en parte de su legado.<\/p>\n<p>\u201cSu legado es sobre una iglesia inclusiva, una iglesia que es para todos, no solo para un peque\u00f1o grupo de personas perfectas. Este es un papa que habla a todos y que habla especialmente a los pecadores\u2026 Lo hemos visto yendo a prisiones en todo el mundo. Lo hemos visto en Jueves Santo yendo a prisiones y lavando los pies de los prisioneros\u201d, dijo Piqu\u00e9.<\/p>\n<p>Emilce Cuda, una te\u00f3loga argentina que trabaj\u00f3 estrechamente con Francisco como secretaria de la Comisi\u00f3n Pontificia para Am\u00e9rica Latina, lo describi\u00f3 como un estratega que usaba el humor para navegar por el Vaticano como papa.<\/p>\n<p>\u201cCualquier persona que llegaba a conocerlo estaba absolutamente nerviosa, pero en dos o tres minutos, el papa Francisco pod\u00eda cambiar la situaci\u00f3n\u201d, dijo Cuda a CNN, explicando c\u00f3mo ten\u00eda el don de encontrar la palabra adecuada para despertar el humor y hacer que la gente se sintiera mejor.<\/p>\n<p>Ese don se pod\u00eda rastrear hasta sus primeros a\u00f1os. El sentido del humor de Bergoglio hab\u00eda sido una parte clave de su car\u00e1cter desde que era muy joven, y era una parte esencial de \u00e9l, seg\u00fan su hermana Mar\u00eda Elena. Ella dijo a CNN en Espa\u00f1ol en 2013: \u201c(Tiene un) gran sentido del humor, creo que lo hered\u00f3 de mi padre. Cuando ten\u00eda que ser firme por algo, lo era, pero con buen humor\u201d.<\/p>\n<p>Crespo dijo que, a pesar de los talentos evidentes de Bergoglio, nunca se les hab\u00eda ocurrido a sus contempor\u00e1neos que llegar\u00eda a liderar la Iglesia cat\u00f3lica romana.<\/p>\n<p>\u201cNunca imagin\u00e9 que un compa\u00f1ero de clase se convertir\u00eda en papa. Habr\u00edamos pensado que, debido a su inteligencia, se convertir\u00eda en ministro, en un cargo p\u00fablico, incluso en presidente, pero \u00bfqu\u00e9 iba a ser papa? No se nos ocurri\u00f3 a ninguno de nosotros\u201d, dijo Crespo.<\/p>\n<p>Fue un papa que nunca olvid\u00f3 sus or\u00edgenes en el fin del mundo y siempre tendi\u00f3 la mano a los marginados, reflexion\u00f3 Piqu\u00e9. Tambi\u00e9n se mantuvo fiel a sus amigos.<\/p>\n<p>\u201cUn d\u00eda de junio de 2013 son\u00f3 el tel\u00e9fono, y una voz familiar dijo: \u2018Hola Oscar, soy Jorge Mario\u2019, y yo dije, \u2018\u00a1El papa me est\u00e1 llamando!\u2019 A pesar de nuestra amistad, todav\u00eda me sorprendi\u00f3 mucho que el papa me llamara\u201d, dijo Crespo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 13 de marzo de 2013, Oscar Crespo estaba viendo la televisi\u00f3n en su natal Buenos Aires cuando vio el humo blanco apareciendo sobre la Capilla Sixtina en el Vaticano: se hab\u00eda elegido un nuevo papa. Al igual que millones de cat\u00f3licos en Latinoam\u00e9rica, ten\u00eda curiosidad por saber qui\u00e9n suceder\u00eda al papa Benedicto XVI. Para [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1461515","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano - Noticias\" \/>\n<meta property=\"og:description\" content=\"El 13 de marzo de 2013, Oscar Crespo estaba viendo la televisi\u00f3n en su natal Buenos Aires cuando vio el humo blanco apareciendo sobre la Capilla Sixtina en el Vaticano: se hab\u00eda elegido un nuevo papa. Al igual que millones de cat\u00f3licos en Latinoam\u00e9rica, ten\u00eda curiosidad por saber qui\u00e9n suceder\u00eda al papa Benedicto XVI. Para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-23T05:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano\",\"datePublished\":\"2025-04-23T05:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/\"},\"wordCount\":1543,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/\",\"name\":\"C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-23T05:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano - Noticias","og_description":"El 13 de marzo de 2013, Oscar Crespo estaba viendo la televisi\u00f3n en su natal Buenos Aires cuando vio el humo blanco apareciendo sobre la Capilla Sixtina en el Vaticano: se hab\u00eda elegido un nuevo papa. Al igual que millones de cat\u00f3licos en Latinoam\u00e9rica, ten\u00eda curiosidad por saber qui\u00e9n suceder\u00eda al papa Benedicto XVI. Para [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/","og_site_name":"Noticias","article_published_time":"2025-04-23T05:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/"},"author":{"name":"","@id":""},"headline":"C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano","datePublished":"2025-04-23T05:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/"},"wordCount":1543,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/","url":"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/","name":"C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-23T05:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano","url":"http:\/\/noticiasya.com\/reno\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2025\/04\/22\/vaticano-papa-francisco-argentina-historia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-23T05:03:50Z","datePublished":"2025-04-23T05:03:50Z","dateModified":"2025-04-23T05:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3mo la vida temprana del papa Francisco en Argentina arroja luz sobre su tiempo en el Vaticano\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/22\\\/vaticano-papa-francisco-argentina-historia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/22\\\/vaticano-papa-francisco-argentina-historia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-23T05:03:50Z\",\"datePublished\":\"2025-04-23T05:03:50Z\",\"dateModified\":\"2025-04-23T05:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461534,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/23\/federico-wals-excolaborador-de-jorge-bergoglio-quedo-incorporado-que-el-papa-debe-ser-austero-como-fue-francisco\/","url_meta":{"origin":1461515,"position":0},"title":"Federico Wals, excolaborador de Jorge Bergoglio: &#171;Qued\u00f3 incorporado que el Papa debe ser austero como fue Francisco&#187;","author":"","date":"abril 23, 2025","format":false,"excerpt":"Federico Wals, exsecretario de prensa de Jorge Bergoglio en el Arzobispado de Bueno Aires, charl\u00f3 con Nacho Gir\u00f3n y equipo sobre su v\u00ednculo con el Papa y record\u00f3 la famosa foto de Francisco en el subte A.En La Ma\u00f1ana de CNN, afirm\u00f3 que \u201cfue un locura lo que pas\u00f3 con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461625,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/25\/exvocero-de-jorge-bergoglio-el-papa-francisco-nunca-cambio\/","url_meta":{"origin":1461515,"position":1},"title":"Exvocero de Jorge Bergoglio: El Papa Francisco &#171;nunca cambi\u00f3&#187;","author":"","date":"abril 25, 2025","format":false,"excerpt":"Roberto Dabusti, exvocero de Jorge Bergoglio en Buenos Aires, cont\u00f3 sus a\u00f1os compartidos con el Papa Francisco.En La Ma\u00f1ana de CNN afirm\u00f3 que le \u201ctoc\u00f3 llegar a la madrugada del martes y empezar a ver desde el aeropuerto carteles con Grazie Francesco. Impresionante bajar ah\u00ed y llegar hasta ac\u00e1 al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461444,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/21\/vida-del-papa-francisco-en-fotos-trax\/","url_meta":{"origin":1461515,"position":2},"title":"El papa Francisco, en fotos: desde su ni\u00f1ez en Argentina hasta los encuentros en el Vaticano","author":"","date":"abril 21, 2025","format":false,"excerpt":"El papa Francisco, portavoz de los pobres que super\u00f3 una f\u00e9rrea resistencia para transformar la Iglesia cat\u00f3lica, falleci\u00f3 el lunes 21 de abril, anunci\u00f3 el Vaticano. Ten\u00eda 88 a\u00f1os.Francisco fue elegido en 2013 tras la jubilaci\u00f3n renuncia de Benedicto XVI.Fue el primer papa latinoamericano de la historia y el primero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461454,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/21\/jose-maria-poirier-bergoglio-fue-un-gran-reformador\/","url_meta":{"origin":1461515,"position":3},"title":"Jos\u00e9 Mar\u00eda Poirier: &#171;Bergoglio fue un gran reformador&#187;","author":"","date":"abril 21, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Jos\u00e9 Mar\u00eda Poirier, director de la Revista Criterio, habl\u00f3 este lunes con Regreso CNN de Mariana Arias y Pepe Gil Vidal sobre la muerte del Papa Francisco, su legado y los desaf\u00edos que se abren para la Iglesia Cat\u00f3lica.\u201cEl Papa implement\u00f3 sus fuerzas a \u00faltimo momento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461448,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/21\/jorge-telerman-francisco-mantuvo-la-simpleza-durante-su-papado\/","url_meta":{"origin":1461515,"position":4},"title":"Jorge Telerman: &#171;Francisco mantuvo la simpleza durante su papado&#187;","author":"","date":"abril 21, 2025","format":false,"excerpt":"Jorge Telerman, exjefe de Gobierno de la Ciudad de Buenos Aires, que tuvo una relaci\u00f3n cercana con Jorge Bergoglio, charl\u00f3 con Nacho Gir\u00f3n y equipo sobre la muerte del Papa Francisco.En La Ma\u00f1ana de CNN, afirm\u00f3 que \u201cel Papa era alguien a quien recurrir siempre\u201d.Destac\u00f3 que \u201cel Papa era un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461439,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/21\/como-fue-vida-familia-papa-francisco-bergoglio-trax\/","url_meta":{"origin":1461515,"position":5},"title":"As\u00ed fue la vida y carrera del papa Francisco: familia, estudios y m\u00e1s","author":"","date":"abril 21, 2025","format":false,"excerpt":"(CNN) \u2013 Este lunes por la ma\u00f1ana, el Vaticano anunci\u00f3 la muerte de Francisco, el papa argentino que es fue primer primer pont\u00edfice no europeo de la era moderna. Echa un vistazo a la vida de Jorge Mario Bergoglio, en datos:Fecha de nacimiento: 17 de diciembre de 1936.Lugar de nacimiento:\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1461515"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461515\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1461515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1461515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1461515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}