{"id":1461516,"date":"2025-04-22T23:03:48","date_gmt":"2025-04-23T06:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/"},"modified":"2025-04-22T23:03:48","modified_gmt":"2025-04-23T06:03:48","slug":"hegseth-trump-pentagono-desorden-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/","title":{"rendered":"Es improbable que Trump despida a Hegseth, pero preocupa la confusi\u00f3n en el c\u00edrculo \u00edntimo del jefe del Pent\u00e1gono"},"content":{"rendered":"<p>El martes por la ma\u00f1ana, un desafiante secretario de Defensa, Pete Hegseth, se present\u00f3 en la cadena de televisi\u00f3n donde sol\u00eda trabajar como presentador para abordar las consecuencias de las revelaciones de que discuti\u00f3 planes militares en un segundo chat grupal de Signal, esta vez con su esposa y su hermano.<\/p>\n<p>Pero despu\u00e9s de que Hegseth enfrentara m\u00faltiples preguntas directas en la entrevista de Fox News sobre el desorden en su c\u00edrculo \u00edntimo, algunos funcionarios consideraron que su aparici\u00f3n solo atrajo m\u00e1s atenci\u00f3n a la historia en lugar de reducir la cobertura, seg\u00fan dos personas familiarizadas con c\u00f3mo se percib\u00eda la entrevista dentro de la administraci\u00f3n.<\/p>\n<p>Sin embargo, es improbable que el presidente Donald Trump despida a Hegseth y ha hablado con \u00e9l dos veces desde que The New York Times y CNN informaron sobre el segundo grupo de Signal el domingo por la noche. En su primera llamada, Trump dijo que respaldaba a Hegseth y expres\u00f3 su frustraci\u00f3n por las \u201cfiltraciones\u201d que, seg\u00fan \u00e9l, intentaban perjudicar a su Gobierno, seg\u00fan una persona familiarizada con la conversaci\u00f3n.<\/p>\n<p>Desde entonces, Trump ha estado solicitando la opini\u00f3n de su entorno sobre el desempe\u00f1o de Hegseth durante las conversaciones, seg\u00fan dos personas familiarizadas con los comentarios. Hasta el momento, la mayor\u00eda, si no todos, han sido positivos sobre el jefe del Pent\u00e1gono. Trump se muestra extremadamente reticente a despedir a cualquier funcionario del gabinete en este momento de su mandato, y mucho menos a Hegseth, dado el arduo trabajo que su equipo luch\u00f3 para conseguir su confirmaci\u00f3n.<\/p>\n<p>Sin embargo, la situaci\u00f3n en su c\u00edrculo \u00edntimo ha preocupado a algunos altos funcionarios que desean ver cambios en el funcionamiento del equipo del secretario en la oficina principal del Pent\u00e1gono. El caos reinante en el Pent\u00e1gono no ha pasado desapercibido para la Casa Blanca, donde los funcionarios han observado con preocupaci\u00f3n c\u00f3mo Hegseth lucha por contener la disfunci\u00f3n y c\u00f3mo su c\u00edrculo \u00edntimo se desmorona.<\/p>\n<p>Los asesores de mayor confianza de Hegseth son ahora su esposa, su abogado y su asistente militar subalterno, quien pronto podr\u00eda ser nombrado su nuevo jefe de despacho, seg\u00fan informaron varias personas familiarizadas con el asunto.<\/p>\n<p>Otras personas cercanas a Hegseth, incluido su asesor, el sargento mayor retirado del Ej\u00e9rcito Eric Geressy \u2013quien sirvi\u00f3 con Hegseth en Iraq y recibi\u00f3 la Cruz por Servicio Distinguido el mes pasado\u2013, se han sentido tan frustrados por la situaci\u00f3n que han indicado a sus colegas que podr\u00edan renunciar, seg\u00fan dos de las fuentes. CNN se ha puesto en contacto con Geressy.<\/p>\n<p>Algunos de los exasesores m\u00e1s cercanos de Hegseth han advertido esta semana de la inestabilidad dentro del Pent\u00e1gono. Entre ellos se encuentran su exportavoz, John Ullyot, y tres exaltos funcionarios que Hegseth despidi\u00f3 la semana pasada: el asesor principal Dan Caldwell; el subjefe de Estado Mayor, Darin Selnick; y Colin Carroll, quien fue jefe de Estado Mayor del subsecretario de Defensa.<\/p>\n<p>\u201cHa sido un mes de caos total en el Pent\u00e1gono. Desde filtraciones de planes operativos sensibles hasta despidos masivos, la disfunci\u00f3n se ha convertido en una gran distracci\u00f3n para el presidente, quien merece algo mejor de sus altos mandos\u201d, declar\u00f3 Ullyot en un comunicado obtenido por CNN.<\/p>\n<p>Un congresista republicano, el representante Don Bacon de Nebraska, intensific\u00f3 este martes sus llamados p\u00fablicos para que Hegseth rinda cuentas.<\/p>\n<p>Cuando Jake Tapper de CNN le pregunt\u00f3 este martes en \u201cThe Lead\u201d qu\u00e9 har\u00eda si fuera presidente y su secretario de Defensa hubiera actuado como Hegseth, Bacon respondi\u00f3: \u201cLos har\u00eda responsables y los despedir\u00eda\u201d. Incluir informaci\u00f3n sensible en una aplicaci\u00f3n como Signal, dijo Bacon, fue \u201cuna gran insensatez\u201d, pero la respuesta de Hegseth \u2013que describi\u00f3 la conversaci\u00f3n de este martes en Fox como \u201ccoordinaciones informales y no clasificadas para la coordinaci\u00f3n de medios y otras cosas\u201d\u2013 exacerb\u00f3 la ofensa. \u201cPodr\u00eda recuperarse de eso con franqueza. Pero cuando se niega que sea un problema, creo que lo empeora a\u00fan m\u00e1s\u201d, dijo Bacon.<\/p>\n<p>El despido de Carroll tambi\u00e9n ha tensado la relaci\u00f3n de Hegseth con el subsecretario de Defensa, Steve Feinberg, quien lo nombr\u00f3 jefe de despacho y no fue consultado antes de su suspensi\u00f3n, seg\u00fan las fuentes.<\/p>\n<p>\u201cEst\u00e1 sumido en la paranoia, contra la pared\u201d, declar\u00f3 una de las fuentes familiarizadas con el estado mental de Hegseth durante el \u00faltimo mes.<\/p>\n<p>El ahora exjefe de despacho de Hegseth, Joe Kasper, se hab\u00eda enfrentado repetidamente en los \u00faltimos meses con los tres hombres que Hegseth despidi\u00f3 la semana pasada, seg\u00fan informaron las fuentes a CNN.<\/p>\n<p>Varios empleados del ala oeste se hab\u00edan frustrado por lo que describieron como la falta de respuesta de Kasper, y a menudo se quejaban de la dificultad para contactar con el jefe de despacho de Hegseth por tel\u00e9fono o para que respondiera a sus solicitudes. En un momento dado, hacia el inicio del mandato de Hegseth, la Casa Blanca intent\u00f3 contactar con Kasper para que Hegseth firmara un memorando que iniciara el proceso de desarrollo del escudo antimisiles C\u00fapula Dorada de Trump, pero el memorando permaneci\u00f3 sin firmar durante tres semanas, seg\u00fan una persona familiarizada con el asunto.<\/p>\n<p>En otro ejemplo del desorden en la oficina principal, en marzo, Hegseth solicit\u00f3 directamente al director de los programas de acceso especial del Departamento de Defensa (que se encuentran entre los programas de mayor secreto dentro del Departamento de Defensa) que leyera a Elon Musk m\u00e1s de dos decenas de programas relacionados con China, seg\u00fan varias personas familiarizadas con el episodio. Sin embargo, Hegseth no someti\u00f3 la idea a un proceso normativo que incluyera abogados, seg\u00fan las fuentes, y finalmente, los abogados de \u00e9tica del Departamento de Defensa en la oficina de Normas de Conducta dijeron que no ser\u00eda apropiado. La idea fracas\u00f3. Las personas familiarizadas con el asunto dijeron que podr\u00eda haber tenido \u00e9xito si se hubiera seguido un proceso de pol\u00edticas m\u00e1s est\u00e1ndar.<\/p>\n<p>Caldwell y Selnick, quienes conocen a Hegseth desde hace a\u00f1os y trabajaron con \u00e9l en la organizaci\u00f3n conservadora de veteranos Concerned Veterans for America, llegaron a creer que Kasper lo estaba aislando y poni\u00e9ndolo en su contra, seg\u00fan las fuentes. Kasper, a su vez, ha declarado desconocer el origen de esas acusaciones: fue Hegseth quien inici\u00f3 la investigaci\u00f3n de la filtraci\u00f3n que condujo a sus despidos, seg\u00fan Kasper.<\/p>\n<p>Kasper dijo no tener \u201cnada que ver\u201d con ninguna de las decisiones tomadas en relaci\u00f3n con la investigaci\u00f3n de la filtraci\u00f3n. \u201cNi siquiera estoy al tanto ni particip\u00e9 en las decisiones\u201d, afirm\u00f3.<\/p>\n<p>Kasper ya no es el jefe de gabinete de Hegseth y est\u00e1 en proceso de asumir un nuevo puesto como funcionario especial del Gobierno, seg\u00fan la persona familiarizada con el caso.<\/p>\n<p>\u201cJoe es un gran tipo. Es un gran estadounidense\u201d, declar\u00f3 Hegseth este martes durante la entrevista en Fox News, y a\u00f1adi\u00f3: \u201cSe queda con nosotros, desempe\u00f1ar\u00e1 un papel ligeramente diferente, pero no se ir\u00e1 a ning\u00fan lado, y mucho menos ser\u00e1 despedido\u201d.<\/p>\n<p>La mayor\u00eda de los altos funcionarios de la Casa Blanca creen que Hegseth ha sido v\u00edctima de lo que \u00e9l denomin\u00f3 \u201cexempleados descontentos\u201d, que fueron despedidos la semana pasada por, seg\u00fan Hegseth, filtraciones no autorizadas a los medios.<\/p>\n<p>Los exempleados en cuesti\u00f3n hab\u00edan sido seleccionados personalmente por Hegseth para formar parte de su equipo directivo, pero en la entrevista con Fox insinu\u00f3 que su lealtad hacia ellos se hab\u00eda agotado.<\/p>\n<p>\u201cNo es mi trabajo protegerlos. Es mi trabajo proteger la seguridad nacional, al presidente de Estados Unidos, y dejar que la investigaci\u00f3n siga su curso\u201d, declar\u00f3.<\/p>\n<p>\u201cLos exempleados descontentos est\u00e1n vendiendo informaci\u00f3n para intentar salvar su pellejo\u201d, declar\u00f3 Hegseth a Fox.<\/p>\n<p>Caldwell neg\u00f3 esta semana haber filtrado informaci\u00f3n y dijo que no hab\u00eda sido interrogado ni sometido a una prueba de pol\u00edgrafo como parte de ninguna investigaci\u00f3n.<\/p>\n<p>\u201cHe sido amigo y partidario de Pete Hegseth durante mucho tiempo, y estoy personalmente devastado por esto. Es horrible\u201d, declar\u00f3 a Tucker Carlson en su podcast. \u201cTodo el Departamento de Defensa no puede seguir sumido en el caos\u201d.<\/p>\n<p>En su propia entrevista en Fox, Hegseth enumer\u00f3 varias noticias recientes que, seg\u00fan sugiri\u00f3, surgieron debido a filtraciones de su personal, incluyendo planes para la toma del canal de Panam\u00e1 por parte de Estados Unidos y una sesi\u00f3n informativa programada para Musk sobre planes de guerra contra China.<\/p>\n<p>Hegseth sugiri\u00f3 que quer\u00eda mantener esos temas fuera de los medios. Pero uno de ellos \u2013el informe sobre los planes para informar a Musk\u2013 sorprendi\u00f3 al propio Trump, quien orden\u00f3 la cancelaci\u00f3n de la sesi\u00f3n informativa. No est\u00e1 claro si el presidente se habr\u00eda enterado de la sesi\u00f3n informativa prevista si no hubiera aparecido en las noticias.<\/p>\n<p>Aunque los asesores de Trump creen que el asunto de Signal se ha resuelto suficientemente, algunos han dicho que a\u00fan creen que podr\u00eda surgir m\u00e1s informaci\u00f3n sobre el liderazgo de Hegseth en el Departamento de Defensa que resultar\u00eda vergonzosa o peor.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El martes por la ma\u00f1ana, un desafiante secretario de Defensa, Pete Hegseth, se present\u00f3 en la cadena de televisi\u00f3n donde sol\u00eda trabajar como presentador para abordar las consecuencias de las revelaciones de que discuti\u00f3 planes militares en un segundo chat grupal de Signal, esta vez con su esposa y su hermano. Pero despu\u00e9s de que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1461516","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Es improbable que Trump despida a Hegseth, pero preocupa la confusi\u00f3n en el c\u00edrculo \u00edntimo del jefe del Pent\u00e1gono - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Es improbable que Trump despida a Hegseth, pero preocupa la confusi\u00f3n en el c\u00edrculo \u00edntimo del jefe del Pent\u00e1gono - Noticias\" \/>\n<meta property=\"og:description\" content=\"El martes por la ma\u00f1ana, un desafiante secretario de Defensa, Pete Hegseth, se present\u00f3 en la cadena de televisi\u00f3n donde sol\u00eda trabajar como presentador para abordar las consecuencias de las revelaciones de que discuti\u00f3 planes militares en un segundo chat grupal de Signal, esta vez con su esposa y su hermano. Pero despu\u00e9s de que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-23T06:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Es improbable que Trump despida a Hegseth, pero preocupa la confusi\u00f3n en el c\u00edrculo \u00edntimo del jefe del Pent\u00e1gono\",\"datePublished\":\"2025-04-23T06:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/\"},\"wordCount\":1605,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/\",\"name\":\"Es improbable que Trump despida a Hegseth, pero preocupa la confusi\u00f3n en el c\u00edrculo \u00edntimo del jefe del Pent\u00e1gono - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-23T06:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Es improbable que Trump despida a Hegseth, pero preocupa la confusi\u00f3n en el c\u00edrculo \u00edntimo del jefe del Pent\u00e1gono\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Es improbable que Trump despida a Hegseth, pero preocupa la confusi\u00f3n en el c\u00edrculo \u00edntimo del jefe del Pent\u00e1gono - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Es improbable que Trump despida a Hegseth, pero preocupa la confusi\u00f3n en el c\u00edrculo \u00edntimo del jefe del Pent\u00e1gono - Noticias","og_description":"El martes por la ma\u00f1ana, un desafiante secretario de Defensa, Pete Hegseth, se present\u00f3 en la cadena de televisi\u00f3n donde sol\u00eda trabajar como presentador para abordar las consecuencias de las revelaciones de que discuti\u00f3 planes militares en un segundo chat grupal de Signal, esta vez con su esposa y su hermano. Pero despu\u00e9s de que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/","og_site_name":"Noticias","article_published_time":"2025-04-23T06:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/"},"author":{"name":"","@id":""},"headline":"Es improbable que Trump despida a Hegseth, pero preocupa la confusi\u00f3n en el c\u00edrculo \u00edntimo del jefe del Pent\u00e1gono","datePublished":"2025-04-23T06:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/"},"wordCount":1605,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/","url":"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/","name":"Es improbable que Trump despida a Hegseth, pero preocupa la confusi\u00f3n en el c\u00edrculo \u00edntimo del jefe del Pent\u00e1gono - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-23T06:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Es improbable que Trump despida a Hegseth, pero preocupa la confusi\u00f3n en el c\u00edrculo \u00edntimo del jefe del Pent\u00e1gono"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Es improbable que Trump despida a Hegseth, pero preocupa la confusi\u00f3n en el c\u00edrculo \u00edntimo del jefe del Pent\u00e1gono","url":"http:\/\/noticiasya.com\/reno\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2025\/04\/22\/hegseth-trump-pentagono-desorden-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-23T06:03:48Z","datePublished":"2025-04-23T06:03:48Z","dateModified":"2025-04-23T06:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Es improbable que Trump despida a Hegseth, pero preocupa la confusi\\u00f3n en el c\\u00edrculo \\u00edntimo del jefe del Pent\\u00e1gono\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/22\\\/hegseth-trump-pentagono-desorden-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/04\\\/22\\\/hegseth-trump-pentagono-desorden-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-23T06:03:48Z\",\"datePublished\":\"2025-04-23T06:03:48Z\",\"dateModified\":\"2025-04-23T06:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461550,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/23\/papel-esposa-pete-hegseth-pentagon-escrutinio-trax\/","url_meta":{"origin":1461516,"position":0},"title":"El papel prominente de la esposa de Pete Hegseth en el Pent\u00e1gono genera escrutinio","author":"","date":"abril 23, 2025","format":false,"excerpt":"Las noticias del fin de semana sobre que la esposa del secretario de Defensa Pete Hegseth, Jennifer, fue incluida en un segundo grupo de chat donde \u00e9l comparti\u00f3 detalles sensibles de operaciones militares, ha centrado la atenci\u00f3n en el papel destacado que ocupa en el Pent\u00e1gono sin ser empleada formalmente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468936,"url":"https:\/\/noticiasya.com\/reno\/2025\/12\/03\/hegseth-riesgo-militares-guerra-signal-trax\/","url_meta":{"origin":1461516,"position":1},"title":"Exclusivo: \u00f3rgano de control concluye que Hegseth arriesg\u00f3 a militares al compartir planes de guerra en Signal, dicen fuentes","author":"","date":"diciembre 3, 2025","format":false,"excerpt":"El secretario de Defensa Pete Hegseth puso en riesgo informaci\u00f3n militar confidencial, lo que podr\u00eda haber representado un peligro para las fuerzas militares de EE.UU. y los objetivos de la misi\u00f3n, cuando us\u00f3 Signal en marzo de este a\u00f1o para compartir planes de ataque altamente sensibles dirigidos contra los rebeldes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461728,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/","url_meta":{"origin":1461516,"position":2},"title":"&#171;Nunca nada es perfecto&#187;: Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic","author":"","date":"abril 28, 2025","format":false,"excerpt":"El editor en jefe de The Atlantic, Jeffrey Goldberg, fue una figura central en la primera gran crisis autoinfligida del segundo mandato de Trump, cuando el prominente periodista fue a\u00f1adido inadvertidamente a un chat de Signal donde funcionarios del gabinete discut\u00edan ataques militares en Yemen. Semanas despu\u00e9s, Trump se sent\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456276,"url":"https:\/\/noticiasya.com\/reno\/2024\/12\/05\/hegseth-candidatura-pentagono-trump-trax\/","url_meta":{"origin":1461516,"position":3},"title":"AN\u00c1LISIS | Hegseth sigue en pie, pero a\u00fan no ha salvado su candidatura al Pent\u00e1gono","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"La selecci\u00f3n de Pete Hegseth para dirigir el Pent\u00e1gono est\u00e1 estancada en el limbo, mientras lucha ferozmente contra las acusaciones de consumo de alcohol y conducta sexual inapropiada y no puede estar seguro de si el presidente electo Donald Trump realmente le cubre las espaldas.Una alta fuente de la transici\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468951,"url":"https:\/\/noticiasya.com\/reno\/2025\/12\/03\/analisis-controversias-envuelven-hegseth-trax\/","url_meta":{"origin":1461516,"position":4},"title":"Las controversias envuelven a Hegseth gracias a una ola de bravuconer\u00eda que rompe las convenciones impulsadas por Trump","author":"","date":"diciembre 3, 2025","format":false,"excerpt":"Cuando un alto funcionario plagado de esc\u00e1ndalos necesita un voto p\u00fablico de confianza de un presidente, generalmente es una se\u00f1al segura de que se dirige a la salida.Pero Pete Hegseth empieza a parecer un secretario de Defensa con siete vidas.Tras sobrevivir a un amargo debate de confirmaci\u00f3n que incluy\u00f3 detalles\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468872,"url":"https:\/\/noticiasya.com\/reno\/2025\/12\/01\/analisis-trump-dilema-venezuela-maduro-trax\/","url_meta":{"origin":1461516,"position":5},"title":"Trump lidia con el dilema de Venezuela mientras Maduro se atrinchera y crece la tormenta por un posible &#171;crimen de guerra&#187;","author":"","date":"diciembre 1, 2025","format":false,"excerpt":"La aventura del presidente Donald Trump para cambiar el r\u00e9gimen en Venezuela corre el peligro de degenerar en un pantano estrat\u00e9gico, pol\u00edtico y jur\u00eddico.Trump cit\u00f3 a los principales funcionarios y asesores de seguridad nacional en una reuni\u00f3n en la Oficina Oval el lunes por la noche buscando definir los pr\u00f3ximos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1461516"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1461516\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1461516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1461516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1461516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}