{"id":1466301,"date":"2025-09-09T15:03:49","date_gmt":"2025-09-09T22:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/"},"modified":"2025-09-09T15:03:49","modified_gmt":"2025-09-09T22:03:49","slug":"maduro-apunta-gobernadora-puerto-rico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/","title":{"rendered":"Maduro apunta a la gobernadora de Puerto Rico: &#171;Si usted va a invadir Venezuela, venga de primera&#187;"},"content":{"rendered":"<p>El presidente de Venezuela, Nicol\u00e1s Maduro, critic\u00f3 a la gobernadora de Puerto Rico, Jenniffer Gonz\u00e1lez, quien este lunes afirm\u00f3 su apoyo a las maniobras militares de Washington en el Caribe, cuando recibi\u00f3 al secretario de Defensa de Estados Unidos, Pete Hegseth.<\/p>\n<p>\u201cLa gobernadora de Puerto Rico se suma a un plan militar. Yo le digo a la gobernadora de Puerto Rico, si usted dice que usted va a invadir a Venezuela, venga de primera, \u00bfoy\u00f3?\u201d, dijo Maduro en una entrevista con el expresidente de Ecuador Rafael Correa, por el <a href=\"https:\/\/actualidad.rt.com\/programas\/conversando-correa\/564171-maduro-eeuu-busca-petroleo-gas-narcotrafico\">canal RT.<\/a><\/p>\n<p>Maduro especul\u00f3 que la postura de la gobernadora no contar\u00eda con apoyo popular en la isla. \u201cYo s\u00e9 que el pueblo de Puerto Rico se va a oponer a que se convierta Puerto Rico en la base militar para agredir a sus hermanos de Sudam\u00e9rica, a sus hermanos del Caribe\u201d, dijo el mandatario.<\/p>\n<p>El lunes, Gonz\u00e1lez dijo en <a href=\"https:\/\/www.facebook.com\/watch\/?v=1434074804560284\">redes sociales<\/a> que Puerto Rico es \u201cla frontera de Estados Unidos en el Caribe\u201d y consider\u00f3: \u201cCreo que estamos combatiendo por primera vez de ra\u00edz el problema, que es atacando de d\u00f3nde viene la droga\u201d. CNN envi\u00f3 una consulta a la Gobernaci\u00f3n sobre las declaraciones de Maduro y est\u00e1 a la espera de respuesta.<\/p>\n<p>Washington ha lanzado un despliegue naval en la zona, seg\u00fan afirma, para combatir al narcotr\u00e1fico, y acusa al Gobierno de Maduro de dirigir un c\u00e1rtel de drogas, se\u00f1alamientos que Caracas ha rechazado enf\u00e1ticamente.<\/p>\n<p>Posteriormente, Gonz\u00e1lez <a href=\"https:\/\/www.facebook.com\/JGOPR51\/videos\/3994357220816673\">dijo <\/a>en conferencia de prensa que las maniobras estadounidenses son positivas para Puerto Rico y consider\u00f3 que son \u201cun mensaje directo al l\u00edder del cartel en Venezuela, Nicol\u00e1s Maduro, que Estados Unidos no le va a pasar una m\u00e1s\u201d.<\/p>\n<p>Maduro reiter\u00f3 en la entrevista que \u201cVenezuela es un pa\u00eds completamente libre del fen\u00f3meno del narcotr\u00e1fico\u201d, y consider\u00f3 que el Gobierno de Donald Trump usa a la banda Tren de Aragua como \u201cun mito para justificar acci\u00f3n militar\u201d.<\/p>\n<p>Sobre las maniobras militares, el mandatario expres\u00f3: \u201cTenemos al frente ocho barcos de guerra, destructores en el Caribe. Nunca se hab\u00eda visto eso (\u2026) 1.200 misiles apuntando a nuestras cabezas\u201d.<\/p>\n<p>La llegada a Puerto Rico este lunes de Hegseth y del jefe del Estado Mayor de las Fuerzas Armadas, el general Daniel Caine, se dio a una semana de que en la isla se hayan iniciado entrenamientos anfibios y operaciones de vuelo militares. Las maniobras est\u00e1n dise\u00f1adas \u201cpara mejorar la preparaci\u00f3n y capacidades de la 22\u00b0 Unidad Expedicionaria de Infanter\u00eda de Marina y a la vez reforzar el v\u00ednculo con la Guardia Nacional de Puerto Rico\u201d, seg\u00fan un comunicado emitido por la Marina de EE.UU.<\/p>\n<p>Las opiniones entre algunos en la isla sobre la presencia de la Marina son diversas.<\/p>\n<p>\u201cQue el Ej\u00e9rcito de los Estados Unidos escoja nuestro balneario para sus pr\u00e1cticas militares es un honor que valoramos profundamente. Este tipo de ejercicios no solo reconocen la ubicaci\u00f3n estrat\u00e9gica de Arroyo, sino que tambi\u00e9n reafirman el compromiso y la relaci\u00f3n hist\u00f3rica que tenemos con las fuerzas armadas. Para nosotros, como comunidad, es motivo de orgullo y respeto\u201d, expres\u00f3 Eric Bachier, alcalde de Arroyo. Recientemente, parte de la costa de ese municipio, localizado en el sureste de la isla, fue escenario de varios entrenamientos con veh\u00edculos anfibios y helic\u00f3pteros.<\/p>\n<p>El domingo, cientos de personas participaron en una protesta de la organizaci\u00f3n \u201cMadres contra la Guerra\u201d en las afueras de la Base A\u00e9rea Muniz en Carolina, expresando su rechazo a las maniobras del Ej\u00e9rcito de Estados Unidos en Puerto Rico y a una posible reactivaci\u00f3n de las antiguas bases militares en la isla, seg\u00fan report\u00f3 la agencia EFE.<\/p>\n<p>Sonia Santiago, portavoz de la organizaci\u00f3n, declar\u00f3 a EFE que la isla es \u201cun pueblo ocupado, un pueblo invadido\u201d por Washington y que est\u00e1n en contra de la existencia de bases militares estadounidenses en la isla. \u201cAhora, desde nuestra gran naci\u00f3n caribe\u00f1a y latinoamericana, (EE.UU.) quiere invadir a Venezuela, eso me huele a lo que le ocurri\u00f3 a Iraq\u201d, en referencia a la invasi\u00f3n militar estadounidense de 2003, tras los ataques a las Torres Gemelas en Nueva York.<\/p>\n<p>El Movimiento Independentista Nacional Hostosiano (MINH) tambi\u00e9n se ha manifestado en contra de los ejercicios militares.<\/p>\n<p>\u201cNos oponemos a este aumento, a este incremento tanto en pr\u00e1cticas como en presencia militar y las instalaciones en nuestra tierra y mucho m\u00e1s que se utilicen para agredir a pueblos hermanos como lo que aparentemente se est\u00e1 planificando en este momento en contra del pueblo soberano y digno de Venezuela\u201d, dijo \u00c1ngel Rodr\u00edguez Le\u00f3n, copresidente del MINH.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Venezuela, Nicol\u00e1s Maduro, critic\u00f3 a la gobernadora de Puerto Rico, Jenniffer Gonz\u00e1lez, quien este lunes afirm\u00f3 su apoyo a las maniobras militares de Washington en el Caribe, cuando recibi\u00f3 al secretario de Defensa de Estados Unidos, Pete Hegseth. \u201cLa gobernadora de Puerto Rico se suma a un plan militar. Yo le digo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466301","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maduro apunta a la gobernadora de Puerto Rico: &quot;Si usted va a invadir Venezuela, venga de primera&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maduro apunta a la gobernadora de Puerto Rico: &quot;Si usted va a invadir Venezuela, venga de primera&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Venezuela, Nicol\u00e1s Maduro, critic\u00f3 a la gobernadora de Puerto Rico, Jenniffer Gonz\u00e1lez, quien este lunes afirm\u00f3 su apoyo a las maniobras militares de Washington en el Caribe, cuando recibi\u00f3 al secretario de Defensa de Estados Unidos, Pete Hegseth. \u201cLa gobernadora de Puerto Rico se suma a un plan militar. Yo le digo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-09T22:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Maduro apunta a la gobernadora de Puerto Rico: &#171;Si usted va a invadir Venezuela, venga de primera&#187;\",\"datePublished\":\"2025-09-09T22:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/\"},\"wordCount\":827,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/\",\"name\":\"Maduro apunta a la gobernadora de Puerto Rico: \\\"Si usted va a invadir Venezuela, venga de primera\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-09T22:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maduro apunta a la gobernadora de Puerto Rico: &#171;Si usted va a invadir Venezuela, venga de primera&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maduro apunta a la gobernadora de Puerto Rico: \"Si usted va a invadir Venezuela, venga de primera\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Maduro apunta a la gobernadora de Puerto Rico: \"Si usted va a invadir Venezuela, venga de primera\" - Noticias","og_description":"El presidente de Venezuela, Nicol\u00e1s Maduro, critic\u00f3 a la gobernadora de Puerto Rico, Jenniffer Gonz\u00e1lez, quien este lunes afirm\u00f3 su apoyo a las maniobras militares de Washington en el Caribe, cuando recibi\u00f3 al secretario de Defensa de Estados Unidos, Pete Hegseth. \u201cLa gobernadora de Puerto Rico se suma a un plan militar. Yo le digo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/","og_site_name":"Noticias","article_published_time":"2025-09-09T22:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/"},"author":{"name":"","@id":""},"headline":"Maduro apunta a la gobernadora de Puerto Rico: &#171;Si usted va a invadir Venezuela, venga de primera&#187;","datePublished":"2025-09-09T22:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/"},"wordCount":827,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/","url":"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/","name":"Maduro apunta a la gobernadora de Puerto Rico: \"Si usted va a invadir Venezuela, venga de primera\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-09T22:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Maduro apunta a la gobernadora de Puerto Rico: &#171;Si usted va a invadir Venezuela, venga de primera&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Maduro apunta a la gobernadora de Puerto Rico: &#171;Si usted va a invadir Venezuela, venga de primera&#187;","url":"http:\/\/noticiasya.com\/reno\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2025\/09\/09\/maduro-apunta-gobernadora-puerto-rico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-09T22:03:49Z","datePublished":"2025-09-09T22:03:49Z","dateModified":"2025-09-09T22:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Maduro apunta a la gobernadora de Puerto Rico: &#171;Si usted va a invadir Venezuela, venga de primera&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/09\\\/09\\\/maduro-apunta-gobernadora-puerto-rico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/09\\\/09\\\/maduro-apunta-gobernadora-puerto-rico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-09T22:03:49Z\",\"datePublished\":\"2025-09-09T22:03:49Z\",\"dateModified\":\"2025-09-09T22:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1466474,"url":"https:\/\/noticiasya.com\/reno\/2025\/09\/15\/f35-aviones-puerto-rico-tension-venezuela-orix\/","url_meta":{"origin":1466301,"position":0},"title":"Aviones F-35 de Estados Unidos llegan a Puerto Rico en medio de la tensi\u00f3n con Venezuela","author":"","date":"septiembre 15, 2025","format":false,"excerpt":"Varios aviones de combate F-35 de Estados Unidos llegaron este fin de semana a Puerto Rico, en medio de la tensi\u00f3n entre Washington y Caracas y el despliegue militar estadounidense en el Caribe bajo el argumento de combatir al narcotr\u00e1fico.Al menos cinco cazas furtivos fueron vistos en el aeropuerto regional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457489,"url":"https:\/\/noticiasya.com\/reno\/2025\/01\/13\/maduro-liberar-puerto-rico-armas-gobernadora-dictador-orix\/","url_meta":{"origin":1466301,"position":1},"title":"Maduro afirma que quiere &#171;liberar&#187; Puerto Rico por las armas; Gobernadora lo califica de &#171;dictador&#187;","author":"","date":"enero 13, 2025","format":false,"excerpt":"La gobernadora de Puerto Rico, Jenniffer Gonz\u00e1lez, dijo este lunes que toma con \u201cmucha precauci\u00f3n\u201d las declaraciones del presidente de Venezuela, Nicol\u00e1s Maduro, acerca de \u201cliberar\u201d la isla utilizando \u201ctropas de Brasil\u201d.En un contexto de mucha ret\u00f3rica populista, exageraciones y reminiscencias hist\u00f3ricas, las declaraciones de Maduro se dieron este domingo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457146,"url":"https:\/\/noticiasya.com\/reno\/2025\/01\/02\/jenniffer-gonzalez-gobernadora-puerto-rico-orix\/","url_meta":{"origin":1466301,"position":2},"title":"Jenniffer Gonz\u00e1lez asume como gobernadora de Puerto Rico y ser\u00e1 la tercera mujer en la historia en ocupar el cargo","author":"","date":"enero 2, 2025","format":false,"excerpt":"Jenniffer Gonz\u00e1lez asume este jueves como nueva gobernadora de Puerto Rico en un acto en las escalinatas del Capitolio en el Viejo San Juan, que incluye varias actividades alrededor del casco de la legendaria zona hist\u00f3rica y La Fortaleza, centro oficial del gobierno.De esta manera, Gonz\u00e1lez se convertir\u00e1 en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466592,"url":"https:\/\/noticiasya.com\/reno\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/","url_meta":{"origin":1466301,"position":3},"title":"Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela","author":"","date":"septiembre 18, 2025","format":false,"excerpt":"La antigua base naval de Roosevelt Roads, en Ceiba, Puerto Rico, cerr\u00f3 en 2004 luego de m\u00e1s de seis d\u00e9cadas de operaciones militares de Estados Unidos. Durante a\u00f1os se intent\u00f3 transformarla en un polo de desarrollo tur\u00edstico y residencial, pero ninguno de esos planes prosper\u00f3. Ahora, el enorme complejo militar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459639,"url":"https:\/\/noticiasya.com\/reno\/2025\/03\/07\/puerto-rico-apoyo-inmigracion-indocumentada-reconstruir-trax\/","url_meta":{"origin":1466301,"position":4},"title":"EE.UU. promete apoyo a Puerto Rico para combatir la inmigraci\u00f3n indocumentada y reconstruir la isla","author":"","date":"marzo 7, 2025","format":false,"excerpt":"La secretaria de Seguridad Nacional de Estados Unidos, Kristi Noem, y la gobernadora de Puerto Rico, Jenniffer Gonz\u00e1lez, se reunieron el jueves en San Juan, donde dialogaron sobre posibles iniciativas conjuntas en asuntos como el combate a las organizaciones criminales, la inmigraci\u00f3n ilegal, la asignaci\u00f3n de fondos federales para la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457652,"url":"https:\/\/noticiasya.com\/reno\/2025\/01\/20\/maduro-puerto-rico-relaciones-ee-uu-y-venezuela-trump-trax\/","url_meta":{"origin":1466301,"position":5},"title":"Lo que la amenaza de Maduro de &#171;liberar&#187; Puerto Rico dice sobre las relaciones entre EE.UU y Venezuela bajo Trump 2.0","author":"","date":"enero 20, 2025","format":false,"excerpt":"El mensaje parec\u00eda dise\u00f1ado para llegar a Washington mientras una administraci\u00f3n se prepara para pasarle la posta a la siguiente: si Estados Unidos sigue meti\u00e9ndose con Venezuela, Caracas tomar\u00e1 represalias \u201cliberando\u201d el territorio estadounidense de Puerto Rico, afirm\u00f3 la semana pasada el presidente venezolano Nicol\u00e1s Maduro .A pesar del hecho\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1466301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1466301"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1466301\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1466301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1466301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1466301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}