{"id":1466342,"date":"2025-09-10T15:03:39","date_gmt":"2025-09-10T22:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/"},"modified":"2025-09-10T15:03:39","modified_gmt":"2025-09-10T22:03:39","slug":"sheinbaum-busca-subir-aranceles-productos-paises-asia-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/","title":{"rendered":"Gobierno de M\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos"},"content":{"rendered":"<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, busca subir los aranceles de casi 1.500 productos \u2013incluyendo autos\u2013 procedentes de China y de otras naciones de Asia con los que su pa\u00eds no tiene tratado comercial, de acuerdo con <a href=\"https:\/\/gaceta.diputados.gob.mx\/PDF\/66\/2025\/sep\/20250909-X.pdf\">una iniciativa<\/a> que la mandataria envi\u00f3 este martes al Congreso.<\/p>\n<p>El documento plantea reformar la Ley de los Impuestos Generales de Importaci\u00f3n y de Exportaci\u00f3n para aumentar hasta un tope del 50 % el arancel que pagan 1.463 mercanc\u00edas de una veintena de sectores, entre ellos, automotriz, textil, vestido, calzado, juguetes y muebles.<\/p>\n<p>La iniciativa dice que el prop\u00f3sito de estos aranceles es proteger la econom\u00eda de M\u00e9xico.<\/p>\n<p>\u201cEl objeto de esta reforma es aprovechar nuestro mercado interno para que la producci\u00f3n tenga lugar en M\u00e9xico y emplee a personas trabajadoras mexicanas, al mismo tiempo que se contribuye a equilibrar los balances de comercio exterior en beneficio de la convivencia y bienestar de todas las mexicanas y mexicanos\u201d, se\u00f1ala.<\/p>\n<p>La propuesta de Sheinbaum fue enviada a la C\u00e1mara de Diputados. Si es aprobada, ser\u00e1 remitida al Senado. El oficialista partido Morena y sus aliados, los partidos del Trabajo y Verde, por s\u00ed solos tienen los votos suficientes para que el documento sea avalado en ambas c\u00e1maras.<\/p>\n<p>Si la iniciativa es aprobada, entrar\u00e1 en vigor 30 d\u00edas naturales despu\u00e9s de que se promulgue y estar\u00e1 vigente hasta el 31 de diciembre de 2026.<\/p>\n<p>El secretario de Econom\u00eda, Marcelo Ebrard, dijo este mi\u00e9rcoles en una rueda de prensa que Sheinbaum decidi\u00f3 no decretar el incremento de aranceles sino plantearlo como una reforma de ley para que la medida se discuta en el Congreso.<\/p>\n<p>La propuesta, expuso Ebrard, es elevar el arancel hasta el tope m\u00e1ximo que permita la Organizaci\u00f3n Mundial del Comercio (OMC) para cada producto. Adem\u00e1s de China, entre los pa\u00edses asi\u00e1ticos cuyas mercanc\u00edas se ver\u00edan afectadas est\u00e1n India, Indonesia, Tailandia y Turqu\u00eda.<\/p>\n<p>Ebrard tambi\u00e9n dijo que con estos aranceles se busca evitar que se pierdan unos 325.000 empleos. Los estados donde se ubican estas fuentes de trabajo son Nuevo Le\u00f3n, Jalisco, Estado de M\u00e9xico, Ciudad de M\u00e9xico y Quer\u00e9taro, entre otros, seg\u00fan un documento que la Secretar\u00eda de Econom\u00eda (SE) difundi\u00f3 a los medios.<\/p>\n<p>\u201cEs un programa para proteger las industrias estrat\u00e9gicas de M\u00e9xico\u201d, se\u00f1al\u00f3 el secretario, quien en 2026 ser\u00e1 uno de los funcionarios que encabecen las renegociaciones del Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 (<a href=\"https:\/\/www.gob.mx\/t-mec\">T-MEC<\/a>).<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, busca subir los aranceles de casi 1.500 productos \u2013incluyendo autos\u2013 procedentes de China y de otras naciones de Asia con los que su pa\u00eds no tiene tratado comercial, de acuerdo con una iniciativa que la mandataria envi\u00f3 este martes al Congreso. El documento plantea reformar la Ley de los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466342","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobierno de M\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno de M\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos - Noticias\" \/>\n<meta property=\"og:description\" content=\"La presidenta de M\u00e9xico, Claudia Sheinbaum, busca subir los aranceles de casi 1.500 productos \u2013incluyendo autos\u2013 procedentes de China y de otras naciones de Asia con los que su pa\u00eds no tiene tratado comercial, de acuerdo con una iniciativa que la mandataria envi\u00f3 este martes al Congreso. El documento plantea reformar la Ley de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-10T22:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gobierno de M\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos\",\"datePublished\":\"2025-09-10T22:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/\"},\"wordCount\":457,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/\",\"name\":\"Gobierno de M\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-10T22:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno de M\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno de M\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno de M\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos - Noticias","og_description":"La presidenta de M\u00e9xico, Claudia Sheinbaum, busca subir los aranceles de casi 1.500 productos \u2013incluyendo autos\u2013 procedentes de China y de otras naciones de Asia con los que su pa\u00eds no tiene tratado comercial, de acuerdo con una iniciativa que la mandataria envi\u00f3 este martes al Congreso. El documento plantea reformar la Ley de los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/","og_site_name":"Noticias","article_published_time":"2025-09-10T22:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/"},"author":{"name":"","@id":""},"headline":"Gobierno de M\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos","datePublished":"2025-09-10T22:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/","url":"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/","name":"Gobierno de M\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-10T22:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Gobierno de M\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Gobierno de M\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos","url":"http:\/\/noticiasya.com\/reno\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2025\/09\/10\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-10T22:03:39Z","datePublished":"2025-09-10T22:03:39Z","dateModified":"2025-09-10T22:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Gobierno de M\\u00e9xico quiere subir hasta un 50 % los aranceles a casi 1.500 productos chinos, incluyendo los autos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/09\\\/10\\\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/09\\\/10\\\/sheinbaum-busca-subir-aranceles-productos-paises-asia-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-10T22:03:39Z\",\"datePublished\":\"2025-09-10T22:03:39Z\",\"dateModified\":\"2025-09-10T22:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456135,"url":"https:\/\/noticiasya.com\/reno\/2024\/11\/28\/trump-proteger-autos-eeuu-aranceles-mexico-canada-trax\/","url_meta":{"origin":1466342,"position":0},"title":"Trump dice que proteger\u00e1 los autos fabricados en EE.UU. con aranceles elevados, pero no existe un auto completamente estadounidense","author":"","date":"noviembre 28, 2024","format":false,"excerpt":"(CNN) -- El presidente electo Donald Trump promete proteger los autos fabricados en EE.UU. con aranceles elevados sobre las importaciones. El problema es que no existe un auto completamente estadounidense.Ahora puedes seguirnos en\u00a0WhatsApp ChannelTrump prometi\u00f3 que los aranceles, que son un impuesto sobre los bienes importados de otro pa\u00eds, ser\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459693,"url":"https:\/\/noticiasya.com\/reno\/2025\/03\/09\/trump-aranceles-mexico-canada-recesion-trax\/","url_meta":{"origin":1466342,"position":1},"title":"Trump dice que aranceles a M\u00e9xico y Canad\u00e1 &#171;podr\u00edan subir&#187; y no descarta posible recesi\u00f3n","author":"","date":"marzo 9, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trumpm dijo que los aranceles sobre algunos productos de Canad\u00e1 y M\u00e9xico previstos para el 2 de abril \u201cpodr\u00edan subir\u201d, y no predijo si Estados Unidos tendr\u00e1 una recesi\u00f3n en 2025.En una entrevista que se emiti\u00f3 en \u201cSunday Morning Futures With Maria Bartiromo\u201d de Fox\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459618,"url":"https:\/\/noticiasya.com\/reno\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/","url_meta":{"origin":1466342,"position":2},"title":"\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.?","author":"","date":"marzo 7, 2025","format":false,"excerpt":"M\u00e9xico logr\u00f3 este jueves un mes m\u00e1s sin que Estados Unidos imponga aranceles a sus productos. Tras una llamada entre la presidenta mexicana, Claudia Sheinbaum, y el mandatario estadounidense, Donald Trump, se acord\u00f3 que por el momento no entrar\u00e1n en vigor los aranceles de 25% a los productos provenientes de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460651,"url":"https:\/\/noticiasya.com\/reno\/2025\/03\/31\/perdida-empleos-industria-automotriz-aranceles-trax\/","url_meta":{"origin":1466342,"position":3},"title":"Se podr\u00edan perder r\u00e1pidamente empleos en la industria automotriz por la guerra arancelaria","author":"","date":"marzo 31, 2025","format":false,"excerpt":"Los inminentes aranceles a los autos importados podr\u00edan significar m\u00e1s que solo precios m\u00e1s altos para los compradores y menores ganancias para los fabricantes de autom\u00f3viles; tambi\u00e9n podr\u00edan significar despidos para los trabajadores del sector automotriz estadounidense.El presidente Donald Trump afirma que sus aranceles a los autom\u00f3viles transformar\u00e1n la industria,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457690,"url":"https:\/\/noticiasya.com\/reno\/2025\/01\/21\/trump-aranceles-a-mexico-y-canada-1-de-febrero-trax\/","url_meta":{"origin":1466342,"position":4},"title":"Trump dice que se impondr\u00e1n aranceles a M\u00e9xico y Canad\u00e1 el 1 de febrero","author":"","date":"enero 21, 2025","format":false,"excerpt":"El presidente Donald Trump dijo que cree que aplicar\u00e1 nuevos aranceles a Canad\u00e1 y M\u00e9xico el 1 de febrero.Trump dijo a los periodistas en la oficina oval que estaba pensando en un arancel del 25% sobre las importaciones de los vecinos norteamericanos de Estados Unidos.Esto equivale a un respiro de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463777,"url":"https:\/\/noticiasya.com\/reno\/2025\/06\/20\/aranceles-precios-inflacion-estados-unidos-orix\/","url_meta":{"origin":1466342,"position":5},"title":"Entonces, \u00bfse ha vuelto algo m\u00e1s caro debido a los aranceles de Trump?","author":"","date":"junio 20, 2025","format":false,"excerpt":"Las predicciones de los economistas convencionales fueron fat\u00eddicas despu\u00e9s de que el presidente Donald Trump lanzara su campa\u00f1a arancelaria apenas un par de semanas despu\u00e9s de comenzar su segundo mandato: los precios subir\u00edan \u2014 dr\u00e1sticamente \u2014, dec\u00edan, reavivando una crisis inflacionaria que decenas de millones de estadounidenses lo eligieron para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1466342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1466342"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1466342\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1466342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1466342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1466342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}