{"id":1466365,"date":"2025-09-11T09:03:55","date_gmt":"2025-09-11T16:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/"},"modified":"2025-09-11T09:03:55","modified_gmt":"2025-09-11T16:03:55","slug":"maduro-venezuela-despliegue-militar-estados-unidos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/","title":{"rendered":"Maduro anuncia un despliegue militar y policial con &#171;284 frentes de batalla&#187; en medio de la tensi\u00f3n entre Venezuela y EE.UU."},"content":{"rendered":"<p>En medio de la tensi\u00f3n con Estados Unidos, el presidente de Venezuela, Nicol\u00e1s Maduro, anunci\u00f3 la puesta en marcha del llamado \u201cPlan Independencia 200\u201d, en el que participar\u00e1n los Cuerpos Combatientes de la milicia, la Milicia Nacional Bolivariana y la Fuerza Armada Nacional Bolivariana (FANB). El despliegue contar\u00e1 con \u201c284 frentes de batalla\u201d, asegur\u00f3 el mandatario.<\/p>\n<p>\u201cEstamos activando en este momento de norte a sur, de este a oeste, desde todas las costas del Caribe venezolano, desde la frontera con Colombia, desde los Andes, desde el oriente del pa\u00eds y el sur, estamos activando 284 frentes de batalla\u201d, dijo Maduro en un acto transmitido por el canal estatal Venezolana de Televisi\u00f3n (VTV), acompa\u00f1ado por el ministro de Defensa, Vladimir Padrino L\u00f3pez. \u201cEstamos preparados para la lucha armada, si fuese necesario\u201d, dijo Maduro.<\/p>\n<p>Esta ma\u00f1ana ya se ve\u00eda en las calles de Caracas mayor presencia policial.<\/p>\n<p>\u201cVamos a garantizar todas las costas, de punta a punta, libres de imperialistas, de invasores y de grupos de violencia\u201d, asegur\u00f3 el mandatario venezolano durante el anuncio. \u201cEstos mares, esta tierra, estos barrios, estas monta\u00f1as, estas inmensidades y las riquezas de estas tierras le pertenecen al pueblo de Venezuela. Jam\u00e1s le pertenecer\u00e1n al imperio norteamericano\u201d, a\u00f1adi\u00f3.<\/p>\n<p>El anuncio de Maduro se da mientras crecen las tensiones con Estados Unidos, que mantiene una recompensa de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/12\/venezuela\/la-recompensa-por-maduro-alcanzo-un-nivel-inedito-por-que-ahora\">US$ 50 millones por datos<\/a> que lleven a la captura del presidente de Venezuela. En agosto, la administraci\u00f3n de Trump despleg\u00f3 en el Caribe ocho barcos militares con misiles y un submarino de propulsi\u00f3n nuclear. Adem\u00e1s, la semana pasada orden\u00f3 el env\u00edo de diez aviones de combate <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/05\/eeuu\/aviones-combate-puerto-rico-carteles-trax\">F-35<\/a> a una base a\u00e9rea en Puerto Rico, todo en el marco de la lucha contra los c\u00e1rteles de droga, seg\u00fan aseguran las autoridades estadounidenses.<\/p>\n<p>Un momento \u00e1lgido se vivi\u00f3 a principios de septiembre luego de que Estados Unidos anunciara que realiz\u00f3 un ataque letal a una embarcaci\u00f3n en aguas del Caribe, supuestamente con un cargamento de droga, en la que <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/02\/eeuu\/lanzan-ataque-caribe-drogas-marina-narcotrafico-trax\">murieron 11 personas<\/a>, seg\u00fan las autoridades estadounidenses.<\/p>\n<p><em>Con informaci\u00f3n de las agencias EFE y Reuters<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En medio de la tensi\u00f3n con Estados Unidos, el presidente de Venezuela, Nicol\u00e1s Maduro, anunci\u00f3 la puesta en marcha del llamado \u201cPlan Independencia 200\u201d, en el que participar\u00e1n los Cuerpos Combatientes de la milicia, la Milicia Nacional Bolivariana y la Fuerza Armada Nacional Bolivariana (FANB). El despliegue contar\u00e1 con \u201c284 frentes de batalla\u201d, asegur\u00f3 el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466365","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maduro anuncia un despliegue militar y policial con &quot;284 frentes de batalla&quot; en medio de la tensi\u00f3n entre Venezuela y EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maduro anuncia un despliegue militar y policial con &quot;284 frentes de batalla&quot; en medio de la tensi\u00f3n entre Venezuela y EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"En medio de la tensi\u00f3n con Estados Unidos, el presidente de Venezuela, Nicol\u00e1s Maduro, anunci\u00f3 la puesta en marcha del llamado \u201cPlan Independencia 200\u201d, en el que participar\u00e1n los Cuerpos Combatientes de la milicia, la Milicia Nacional Bolivariana y la Fuerza Armada Nacional Bolivariana (FANB). El despliegue contar\u00e1 con \u201c284 frentes de batalla\u201d, asegur\u00f3 el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-11T16:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Maduro anuncia un despliegue militar y policial con &#171;284 frentes de batalla&#187; en medio de la tensi\u00f3n entre Venezuela y EE.UU.\",\"datePublished\":\"2025-09-11T16:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/\"},\"wordCount\":398,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/\",\"name\":\"Maduro anuncia un despliegue militar y policial con \\\"284 frentes de batalla\\\" en medio de la tensi\u00f3n entre Venezuela y EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-11T16:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maduro anuncia un despliegue militar y policial con &#171;284 frentes de batalla&#187; en medio de la tensi\u00f3n entre Venezuela y EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maduro anuncia un despliegue militar y policial con \"284 frentes de batalla\" en medio de la tensi\u00f3n entre Venezuela y EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Maduro anuncia un despliegue militar y policial con \"284 frentes de batalla\" en medio de la tensi\u00f3n entre Venezuela y EE.UU. - Noticias","og_description":"En medio de la tensi\u00f3n con Estados Unidos, el presidente de Venezuela, Nicol\u00e1s Maduro, anunci\u00f3 la puesta en marcha del llamado \u201cPlan Independencia 200\u201d, en el que participar\u00e1n los Cuerpos Combatientes de la milicia, la Milicia Nacional Bolivariana y la Fuerza Armada Nacional Bolivariana (FANB). El despliegue contar\u00e1 con \u201c284 frentes de batalla\u201d, asegur\u00f3 el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/","og_site_name":"Noticias","article_published_time":"2025-09-11T16:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/"},"author":{"name":"","@id":""},"headline":"Maduro anuncia un despliegue militar y policial con &#171;284 frentes de batalla&#187; en medio de la tensi\u00f3n entre Venezuela y EE.UU.","datePublished":"2025-09-11T16:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/"},"wordCount":398,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/","url":"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/","name":"Maduro anuncia un despliegue militar y policial con \"284 frentes de batalla\" en medio de la tensi\u00f3n entre Venezuela y EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-11T16:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Maduro anuncia un despliegue militar y policial con &#171;284 frentes de batalla&#187; en medio de la tensi\u00f3n entre Venezuela y EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Maduro anuncia un despliegue militar y policial con &#171;284 frentes de batalla&#187; en medio de la tensi\u00f3n entre Venezuela y EE.UU.","url":"http:\/\/noticiasya.com\/reno\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2025\/09\/11\/maduro-venezuela-despliegue-militar-estados-unidos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-11T16:03:55Z","datePublished":"2025-09-11T16:03:55Z","dateModified":"2025-09-11T16:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Maduro anuncia un despliegue militar y policial con &#171;284 frentes de batalla&#187; en medio de la tensi\\u00f3n entre Venezuela y EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/09\\\/11\\\/maduro-venezuela-despliegue-militar-estados-unidos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/09\\\/11\\\/maduro-venezuela-despliegue-militar-estados-unidos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-11T16:03:55Z\",\"datePublished\":\"2025-09-11T16:03:55Z\",\"dateModified\":\"2025-09-11T16:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468231,"url":"https:\/\/noticiasya.com\/reno\/2025\/11\/11\/maduro-despliegue-militar-masivo-tension-eeuu-orix\/","url_meta":{"origin":1466365,"position":0},"title":"Maduro ordena despliegue masivo de todas sus fuerzas militares tras casi tres meses tensiones con Estados Unidos","author":"","date":"noviembre 11, 2025","format":false,"excerpt":"El Ministerio de Defensa de Venezuela inform\u00f3 este martes que puso en marcha una nueva fase del \u201cPlan Independencia 200\u201d, que contempla una \u201cmovilizaci\u00f3n masiva\u201d de efectivos, sistemas de armas y medios militares. El despliegue llega en respuesta a lo que el gobierno venezolano califica como la \u201camenaza imperialista\u201d de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466168,"url":"https:\/\/noticiasya.com\/reno\/2025\/09\/04\/maduro-convoca-activacion-milicia-bolivariana-orix\/","url_meta":{"origin":1466365,"position":1},"title":"Maduro anuncia &#171;primera activaci\u00f3n&#187; de la Milicia Bolivariana. Dice que alistamiento ser\u00e1 permanente","author":"","date":"septiembre 4, 2025","format":false,"excerpt":"El presidente de Venezuela, Nicol\u00e1s Maduro, convoc\u00f3 este jueves a que las personas que en las \u00faltimas dos semanas se inscribieron en la Milicia Bolivariana, un cuerpo de reservistas integrado por voluntarios, acudan este viernes al \u201cprimera activaci\u00f3n\u201d para defender al pa\u00eds.Maduro lanz\u00f3 la convocatoria durante una transmisi\u00f3n de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467498,"url":"https:\/\/noticiasya.com\/reno\/2025\/10\/18\/maduro-plan-defensa-amenaza-eeuu-efe\/","url_meta":{"origin":1466365,"position":2},"title":"Maduro dice que se complet\u00f3 el plan de defensa en toda Venezuela ante la &#171;amenaza&#187; de EE.UU.","author":"","date":"octubre 18, 2025","format":false,"excerpt":"El presidente de Venezuela, Nicol\u00e1s Maduro, asegur\u00f3 este s\u00e1bado que se completaron las Zonas de Defensa Integral en el pa\u00eds, como parte del plan denominado \u201cIndependencia 200\u201d, ante lo que denuncia como \u201camenaza\u201d de Estados Unidos, que mantiene un despliegue militar en el mar Caribe cerca de la naci\u00f3n sudamericana.\u201cHoy\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467332,"url":"https:\/\/noticiasya.com\/reno\/2025\/10\/13\/maduro-brigadas-indigenas-milicias-sudamericanos-efe\/","url_meta":{"origin":1466365,"position":3},"title":"&#171;Brigadas ind\u00edgenas&#187;: las nuevas milicias que quiere formar Maduro para defenderse","author":"","date":"octubre 13, 2025","format":false,"excerpt":"El presidente de Venezuela, Nicol\u00e1s Maduro, orden\u00f3 este domingo conformar \u201cbrigadas milicianas\u201d de pueblos ind\u00edgenas de Sudam\u00e9rica para que vayan al pa\u00eds a defenderlo \u201csi fuese necesario\u201d, ante la \u201camenaza\u201d que, insiste, representa el despliegue militar de Estados Unidos en aguas del mar Caribe cercanas a la naci\u00f3n sudamericana.El mandatario,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465937,"url":"https:\/\/noticiasya.com\/reno\/2025\/08\/28\/venezolanos-rutina-tensiones-eeuu-orix\/","url_meta":{"origin":1466365,"position":4},"title":"&#171;Puro teatro, no hay nada&#187;: muchos venezolanos viven inmersos en la rutina en medio de las tensiones con EE.UU.","author":"","date":"agosto 28, 2025","format":false,"excerpt":"Mientras crecen las tensiones entre Venezuela y Estados Unidos por el anuncio del despliegue de buques en el Caribe, y el Gobierno del presidente Nicol\u00e1s Maduro llama a \u201cdefender la patria\u201d a trav\u00e9s de la Milicia Bolivariana, varios venezolanos entrevistados por CNN en las calles de Caracas aseguraron que, m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465812,"url":"https:\/\/noticiasya.com\/reno\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/","url_meta":{"origin":1466365,"position":5},"title":"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU.","author":"","date":"agosto 24, 2025","format":false,"excerpt":"Multitudes se convocaron Caracas el s\u00e1bado para inscribirse en la milicia venezolana despu\u00e9s de que el presidente Nicol\u00e1s Maduro hiciera un llamado a reforzar la defensa ante amenazas de Estados Unidos.CNN observ\u00f3 a los inscritos formar largas filas en la Plaza Bol\u00edvar, ubicada en el coraz\u00f3n de Caracas, para entregar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1466365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1466365"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1466365\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1466365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1466365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1466365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}