{"id":1466378,"date":"2025-09-11T18:03:49","date_gmt":"2025-09-12T01:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/"},"modified":"2025-09-11T18:03:49","modified_gmt":"2025-09-12T01:03:49","slug":"ftc-investiga-chatbots-posibles-danos-ninos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/","title":{"rendered":"La FTC investiga chatbots de IA &#171;acompa\u00f1antes&#187; ante creciente preocupaci\u00f3n por posibles da\u00f1os a ni\u00f1os"},"content":{"rendered":"<p>La Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s) abri\u00f3 una investigaci\u00f3n sobre siete empresas tecnol\u00f3gicas por los posibles da\u00f1os que sus chatbots de inteligencia artificial podr\u00edan causar a ni\u00f1os y adolescentes.<\/p>\n<p>La investigaci\u00f3n se centra en chatbots de IA que funcionan como acompa\u00f1antes, los cuales \u201cimitan efectivamente caracter\u00edsticas, emociones e intenciones humanas, y en general est\u00e1n dise\u00f1ados para comunicarse como un amigo o confidente, lo que puede llevar a que algunos usuarios, especialmente ni\u00f1os y adolescentes, conf\u00eden en ellos y establezcan relaciones con los chatbots\u201d, dijo la agencia en un comunicado el jueves.<\/p>\n<p>La FTC envi\u00f3 \u00f3rdenes a Alphabet, empresa matriz de Google; Character.AI; Instagram y su matriz, Meta; OpenAI; Snap; y xAI, de Elon Musk. La agencia busca informaci\u00f3n sobre si las compa\u00f1\u00edas miden el impacto de sus chatbots en los usuarios j\u00f3venes, c\u00f3mo protegen frente a riesgos y de qu\u00e9 manera alertan a los padres.<\/p>\n<p>La investigaci\u00f3n surge en medio de una creciente preocupaci\u00f3n por el uso de la IA entre ni\u00f1os y adolescentes, tras una serie de demandas y reportes que acusan a los chatbots de estar implicados en suicidios, explotaci\u00f3n sexual y otros da\u00f1os. Eso incluye una demanda contra OpenAI y dos contra Character.AI que siguen en curso, incluso cuando las compa\u00f1\u00edas aseguran que est\u00e1n incorporando nuevas funciones para proteger a los usuarios de interacciones da\u00f1inas.<\/p>\n<p>Tambi\u00e9n han surgido preocupaciones m\u00e1s amplias de que incluso usuarios adultos est\u00e1n desarrollando v\u00ednculos emocionales poco saludables con los chatbots de IA, en parte porque estas herramientas suelen estar dise\u00f1adas para ser complacientes y de apoyo.<\/p>\n<p>Al menos un grupo de defensa de la seguridad en l\u00ednea, Common Sense Media, ha argumentado que las aplicaciones de IA \u201ccompa\u00f1eras\u201d plantean riesgos inaceptables para los ni\u00f1os y no deber\u00edan estar disponibles para menores de 18 a\u00f1os. Dos <a href=\"https:\/\/leginfo.legislature.ca.gov\/faces\/home.xhtml\">proyectos de ley <\/a>estatales en California sobre seguridad de chatbots de IA para menores, incluido uno respaldado por Common Sense Media, recibir\u00e1n esta semana sus votos finales y, de aprobarse, llegar\u00e1n al escritorio del gobernador de California, Gavin Newsom. El Comit\u00e9 Judicial del Senado de EE.UU. tambi\u00e9n celebrar\u00e1 la pr\u00f3xima semana una audiencia titulada \u201cExaminando el da\u00f1o de los chatbots de IA\u201d.<\/p>\n<p>\u201cA medida que evolucionan las tecnolog\u00edas de IA, es importante considerar los efectos que los chatbots pueden tener en los ni\u00f1os, al mismo tiempo que se asegura que Estados Unidos mantenga su papel como l\u00edder mundial en esta nueva y emocionante industria\u201d, dijo el jueves el presidente de la FTC, Andrew Ferguson. \u201cEl estudio que lanzamos hoy nos ayudar\u00e1 a comprender mejor c\u00f3mo las empresas de IA est\u00e1n desarrollando sus productos y qu\u00e9 pasos est\u00e1n tomando para proteger a los ni\u00f1os\u201d.<\/p>\n<p>En particular, las \u00f3rdenes de la FTC buscan informaci\u00f3n sobre c\u00f3mo las compa\u00f1\u00edas monetizan la interacci\u00f3n de los usuarios, generan respuestas a las consultas, desarrollan y aprueban personajes de IA, usan o comparten informaci\u00f3n personal obtenida a trav\u00e9s de las conversaciones y mitigan los impactos negativos en los ni\u00f1os, entre otros detalles.<\/p>\n<p>Google, Snap y xAI no respondieron de inmediato a las solicitudes de comentarios.<\/p>\n<p>\u201cNuestra prioridad es que ChatGPT sea \u00fatil y seguro para todos, y sabemos que la seguridad es lo m\u00e1s importante cuando se trata de j\u00f3venes. Reconocemos que la FTC tiene preguntas y preocupaciones abiertas, y estamos comprometidos a colaborar de forma constructiva y responder directamente\u201d, dijo en un comunicado Liz Bourgeois, vocera de OpenAI. Agreg\u00f3 que OpenAI cuenta con salvaguardas como notificaciones que dirigen a los usuarios a l\u00edneas de ayuda en crisis y planes para implementar controles parentales para menores.<\/p>\n<p>Despu\u00e9s de que los padres de Adam Raine, de 16 a\u00f1os, demandaran a OpenAI el mes pasado alegando que ChatGPT alent\u00f3 el suicidio de su hijo, la empresa reconoci\u00f3 que sus salvaguardas pueden ser \u201cmenos confiables\u201d cuando los usuarios mantienen conversaciones prolongadas con los chatbots y dijo que trabaja con expertos para mejorarlas.<\/p>\n<p>Meta evit\u00f3 comentar directamente sobre la investigaci\u00f3n de la FTC. La compa\u00f1\u00eda dijo que actualmente limita el acceso de adolescentes a un grupo selecto de sus personajes de IA, como aquellos que ayudan con tareas escolares. Tambi\u00e9n entrena a sus chatbots para no responder a menciones de temas sensibles, como autolesiones o conversaciones rom\u00e1nticas inapropiadas, y en su lugar dirigir a los adolescentes a recursos de expertos.<\/p>\n<p>\u201cEsperamos colaborar con la FTC en esta investigaci\u00f3n y ofrecer una visi\u00f3n sobre la industria de la IA de consumo y la tecnolog\u00eda de r\u00e1pida evoluci\u00f3n en este \u00e1mbito\u201d, dijo en un comunicado Jerry Ruoti, jefe de confianza y seguridad de Character.AI. A\u00f1adi\u00f3 que la empresa ha invertido en recursos de seguridad y confianza, como una nueva experiencia para menores de 18 a\u00f1os en la plataforma, una herramienta de informaci\u00f3n para padres y advertencias que recuerdan a los usuarios que est\u00e1n interactuando con una IA.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s) abri\u00f3 una investigaci\u00f3n sobre siete empresas tecnol\u00f3gicas por los posibles da\u00f1os que sus chatbots de inteligencia artificial podr\u00edan causar a ni\u00f1os y adolescentes. La investigaci\u00f3n se centra en chatbots de IA que funcionan como acompa\u00f1antes, los cuales \u201cimitan efectivamente caracter\u00edsticas, emociones e intenciones humanas, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466378","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La FTC investiga chatbots de IA &quot;acompa\u00f1antes&quot; ante creciente preocupaci\u00f3n por posibles da\u00f1os a ni\u00f1os - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La FTC investiga chatbots de IA &quot;acompa\u00f1antes&quot; ante creciente preocupaci\u00f3n por posibles da\u00f1os a ni\u00f1os - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s) abri\u00f3 una investigaci\u00f3n sobre siete empresas tecnol\u00f3gicas por los posibles da\u00f1os que sus chatbots de inteligencia artificial podr\u00edan causar a ni\u00f1os y adolescentes. La investigaci\u00f3n se centra en chatbots de IA que funcionan como acompa\u00f1antes, los cuales \u201cimitan efectivamente caracter\u00edsticas, emociones e intenciones humanas, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-12T01:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La FTC investiga chatbots de IA &#171;acompa\u00f1antes&#187; ante creciente preocupaci\u00f3n por posibles da\u00f1os a ni\u00f1os\",\"datePublished\":\"2025-09-12T01:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/\"},\"wordCount\":901,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/\",\"name\":\"La FTC investiga chatbots de IA \\\"acompa\u00f1antes\\\" ante creciente preocupaci\u00f3n por posibles da\u00f1os a ni\u00f1os - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-12T01:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La FTC investiga chatbots de IA &#171;acompa\u00f1antes&#187; ante creciente preocupaci\u00f3n por posibles da\u00f1os a ni\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La FTC investiga chatbots de IA \"acompa\u00f1antes\" ante creciente preocupaci\u00f3n por posibles da\u00f1os a ni\u00f1os - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La FTC investiga chatbots de IA \"acompa\u00f1antes\" ante creciente preocupaci\u00f3n por posibles da\u00f1os a ni\u00f1os - Noticias","og_description":"La Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s) abri\u00f3 una investigaci\u00f3n sobre siete empresas tecnol\u00f3gicas por los posibles da\u00f1os que sus chatbots de inteligencia artificial podr\u00edan causar a ni\u00f1os y adolescentes. La investigaci\u00f3n se centra en chatbots de IA que funcionan como acompa\u00f1antes, los cuales \u201cimitan efectivamente caracter\u00edsticas, emociones e intenciones humanas, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-12T01:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/"},"author":{"name":"","@id":""},"headline":"La FTC investiga chatbots de IA &#171;acompa\u00f1antes&#187; ante creciente preocupaci\u00f3n por posibles da\u00f1os a ni\u00f1os","datePublished":"2025-09-12T01:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/"},"wordCount":901,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/","name":"La FTC investiga chatbots de IA \"acompa\u00f1antes\" ante creciente preocupaci\u00f3n por posibles da\u00f1os a ni\u00f1os - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-12T01:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La FTC investiga chatbots de IA &#171;acompa\u00f1antes&#187; ante creciente preocupaci\u00f3n por posibles da\u00f1os a ni\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La FTC investiga chatbots de IA &#171;acompa\u00f1antes&#187; ante creciente preocupaci\u00f3n por posibles da\u00f1os a ni\u00f1os","url":"http:\/\/noticiasya.com\/reno\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2025\/09\/11\/ftc-investiga-chatbots-posibles-danos-ninos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-12T01:03:49Z","datePublished":"2025-09-12T01:03:49Z","dateModified":"2025-09-12T01:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La FTC investiga chatbots de IA &#171;acompa\\u00f1antes&#187; ante creciente preocupaci\\u00f3n por posibles da\\u00f1os a ni\\u00f1os\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/09\\\/11\\\/ftc-investiga-chatbots-posibles-danos-ninos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2025\\\/09\\\/11\\\/ftc-investiga-chatbots-posibles-danos-ninos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-12T01:03:49Z\",\"datePublished\":\"2025-09-12T01:03:49Z\",\"dateModified\":\"2025-09-12T01:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1466386,"url":"https:\/\/noticiasya.com\/reno\/2025\/09\/12\/5-cosas-12-de-septiembre-orix\/","url_meta":{"origin":1466378,"position":0},"title":"Las 5 cosas que debes saber este 12 de septiembre: condena de Bolsonaro, atacante de Charlie Kirk y Demon Slayer","author":"","date":"septiembre 12, 2025","format":false,"excerpt":"Un nuevo video muestra al sospechoso del asesinato de Charlie Kirk, que sigue pr\u00f3fugo. Los nombres de los centros de detenci\u00f3n de migrantes en EE.UU. \u00bfQu\u00e9 pas\u00f3 antes y despu\u00e9s de la explosi\u00f3n del cami\u00f3n con gas en M\u00e9xico? Esto es lo que debes saber para comenzar el d\u00eda. Primero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465696,"url":"https:\/\/noticiasya.com\/reno\/2025\/08\/20\/hijo-usara-inteligencia-artificial-ahora-que-trax\/","url_meta":{"origin":1466378,"position":1},"title":"Tu hijo usar\u00e1 inteligencia artificial para hacer las tareas este a\u00f1o. \u00bfY ahora qu\u00e9?","author":"","date":"agosto 20, 2025","format":false,"excerpt":"Cuando los ni\u00f1os regresen a clases, hay una alta probabilidad de que planeen usar la inteligencia artificial para hacer sus trabajos escolares.El 26 % de los adolescentes de entre 13 y 17 a\u00f1os dijeron haber usado ChatGPT para sus tareas escolares en una encuesta del Centro de Investigaciones Pew en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465926,"url":"https:\/\/noticiasya.com\/reno\/2025\/08\/28\/terapeuta-ia-podria-ilegal-pronto-trax\/","url_meta":{"origin":1466378,"position":2},"title":"Tu terapeuta de IA podr\u00eda ser ilegal pronto. Aqu\u00ed te explicamos por qu\u00e9","author":"","date":"agosto 28, 2025","format":false,"excerpt":"A medida que los chatbots de inteligencia artificial se vuelven una forma popular de acceder a asesoramiento y compa\u00f1\u00eda gratuitos, est\u00e1 surgiendo un mosaico de regulaciones estatales que restringen la forma en que se puede usar esta tecnolog\u00eda en las pr\u00e1cticas terap\u00e9uticas y determinan si puede reemplazar a los terapeutas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467484,"url":"https:\/\/noticiasya.com\/reno\/2025\/10\/17\/instagram-padres-impedir-adolescentes-chateen-ia-trax\/","url_meta":{"origin":1466378,"position":3},"title":"Instagram pronto permitir\u00e1 a los padres impedir que los adolescentes chateen con personajes de IA","author":"","date":"octubre 17, 2025","format":false,"excerpt":"Instagram lanzar\u00e1 nuevas funciones de seguridad para adolescentes, incluida la posibilidad de que los padres impidan que sus hijos chateen con los personajes de IA de la plataforma, anunci\u00f3 este viernes la empresa matriz Meta. Es una de varias nuevas funciones de seguridad de Meta y OpenAI destinadas a combatir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456741,"url":"https:\/\/noticiasya.com\/reno\/2024\/12\/18\/chatbots-inteligencia-artificial-terapia-expertos-trax\/","url_meta":{"origin":1466378,"position":4},"title":"Los chatbots de inteligencia artificial se est\u00e1n popularizando para la terapia; esto opinan los expertos en salud mental","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"Recurr\u00ed a ChatGPT en mi laptop para comprobar las habilidades terap\u00e9uticas de este bot de inteligencia artificial.\u201cHola, soy Therapist GPT, tu amable y emp\u00e1tico compa\u00f1ero que te escuchar\u00e1 y te ayudar\u00e1 con lo que tengas en mente\u201d, me escribi\u00f3 el bot de ChatGPT creado por un usuario. (El a\u00f1o pasado,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456822,"url":"https:\/\/noticiasya.com\/reno\/2024\/12\/20\/citas-apps-inteligencia-artificial-trax\/","url_meta":{"origin":1466378,"position":5},"title":"Las citas online est\u00e1n a punto de cambiar radicalmente","author":"","date":"diciembre 20, 2024","format":false,"excerpt":"Chatbots personalizados que tienen citas con otros chatbots en tu lugar. Conserjes de inteligencia artificial que responden a preguntas sobre posibles parejas. Algoritmos avanzados que predicen la compatibilidad mejor que nunca. Las aplicaciones de citas est\u00e1n a punto de experimentar una gran transformaci\u00f3n.Mientras gran parte de la industria tecnol\u00f3gica se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1466378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1466378"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1466378\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1466378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1466378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1466378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}