{"id":1470433,"date":"2026-01-23T17:03:40","date_gmt":"2026-01-24T01:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/"},"modified":"2026-01-23T17:03:40","modified_gmt":"2026-01-24T01:03:40","slug":"exclusivo-entrevista-familia-liam-ice-minnesota-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/","title":{"rendered":"Exclusivo CNN: &#171;Un ni\u00f1o de 5 a\u00f1os no comete ning\u00fan delito&#187;, dice t\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota"},"content":{"rendered":"<p>Luis Conejo intenta mostrarse firme pero su mirada se nubla y contiene el llanto mientras habla de la indignaci\u00f3n que le produce ver im\u00e1genes que muestran c\u00f3mo agentes de inmigraci\u00f3n <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/23\/latinoamerica\/gobierno-ecuador-ice-liam-conejo-ramos-padre-oposicion-critica-orix\">se llevaron el martes<\/a> a su hermano y a su sobrino Liam, de apenas cinco a\u00f1os, en la ciudad de Minneapolis, en el estado de Minnesota, al norte de Estados Unidos.<\/p>\n<p>\u201cSolo mirar las im\u00e1genes es algo indignante, es una verg\u00fcenza utilizar a un ni\u00f1o de cualquier forma, de cualquier cultura, sea de cualquier pa\u00eds. Utilizar a un ni\u00f1o es lo m\u00e1s bajo que se puede hacer\u201d, dice en entrevista con CNN, a quien recibi\u00f3 en el norte de Quito, la capital de Ecuador.<\/p>\n<p>El martes, el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) detuvo al padre de Liam, Adri\u00e1n Alexander Conejo Arias, un ciudadano ecuatoriano de 33 a\u00f1os, cuando estaba junto al ni\u00f1o a metros de su casa. Los dos permanecen detenidos en una instalaci\u00f3n de ICE en Texas desde el jueves.<\/p>\n<p>El caso ha generado indignaci\u00f3n en la comunidad. Fueron los vecinos quienes registraron en video el momento de la detenci\u00f3n, donde se puede ver a Liam vestido con un abrigo a cuadros, su gorro de conejo tejido de color azul y una mochila de Spiderman. Parece atemorizado mientras un agente de inmigraci\u00f3n lo sujeta por la mochila y luego sube a una camioneta negra.<\/p>\n<p>Al ver esas im\u00e1genes, su t\u00edo dice sentir dolor por la forma como trataron a su familia. \u201cUn ni\u00f1o de cinco a\u00f1os no cometi\u00f3 ning\u00fan delito\u201d, dice. \u201cNi mi hermano ni mi sobrino son criminales\u201d.<\/p>\n<p>Liam y su familia son originarios de Ecuador y se presentaron ante los oficiales fronterizos en Texas en diciembre de 2024 para solicitar asilo, dijo el abogado de la familia, Marc Prokosch.<\/p>\n<p>Adri\u00e1n Conejo y Pamela Ramos, de 29 a\u00f1os, emigraron de Ecuador hacia EE.UU. con sus dos hijos: Tadeo, de 12, y Liam, de cinco. Pamela est\u00e1 embarazada de su tercer hijo.<\/p>\n<p>El Departamento de Seguridad Nacional de EE.UU. (DHS, por sus siglas en ingl\u00e9s) describi\u00f3 al padre de Liam como un \u201cinmigrante ilegal\u201d que era el objetivo de la operaci\u00f3n llevada a cabo. El abogado de la familia, sin embargo, rechaza este se\u00f1alamiento.<\/p>\n<p>\u201cNo son inmigrantes ilegales\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/22\/eeuu\/video\/abogado-liam-conejo-nino-detenido-ice-vance-trax\">dijo Prokosch<\/a>. \u201cEstaban siguiendo todos los protocolos establecidos, tramitando su solicitud de asilo, acudiendo a sus audiencias judiciales, y no representaban ninguna seguridad, ning\u00fan riesgo de fuga y nunca debieron haber sido detenidos\u201d.<\/p>\n<p>El t\u00edo de Liam cuenta que desde hace tiempo, en el grupo de WhatsApp que comparte la familia, los mensajes que enviaban Adri\u00e1n y Pamela hablaban con frecuencia sobre el temor a ser detenidos.<\/p>\n<p>El martes, ese miedo se volvi\u00f3 una realidad. \u201cNos llama en shock, en un nerviosismo total, sin poder hablar\u201d, dice sobre el momento en que su cu\u00f1ada le cont\u00f3 sobre la detenci\u00f3n de Adri\u00e1n y Liam a pocos metros de la vivienda donde ella estaba.<\/p>\n<p>La raz\u00f3n por la que Liam fue separado de su madre y llevado a una detenci\u00f3n con su padre es un tema que gener\u00f3 controversia.<\/p>\n<p>El DHS dijo que el ni\u00f1o fue \u201cabandonado\u201d por el padre, que \u201chuy\u00f3\u201d del lugar, y que su madre se neg\u00f3 a tomar la custodia. Las autoridades argumentan haber hecho \u201cm\u00faltiples intentos\u201d para que la madre abriera la puerta y el ni\u00f1o entrara a la casa; incluso, que \u201cle aseguraron que no la arrestar\u00edan\u201d.<\/p>\n<p>La madre estaba \u201caterrorizada\u201d por los agentes federales, <a href=\"https:\/\/www.cnn.com\/2026\/01\/22\/us\/minnesota-liam-conejo-ramos-ice-detained\">dijo<\/a> el jueves a CNN el pastor Sergio Amezcua, quien la asiste desde que detuvieron a su esposo e hijo.<\/p>\n<p>Para el t\u00edo de Liam, la intenci\u00f3n de las autoridades era \u201cutilizar\u201d al ni\u00f1o para persuadir a la madre para que abriera la puerta y poder detenerla tambi\u00e9n. \u201cEs algo muy, muy triste. Son im\u00e1genes muy fuertes, que llegan al coraz\u00f3n, y no puede suceder m\u00e1s esto\u201d, dice.<\/p>\n<p>ICE, en tanto, afirma que <a href=\"https:\/\/x.com\/ICEgov\/status\/2014358760630735012?s=20\">nunca ha \u201cutilizado a un ni\u00f1o como cebo\u201d.<\/a><\/p>\n<p>\u201cEs muy duro lo que est\u00e1 pasando en la familia. Se viraliz\u00f3 tanto, en todos lados est\u00e1n las im\u00e1genes de Liam y mucha gente se siente identificada porque tienen sus ni\u00f1os en casa\u201d, afirma el t\u00edo del ni\u00f1o. \u00c9l tambi\u00e9n es padre y dice que siente impotencia de estar lejos y no poder hacer algo para ayudarlos.<\/p>\n<p>La familia Conejo es oriunda de Otavalo, una ciudad del norte de Ecuador. La comunidad otavale\u00f1a es reconocida por sus artesan\u00edas y por representar a la cultura ecuatoriana en otros pa\u00edses.<\/p>\n<p>Luis cuenta que su hermano fue con muchos sue\u00f1os a EE.UU., a donde fue \u201cllevando la cultura y el arte en sus manos\u201d para trabajar all\u00ed con ilusi\u00f3n. Cree que, con todo lo que le est\u00e1 ocurriendo, Adri\u00e1n ya no ver\u00e1 a ese pa\u00eds con los mismos ojos.<\/p>\n<p>\u201cTenemos mucha suerte de que estaban los vecinos, que hab\u00eda c\u00e1maras y que hay registrados videos, fotograf\u00edas. Imag\u00ednese casos de ni\u00f1os que no tuvieron la misma oportunidad, y que nadie pudo decir nada por ellos\u201d, dice el t\u00edo de Liam.<\/p>\n<p>Cuenta que su hermano se dedica a la alba\u00f1iler\u00eda, a trabajos de pintura y reparaciones de distinta \u00edndole. \u201cEs muy trabajador mi hermano\u201d, dice.<\/p>\n<p>La situaci\u00f3n econ\u00f3mica, la inseguridad y las condiciones inconstantes de empleo en Ecuador los llevaron a dejar su pa\u00eds \u201cpara un buen vivir\u201d, afirma. Su hermano ten\u00eda trabajo en Ecuador, pero no lograba las condiciones necesarias para que sus hijos \u201ctengan un futuro\u201d, una mejor vida que fueron a buscar a EE.UU.<\/p>\n<p>Cuando la familia tom\u00f3 la decisi\u00f3n de irse, aunque eso implicaba que estar\u00edan lejos, lo apoyaron y acompa\u00f1aron su decisi\u00f3n, cuenta Conejo.<\/p>\n<p>Afectado por lo que est\u00e1 atravesando su familia, exige que dejen en libertad a su hermano y a su sobrino y desmiente las versiones que dieron las autoridades.<\/p>\n<p>La Canciller\u00eda de Ecuador, citando informaci\u00f3n del DHS, afirm\u00f3 que Adri\u00e1n Conejo \u201chuy\u00f3 ante la presencia de los agentes de ICE, dejando al menor en el veh\u00edculo en el que se encontraba\u201d.<\/p>\n<p>Luis responde: \u201cNo es verdad lo que dice Canciller\u00eda que mi hermano sali\u00f3 huyendo y dej\u00f3 solo a su ni\u00f1o con lo del ICE. No es verdad lo que dice el vicepresidente (J.D. Vance) de que es un criminal. Es absolutamente falso\u201d.<\/p>\n<p>Durante la entrevista con CNN, el t\u00edo de Liam mostr\u00f3 el certificado expedido por el Ministerio del Interior de Ecuador, donde dice que Adri\u00e1n Conejo no posee antecedentes penales. CNN verific\u00f3 de manera independiente ese registro.<\/p>\n<p>\u201cTenemos que detener ya este trato a los migrantes. Los migrantes son trabajadores. No somos delincuentes como nos quieren llamar, no somos terroristas, no somos ladrones. Vamos a trabajar y sobre todo nosotros, los ind\u00edgenas kichwa otavale\u00f1os. Estamos en todo el mundo trabajando honradamente, no estamos delinquiendo\u201d, dice Conejo.<\/p>\n<p>La Canciller\u00eda de Ecuador emiti\u00f3 un <a href=\"https:\/\/x.com\/cancilleriaec\/status\/2014824717115428890?s=46&#038;t=vWSsaMsKttiCRFRT9JR29g\">nuevo comunicado<\/a> en la tarde del viernes en el que afirma que tanto el menor como su padre \u201cse encuentran juntos\u201d en el Centro de Procesamiento de Inmigraci\u00f3n de Dilley, en Texas.<\/p>\n<p>Agrega que \u201cse encuentra monitoreando la situaci\u00f3n del menor y su padre a fin de precautelar su bienestar y el debido proceso, en vista de que mantienen una petici\u00f3n de asilo en curso en ese pa\u00eds\u201d.<\/p>\n<p>Mientras tanto, la familia Conejo espera con incertidumbre las pr\u00f3ximas horas con el deseo de que pronto Adri\u00e1n y Liam puedan regresar a su hogar.<\/p>\n<p>\u201cLiam es un ni\u00f1o muy, muy alegre. Es el m\u00e1s juguet\u00f3n de la familia\u201d, dice su t\u00edo. \u201cTodo el tiempo est\u00e1 aqu\u00ed, todo el tiempo est\u00e1 ac\u00e1\u201d, agrega, al tiempo que se\u00f1ala con la mano izquierda primero su cabeza y luego su coraz\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luis Conejo intenta mostrarse firme pero su mirada se nubla y contiene el llanto mientras habla de la indignaci\u00f3n que le produce ver im\u00e1genes que muestran c\u00f3mo agentes de inmigraci\u00f3n se llevaron el martes a su hermano y a su sobrino Liam, de apenas cinco a\u00f1os, en la ciudad de Minneapolis, en el estado de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470433","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exclusivo CNN: &quot;Un ni\u00f1o de 5 a\u00f1os no comete ning\u00fan delito&quot;, dice t\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exclusivo CNN: &quot;Un ni\u00f1o de 5 a\u00f1os no comete ning\u00fan delito&quot;, dice t\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota - Noticias\" \/>\n<meta property=\"og:description\" content=\"Luis Conejo intenta mostrarse firme pero su mirada se nubla y contiene el llanto mientras habla de la indignaci\u00f3n que le produce ver im\u00e1genes que muestran c\u00f3mo agentes de inmigraci\u00f3n se llevaron el martes a su hermano y a su sobrino Liam, de apenas cinco a\u00f1os, en la ciudad de Minneapolis, en el estado de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-24T01:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Exclusivo CNN: &#171;Un ni\u00f1o de 5 a\u00f1os no comete ning\u00fan delito&#187;, dice t\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota\",\"datePublished\":\"2026-01-24T01:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/\"},\"wordCount\":1405,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/\",\"name\":\"Exclusivo CNN: \\\"Un ni\u00f1o de 5 a\u00f1os no comete ning\u00fan delito\\\", dice t\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-24T01:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exclusivo CNN: &#171;Un ni\u00f1o de 5 a\u00f1os no comete ning\u00fan delito&#187;, dice t\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exclusivo CNN: \"Un ni\u00f1o de 5 a\u00f1os no comete ning\u00fan delito\", dice t\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Exclusivo CNN: \"Un ni\u00f1o de 5 a\u00f1os no comete ning\u00fan delito\", dice t\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota - Noticias","og_description":"Luis Conejo intenta mostrarse firme pero su mirada se nubla y contiene el llanto mientras habla de la indignaci\u00f3n que le produce ver im\u00e1genes que muestran c\u00f3mo agentes de inmigraci\u00f3n se llevaron el martes a su hermano y a su sobrino Liam, de apenas cinco a\u00f1os, en la ciudad de Minneapolis, en el estado de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-24T01:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/"},"author":{"name":"","@id":""},"headline":"Exclusivo CNN: &#171;Un ni\u00f1o de 5 a\u00f1os no comete ning\u00fan delito&#187;, dice t\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota","datePublished":"2026-01-24T01:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/"},"wordCount":1405,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/","name":"Exclusivo CNN: \"Un ni\u00f1o de 5 a\u00f1os no comete ning\u00fan delito\", dice t\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-24T01:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Exclusivo CNN: &#171;Un ni\u00f1o de 5 a\u00f1os no comete ning\u00fan delito&#187;, dice t\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Exclusivo CNN: &#171;Un ni\u00f1o de 5 a\u00f1os no comete ning\u00fan delito&#187;, dice t\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota","url":"http:\/\/noticiasya.com\/reno\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2026\/01\/23\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-24T01:03:40Z","datePublished":"2026-01-24T01:03:40Z","dateModified":"2026-01-24T01:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Exclusivo CNN: &#171;Un ni\\u00f1o de 5 a\\u00f1os no comete ning\\u00fan delito&#187;, dice t\\u00edo de Liam Conejo, el menor detenido por ICE en Minnesota\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/01\\\/23\\\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/01\\\/23\\\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-24T01:03:40Z\",\"datePublished\":\"2026-01-24T01:03:40Z\",\"dateModified\":\"2026-01-24T01:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470502,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/26\/ecuador-cancilleria-caso-liam-conejo-familia-orix\/","url_meta":{"origin":1470433,"position":0},"title":"Canciller\u00eda de Ecuador dice que da seguimiento al caso de Liam Conejo y que su familia &#171;ha pedido que no intervengamos&#187;","author":"","date":"enero 26, 2026","format":false,"excerpt":"La canciller de Ecuador, Gabriela Sommerfeld, dijo este lunes que el Gobierno est\u00e1 pendiente del caso del ni\u00f1o ecuatoriano de cinco a\u00f1os Liam Conejo, quien fue detenido la semana pasada por agentes del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Minneapolis, junto a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470427,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/23\/que-paso-liam-conejo-ramos-5-anios-ice-trax\/","url_meta":{"origin":1470433,"position":1},"title":"\u00bfQu\u00e9 pas\u00f3 con el ni\u00f1o de 5 a\u00f1os Liam Conejo? Un pastor dice que ICE lo us\u00f3 de carnada y autoridades defienden la detenci\u00f3n","author":"","date":"enero 23, 2026","format":false,"excerpt":"Envuelto en su peque\u00f1o abrigo de cuadros y un gorro azul tejido de conejito, Liam Conejo Ramos, de 5 a\u00f1os, parece aterrorizado mientras desconocidos lo alejan de su hogar en Minnesota.Un agente federal enmascarado camina detr\u00e1s del ni\u00f1o, sosteniendo la manija de su mochila de Spiderman mientras Liam sube a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470709,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/31\/que-paso-liam-conejo-ramos-trax\/","url_meta":{"origin":1470433,"position":2},"title":"\u00bfQu\u00e9 pas\u00f3 con el ni\u00f1o de 5 a\u00f1os Liam Conejo Ramos?","author":"","date":"enero 31, 2026","format":false,"excerpt":"El martes 20 de enero, Liam Conejo Ramos, de 5 a\u00f1os, fue llevado por funcionarios del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) despu\u00e9s de regresar a casa del preescolar en el suburbio de Columbia Heights, Minneapolis.Envuelto en su peque\u00f1o abrigo de cuadros y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470387,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/22\/liam-conejo-ramos-nino-5-anios-preescolar-detenido-ice-trax\/","url_meta":{"origin":1470433,"position":3},"title":"Liam Conejo Ramos: el ni\u00f1o de 5 a\u00f1os que fue detenido por ICE junto con su padre ecuatoriano","author":"","date":"enero 22, 2026","format":false,"excerpt":"Un ni\u00f1o de 5 a\u00f1os que fue llevado por agentes federales desde la entrada de su casa en el \u00e1rea metropolitana de Minneapolis el martes tras regresar del preescolar est\u00e1 detenido junto con su padre en una instalaci\u00f3n de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470708,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/","url_meta":{"origin":1470433,"position":4},"title":"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente","author":"","date":"enero 31, 2026","format":false,"excerpt":"Un juez federal ha ordenado la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre del Centro Residencial Familiar del Sur de Texas en Dilley, Texas, seg\u00fan una fuente con conocimiento del fallo del juez federal emitido el s\u00e1bado.CNN no logr\u00f3 hasta el momento obtener una copia del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470533,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/27\/liam-cornejo-juez-bloquea-deportacion-padre-hijo-cinco-anos-trax\/","url_meta":{"origin":1470433,"position":5},"title":"Un juez federal bloquea, por ahora, la posible deportaci\u00f3n del ni\u00f1o de 5 a\u00f1os Liam Conejo Ramos y su padre","author":"","date":"enero 27, 2026","format":false,"excerpt":"Un ni\u00f1o de preescolar de Minnesota detenido en Texas con su padre no puede ser deportado de manera inminente, dictamin\u00f3 un juez federal el lunes.Liam Conejo Ramos, de 5 a\u00f1os, fue separado de la entrada de la casa de su familia en los suburbios de Minneapolis la semana pasada despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1470433"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470433\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1470433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1470433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1470433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}