{"id":1470457,"date":"2026-01-24T21:03:38","date_gmt":"2026-01-25T05:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/"},"modified":"2026-01-24T21:03:38","modified_gmt":"2026-01-25T05:03:38","slug":"videos-agente-arma-alex-pretti-tiroteo-analisis-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/","title":{"rendered":"Videos parecen mostrar que un agente federal tom\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\u00fan an\u00e1lisis de CNN"},"content":{"rendered":"<p>Un an\u00e1lisis de video de CNN parece mostrar a un agente federal de inmigraci\u00f3n quit\u00e1ndole un arma de <a href=\"https:\/\/cnnespanol.cnn.com\/eeuu\/live-news\/hombre-baleado-autoridades-federales-minneapolis-noticias-reacciones-orix?post-id=cmkt32dy8001d3j6qi2xz3u3l\">Alex Pretti<\/a> justo antes de que los funcionarios le dispararan fatalmente.<\/p>\n<p>El video de un transe\u00fante muestra a un agente metiendo la mano entre el grupo de agentes que intentaban inmovilizar a Pretti y recuperando un arma que parece coincidir con el arma de fuego que el Departamento de Seguridad Nacional dice que Pretti pose\u00eda.<\/p>\n<p>Se escucha a los agentes gritar \u201ctiene un arma\u201d cuando el agente no identificado mete la mano en la cintura de Pretti mientras el grupo de funcionarios intenta someterlo. Poco m\u00e1s de un segundo despu\u00e9s de que el agente aparece sosteniendo el arma, se escucha un disparo, seguido de al menos otros nueve, seg\u00fan los videos.<\/p>\n<p>Las grabaciones muestran que el agente que recuper\u00f3 el arma no ten\u00eda nada en la mano antes de acercarse a Pretti. No est\u00e1 claro en los videos revisados por CNN si el agente que tom\u00f3 el arma de Pretti inform\u00f3 a los dem\u00e1s una vez que la hab\u00eda retirado.<\/p>\n<p>Pero aproximadamente un minuto despu\u00e9s del tiroteo, mientras el cuerpo de Pretti yac\u00eda inm\u00f3vil en la calle, en otro video se puede escuchar a un agente preguntando: \u201c\u00bfD\u00f3nde est\u00e1 el arma?\u201d El funcionario que recuper\u00f3 el arma se acerca y responde: \u201cYo tengo el arma\u201d.<\/p>\n<p>No est\u00e1 claro cu\u00e1l agente dispar\u00f3 primero a Pretti.<\/p>\n<p>En un comunicado, el Departamento de Seguridad Nacional dijo que un agente dispar\u00f3 contra Pretti, de 37 a\u00f1os, temiendo por su vida.<\/p>\n<p>\u201cLos agentes intentaron desarmar al sospechoso, pero el sospechoso armado resisti\u00f3 violentamente\u201d, dijo McLaughlin. \u201cTemiendo por su vida y la vida y seguridad de sus compa\u00f1eros, un agente realiz\u00f3 disparos defensivos\u201d. Agreg\u00f3 que los param\u00e9dicos asistieron a Pretti, pero fue declarado muerto en el lugar.<\/p>\n<p>En ning\u00fan momento en los videos revisados por CNN se ve a Pretti empu\u00f1ando un arma; se le ve portando un tel\u00e9fono celular en una mano al principio del encuentro.<\/p>\n<p>El jefe de la Polic\u00eda de Minneapolis dijo que se cre\u00eda que Pretti era un propietario legal de armas con permiso para portar.<\/p>\n<p>\u201cPor lo que veo ahora, esto no parece un tiroteo justificado\u201d, dijo Charles Ramsey, ex comisionado de Polic\u00eda de Filadelfia y Washington y analista de seguridad para CNN, quien revis\u00f3 los videos. \u201cEl hombre est\u00e1 boca abajo en la acera\u2026 y a\u00fan as\u00ed siguen dispar\u00e1ndole\u201d.<\/p>\n<p>Antes del tiroteo, los videos revisados por CNN muestran que las tensiones aumentaron r\u00e1pidamente en un vecindario del sur de Minneapolis donde un grupo de agentes federales realizaba una operaci\u00f3n. Aproximadamente dos minutos antes de los disparos, varios agentes son vistos deteniendo a una persona en la calle mientras transe\u00fantes hacen sonar silbatos, tocan bocinas de autos y graban video, seg\u00fan un video filmado desde un auto cercano.<\/p>\n<p>Pretti \u2013un hombre de 37 a\u00f1os que trabajaba como enfermero de UCI en un hospital de veteranos de Minneapolis, seg\u00fan su familia\u2013 es visto por primera vez de pie en la calle, sosteniendo su tel\u00e9fono en una mano y grabando a los funcionarios mientras dirige el tr\u00e1fico con la otra. Mientras un agente federal interact\u00faa con otros transe\u00fantes, Pretti le grita al funcionario: \u201c\u00a1No los empuje hacia el tr\u00e1fico!\u201d<\/p>\n<p>El funcionario entonces camina hacia Pretti y varios otros transe\u00fantes, y empuja a una mujer al suelo. Pretti se interpone entre el agente y la mujer. El agente roc\u00eda a Pretti con un irritante qu\u00edmico y lo arrastra de rodillas mientras Pretti tira de la mochila del otro transe\u00fante, posiblemente alcanzando una botella de agua.<\/p>\n<p>Al menos otros seis agentes se re\u00fanen r\u00e1pidamente, con funcionarios de pie sobre Pretti y empuj\u00e1ndolo al suelo mientras \u00e9l parece resistirse, lo que lleva a un forcejeo en la calle.<\/p>\n<p>Un agente parece golpear repetidamente a Pretti mientras est\u00e1 en el suelo. Otro agente, con chaqueta gris, se puede ver desde algunos \u00e1ngulos de c\u00e1mara metiendo la mano entre el grupo de funcionarios y recuperando un arma que parece coincidir con el arma de fuego que el DHS dice que Pretti pose\u00eda. Ese mismo agente luego se aleja r\u00e1pidamente del altercado.<\/p>\n<p>El presidente Donald Trump y otros funcionarios federales publicaron una foto de un arma que dijeron pertenec\u00eda a Pretti en redes sociales, y McLaughlin se\u00f1al\u00f3 el hecho de que el arma ten\u00eda dos cargadores para argumentar, sin pruebas, que \u201cesto parece una situaci\u00f3n en la que un individuo quer\u00eda causar el m\u00e1ximo da\u00f1o y masacrar a las fuerzas del orden\u201d.<\/p>\n<p>Ramsey refut\u00f3 esa caracterizaci\u00f3n.<\/p>\n<p>Dijo que parec\u00eda que la gran cantidad de agentes que estaban \u201crodeando\u201d a Pretti pudo haber provocado que \u201cdemasiados funcionarios se interpusieran entre s\u00ed\u201d o a\u00f1adido confusi\u00f3n sobre el estado del arma de Pretti.<\/p>\n<p>Y argument\u00f3 que era necesaria una investigaci\u00f3n independiente y de terceros sobre el tiroteo, especialmente despu\u00e9s de las declaraciones de la secretaria de Seguridad Nacional, Kristi Noem, y otros l\u00edderes de la administraci\u00f3n Trump defendiendo a los agentes poco despu\u00e9s del incidente.<\/p>\n<p>Una vez que los l\u00edderes \u201csalen y pr\u00e1cticamente absuelven al agente, calific\u00e1ndo el tiroteo como justificado, no se puede esperar una investigaci\u00f3n objetiva basada en hechos\u201d, dijo Ramsey, calificando la actuaci\u00f3n del DHS como \u201cinaceptable\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un an\u00e1lisis de video de CNN parece mostrar a un agente federal de inmigraci\u00f3n quit\u00e1ndole un arma de Alex Pretti justo antes de que los funcionarios le dispararan fatalmente. El video de un transe\u00fante muestra a un agente metiendo la mano entre el grupo de agentes que intentaban inmovilizar a Pretti y recuperando un arma [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470457","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Videos parecen mostrar que un agente federal tom\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\u00fan an\u00e1lisis de CNN - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Videos parecen mostrar que un agente federal tom\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\u00fan an\u00e1lisis de CNN - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un an\u00e1lisis de video de CNN parece mostrar a un agente federal de inmigraci\u00f3n quit\u00e1ndole un arma de Alex Pretti justo antes de que los funcionarios le dispararan fatalmente. El video de un transe\u00fante muestra a un agente metiendo la mano entre el grupo de agentes que intentaban inmovilizar a Pretti y recuperando un arma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-25T05:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Videos parecen mostrar que un agente federal tom\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\u00fan an\u00e1lisis de CNN\",\"datePublished\":\"2026-01-25T05:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/\"},\"wordCount\":963,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/\",\"name\":\"Videos parecen mostrar que un agente federal tom\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\u00fan an\u00e1lisis de CNN - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-25T05:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Videos parecen mostrar que un agente federal tom\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\u00fan an\u00e1lisis de CNN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Videos parecen mostrar que un agente federal tom\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\u00fan an\u00e1lisis de CNN - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Videos parecen mostrar que un agente federal tom\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\u00fan an\u00e1lisis de CNN - Noticias","og_description":"Un an\u00e1lisis de video de CNN parece mostrar a un agente federal de inmigraci\u00f3n quit\u00e1ndole un arma de Alex Pretti justo antes de que los funcionarios le dispararan fatalmente. El video de un transe\u00fante muestra a un agente metiendo la mano entre el grupo de agentes que intentaban inmovilizar a Pretti y recuperando un arma [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-25T05:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/"},"author":{"name":"","@id":""},"headline":"Videos parecen mostrar que un agente federal tom\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\u00fan an\u00e1lisis de CNN","datePublished":"2026-01-25T05:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/"},"wordCount":963,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/","name":"Videos parecen mostrar que un agente federal tom\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\u00fan an\u00e1lisis de CNN - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-25T05:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Videos parecen mostrar que un agente federal tom\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\u00fan an\u00e1lisis de CNN"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Videos parecen mostrar que un agente federal tom\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\u00fan an\u00e1lisis de CNN","url":"http:\/\/noticiasya.com\/reno\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2026\/01\/24\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-25T05:03:38Z","datePublished":"2026-01-25T05:03:38Z","dateModified":"2026-01-25T05:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Videos parecen mostrar que un agente federal tom\\u00f3 el arma de Alex Pretti justo antes del tiroteo fatal, seg\\u00fan an\\u00e1lisis de CNN\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/01\\\/24\\\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/01\\\/24\\\/videos-agente-arma-alex-pretti-tiroteo-analisis-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-25T05:03:38Z\",\"datePublished\":\"2026-01-25T05:03:38Z\",\"dateModified\":\"2026-01-25T05:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470636,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/29\/agentes-encuentro-tiroteo-mortal-alex-pretti-trax\/","url_meta":{"origin":1470457,"position":0},"title":"As\u00ed fue como dos agentes federales convirtieron un encuentro con Alex Pretti en un tiroteo mortal","author":"","date":"enero 29, 2026","format":false,"excerpt":"En los momentos ca\u00f3ticos previos a la muerte de Alex Pretti el s\u00e1bado, las acciones agresivas de dos agentes federales transformaron el encuentro en un tiroteo mortal, seg\u00fan revela un an\u00e1lisis de CNN de los videos disponibles.Mientras otros agentes ayudaban a someter a Pretti en una calle de Minneapolis y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470484,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/26\/dichos-funcionarios-trump-alex-pretti-trax\/","url_meta":{"origin":1470457,"position":1},"title":"Lo que dijeron los funcionarios de Trump sobre Alex Pretti, y lo que realmente muestran las pruebas","author":"","date":"enero 26, 2026","format":false,"excerpt":"Los altos funcionarios de la administraci\u00f3n del presidente Donald Trump han respondido a la muerte de Alex Pretti a manos de la Patrulla Fronteriza en Minneapolis el s\u00e1bado con una avalancha de afirmaciones que est\u00e1n contradichas por videos o no cuentan con pruebas presentadas hasta ahora.La secretaria de Seguridad Nacional,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470538,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/27\/exclusivo-agentes-dispararon-encuentro-pretti-dhs-trax\/","url_meta":{"origin":1470457,"position":2},"title":"Exclusivo: los agentes dispararon sus armas durante el encuentro con Pretti, dice el DHS en informe inicial","author":"","date":"enero 27, 2026","format":false,"excerpt":"Dos agentes dispararon sus armas durante el mortal encuentro con Alex Pretti en Minneapolis durante el fin de semana, de acuerdo con un informe inicial al Congreso del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) revisado por CNN.El informe \u2014de la investigaci\u00f3n inicial de la Oficina de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470479,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/26\/videos-testigos-momentos-previos-tiroteo-alex-pretti-trax\/","url_meta":{"origin":1470457,"position":3},"title":"Videos y declaraciones de testigos aportan detalles sobre los momentos previos al tiroteo en el que muri\u00f3 Alex Pretti","author":"","date":"enero 26, 2026","format":false,"excerpt":"Poco antes de su fatal encuentro con agentes federales de inmigraci\u00f3n el s\u00e1bado, Alex Pretti fue confrontado en una calle de Minneapolis por un agente que luego estuvo en la escena del tiroteo, seg\u00fan muestra un video analizado por CNN.Ese video, combinado con declaraciones judiciales presentadas por testigos presenciales, arroja\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470764,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/02\/narrativa-gobierno-trump-muerte-alex-pretti-desmoronada-analisis-trax\/","url_meta":{"origin":1470457,"position":4},"title":"La narrativa del Gobierno de Trump sobre la muerte de Alex Pretti se ha desmoronado","author":"","date":"febrero 2, 2026","format":false,"excerpt":"Seamos sinceros: bajo el peso de la creciente evidencia en video y las declaraciones posteriores de altos funcionarios del Gobierno de Trump, la narrativa que presentaba a Alex Pretti como un terrorista interno empe\u00f1ado en masacrar agentes federales se ha desmoronado.Ahora, altos funcionarios del Gobierno parecen estar echando la culpa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470508,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/26\/confusion-interrogantes-punto-encuentran-investigaciones-trax\/","url_meta":{"origin":1470457,"position":5},"title":"Confusi\u00f3n e interrogantes: \u00bfEn qu\u00e9 punto se encuentran las investigaciones sobre la muerte de Alex Pretti?","author":"","date":"enero 26, 2026","format":false,"excerpt":"Dos d\u00edas despu\u00e9s de que agentes del Departamento de Seguridad Nacional dispararan y mataran a Alex Pretti, est\u00e1 en curso una investigaci\u00f3n confusa.El Departamento de Justicia no ha abierto pesquisas sobre derechos civiles, ha sido instalado un centro de coordinaci\u00f3n de crisis en Minneapolis para investigar a los manifestantes y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1470457"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470457\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1470457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1470457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1470457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}