{"id":1470463,"date":"2026-01-25T10:03:50","date_gmt":"2026-01-25T18:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/"},"modified":"2026-01-25T10:03:50","modified_gmt":"2026-01-25T18:03:50","slug":"nuevas-excarcelaciones-presos-politicos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/","title":{"rendered":"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela"},"content":{"rendered":"<p>La organizaci\u00f3n no gubernamental Foro Penal dijo que al menos 80 presos pol\u00edticos fueron liberados este domingo en Venezuela, mientras trabaja por confirmar las identidades de los involucrados.<\/p>\n<p>\u201cAl menos 80 presos pol\u00edticos que estamos verificando han sido excarcelados el d\u00eda de hoy en todo el pa\u00eds. Probablemente se producen m\u00e1s excarcelaciones\u201d, dijo <a href=\"https:\/\/x.com\/alfredoromero\/status\/2015452350526128307\">en X<\/a> el presidente de la ONG, Alfredo Romero.<\/p>\n<p>Por su parte, Gonzalo Himiob, vicepresidente de Foro Penal, <a href=\"https:\/\/x.com\/HimiobSantome\/status\/2015451473744634233\">dijo<\/a> que las excarcelaciones \u201cse habr\u00edan producido durante la madrugada\u201d y agreg\u00f3 que el n\u00famero \u201cpuede aumentar a medida que hagamos mas verificaciones\u201d.<\/p>\n<p>Es una de las cifras diarias m\u00e1s altas desde que el titular de la Asamblea Nacional, Jorge Rodr\u00edguez, anunci\u00f3 a inicios de mes que el Gobierno liberar\u00eda a \u201cun n\u00famero importante\u201d de detenidos.<\/p>\n<p>CNN envi\u00f3 una consulta al Gobierno de Venezuela, que por el momento no ha emitido un comunicado al respecto. La presidenta encargada, Delcy Rodr\u00edguez, dijo el viernes que 626 personas han sido excarceladas en las \u00faltimas semanas en el pa\u00eds y anunci\u00f3 que llamar\u00e1 a la oficina del Alto Comisionado de las Naciones Unidas, Volker T\u00fcrk, para que verifique la lista, que no ha sido difundida pese a reclamos de activistas y opositores.<\/p>\n<p>Hasta el viernes, Foro Penal contabilizaba la excarcelaci\u00f3n de 156 presos pol\u00edticos desde el 8 de enero, tras constataciones con los familiares.<\/p>\n<p>Por su parte, la organizaci\u00f3n Justicia, Encuentro y Perd\u00f3n difundi\u00f3 este domingo una lista de 191 excarcelados en los \u00faltimos 20 d\u00edas que, seg\u00fan sus datos, son cerca del \u201c15 % del total de casos de presos pol\u00edticos identificados\u201d en el pa\u00eds.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n no gubernamental Foro Penal dijo que al menos 80 presos pol\u00edticos fueron liberados este domingo en Venezuela, mientras trabaja por confirmar las identidades de los involucrados. \u201cAl menos 80 presos pol\u00edticos que estamos verificando han sido excarcelados el d\u00eda de hoy en todo el pa\u00eds. Probablemente se producen m\u00e1s excarcelaciones\u201d, dijo en X [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470463","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"La organizaci\u00f3n no gubernamental Foro Penal dijo que al menos 80 presos pol\u00edticos fueron liberados este domingo en Venezuela, mientras trabaja por confirmar las identidades de los involucrados. \u201cAl menos 80 presos pol\u00edticos que estamos verificando han sido excarcelados el d\u00eda de hoy en todo el pa\u00eds. Probablemente se producen m\u00e1s excarcelaciones\u201d, dijo en X [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-25T18:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela\",\"datePublished\":\"2026-01-25T18:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/\"},\"wordCount\":307,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/\",\"name\":\"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-25T18:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela - Noticias","og_description":"La organizaci\u00f3n no gubernamental Foro Penal dijo que al menos 80 presos pol\u00edticos fueron liberados este domingo en Venezuela, mientras trabaja por confirmar las identidades de los involucrados. \u201cAl menos 80 presos pol\u00edticos que estamos verificando han sido excarcelados el d\u00eda de hoy en todo el pa\u00eds. Probablemente se producen m\u00e1s excarcelaciones\u201d, dijo en X [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-25T18:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/"},"author":{"name":"","@id":""},"headline":"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela","datePublished":"2026-01-25T18:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/"},"wordCount":307,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/","name":"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-25T18:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela","url":"http:\/\/noticiasya.com\/reno\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-25T18:03:50Z","datePublished":"2026-01-25T18:03:50Z","dateModified":"2026-01-25T18:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\\u00edticos en Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/01\\\/25\\\/nuevas-excarcelaciones-presos-politicos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/01\\\/25\\\/nuevas-excarcelaciones-presos-politicos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-25T18:03:50Z\",\"datePublished\":\"2026-01-25T18:03:50Z\",\"dateModified\":\"2026-01-25T18:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470194,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/17\/foro-penal-confirma-139-excarcelaciones-presos-politicos-orix\/","url_meta":{"origin":1470463,"position":0},"title":"Foro Penal dice que ha confirmado 139 excarcelaciones de presos pol\u00edticos en Venezuela desde el 8 de enero","author":"","date":"enero 17, 2026","format":false,"excerpt":"139 presos pol\u00edticos han sido excarcelados en Venezuela desde el 8 de enero, dijo este s\u00e1bado Gonzalo Himiob Santom\u00e9, director vicepresidente de la organizaci\u00f3n no gubernamental de derechos humanos Foro Penal.Himiob detall\u00f3 que ese n\u00famero se registr\u00f3 hasta las 5 PM del s\u00e1bado, hora local de Venezuela, seg\u00fan dijo en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470086,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/14\/foro-penal-numeros-presos-politicos-excarcelados-orix\/","url_meta":{"origin":1470463,"position":1},"title":"Las divergencias entre las cifras de excarcelados reportadas por el Gobierno y por Foro Penal en Venezuela: qu\u00e9 dice cada uno","author":"","date":"enero 14, 2026","format":false,"excerpt":"Casi una semana despu\u00e9s de que el presidente de la Asamblea Nacional de Venezuela, Jorge Rodr\u00edguez, anunci\u00f3 que saldr\u00edan de prisi\u00f3n un gran n\u00famero de presos pol\u00edticos, la informaci\u00f3n oficial es escasa y hay marcadas diferencias entre los datos que anunci\u00f3 el Gobierno venezolano y los que reportan organizaciones no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470002,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/12\/exacarcelaciones-presos-politicos-venezuela-rodeo-crisalidas-orix\/","url_meta":{"origin":1470463,"position":2},"title":"Al menos 24 presos pol\u00edticos fueron excarcelados esta madrugada en Venezuela, seg\u00fan Foro Penal","author":"","date":"enero 12, 2026","format":false,"excerpt":"Al menos 24 presos pol\u00edticos fueron excarcelados esta madrugada en Venezuela, seg\u00fan confirm\u00f3 la ONG Foro Penal. Se trata de 9 mujeres que estaban en la c\u00e1rcel Las Cris\u00e1lidas y unos 15 hombres que estaban detenidos en el penal Rodeo I, detall\u00f3 Alfredo Romero, presidente de Foro Penal, en su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469960,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/","url_meta":{"origin":1470463,"position":3},"title":"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela","author":"","date":"enero 10, 2026","format":false,"excerpt":"El director presidente de la organizaci\u00f3n sin fines de lucro Foro Penal, Alfredo Romero, dijo este s\u00e1bado que hasta ahora han confirmado la excarcelaci\u00f3n de doce presos pol\u00edticos desde el anuncio del jueves por parte del presidente de la Asamblea Nacional, Jorge Rodr\u00edguez, quien asegur\u00f3 que Venezuela liberar\u00eda \u201cun n\u00famero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456810,"url":"https:\/\/noticiasya.com\/reno\/2024\/12\/20\/fiscalia-venezuela-dice-733-excarcelaciones-protestas-orix\/","url_meta":{"origin":1470463,"position":4},"title":"Fiscal\u00eda de Venezuela dice que suman 733 excarcelaciones tras protestas poselectorales; Foro Penal registra solo 155","author":"","date":"diciembre 20, 2024","format":false,"excerpt":"La Fiscal\u00eda General de Venezuela dijo este viernes que excarcel\u00f3 a otras 200 personas que fueron detenidas durante las protestas ocurridas despu\u00e9s de las controvertidas elecciones presidenciales del 28 de julio, con lo cual, seg\u00fan la instituci\u00f3n, suman 733 excarcelaciones.En un comunicado, la Fiscal\u00eda dijo que continuar\u00e1 con la revisi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469713,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/01\/excarcelacion-personas-detenidas-tocoron-orix\/","url_meta":{"origin":1470463,"position":5},"title":"Gobierno de Venezuela anuncia excarcelaci\u00f3n de 88 personas detenidas durante las protestas de 2024","author":"","date":"enero 1, 2026","format":false,"excerpt":"El Gobierno de Venezuela anunci\u00f3 este jueves la excarcelaci\u00f3n de 88 personas detenidas en medio de la crisis poselectoral tras la votaci\u00f3n presidencial de 2024, apenas una semana despu\u00e9s de la liberaci\u00f3n de otras 99 personas en Navidad.El Ministerio del Poder Popular para el Servicio Penitenciario dijo en redes sociales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1470463"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470463\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1470463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1470463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1470463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}