{"id":1470467,"date":"2026-01-25T15:03:48","date_gmt":"2026-01-25T23:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/"},"modified":"2026-01-25T15:03:48","modified_gmt":"2026-01-25T23:03:48","slug":"trump-discombobulator-arma-secreta-captura-maduro-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/","title":{"rendered":"Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro"},"content":{"rendered":"<p>El presidente Donald Trump afirm\u00f3 que Estados Unidos utiliz\u00f3 un arma a la que se refiri\u00f3 como un \u201cdiscombobulator\u201d para capturar este mes al entonces presidente de Venezuela, Nicol\u00e1s Maduro, pero un alto funcionario estadounidense dijo que probablemente est\u00e1 confundiendo distintas herramientas usadas por el Ej\u00e9rcito de EE.UU.<\/p>\n<p>\u201cEl \u2018discombobulator\u2019, no tengo permitido hablar de eso\u201d, dijo Trump al <a href=\"https:\/\/nypost.com\/2026\/01\/24\/us-news\/trump-reveals-to-the-post-secret-discombobulator-weapon-was-crucial-to-venezuelan-raid-on-maduro\/\">New York Post<\/a> en una entrevista publicada el s\u00e1bado, aunque a\u00f1adi\u00f3 que hizo que \u201cel equipo [enemigo] dejara de funcionar\u201d durante la captura.<\/p>\n<p>El presidente podr\u00eda estar combinando varias capacidades en una sola arma que no existe, dijo un alto funcionario estadounidense a CNN. Las fuerzas de EE.UU. s\u00ed utilizaron herramientas cibern\u00e9ticas para desactivar los sistemas de alerta temprana y otras defensas venezolanas durante la operaci\u00f3n, y tambi\u00e9n emplearon sistemas ac\u00fasticos existentes para desorientar al personal en tierra.<\/p>\n<p>Las Fuerzas Armadas de EE.UU. tambi\u00e9n cuentan desde hace a\u00f1os con un arma de rayo de calor, llamada Sistema de Negaci\u00f3n Activa (Active Denial System, ADS), que utiliza energ\u00eda dirigida y pulsada. Se desconoce si esta tambi\u00e9n fue utilizada.<\/p>\n<p>CNN inform\u00f3 previamente que el ADS, seg\u00fan el ej\u00e9rcito de EE.UU., es un arma no letal que dispara un rayo invisible de ondas electromagn\u00e9ticas que puede alcanzar poco m\u00e1s de medio kil\u00f3metro. Penetra la piel humana y crea una sensaci\u00f3n de calor que hace que las personas se alejen del rayo.<\/p>\n<p>Pocos d\u00edas despu\u00e9s de la captura de Maduro, la<a href=\"https:\/\/x.com\/PressSec\/status\/2009997866425897308?s=20\"> secretaria de prensa de la Casa Blanca, Karoline Leavitt,<\/a> volvi\u00f3 a publicar comentarios supuestamente de un guardia de seguridad venezolano que afirm\u00f3 que Estados Unidos \u201clanz\u00f3 algo\u201d durante la operaci\u00f3n que \u201cera como una onda sonora muy intensa\u201d.<\/p>\n<p>\u201cDe repente sent\u00ed como si mi cabeza estuviera explotando desde adentro\u201d, agreg\u00f3 el guardia de seguridad. \u201cTodos empezamos a sangrar por la nariz. Algunos vomitaban sangre. Ca\u00edmos al suelo, incapaces de movernos\u201d.<\/p>\n<p>Ese testimonio no ha sido verificado por CNN.<\/p>\n<p>Seg\u00fan el <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/23\/venezuela\/maduro-captura-riesgos-eeuu-trax\">an\u00e1lisis de CNN sobre la operaci\u00f3n del 3 de enero<\/a>, la misi\u00f3n estadounidense comenz\u00f3 con una serie de ataques contra objetivos en todo el pa\u00eds, que inutilizaron radares, comunicaciones e infraestructura de defensa a\u00e9rea, y despejaron el camino para helic\u00f3pteros estadounidenses.<\/p>\n<p>M\u00e1s de 150 aeronaves \u2014incluidos bombarderos, cazas y plataformas de inteligencia y vigilancia\u2014 despegaron desde 20 bases en tierra y en el mar, seg\u00fan el general de la Fuerza A\u00e9rea Dan Caine, jefe del Estado Mayor Conjunto de EE.UU.<\/p>\n<p>Seg\u00fan un experto, es probable que Estados Unidos tambi\u00e9n haya utilizado drones de ataque de una sola v\u00eda para los ataques en la ciudad costera de Higuerote, donde hay sistemas de defensa a\u00e9rea venezolanos.<\/p>\n<p>Videos del momento en que las fuerzas estadounidenses aterrizaron dentro del complejo militar de Fuerte Tiuna muestran r\u00e1fagas sostenidas de disparos, cuyo sonido \u2014seg\u00fan expertos militares\u2014 es consistente con helic\u00f3pteros de ataque estadounidenses MH-60 Black Hawk de acci\u00f3n directa, disparando ca\u00f1ones autom\u00e1ticos de 30 mil\u00edmetros.<\/p>\n<p>La ubicaci\u00f3n exacta dentro de Fuerte Tiuna donde Maduro fue capturado, as\u00ed como los detalles de lo ocurrido cuando las fuerzas estadounidenses ingresaron al complejo, no han sido revelados por completo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump afirm\u00f3 que Estados Unidos utiliz\u00f3 un arma a la que se refiri\u00f3 como un \u201cdiscombobulator\u201d para capturar este mes al entonces presidente de Venezuela, Nicol\u00e1s Maduro, pero un alto funcionario estadounidense dijo que probablemente est\u00e1 confundiendo distintas herramientas usadas por el Ej\u00e9rcito de EE.UU. \u201cEl \u2018discombobulator\u2019, no tengo permitido hablar de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470467","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump afirm\u00f3 que Estados Unidos utiliz\u00f3 un arma a la que se refiri\u00f3 como un \u201cdiscombobulator\u201d para capturar este mes al entonces presidente de Venezuela, Nicol\u00e1s Maduro, pero un alto funcionario estadounidense dijo que probablemente est\u00e1 confundiendo distintas herramientas usadas por el Ej\u00e9rcito de EE.UU. \u201cEl \u2018discombobulator\u2019, no tengo permitido hablar de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-25T23:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro\",\"datePublished\":\"2026-01-25T23:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/\"},\"wordCount\":583,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/\",\"name\":\"Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-25T23:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro - Noticias","og_description":"El presidente Donald Trump afirm\u00f3 que Estados Unidos utiliz\u00f3 un arma a la que se refiri\u00f3 como un \u201cdiscombobulator\u201d para capturar este mes al entonces presidente de Venezuela, Nicol\u00e1s Maduro, pero un alto funcionario estadounidense dijo que probablemente est\u00e1 confundiendo distintas herramientas usadas por el Ej\u00e9rcito de EE.UU. \u201cEl \u2018discombobulator\u2019, no tengo permitido hablar de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-25T23:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/"},"author":{"name":"","@id":""},"headline":"Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro","datePublished":"2026-01-25T23:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/"},"wordCount":583,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/","name":"Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-25T23:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro","url":"http:\/\/noticiasya.com\/reno\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-25T23:03:48Z","datePublished":"2026-01-25T23:03:48Z","dateModified":"2026-01-25T23:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump afirma que se us\\u00f3 un arma secreta para ayudar a capturar a Maduro\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/01\\\/25\\\/trump-discombobulator-arma-secreta-captura-maduro-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/01\\\/25\\\/trump-discombobulator-arma-secreta-captura-maduro-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-25T23:03:48Z\",\"datePublished\":\"2026-01-25T23:03:48Z\",\"dateModified\":\"2026-01-25T23:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473093,"url":"https:\/\/noticiasya.com\/reno\/2026\/04\/13\/papa-leon-xiv-miedo-trump-guerra-trax\/","url_meta":{"origin":1470467,"position":0},"title":"El papa dice que &#171;no tiene miedo de la administraci\u00f3n Trump&#187; tras las cr\u00edticas del presidente a su posici\u00f3n sobre la guerra","author":"","date":"abril 13, 2026","format":false,"excerpt":"El papa Le\u00f3n XIV rechaz\u00f3 con firmeza este lunes las cr\u00edticas del presidente de Estados Unidos, Donald Trump, y defendi\u00f3 su postura de buscar la paz y rechazar la violencia en medio de la guerra con Ir\u00e1n.\u201cNo tengo miedo de la administraci\u00f3n Trump ni de hablar en voz alta del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468443,"url":"https:\/\/noticiasya.com\/reno\/2025\/11\/17\/maduro-intervencion-fin-politico-trump-dialogo-orix\/","url_meta":{"origin":1470467,"position":1},"title":"Maduro advierte que una intervenci\u00f3n militar de EE.UU. ser\u00eda el &#171;fin pol\u00edtico&#187; de Trump y abre la puerta a un di\u00e1logo","author":"","date":"noviembre 17, 2025","format":false,"excerpt":"El presidente de Venezuela, Nicol\u00e1s Maduro, dijo este lunes que una intervenci\u00f3n militar de Estados Unidos en su pa\u00eds ser\u00eda el \u201cfin pol\u00edtico\u201d del liderazgo de Donald Trump.En su programa semanal en VTV, Maduro afirm\u00f3 que sectores dentro y fuera del entorno del presidente estadounidense estar\u00edan \u201cprovocando\u201d una acci\u00f3n armada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469777,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/04\/venezuela-politica-gobierno-petroleo-trump-maduro-trax\/","url_meta":{"origin":1470467,"position":2},"title":"Surge una imagen m\u00e1s clara de lo que Trump quiso decir cuando afirm\u00f3 que EE.UU. &#171;dirigir\u00e1&#187; Venezuela","author":"","date":"enero 4, 2026","format":false,"excerpt":"El Gobierno del presidente Donald Trump trabaja para establecer un gobierno interino af\u00edn en Venezuela tras la dram\u00e1tica captura de Nicol\u00e1s Maduro, seg\u00fan funcionarios estadounidenses, priorizando la estabilidad administrativa y la reparaci\u00f3n de la infraestructura petrolera del pa\u00eds por encima de un giro inmediato hacia la democracia.Los funcionarios describieron una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461109,"url":"https:\/\/noticiasya.com\/reno\/2025\/04\/12\/eeuu-iran-conversaciones-nucleares-trax\/","url_meta":{"origin":1470467,"position":3},"title":"EE.UU. e Ir\u00e1n comienzan unas cruciales conversaciones nucleares en medio de amenazas de guerra de Trump","author":"","date":"abril 12, 2025","format":false,"excerpt":"Ir\u00e1n y Estados Unidos comienzan este s\u00e1bado conversaciones de alto riesgo para alcanzar un nuevo acuerdo nuclear, precedidas por la amenaza del presidente Trump de ataques militares en caso de un fracaso y la advertencia de Teher\u00e1n de que cualquier ataque en su contra arrastrar\u00eda a EE.UU. a un conflicto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473342,"url":"https:\/\/noticiasya.com\/reno\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/","url_meta":{"origin":1470467,"position":4},"title":"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla","author":"","date":"abril 20, 2026","format":false,"excerpt":"Una delegaci\u00f3n estadounidense de alto nivel se reuni\u00f3 con funcionarios del Gobierno de Cuba mientras el Gobierno de Trump intensifica sus esfuerzos para presionar a La Habana a llegar a un acuerdo, al tiempo que contin\u00faa ejerciendo su asfixia econ\u00f3mica sobre la isla.Fue una de las visitas de m\u00e1s alto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462466,"url":"https:\/\/noticiasya.com\/reno\/2025\/05\/17\/iran-rechaza-amenazas-trump-conversaciones-nucleares-trax\/","url_meta":{"origin":1470467,"position":5},"title":"Ir\u00e1n rechaza las &#171;amenazas&#187; de Trump y dice que continuar\u00e1n las conversaciones nucleares","author":"","date":"mayo 17, 2025","format":false,"excerpt":"El presidente de Ir\u00e1n, Masoud Pezeshkian, dijo que su pa\u00eds est\u00e1 a favor de las negociaciones con Estados Unidos para evitar una guerra, pero rechaz\u00f3 lo que describi\u00f3 como amenazas del presidente Donald Trump.\u201cNo buscamos una guerra, estamos a favor de la negociaci\u00f3n y del di\u00e1logo, pero tampoco tenemos miedo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1470467"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470467\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1470467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1470467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1470467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}