{"id":1470855,"date":"2026-02-04T09:03:50","date_gmt":"2026-02-04T17:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/"},"modified":"2026-02-04T09:03:50","modified_gmt":"2026-02-04T17:03:50","slug":"the-washington-post-jeff-bezos-despide-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/","title":{"rendered":"The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal"},"content":{"rendered":"<p>El diario The Washington Post despidi\u00f3 a aproximadamente uno de cada tres empleados en la ma\u00f1ana de este mi\u00e9rcoles, lo que asest\u00f3 otro duro golpe a una redacci\u00f3n que ya se encuentra al borde del colapso.<\/p>\n<p>El propietario de The Post, Jeff Bezos, no hizo comentarios hasta ahora sobre los recortes.<\/p>\n<p>Bezos ha estado presionando al equipo directivo de The Post para que la publicaci\u00f3n vuelva a ser rentable, pero muchos periodistas del peri\u00f3dico han criticado su enfoque y cuestionado sus motivos.<\/p>\n<p>\u201cBezos no intenta salvar a The Washington Post. Intenta sobrevivir a Donald Trump\u201d, declar\u00f3 Glenn Kessler, exverificador de datos del Post, en una columna a principios de esta semana.<\/p>\n<p>Bezos y la empresa que fund\u00f3, Amazon, tienen relaciones complicadas con el Gobierno de Trump. A principios de esta semana, Bezos recibi\u00f3 al secretario de Defensa, Pete Hegseth, en la empresa de cohetes Blue Origin, tambi\u00e9n de su propiedad.<\/p>\n<p>Los empleados de The Post llevaban varias semanas prepar\u00e1ndose para despidos generalizados. El mi\u00e9rcoles por la ma\u00f1ana, se les indic\u00f3 a los empleados que \u201cse quedaran en casa hoy\u201d mientras se enviaban avisos sobre los despidos.<\/p>\n<p>\u201cEstas medidas incluyen reducciones sustanciales en la redacci\u00f3n que afectan a casi todos los departamentos de noticias\u201d, declar\u00f3 el editor ejecutivo Matt Murray en un memorando interno.<\/p>\n<p>El impacto incluye la dr\u00e1stica reducci\u00f3n de la secci\u00f3n de Metro, el cierre de casi toda la secci\u00f3n de Deportes, el cierre de la secci\u00f3n de Libros y la cancelaci\u00f3n del podcast diario \u201cPost Reports\u201d, seg\u00fan informaron fuentes del peri\u00f3dico.<\/p>\n<p>La cobertura internacional del Post tambi\u00e9n se reducir\u00e1 notablemente, aunque algunas corresponsales fuera de EE.UU. mantendr\u00e1n una \u201cpresencia estrat\u00e9gica en el extranjero\u201d, afirm\u00f3 Murray.<\/p>\n<p>Tambi\u00e9n se anunciaron importantes recortes en el \u00e1rea comercial de las operaciones de The Post, que se encuentra en crisis.<\/p>\n<p>Murray afirm\u00f3 que \u201cesta reestructuraci\u00f3n ayudar\u00e1 a asegurar nuestro futuro al servicio de nuestra misi\u00f3n period\u00edstica y nos brindar\u00e1 estabilidad de cara al futuro\u201d, aunque muchos empleados se mostraron esc\u00e9pticos ante su afirmaci\u00f3n.<\/p>\n<p>Los empleados describieron los severos recortes en publicaciones en redes sociales el mi\u00e9rcoles por la ma\u00f1ana. \u201cMe voy, junto con un mont\u00f3n de los mejores del sector. Horrible\u201d, escribi\u00f3 Caroline O\u2019Donovan, reportera de The Post especializada en Amazon, en X.<\/p>\n<p>\u201cEstoy entre los cientos de personas despedidas por The Post\u201d, escribi\u00f3 Emmanuel Felton, reportero de raza y etnicidad. \u201cEsto ocurre seis meses despu\u00e9s de escuchar en una reuni\u00f3n nacional que la cobertura racial impulsa las suscripciones. No fue una decisi\u00f3n financiera, sino ideol\u00f3gica\u201d.<\/p>\n<p>El editor de The Post, Will Lewis, ha hablado en privado sobre c\u00f3mo encontrar una v\u00eda para la rentabilidad del peri\u00f3dico centrando la inversi\u00f3n en pol\u00edtica y algunas otras \u00e1reas clave, a la vez que recorta en \u00e1reas como deportes y asuntos exteriores.<\/p>\n<p>Esta conversaci\u00f3n impuls\u00f3 a equipos de reporteros a enviar a Bezos cartas vehementes en la que lo instaban a no reducir la redacci\u00f3n.<\/p>\n<p>En una carta obtenida por CNN, firmada por el jefe de la oficina, Matt Viser, y otros siete reporteros de la Casa Blanca, el personal afirm\u00f3 que no podr\u00e1 mantener su historial de excelencia period\u00edstica si el peri\u00f3dico despide a un n\u00famero significativo de empleados de otras unidades de noticias.<\/p>\n<p>\u201cSi el plan \u2014si es que hay uno\u2014 es reorientarnos hacia la pol\u00edtica, quer\u00edamos dejar en claro cu\u00e1nto dependemos de la colaboraci\u00f3n con el periodismo internacional, deportivo, local; en realidad, con todo el peri\u00f3dico. Y si otras secciones se ven afectadas, nosotros tambi\u00e9n\u201d, dijeron Viser y los dem\u00e1s firmantes.<\/p>\n<p>Pero Lewis sigui\u00f3 adelante con el plan.<\/p>\n<p>El mi\u00e9rcoles por la ma\u00f1ana, Murray escribi\u00f3 en un memorando dirigido a todo el personal: \u201cEn el futuro inmediato, nos concentraremos en \u00e1reas que demuestren autoridad, distinci\u00f3n e impacto, y que conecten con los lectores: pol\u00edtica, asuntos nacionales, personas, poder y tendencias; seguridad nacional en Washington D.C. y en el extranjero; fuerzas que configuran el futuro, como la ciencia, la salud, la medicina, la tecnolog\u00eda, el clima y los negocios; periodismo que empodere a las personas para actuar, desde consejos hasta bienestar; investigaciones reveladoras; y lo que capta la atenci\u00f3n en la cultura, en l\u00ednea y en la vida cotidiana\u201d.<\/p>\n<p>El legendario exeditor ejecutivo de The Post, Marty Baron, quien se jubil\u00f3 del peri\u00f3dico en 2021, declar\u00f3 en un comunicado que \u201ceste es uno de los d\u00edas m\u00e1s oscuros en la historia de una de las organizaciones de noticias m\u00e1s importantes del mundo\u201d.<\/p>\n<p>\u201cPor supuesto, hubo graves problemas comerciales que deb\u00edan abordarse\u201d, escribi\u00f3 Baron. \u201cNadie puede negarlo\u201d.<\/p>\n<p>The Post, como muchos otros peri\u00f3dicos estadounidenses, ha experimentado numerosas rondas de recortes de costos a lo largo de los a\u00f1os.<\/p>\n<p>Pero esas dificultades \u201cse agravaron enormemente por decisiones desacertadas que vinieron desde la c\u00fapula\u201d, escribi\u00f3 Baron.<\/p>\n<p>Cientos de miles de suscriptores leales \u201cse alejaron\u201d, escribi\u00f3 Baron, citando, entre otros factores, la decisi\u00f3n de Bezos a finales de 2024 de retirar su respaldo a Kamala Harris en una p\u00e1gina editorial.<\/p>\n<p>Esa decisi\u00f3n, aunque independiente de las operaciones de la redacci\u00f3n, provoc\u00f3 cancelaciones masivas de suscriptores, lo que perjudic\u00f3 los resultados del Post.<\/p>\n<p>Baron tambi\u00e9n cit\u00f3 lo que llam\u00f3 los repugnantes intentos de Bezos por congraciarse con Trump.<\/p>\n<p>Hace un a\u00f1o, Bezos esboz\u00f3 una nueva visi\u00f3n para la otrora respetada secci\u00f3n de opini\u00f3n del Post, promoviendo ideales libertarios, incluyendo el libre mercado y las libertades personales. Esa decisi\u00f3n llev\u00f3 al editor de opini\u00f3n David Shipley a abandonar la empresa.<\/p>\n<p>Cuando Baron dirig\u00eda la redacci\u00f3n, record\u00f3, Bezos \u201ca menudo declaraba que el \u00e9xito del Post ser\u00eda uno de los logros de los que m\u00e1s se enorgullecer\u00eda en su vida. Ojal\u00e1 hubiera percibido ese mismo esp\u00edritu hoy. No hay rastro de \u00e9l\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El diario The Washington Post despidi\u00f3 a aproximadamente uno de cada tres empleados en la ma\u00f1ana de este mi\u00e9rcoles, lo que asest\u00f3 otro duro golpe a una redacci\u00f3n que ya se encuentra al borde del colapso. El propietario de The Post, Jeff Bezos, no hizo comentarios hasta ahora sobre los recortes. Bezos ha estado presionando [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470855","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal - Noticias\" \/>\n<meta property=\"og:description\" content=\"El diario The Washington Post despidi\u00f3 a aproximadamente uno de cada tres empleados en la ma\u00f1ana de este mi\u00e9rcoles, lo que asest\u00f3 otro duro golpe a una redacci\u00f3n que ya se encuentra al borde del colapso. El propietario de The Post, Jeff Bezos, no hizo comentarios hasta ahora sobre los recortes. Bezos ha estado presionando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-04T17:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal\",\"datePublished\":\"2026-02-04T17:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/\"},\"wordCount\":1045,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/\",\"name\":\"The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-04T17:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/","og_locale":"es_ES","og_type":"article","og_title":"The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal - Noticias","og_description":"El diario The Washington Post despidi\u00f3 a aproximadamente uno de cada tres empleados en la ma\u00f1ana de este mi\u00e9rcoles, lo que asest\u00f3 otro duro golpe a una redacci\u00f3n que ya se encuentra al borde del colapso. El propietario de The Post, Jeff Bezos, no hizo comentarios hasta ahora sobre los recortes. Bezos ha estado presionando [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-04T17:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/"},"author":{"name":"","@id":""},"headline":"The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal","datePublished":"2026-02-04T17:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/"},"wordCount":1045,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/","name":"The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-04T17:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal","url":"http:\/\/noticiasya.com\/reno\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2026\/02\/04\/the-washington-post-jeff-bezos-despide-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-04T17:03:50Z","datePublished":"2026-02-04T17:03:50Z","dateModified":"2026-02-04T17:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"The Washington Post, propiedad de Jeff Bezos, despide a un tercio de su personal\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/02\\\/04\\\/the-washington-post-jeff-bezos-despide-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/02\\\/04\\\/the-washington-post-jeff-bezos-despide-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-04T17:03:50Z\",\"datePublished\":\"2026-02-04T17:03:50Z\",\"dateModified\":\"2026-02-04T17:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455416,"url":"https:\/\/noticiasya.com\/reno\/2024\/10\/29\/jeff-bezos-defiende-falta-respaldo-electorial-washington-trax\/","url_meta":{"origin":1470855,"position":0},"title":"Jeff Bezos defiende la falta de respaldo electoral del Washington Post tras la huida de suscriptores y la dimisi\u00f3n de empleados","author":"","date":"octubre 29, 2024","format":false,"excerpt":"(CNN) -- El propietario del peri\u00f3dico The Washington Post, Jeff Bezos, en sus primeros comentarios p\u00fablicos desde que desat\u00f3 el revuelo la semana pasada por su decisi\u00f3n de retener el respaldo del venerable peri\u00f3dico en la carrera presidencial, defendi\u00f3 la medida en un poco com\u00fan art\u00edculo de opini\u00f3n publicado este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455377,"url":"https:\/\/noticiasya.com\/reno\/2024\/10\/26\/washington-post-agitacion-bezos-silencio-no-respaldo-candidatura\/","url_meta":{"origin":1470855,"position":1},"title":"El Washington Post est\u00e1 sumido en una profunda agitaci\u00f3n mientras Bezos guarda silencio sobre el no respaldo a ning\u00fan candidato","author":"","date":"octubre 26, 2024","format":false,"excerpt":"(CNN) -- Un d\u00eda despu\u00e9s de que The Washington Post anunciara que no respaldar\u00eda a un candidato presidencial en las elecciones de Estados Unidos este a\u00f1o ni en el futuro, su multimillonario propietario permanece en silencio mientras el personal del peri\u00f3dico est\u00e1 convulsionado.Jeff Bezos hasta ahora ha declinado comentar sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470607,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/29\/periodistas-washington-post-piden-bezos-detener-despidos-trax\/","url_meta":{"origin":1470855,"position":2},"title":"Periodistas de pol\u00edtica de The Washington Post instan a Jeff Bezos a detener los recortes masivos esperados en la redacci\u00f3n","author":"","date":"enero 29, 2026","format":false,"excerpt":"Ante los despidos masivos que se esperan en The Washington Post en las pr\u00f3ximas semanas, equipos de periodistas est\u00e1n enviando cartas apasionadas al propietario Jeff Bezos, inst\u00e1ndolo a no reducir la redacci\u00f3n.En una carta obtenida por CNN, los periodistas del peri\u00f3dico que cubren la Casa Blanca se unieron para defender\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457212,"url":"https:\/\/noticiasya.com\/reno\/2025\/01\/04\/caricaturista-washington-post-renuncia-trax\/","url_meta":{"origin":1470855,"position":3},"title":"Caricaturista del Washington Post renuncia ante negativa del peri\u00f3dico a publicar una s\u00e1tira de Bezos y Trump","author":"","date":"enero 4, 2025","format":false,"excerpt":"La caricaturista ganadora del premio Pulitzer Ann Telnaes anunci\u00f3 el viernes que hab\u00eda renunciado a The Washington Post despu\u00e9s de que el peri\u00f3dico se negara a publicar una caricatura sat\u00edrica que mostraba al multimillonario propietario del Post, Jeff Bezos, de rodillas frente al presidente electo Donald Trump.Talnaes, que hab\u00eda estado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448054,"url":"https:\/\/noticiasya.com\/reno\/2024\/04\/13\/empresas-jeff-bezos-orix\/","url_meta":{"origin":1470855,"position":4},"title":"\u00bfCu\u00e1ntas empresas tiene Jeff Bezos?","author":"","date":"abril 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El empresario estadounidense Jeff Bezos\u00a0es la segunda persona m\u00e1s rica del mundo, seg\u00fan los rankings de Forbes y Bloomberg, con m\u00e1s de US$ 200.000 millones, pero \u00bfc\u00f3mo est\u00e1 compuesta esa fortuna?Las empresas de Bezos pueden dividirse en cinco grandes grupos.AmazonBezos fund\u00f3 Amazon en 1994 en Seattle, inicialmente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468654,"url":"https:\/\/noticiasya.com\/reno\/2025\/11\/24\/criticas-patrocinio-bezos-gala-met-trax\/","url_meta":{"origin":1470855,"position":5},"title":"La Gala del Met enfrenta cr\u00edticas por el patrocinio de Jeff Bezos y su esposa Lauren S\u00e1nchez. Esto opina Anna Wintour","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"Anna Wintour describi\u00f3 a la fil\u00e1ntropa y experiodista estadounidense Lauren S\u00e1nchez Bezos como una \u201cgran amante del vestuario y, obviamente, de la moda\u201d al ser consultada sobre las cr\u00edticas en torno a su papel como patrocinadora de la Gala del Met de 2026.En declaraciones a CNN en Doha, Qatar, durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1470855"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470855\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1470855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1470855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1470855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}