{"id":1470859,"date":"2026-02-04T11:03:39","date_gmt":"2026-02-04T19:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/"},"modified":"2026-02-04T11:03:39","modified_gmt":"2026-02-04T19:03:39","slug":"fin-tratado-new-start-armas-nucleares-rusia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/","title":{"rendered":"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de &#171;superpotencia&#187; de Rusia"},"content":{"rendered":"<p>Desde el colapso de la antigua Uni\u00f3n Sovi\u00e9tica, Rusia ha tenido un papel considerablemente disminuido en el escenario internacional.<\/p>\n<p>La desintegraci\u00f3n, en 1991, de lo que el presidente estadounidense Ronald Reagan alguna vez llam\u00f3 un \u201cimperio del mal\u201d dej\u00f3 al Kremlin con menos territorio, menos poder financiero y menos influencia en todo el mundo.<\/p>\n<p>No obstante, Rusia mantuvo su peso en un \u00e1rea crucial.<\/p>\n<p>Su estatus continuo como superpotencia nuclear, en pie de igualdad aproximada con EE.UU., garantizaba incluso a una Mosc\u00fa debilitada un lugar en la mesa principal de la diplomacia internacional.<\/p>\n<p>En cumbres nucleares, el l\u00edder del Kremlin pod\u00eda sentarse con toda pompa frente al ocupante de la Casa Blanca, como en los d\u00edas de gloria de la Guerra Fr\u00eda, para decidir sobre asuntos de seguridad internacional.<\/p>\n<p>En 2010, el entonces presidente de EE.UU., Barack Obama, y su brevemente empoderado hom\u00f3logo ruso, Dmitry Medvedev, hicieron justamente eso, al acordar el tratado New START (Tratado de Reducci\u00f3n de Armas Estrat\u00e9gicas), que en su momento fue calificado por la Casa Blanca como \u201chist\u00f3rico\u201d. El tratado New START limita a ambos pa\u00edses a un m\u00e1ximo de 1.550 ojivas nucleares estrat\u00e9gicas desplegadas en sistemas de lanzamiento, incluidos misiles bal\u00edsticos intercontinentales, misiles bal\u00edsticos lanzados desde submarinos y bombarderos.<\/p>\n<p>Pero esos d\u00edas, al igual que el propio tratado New START que expira este jueves, parecen haber terminado.<\/p>\n<p>La desaparici\u00f3n del \u00faltimo acuerdo de control de armas entre EE.UU. y Rusia \u2014acuerdo que Washington acus\u00f3 repetidamente a Mosc\u00fa de violar al negar inspecciones en instalaciones nucleares rusas\u2014 ha sido minimizada por el Gobierno de Trump, con el propio presidente estadounidense restando importancia a la aterradora perspectiva de un mundo sin l\u00edmites en armas nucleares.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/01\/15\/world\/nuclear-weapons-no-testing-record-intl-hnk-ml\">\u201cSi expira, expira\u201d<\/a>, brome\u00f3 Trump en enero, mientras suger\u00eda que eventualmente se podr\u00eda lograr un acuerdo \u201cmejor\u201d.<\/p>\n<p>Esa clara falta de urgencia en Washington contrasta marcadamente con la ansiedad en Mosc\u00fa, donde ha habido muchas quejas y lamentos sobre el tema de la reducci\u00f3n de armas.<\/p>\n<p>Hablando con periodistas en Mosc\u00fa mientras se acercaba la finalizaci\u00f3n del tratado New START, Medvedev \u2014ya no presidente, pero s\u00ed un funcionario de seguridad franco en los m\u00e1rgenes del poder\u2014 advirti\u00f3 sobre el peligro de dejar que el acuerdo expire. Sugiri\u00f3 que esto acelerar\u00eda el \u201cReloj del Juicio Final\u201d, la representaci\u00f3n simb\u00f3lica de cu\u00e1n cerca est\u00e1 la humanidad de destruir el mundo.<\/p>\n<p>\u201cNo quiero decir que esto signifique inmediatamente una cat\u00e1strofe y que comenzar\u00e1 una guerra nuclear, pero deber\u00eda preocupar a todos\u201d, a\u00f1adi\u00f3 Medvedev.<\/p>\n<p>El Kremlin ciertamente parece preocupado.<\/p>\n<p>Su propuesta de extender los t\u00e9rminos del New START, seg\u00fan el portavoz del Kremlin, Dmitry Peskov, hasta ahora ha sido recibida con silencio por parte de EE.UU., lo que amenaza con desatar una nueva era de inseguridad.<\/p>\n<p>\u201cPor primera vez, Estados Unidos y Rusia, los dos pa\u00edses que poseen los mayores arsenales nucleares del mundo, se quedar\u00e1n sin un documento fundamental que limite y establezca controles sobre estos arsenales\u201d, dijo Peskov a periodistas en una reciente conferencia telef\u00f3nica centrada en el tema nuclear.<\/p>\n<p>\u201cCreemos que esto es muy malo para la seguridad global y estrat\u00e9gica\u201d, a\u00f1adi\u00f3, apelando a temores que probablemente sean compartidos en gran parte del mundo.<\/p>\n<p>Pero las expresiones de preocupaci\u00f3n del Kremlin pueden ser m\u00e1s interesadas y estrat\u00e9gicas de lo que est\u00e1n dispuestos a admitir.<\/p>\n<p>Adem\u00e1s de verse privados de una plataforma de reducci\u00f3n de armas que exhibe uno de sus \u00faltimos vestigios de poder de la era sovi\u00e9tica, Mosc\u00fa ahora enfrenta un futuro de posible expansi\u00f3n nuclear estadounidense sin restricciones.<\/p>\n<p>El Gobierno de Trump, por ejemplo, ya ha vuelto a plantear la idea de los acorazados \u201cclase Trump\u201d dotados con armas nucleares, una medida de la era de la Guerra Fr\u00eda que fue abandonada hace d\u00e9cadas.<\/p>\n<p>La antigua Uni\u00f3n Sovi\u00e9tica podr\u00eda haber igualado esto. Pero con una econom\u00eda y un presupuesto de defensa que son una fracci\u00f3n de los de Washington, Mosc\u00fa pr\u00e1cticamente no tiene esperanzas de mantenerse al ritmo, lo que exacerba la ya enorme brecha de poder e influencia entre los viejos rivales.<\/p>\n<p>Por supuesto, EE.UU. tiene sus propias razones para permitir que el control de armas nucleares con Rusia caduque, entre ellas su deseo de incluir a China, una potencia nuclear emergente, en futuros acuerdos.<\/p>\n<p>Pero la expiraci\u00f3n de New START marca el fin de una era, no solo de los tratados de control de armas de las \u201csuperpotencias\u201d que se enfocaban exclusivamente en Mosc\u00fa y Washington, sino tambi\u00e9n de una \u00e9poca en la que EE.UU. estaba dispuesto a aceptar l\u00edmites nucleares.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el colapso de la antigua Uni\u00f3n Sovi\u00e9tica, Rusia ha tenido un papel considerablemente disminuido en el escenario internacional. La desintegraci\u00f3n, en 1991, de lo que el presidente estadounidense Ronald Reagan alguna vez llam\u00f3 un \u201cimperio del mal\u201d dej\u00f3 al Kremlin con menos territorio, menos poder financiero y menos influencia en todo el mundo. No [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470859","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de &quot;superpotencia&quot; de Rusia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de &quot;superpotencia&quot; de Rusia - Noticias\" \/>\n<meta property=\"og:description\" content=\"Desde el colapso de la antigua Uni\u00f3n Sovi\u00e9tica, Rusia ha tenido un papel considerablemente disminuido en el escenario internacional. La desintegraci\u00f3n, en 1991, de lo que el presidente estadounidense Ronald Reagan alguna vez llam\u00f3 un \u201cimperio del mal\u201d dej\u00f3 al Kremlin con menos territorio, menos poder financiero y menos influencia en todo el mundo. No [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-04T19:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de &#171;superpotencia&#187; de Rusia\",\"datePublished\":\"2026-02-04T19:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/\"},\"wordCount\":838,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/\",\"name\":\"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de \\\"superpotencia\\\" de Rusia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-04T19:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de &#171;superpotencia&#187; de Rusia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de \"superpotencia\" de Rusia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de \"superpotencia\" de Rusia - Noticias","og_description":"Desde el colapso de la antigua Uni\u00f3n Sovi\u00e9tica, Rusia ha tenido un papel considerablemente disminuido en el escenario internacional. La desintegraci\u00f3n, en 1991, de lo que el presidente estadounidense Ronald Reagan alguna vez llam\u00f3 un \u201cimperio del mal\u201d dej\u00f3 al Kremlin con menos territorio, menos poder financiero y menos influencia en todo el mundo. No [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-04T19:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/"},"author":{"name":"","@id":""},"headline":"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de &#171;superpotencia&#187; de Rusia","datePublished":"2026-02-04T19:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/"},"wordCount":838,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/","name":"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de \"superpotencia\" de Rusia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-04T19:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de &#171;superpotencia&#187; de Rusia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de &#171;superpotencia&#187; de Rusia","url":"http:\/\/noticiasya.com\/reno\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-04T19:03:39Z","datePublished":"2026-02-04T19:03:39Z","dateModified":"2026-02-04T19:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de &#171;superpotencia&#187; de Rusia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/02\\\/04\\\/fin-tratado-new-start-armas-nucleares-rusia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/02\\\/04\\\/fin-tratado-new-start-armas-nucleares-rusia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-04T19:03:39Z\",\"datePublished\":\"2026-02-04T19:03:39Z\",\"dateModified\":\"2026-02-04T19:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1463172,"url":"https:\/\/noticiasya.com\/reno\/2025\/06\/04\/amenaza-nuclear-ucrania-rusia-latam-trax\/","url_meta":{"origin":1470859,"position":0},"title":"Mientras Ucrania azota a Rusia con audaces ataques, incendiarios comentaristas pro-Kremlin hacen sonar sus sables nucleares","author":"","date":"junio 4, 2025","format":false,"excerpt":"\u00bfC\u00f3mo responder\u00e1 Mosc\u00fa a los impactantes ataques con drones ucranianos contra su flota de aviones estrat\u00e9gicos?Hasta el momento, el Kremlin ha guardado silencio, limit\u00e1ndose a decir que espera los resultados de una investigaci\u00f3n formal sobre los ataques, que impactaron bases a\u00e9reas a miles de kil\u00f3metros de la frontera con Ucrania.Pero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465083,"url":"https:\/\/noticiasya.com\/reno\/2025\/08\/03\/dmitry-medvedev-rusia-trump-trax\/","url_meta":{"origin":1470859,"position":1},"title":"De presidente a provocador: el largo camino de Dmitry Medvedev en Rusia, el &#171;perro de ataque&#187; del Kremlin","author":"","date":"agosto 3, 2025","format":false,"excerpt":"Dmitry Medvedevd ha recorrido un largo camino desde su \u00e9poca como presidente de Rusia, cuando una vez se par\u00f3 junto al entonces presidente de Estados Unidos, Barack Obama, y declar\u00f3 que \u201cla soluci\u00f3n de muchos problemas mundiales depende de la voluntad conjunta de Estados Unidos y Rusia\u201d.Esta semana, en su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465080,"url":"https:\/\/noticiasya.com\/reno\/2025\/08\/03\/trump-amenaza-nuclear-distraccion-trax\/","url_meta":{"origin":1470859,"position":2},"title":"Para Trump, la amenaza nuclear rusa podr\u00eda ser una distracci\u00f3n \u00fatil","author":"","date":"agosto 3, 2025","format":false,"excerpt":"Hay algo ligeramente indigno en el hecho de que un presidente de Estados Unidos sea incitado por un funcionario ruso de menor rango a hacer amenazas nucleares en las redes sociales.Pero eso es exactamente lo que ha hecho ahora el presidente Donald Trump al ordenar el reposicionamiento de dos submarinos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470880,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/05\/aumentan-temores-carrera-armamentista-nuclear-trax\/","url_meta":{"origin":1470859,"position":3},"title":"Aumentan los temores de una carrera armamentista nuclear despu\u00e9s de expirar el tratado entre Estados Unidos y Rusia","author":"","date":"febrero 5, 2026","format":false,"excerpt":"La expiraci\u00f3n este jueves del \u00faltimo tratado nuclear restante entre Estados Unidos y Rusia ha despertado temores de una posible carrera armamentista nuclear, debido a que las dos mayores superpotencias nucleares no tienen limitados sus arsenales por primera vez en d\u00e9cadas.\u201cEl peor de los casos es que la situaci\u00f3n se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463706,"url":"https:\/\/noticiasya.com\/reno\/2025\/06\/18\/rusia-iran-israel-aliado-conflicto-medio-oriente-trax\/","url_meta":{"origin":1470859,"position":4},"title":"Incluso si Rusia pierde otro aliado en Medio Oriente, se beneficiar\u00e1 del caos","author":"","date":"junio 18, 2025","format":false,"excerpt":"Desde hace tiempo existe una tensi\u00f3n inc\u00f3moda en el coraz\u00f3n de la compleja relaci\u00f3n del Kremlin con Medio Oriente.Por un lado, las alianzas y la influencia econ\u00f3mica rusas all\u00ed han sido tradicionalmente s\u00f3lidas.Por otro lado, como uno de los mayores productores de petr\u00f3leo y gas del mundo, Rusia tiende a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467636,"url":"https:\/\/noticiasya.com\/reno\/2025\/10\/22\/putin-ejercicios-militares-nucleares-trax\/","url_meta":{"origin":1470859,"position":5},"title":"Putin supervis\u00f3 ejercicios militares de preparaci\u00f3n de las fuerzas nucleares rusas","author":"","date":"octubre 22, 2025","format":false,"excerpt":"Las fuerzas nucleares estrat\u00e9gicas de Rusia realizaron este mi\u00e9rcoles una prueba de preparaci\u00f3n supervisada por el presidente Vladimir Putin, seg\u00fan inform\u00f3 el Kremlin.\u201cHoy llevamos a cabo un ejercicio planificado \u2014quiero enfatizar, planificado\u2014 de mando y control de las fuerzas nucleares\u201d, declar\u00f3 Putin en una videoconferencia con la c\u00fapula militar.El Ministerio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1470859"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470859\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1470859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1470859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1470859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}