{"id":1470877,"date":"2026-02-04T21:03:46","date_gmt":"2026-02-05T05:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/"},"modified":"2026-02-04T21:03:46","modified_gmt":"2026-02-05T05:03:46","slug":"correos-amistosos-vulgares-peter-attia-epstein-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/","title":{"rendered":"Correos amistosos con frases vulgares entre el famoso m\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores"},"content":{"rendered":"<p>El martes de la semana pasada, CBS News anunci\u00f3 un grupo de 19 nuevos colaboradores, como parte de los esfuerzos continuos de su reci\u00e9n instalada editora en jefe, Bari Weiss, para renovar el perfil p\u00fablico de la cadena. Entre los nombres \u2014\u201ctodos expertos en sus campos\u201d, seg\u00fan CBS\u2014 estaba el del Dr. Peter Attia, un m\u00e9dico famoso especializado en medicina de longevidad.<\/p>\n<p>Tres d\u00edas despu\u00e9s, el Departamento de Justicia public\u00f3 un nuevo conjunto de documentos de los archivos de Jeffrey Epstein, que inclu\u00edan una correspondencia amistosa y de tono sexual entre Attia y el depredador sexual convicto. En una respuesta particularmente vulgar, <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2011\/EFTA02471177.pdf\">Attia escribi\u00f3: <\/a>\u201cLa vagina es, de hecho, baja en carbohidratos. Aunque todav\u00eda estoy esperando los resultados sobre el contenido de gluten\u201d.<\/p>\n<p>Algunos de los seguidores de Attia han expresado repugnancia desde que los correos electr\u00f3nicos se hicieron p\u00fablicos.<a href=\"https:\/\/www.reddit.com\/r\/PeterAttia\/comments\/1qu5x6y\/in_defense_of_dr_peter_attias_platform\/\"> <\/a>Un usuario en Reddit, quien dijo haber aprendido \u201cmucho\u201d del trabajo de Attia a lo largo de los a\u00f1os, lo calific\u00f3 de \u201cmoralmente en bancarrota, trepador social, eg\u00f3latra\u201d. La publicaci\u00f3n m\u00e1s reciente de Attia en Instagram se llen\u00f3 de respuestas enojadas, incluida una de una<em> influencer <\/em>y enfermera retirada que dec\u00eda \u201cTIENES UNA HIJA\u201d. Otra, de un exseguidor, dijo: \u201cOjal\u00e1 pudiera recuperar cada centavo que gast\u00e9 en tu libro y en recomendarte a la gente. Me das asco\u201d.<\/p>\n<p>Attia tiene una peque\u00f1a, aunque costosa, pr\u00e1ctica m\u00e9dica llamada Early Medical, con una lista de espera para los pacientes que deseen unirse. Seg\u00fan <a href=\"https:\/\/www.cbsnews.com\/news\/dr-peter-attia-says-enjoying-longer-healthier-life-requires-serious-training-60-minutes-transcript\/\">dijo a \u201c60 Minutes\u201d de CBS en 2025,<\/a> ve\u00eda a menos de 75 pacientes. No revel\u00f3 el precio exacto de sus servicios, solo que cobraba \u201cm\u00e1s cerca de US$ 100.000 que de US$ 500.000\u201d.<\/p>\n<p>Sin embargo, su inter\u00e9s en alargar la vida lo ha convertido en un nombre destacado en los \u00faltimos a\u00f1os. Ha hecho apariciones en \u201cThe Joe Rogan Experience\u201d y en<a href=\"https:\/\/www.cnn.com\/2025\/05\/02\/business\/video\/anderson-intelligent-futures-longevity-05029aseg1-ctw-cnni-business-fast\"> CNN International,<\/a> donde fue entrevistado por Becky Anderson sobre c\u00f3mo la tecnolog\u00eda est\u00e1 cambiando la salud. Tambi\u00e9n fue entrevistado por Oprah, donde ambos hablaron sobre <a href=\"https:\/\/www.youtube.com\/watch?v=JF4vF5hkc50\">\u201cvivir mejor por m\u00e1s tiempo\u201d.<\/a> Ese video, que pod\u00eda verse a principios de esta semana en YouTube, ya no est\u00e1 disponible p\u00fablicamente.<\/p>\n<p>Y antes de que Weiss asumiera el mando en CBS News, \u00e9l habl\u00f3 con ella en<a href=\"https:\/\/www.thefp.com\/p\/outlive-living-forever-longevity-peter-attia\"> su podcast, \u201cHonestly\u201d. <\/a>En esa entrevista, Weiss dijo que Attia \u201csiempre logra ir al grano\u201d en la industria de la salud y el bienestar.<\/p>\n<p>En una declaraci\u00f3n publicada en X el lunes, Attia dijo que \u201cno estuvo involucrado en ninguna actividad delictiva\u201d, que \u201cno tuvo nada que ver con el abuso sexual ni la explotaci\u00f3n de Epstein contra nadie\u201d, y que nunca estuvo \u201cpresente en ninguna fiesta sexual\u201d. Attia no ha sido acusado de ning\u00fan delito.<\/p>\n<p>\u201cPara ser claro, nunca presenci\u00e9 comportamientos ilegales ni vi a nadie que pareciera menor de edad en su presencia\u201d, escribi\u00f3.<\/p>\n<p>Hasta el martes, CBS News supuestamente <a href=\"https:\/\/variety.com\/2026\/tv\/news\/cbs-news-pulls-peter-attia-60-minutes-segment-epstein-1236650930\/\">retir\u00f3 una repetici\u00f3n <\/a>planeada de un segmento de \u201c60 Minutes\u201d con Attia de octubre que iba a emitirse durante el Super Bowl, report\u00f3 <a href=\"https:\/\/x.com\/jeremymbarr\/status\/2018488376567955962\">primero The Guardian. <\/a>La cadena tambi\u00e9n estar\u00eda<a href=\"https:\/\/www.thewrap.com\/creative-content\/tv-shows\/peter-attia-epstein-cbs-paramount\/\"> considerando el despido de Attia, <\/a>inform\u00f3 TheWrap.<\/p>\n<p>Attia y CBS News no respondieron a las solicitudes de comentarios de CNN.<\/p>\n<p>En los \u00faltimos a\u00f1os, Attia se ha convertido en un nombre familiar para quienes tienen curiosidad sobre la medicina de longevidad, la ciencia detr\u00e1s de extender la esperanza de vida mientras se protege la salud y la vitalidad. \u00c9l llama a su programa \u201cMedicina 3.0\u201d, que dice usa tecnolog\u00eda m\u00e9dica para combatir enfermedades cr\u00f3nicas asociadas con el envejecimiento antes de que aparezcan, enfoc\u00e1ndose en la prevenci\u00f3n en lugar del tratamiento.<\/p>\n<p>Antes de convertirse en un gur\u00fa cient\u00edfico de la salud para los ricos, Attia se gradu\u00f3 de la Facultad de Medicina de la Universidad de Stanford y se form\u00f3 en el Hospital Johns Hopkins como residente de cirug\u00eda general. Pero abandon\u00f3 la residencia en 2006, cuando le faltaban dos a\u00f1os, de acuerdo con su <a href=\"https:\/\/www.cbsnews.com\/news\/dr-peter-attia-says-enjoying-longer-healthier-life-requires-serious-training-60-minutes-transcript\/\">aparici\u00f3n en \u201c60 Minutes\u201d<\/a> en 2025, y se fue a trabajar para la firma de consultor\u00eda McKinsey &#038; Company.<\/p>\n<p>Abri\u00f3 su propia consulta privada en 2014 y se centr\u00f3 en la medicina preventiva y la longevidad. Consolid\u00f3 su marca escribiendo en blogs, con art\u00edculos como \u201c\u00bfEs el az\u00facar t\u00f3xico?\u201d, y publicando videos en YouTube enfocados en ejercicios con el peso corporal y la t\u00e9cnica adecuada. En 2023, salt\u00f3 a la fama con su libro \u201cOutlive: The Science &#038; Art of Longevity\u201d, un \u00e9xito de ventas que promueve c\u00f3mo extender la esperanza de vida antes de que enfermedades como el Alzheimer, el c\u00e1ncer o la diabetes tipo 2 aparezcan.<\/p>\n<p>Ese libro, coescrito con Bill Gifford, ha vendido <a href=\"https:\/\/www.penguinrandomhouse.com\/books\/705161\/outlive-by-peter-attia-md-with-bill-gifford\/\">m\u00e1s de 3 millones de copias. <\/a>Ahora, Attia cuenta con m\u00e1s de 3 millones de seguidores combinados entre X, Instagram y YouTube, y ha atra\u00eddo la atenci\u00f3n de nombres de alto perfil como el multimillonario<a href=\"https:\/\/fortune.com\/well\/2025\/04\/01\/peter-attia-outlive-takeaways\/\"> Bill Ackman <\/a>y las celebridades de Hollywood <a href=\"https:\/\/peterattiamd.com\/hughjackman\/\">Hugh Jackman<\/a> y <a href=\"https:\/\/goop.com\/the-goop-podcast\/gwyneth-paltrow-x-peter-attia-data-backed-ways-to-support-cognition-as-you-age\/?srsltid=AfmBOopIUoqIIMfgHS9LZMjo4eThms4pQ8iB6XiehJXjir7vY-GmhBW9\">Gwyneth Paltrow<\/a>.<\/p>\n<p>El enfoque caracter\u00edstico de Attia consiste en discutir la ciencia en gran detalle. En episodios recientes de su podcast, \u201cThe Peter Attia Drive\u201d, que duran casi dos horas cada uno, invita a otros m\u00e9dicos o investigadores de la salud acreditados para discutir temas como aceites de semillas vs. grasas saturadas, profundizando en las historias de cada tipo de grasa y explicando los estudios asociados, y examina lo que la investigaci\u00f3n ha dicho sobre si el Tylenol tiene alg\u00fan efecto en el embarazo.<\/p>\n<p>Aunque estos son temas de inter\u00e9s entre el movimiento \u201cMake America Healthy Again\u201d del Gobierno de Trump, Attia evita afirmaciones tajantes y prefiere conclusiones mesuradas. En el caso del paracetamol y el embarazo, por ejemplo, describi\u00f3 la posibilidad de que tomar acetaminof\u00e9n cause que un ni\u00f1o desarrolle autismo, como ha advertido el secretario de Salud y Servicios Humanos Robert F. Kennedy Jr., como un \u201cevento poco probable\u201d.<\/p>\n<p>Aun as\u00ed, su enfoque en el ejercicio y la autooptimizaci\u00f3n lo ha hecho popular en los sectores m\u00e1s masculinos de la \u201cmanosfera\u201d.<\/p>\n<p>En su declaraci\u00f3n, Attia dijo que conoci\u00f3 a Epstein en 2014 mientras recaudaba fondos para investigaci\u00f3n cient\u00edfica, una pr\u00e1ctica com\u00fan para Epstein, quien ten\u00eda v\u00ednculos a lo largo de la academia. Entre 2014 y 2019, ambos se reunieron en \u201caproximadamente siete u ocho ocasiones\u201d en la casa de Epstein en Nueva York, escribi\u00f3.<\/p>\n<p>El nombre de Attia aparece muchas veces en los <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/04\/eeuu\/analisis-archivos-epstein-trump-clinton-musk-trax\">archivos de Epstein publicados el viernes,<\/a> incluyendo correos electr\u00f3nicos que cubren la programaci\u00f3n de visitas, llamadas telef\u00f3nicas, dolor de espalda y una \u201cpeque\u00f1a \u2018situaci\u00f3n\u2019\u201d no especificada sobre la cual Attia buscaba consejo. En todos los correos electr\u00f3nicos, Attia parece estar asombrado con Epstein, intentando hacer planes para hablar o visitarlo.<\/p>\n<p>En una cadena de correos electr\u00f3nicos de 2015 con el asunto \u201cRecib\u00ed un nuevo env\u00edo\u201d, Epstein responde \u201cyo tambi\u00e9n\u201d y la foto adjunta est\u00e1 editada por protecci\u00f3n. El intercambio contin\u00faa: Attia: \u201cPor favor, dime que encontraste esa foto en l\u00ednea\u2026 bastardo\u201d.<\/p>\n<p>Epstein: \u201cMe temo que no\u201d.<\/p>\n<p>En su declaraci\u00f3n, Attia dijo que el \u201cnuevo env\u00edo\u201d eran botellas de metformina, un medicamento que hab\u00eda recibido. La respuesta de Epstein incluy\u00f3 una foto de una mujer adulta, afirm\u00f3 Attia, y lo que sigui\u00f3 fue \u201cuna broma vulgar y de mal gusto\u201d. Llam\u00f3 al intercambio \u201cmuy vergonzoso, y no lo voy a defender\u201d.<\/p>\n<p>Tambi\u00e9n tom\u00f3 prestado un apartamento de Epstein en 2016, <a href=\"https:\/\/www.justice.gov\/age-verify?destination=\/epstein\/files\/DataSet%209\/EFTA00330605.pdf\">escribiendo a la asistente de Epstein: <\/a>\u201cMe da s\u00edndrome de abstinencia de JE cuando no lo veo\u2026\u201d<\/p>\n<p>Despu\u00e9s, ese mismo a\u00f1o,<a href=\"https:\/\/www.justice.gov\/age-verify?destination=\/epstein\/files\/DataSet%209\/EFTA01061239.pdf\"> escribi\u00f3 directamente a Epstein: \u201c<\/a>\u00a1Te extra\u00f1o!\u201d y \u201cQuiz\u00e1 deba visitarte\u201d en Palm Beach. En un correo aparte, escribi\u00f3 sobre la isla privada de Epstein, <a href=\"https:\/\/www.justice.gov\/age-verify?destination=\/epstein\/files\/DataSet%209\/EFTA00648630.pdf\">diciendo: \u201cAlg\u00fan d\u00eda tengo que visitarla\u2026\u201d<\/a> En su declaraci\u00f3n, Attia dijo que nunca fue a la isla de Epstein.<\/p>\n<p>Luego vino la frase \u201cLa vagina es, efectivamente, baja en carbohidratos\u201d, <a href=\"https:\/\/www.justice.gov\/age-verify?destination=\/epstein\/files\/DataSet%2011\/EFTA02471177.pdf\">tambi\u00e9n enviada en 2016.<\/a><\/p>\n<p>\u201cMe disculpo y lamento haberme puesto en una posici\u00f3n donde correos electr\u00f3nicos, algunos de ellos embarazosos, de mal gusto e indefendibles, ahora sean p\u00fablicos\u201d, dijo Attia en su declaraci\u00f3n.<\/p>\n<p>Algunos contenidos, como el correo electr\u00f3nico que hace referencia a una vagina, \u201cson inquietantes\u201d, escribi\u00f3 la Dra. Jen Gunter, ginec\u00f3loga obstetra, <a href=\"https:\/\/vajenda.substack.com\/p\/doj-released-files-include-emails\">en Substack, <\/a>\u201cy bien fuera de lo que la mayor\u00eda de los m\u00e9dicos considerar\u00eda apropiado enviarle a alguien que est\u00e1 obligado a registrarse como delincuente sexual porque coaccion\u00f3 a un menor para prostituci\u00f3n\u201d.<\/p>\n<p>Attia renunci\u00f3 a su cargo como director cient\u00edfico en David Protein, una popular marca de barras de prote\u00edna, <a href=\"https:\/\/x.com\/PeterRahal\/status\/2018536070183575750\">dijo su CEO Peter Rahal en X.<\/a> AG1, una marca de suplementos en polvo, tampoco emplea ya a Attia como asesor de la empresa, seg\u00fan un comunicado.<\/p>\n<p>En su declaraci\u00f3n del lunes, Attia dijo que sinti\u00f3 \u201cn\u00e1useas\u201d cuando ley\u00f3 el art\u00edculo del Miami Herald de noviembre de 2018 sobre las protecciones sist\u00e9micas que se le proporcionaron a Epstein cuando los fiscales federales le otorgaron un acuerdo de no procesamiento en 2008, a cambio de que se declarara culpable de cargos de prostituci\u00f3n en un tribunal estatal de Florida. De acuerdo con su declaraci\u00f3n, le dijo a Epstein que deb\u00eda asumir la responsabilidad e insisti\u00f3 en que Epstein financiara la atenci\u00f3n que necesitar\u00edan las v\u00edctimas.<\/p>\n<p>Seg\u00fan los archivos, menos de una semana despu\u00e9s de la publicaci\u00f3n de la historia, Attia habl\u00f3 con Epstein en un hilo de correos electr\u00f3nicos titulado \u201c\u00bfEst\u00e1s en FL?\u201d. Despu\u00e9s de mencionar el estr\u00e9s laboral, <a href=\"https:\/\/www.justice.gov\/age-verify?destination=\/epstein\/files\/DataSet%209\/EFTA01014463.pdf\">Attia pregunt\u00f3:<\/a> \u201c\u00bfCu\u00e1l es la repercusi\u00f3n de la historia reciente?\u201d No hubo respuesta de Epstein incluida en esa serie de correos electr\u00f3nicos.<\/p>\n<p>\u201cNo estoy pidiendo que me perdonen. No le pido a nadie que ignore los correos electr\u00f3nicos o que pretenda que no son desagradables. Simplemente lo son\u201d, escribi\u00f3 Attia en su declaraci\u00f3n del lunes. \u201cEl hombre que soy hoy, aproximadamente diez a\u00f1os despu\u00e9s, no los escribir\u00eda y no se asociar\u00eda en absoluto con Epstein. Cualquier crecimiento que haya tenido durante la \u00faltima d\u00e9cada no borra los correos electr\u00f3nicos que escrib\u00ed en ese entonces\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El martes de la semana pasada, CBS News anunci\u00f3 un grupo de 19 nuevos colaboradores, como parte de los esfuerzos continuos de su reci\u00e9n instalada editora en jefe, Bari Weiss, para renovar el perfil p\u00fablico de la cadena. Entre los nombres \u2014\u201ctodos expertos en sus campos\u201d, seg\u00fan CBS\u2014 estaba el del Dr. Peter Attia, un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470877","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Correos amistosos con frases vulgares entre el famoso m\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Correos amistosos con frases vulgares entre el famoso m\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores - Noticias\" \/>\n<meta property=\"og:description\" content=\"El martes de la semana pasada, CBS News anunci\u00f3 un grupo de 19 nuevos colaboradores, como parte de los esfuerzos continuos de su reci\u00e9n instalada editora en jefe, Bari Weiss, para renovar el perfil p\u00fablico de la cadena. Entre los nombres \u2014\u201ctodos expertos en sus campos\u201d, seg\u00fan CBS\u2014 estaba el del Dr. Peter Attia, un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-05T05:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Correos amistosos con frases vulgares entre el famoso m\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores\",\"datePublished\":\"2026-02-05T05:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/\"},\"wordCount\":1767,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/\",\"name\":\"Correos amistosos con frases vulgares entre el famoso m\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-05T05:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Correos amistosos con frases vulgares entre el famoso m\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Correos amistosos con frases vulgares entre el famoso m\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Correos amistosos con frases vulgares entre el famoso m\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores - Noticias","og_description":"El martes de la semana pasada, CBS News anunci\u00f3 un grupo de 19 nuevos colaboradores, como parte de los esfuerzos continuos de su reci\u00e9n instalada editora en jefe, Bari Weiss, para renovar el perfil p\u00fablico de la cadena. Entre los nombres \u2014\u201ctodos expertos en sus campos\u201d, seg\u00fan CBS\u2014 estaba el del Dr. Peter Attia, un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-05T05:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/"},"author":{"name":"","@id":""},"headline":"Correos amistosos con frases vulgares entre el famoso m\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores","datePublished":"2026-02-05T05:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/"},"wordCount":1767,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/","name":"Correos amistosos con frases vulgares entre el famoso m\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-05T05:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Correos amistosos con frases vulgares entre el famoso m\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Correos amistosos con frases vulgares entre el famoso m\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores","url":"http:\/\/noticiasya.com\/reno\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2026\/02\/04\/correos-amistosos-vulgares-peter-attia-epstein-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-05T05:03:46Z","datePublished":"2026-02-05T05:03:46Z","dateModified":"2026-02-05T05:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Correos amistosos con frases vulgares entre el famoso m\\u00e9dico Peter Attia y Jeffrey Epstein conmocionan a sus seguidores\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/02\\\/04\\\/correos-amistosos-vulgares-peter-attia-epstein-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/02\\\/04\\\/correos-amistosos-vulgares-peter-attia-epstein-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-05T05:03:46Z\",\"datePublished\":\"2026-02-05T05:03:46Z\",\"dateModified\":\"2026-02-05T05:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470807,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/03\/famosos-archivos-epstein-musk-gates-allen-trax\/","url_meta":{"origin":1470877,"position":0},"title":"\u00bfQui\u00e9nes son los famosos que aparecen en los archivos de Epstein? Musk, Gates, Allen y la lista sigue","author":"","date":"febrero 3, 2026","format":false,"excerpt":"Los principales titulares de la \u00faltima filtraci\u00f3n de archivos relacionados con el delincuente sexual convicto Jeffrey Epstein se centran en el presidente Donald Trump, el expresidente Bill Clinton, Bill Gates, Elon Musk y el expr\u00edncipe Andr\u00e9s, entre otros. Y con raz\u00f3n. Esos nombres aparecen dispersos por todos los documentos.Mientras tanto,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471214,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/13\/claves-rendicion-cuentas-caso-epstein-trax\/","url_meta":{"origin":1470877,"position":1},"title":"\u00bfC\u00f3mo ser\u00e1 la rendici\u00f3n de cuentas del caso Epstein?","author":"","date":"febrero 13, 2026","format":false,"excerpt":"No falta indignaci\u00f3n contra Jeffrey Epstein y quienes formaban parte de su red de poder e influencia.Encontrar rendici\u00f3n de cuentas, en cambio, es mucho m\u00e1s complejo, a medida que las repercusiones de los archivos impactan al Gobierno, la pol\u00edtica, el mundo acad\u00e9mico, los negocios y Hollywood.En particular, Andrew Mountbatten-Windsor, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471562,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/23\/arrestan-peter-mandelson-exembajador-reino-unido-epstein-trax\/","url_meta":{"origin":1470877,"position":2},"title":"Arrestan a Peter Mandelson, exembajador del Reino Unido en EE.UU., bajo sospecha de conducta inapropiada en un cargo p\u00fablico","author":"","date":"febrero 23, 2026","format":false,"excerpt":"El exembajador del Reino Unido en EE.UU. Peter Mandelson fue arrestado el lunes bajo sospecha de conducta inapropiada en el ejercicio de un cargo p\u00fablico, seg\u00fan PA Media.Mandelson, veterano pol\u00edtico del Partido Laborista, ha sido acusado de pasar informaci\u00f3n al delincuente sexual convicto Jeffrey Epstein cuando era secretario de negocios,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447398,"url":"https:\/\/noticiasya.com\/reno\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/","url_meta":{"origin":1470877,"position":3},"title":"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein?","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Durante los \u00faltimos d\u00edas, cientos de documentos de una demanda relacionada con Jeffrey Epstein se hicieron p\u00fablicos por primera vez. El conjunto m\u00e1s reciente de esos documentos se revel\u00f3 este martes.El alcance total de la supuesta actividad criminal de Jeffrey Epstein sigue envuelto en un velo de misterio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443507,"url":"https:\/\/noticiasya.com\/reno\/2024\/01\/11\/que-revelaron-y-que-no-los-documentos-sobre-jeffrey-epstein\/","url_meta":{"origin":1470877,"position":4},"title":"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein?","author":"","date":"enero 11, 2024","format":false,"excerpt":"(CNN) -- Durante los \u00faltimos d\u00edas, cientos de documentos de una demanda relacionada con Jeffrey Epstein se hicieron p\u00fablicos por primera vez. El conjunto m\u00e1s reciente de esos documentos se revel\u00f3 este martes.El alcance total de la supuesta actividad criminal de Jeffrey Epstein sigue envuelto en un velo de misterio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468578,"url":"https:\/\/noticiasya.com\/reno\/2025\/11\/21\/jeffrey-epstein-red-poder-revelada-trax\/","url_meta":{"origin":1470877,"position":5},"title":"Dentro de la red de poder de Jeffrey Epstein que fue revelada en los nuevos correos electr\u00f3nicos","author":"","date":"noviembre 21, 2025","format":false,"excerpt":"Son titanes de la industria y autores de best sellers, cient\u00edficos de renombre mundial y magnates bancarios, periodistas de primer nivel y figuras de poder pol\u00edtico.Mensaje tras mensaje, puede verse que a menudo recurr\u00edan al mismo hombre en busca de consejos, contactos y para bromear e intercambiar chismes sobre el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1470877"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470877\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1470877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1470877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1470877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}