{"id":1470913,"date":"2026-02-05T15:03:41","date_gmt":"2026-02-05T23:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/"},"modified":"2026-02-05T15:03:41","modified_gmt":"2026-02-05T23:03:41","slug":"bill-gates-escrutinio-lazos-epstein-documentos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/","title":{"rendered":"Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\u00f3n de documentos del Departamento de Justicia"},"content":{"rendered":"<p>La reciente publicaci\u00f3n de archivos relacionados con Jeffrey Epstein ha arrojado una nueva sombra sobre los v\u00ednculos del multimillonario Bill Gates con el delincuente sexual convicto, revelando una serie de acusaciones gr\u00e1ficas y no verificadas, as\u00ed como un nivel de coordinaci\u00f3n filantr\u00f3pica entre ambos m\u00e1s detallado de lo que se conoc\u00eda anteriormente.<\/p>\n<p>Los elementos m\u00e1s pol\u00e9micos de la publicaci\u00f3n involucran dos borradores de correos electr\u00f3nicos que, al parecer, Epstein escribi\u00f3 para s\u00ed mismo en julio de 2013. En estas notas, llenas de errores tipogr\u00e1ficos y tono hostil, Epstein parece afirmar que facilit\u00f3 encuentros sexuales para Gates y lo ayud\u00f3 a conseguir medicamentos para ocultar una infecci\u00f3n de transmisi\u00f3n sexual a su esposa.<\/p>\n<p>No est\u00e1 claro qui\u00e9n escribi\u00f3 los <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%209\/EFTA00965773.pdf\">borradores de 2013<\/a> guardados en la cuenta de correo electr\u00f3nico de Epstein, pero est\u00e1n dirigidos de Epstein a s\u00ed mismo.<\/p>\n<p>Gates ha negado rotundamente estas afirmaciones, calific\u00e1ndolas de \u201cfalsas\u201d.<\/p>\n<p>La publicaci\u00f3n m\u00e1s amplia de documentos del Departamento de Justicia, que suma m\u00e1s de 3 millones de p\u00e1ginas, contiene numerosos correos electr\u00f3nicos entre ambos que muestran la coordinaci\u00f3n de reuniones y discusiones sobre el trabajo filantr\u00f3pico de Gates.<\/p>\n<p>Todas las interacciones documentadas con Gates ocurrieron despu\u00e9s de la condena de Epstein en 2008 por cargos relacionados con la prostituci\u00f3n.<\/p>\n<p>Una revisi\u00f3n de CNN KFile encontr\u00f3 varios cientos de referencias a Gates en los archivos reci\u00e9n publicados, incluidos numerosos correos electr\u00f3nicos detallando agendas con reuniones, comidas, llamadas telef\u00f3nicas<a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2011\/EFTA02643767.pdf\"> propuestas <\/a>y esfuerzos de Epstein para concertar encuentros con Gates.<\/p>\n<p>Algunos ejemplos incluyen una cena con Gates en <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2011\/EFTA02414311.pdf\">diciembre<\/a> de 2010 y un <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2011\/EFTA02565753.pdf\">posible almuerzo<\/a> en febrero de 2013, seguido de reuniones en <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2010\/EFTA01868715.pdf\">abril<\/a> y <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2011\/EFTA02545340.pdf\">octubre de 2011.<\/a> Los registros tambi\u00e9n reflejan una reuni\u00f3n en Noruega en <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2010\/EFTA02164765.pdf\">agosto de 2012<\/a> y otra <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2010\/EFTA01871123.pdf\">una semana<\/a> despu\u00e9s, <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%209\/EFTA00692565.pdf\">dos reuniones<\/a> en febrero de 2013 y una <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%209\/EFTA00966909.pdf\">posible cena<\/a> en septiembre de 2013 en la que Epstein <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2011\/EFTA02573882.pdf\">extendi\u00f3 una invitaci\u00f3n<\/a> a un diplom\u00e1tico noruego. Adem\u00e1s, incluyen un recordatorio en Google Calendar de una reuni\u00f3n por Skype con Gates en<a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2010\/EFTA02115572.pdf\"> enero de 2014<\/a> y una reuni\u00f3n y llamada telef\u00f3nica en septiembre de 2014.<\/p>\n<p>Las fotos publicadas en noviembre por la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, procedentes del patrimonio de Epstein, tambi\u00e9n mostraban a Gates y al pr\u00edncipe Andr\u00e9s junto a un <a href=\"https:\/\/www.politico.com\/news\/2025\/12\/12\/bill-gates-appears-in-newly-released-photos-from-epstein-estate-00688695\">piloto <\/a>cerca de un avi\u00f3n, as\u00ed como una <a href=\"https:\/\/www.pbs.org\/newshour\/politics\/lolita-passports-and-more-famous-figures-pictured-in-latest-epstein-photo-release\">imagen<\/a> de Gates con una mujer cuyo rostro fue editado por protecci\u00f3n.<\/p>\n<p>Parte de los intercambios se refiere a los extensos esfuerzos filantr\u00f3picos de Gates. El cofundador de Microsoft se ha comprometido a donar la gran mayor\u00eda de su fortuna, con enfoque en la salud global y la reducci\u00f3n de la pobreza.<\/p>\n<p>Epstein ofrec\u00eda repetidamente consejos sobre el enfoque filantr\u00f3pico de Gates a trav\u00e9s de la Fundaci\u00f3n Gates, con respuestas de Gates que indican que tomaba esa orientaci\u00f3n en serio y, en ocasiones, estaba expl\u00edcitamente de acuerdo con las recomendaciones de Epstein.<\/p>\n<p>\u201cDisfrut\u00e9 mucho el desayuno\u201d, <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2011\/EFTA02597199.pdf\">escribi\u00f3<\/a> Gates a Epstein en diciembre de 2014. \u201cTodos los asistentes eran personas interesantes. Logramos hablar lo suficiente sobre filantrop\u00eda para obtener sus reacciones sin incomodarlos demasiado\u2026 As\u00ed que creo que el desayuno fue un \u00e9xito en t\u00e9rminos de relaciones que valoro y en las que seguir\u00e9 invirtiendo tiempo\u201d.<\/p>\n<p>\u201cComo siempre, a todos les ca\u00edste muy bien. Cada uno sorprendido por lo informado que estabas sobre muchos temas variados\u201d, respondi\u00f3 Epstein. \u201cSugiero que tengamos otra reuni\u00f3n. D\u00e9jame organizarla, moderarla, etc., o si prefieres, estoy dispuesto a que otra persona ocupe mi lugar, pero esa persona debe presentar una estructura, explicarla y hacer preguntas a todos\u201d.<\/p>\n<p>Epstein concluy\u00f3 ofreciendo a Gates una invitaci\u00f3n a su isla privada: \u201cAlgunas personas interesantes visitar\u00e1n la isla durante las vacaciones. Por supuesto, t\u00fa y tu familia son bienvenidos\u201d. Gates sostiene que nunca visit\u00f3 la isla y no hay indicios de que haya aceptado la invitaci\u00f3n.<\/p>\n<p>Sin embargo, los intercambios filantr\u00f3picos conviven con acusaciones mucho m\u00e1s expl\u00edcitas contenidas en el borrador no enviado del correo electr\u00f3nico de Epstein. Los dos correos, <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%209\/EFTA00965773.pdf\">fechados<\/a> el 18 de julio de 2013, <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2010\/EFTA01965732.pdf\">parecen<\/a> ser mensajes que Epstein escribi\u00f3 para s\u00ed mismo. No est\u00e1 claro si alguna vez fueron enviados.<\/p>\n<p>Aunque los correos electr\u00f3nicos sugieren en ese momento alg\u00fan tipo de distanciamiento en su amistad, las reuniones e intercambios de correos electr\u00f3nicos continuaron durante ese tiempo.<\/p>\n<p>Epstein afirm\u00f3 en un correo electr\u00f3nico que ayud\u00f3 a Gates a conseguir medicamentos \u201cpara lidiar con las consecuencias de relaciones sexuales con mujeres rusas\u201d y \u201cencuentros il\u00edcitos con mujeres casadas\u201d. El correo electr\u00f3nico tambi\u00e9n hace referencia a que Gates pidi\u00f3 a Epstein que le proporcionara Adderall para torneos de bridge.<\/p>\n<p>Un borrador de correo electr\u00f3nico alega que Gates, entre l\u00e1grimas, le pidi\u00f3 a Epstein que eliminara mensajes haciendo referencia a una infecci\u00f3n de transmisi\u00f3n sexual, \u201ctu petici\u00f3n de que te proporcionara antibi\u00f3ticos que pudieras darle a Melinda de forma encubierta\u201d, y que eliminara detalles personales expl\u00edcitos sobre su pene.<\/p>\n<p>Las denuncias contenidas en el borrador del correo electr\u00f3nico no han sido verificadas ni corroboradas. No hay indicios de que el mensaje haya sido compartido alguna vez con Gates o cualquier otra persona, y Gates no ha sido acusado de ning\u00fan delito relacionado con Epstein.<\/p>\n<p>Gates ha negado en\u00e9rgicamente las afirmaciones y un representante de Gates dijo a CNN: \u201cEstas afirmaciones son absolutamente absurdas y completamente falsas. Lo \u00fanico que demuestran estos documentos es la frustraci\u00f3n de Epstein de no tener una relaci\u00f3n continua con Gates y hasta d\u00f3nde estar\u00eda dispuesto a llegar para atrapar y difamar. Aunque el se\u00f1or Gates reconoce que reunirse con Epstein fue un grave error de juicio, niega categ\u00f3ricamente cualquier conducta inapropiada relacionada con Epstein y las horribles actividades en las que Epstein estuvo involucrado. El se\u00f1or Gates nunca visit\u00f3 la isla de Epstein, nunca asisti\u00f3 a fiestas con \u00e9l y no tuvo ninguna participaci\u00f3n en actividades ilegales asociadas con Epstein\u201d.<\/p>\n<p>Posteriormente, a Gates se le pregunt\u00f3 sobre los \u00faltimos documentos en una entrevista con Nine News, filial de CNN en Australia.<\/p>\n<p>\u201cAparentemente, Jeffrey se escribi\u00f3 un correo electr\u00f3nico a s\u00ed mismo. Ese correo electr\u00f3nico nunca fue enviado, es falso. As\u00ed que no s\u00e9 cu\u00e1l era su intenci\u00f3n. Simplemente me recuerda que cada minuto que pas\u00e9 con \u00e9l lo lamento y me disculpo por haberlo hecho\u201d, dijo Gates.<\/p>\n<p>Agreg\u00f3: \u201cEs un hecho que solo estuve en cenas, nunca fui a la isla. Nunca conoc\u00ed a ninguna mujer. Y mientras m\u00e1s salga a la luz, m\u00e1s claro ser\u00e1 que, aunque ese tiempo fue un error, no tuvo nada que ver con ese tipo de comportamiento\u201d.<\/p>\n<p>Su exesposa, Melinda French Gates, ha dicho en un reciente adelanto de una entrevista con NPR que la publicaci\u00f3n de nuevos documentos sobre Epstein le trajo recuerdos dolorosos de su matrimonio y que cualquier pregunta pendiente sobre Epstein corresponde responderla a su exesposo.<\/p>\n<p>\u201cCualesquiera que sean las preguntas que queden sobre eso \u2014ni siquiera puedo empezar a saberlo todo\u2014, esas preguntas son para esas personas e incluso para mi exmarido. Ellos tienen que responder por esas cosas, no yo\u201d, dijo.<\/p>\n<p>Se dice que los v\u00ednculos de su exesposo con Epstein fueron un factor en su divorcio, de acuerdo con una historia de 2021 del Wall Street Journal. El informe cit\u00f3 documentos que dec\u00edan que Melinda Gates y sus asesores sostuvieron varias llamadas en octubre de 2019 cuando el <a href=\"https:\/\/www.nytimes.com\/2019\/10\/12\/business\/jeffrey-epstein-bill-gates.html\">New York Times<\/a> inform\u00f3 que Gates se hab\u00eda reunido en numerosas ocasiones con Epstein.<\/p>\n<p>Epstein parece haber estado al tanto, al menos en parte, de la incomodidad de Melinda Gates por su relaci\u00f3n.<\/p>\n<p>En <a href=\"https:\/\/journaliststudio.google.com\/pinpoint\/document-view?collection=092314e384a58618&#038;utm_source=collection_share_link&#038;p=1&#038;docid=661fb20aa6d81c18_092314e384a58618_0&#038;dapvm=1\">enero de 2017<\/a>, Epstein intercambi\u00f3 mensajes con un remitente an\u00f3nimo, quien mencion\u00f3 que ver\u00eda pronto a Bill Gates. El usuario escribi\u00f3: \u201cQuiere hablar contigo, pero su esposa no lo permite\u201d.<\/p>\n<p>\u201cPor cierto, se siente mal por el fondo asesorado por donantes. Pens\u00f3 que era una gran idea, pero su esposa no lo permiti\u00f3\u201d, escribi\u00f3 el usuario an\u00f3nimo, posiblemente haciendo referencia a un fondo asesorado por donantes como una forma de continuar realizando donaciones ben\u00e9ficas.<\/p>\n<p>El usuario sugiri\u00f3 que podr\u00eda llamar a Epstein mientras estaba con Gates, agregando que Gates \u201cte aprecia\u201d y \u201cte manda saludos\u201d.<\/p>\n<p>Epstein entonces sugiri\u00f3 que Melinda se reuniera con Kathy Ruemmler, exconsejera de la Casa Blanca del presidente Barack Obama y una de las principales abogadas del pa\u00eds, como una forma de calmar las preocupaciones de Melinda Gates.<\/p>\n<p>\u201cBill conoci\u00f3 a mi amiga Kathy Ruemmler, consejera de Obama durante 5 a\u00f1os. A ella le encantar\u00eda sentarse con Melinda y darle el otro punto de vista sobre Jeffrey\u201d, escribi\u00f3 Epstein, a\u00f1adiendo: \u201cElla es una gran defensora m\u00eda\u201d.<\/p>\n<p>Ruemmler dijo anteriormente a CNN en un comunicado que nunca se reuni\u00f3 con Bill Gates ni defendi\u00f3 sus intereses ante ning\u00fan tercero, incluida Melinda Gates.<\/p>\n<p>Representantes de Bill y Melinda Gates previamente no respondieron a las solicitudes de comentarios sobre este intercambio.<\/p>\n<p>A lo largo de numerosos correos electr\u00f3nicos, Epstein y Gates discutieron su enfoque hacia la filantrop\u00eda y el trabajo en la Fundaci\u00f3n Gates, <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2011\/EFTA02561337.pdf\">con asesores<\/a> de Gates que a veces reenviaban correos electr\u00f3nicos de Epstein sobre su trabajo.<\/p>\n<p>En febrero de <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2011\/EFTA02535231.pdf\">2011<\/a>, Epstein envi\u00f3 un correo electr\u00f3nico a una persona cuyo nombre est\u00e1 editado por protecci\u00f3n: \u201cT\u00fa y yo estamos invitados a Seattle para pasar tiempo con Bill Gates\u201d.<\/p>\n<p>Dos meses despu\u00e9s, un <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2011\/EFTA02721323.pdf\">correo electr\u00f3nico<\/a> muestra a Lesley Groff, asistente de Epstein, enviando un correo a Larry Summers, exsecretario del Tesoro y expresidente de la Universidad de Harvard, advirti\u00e9ndole que no esperara cenar durante una reuni\u00f3n en<a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2010\/EFTA01868715.pdf\"> abril de 2011<\/a> en Nueva York.<\/p>\n<p>\u201cBuenos d\u00edas, Larry. Jeffrey quer\u00eda que le informara que el lunes por la noche, Bill Gates ya habr\u00e1 cenado antes de su llegada\u2026 por lo tanto, Jeffrey solo servir\u00e1 pastelitos, postres, caf\u00e9, etc\u00e9tera, ese tipo de cosas. Quiere asegurarse de que no vengas con demasiada hambre esperando cenar. Gracias por entender. Que tengas un excelente fin de semana\u201d, escribi\u00f3 Groff.<\/p>\n<p>\u201cBien. Por favor, aseg\u00farate con Jeffrey de que esto va a suceder porque estoy ajustando mucho mi agenda para estar all\u00ed. Lo espero con inter\u00e9s\u201d, respondi\u00f3 Summers.<\/p>\n<p>Otro intercambio de correos electr\u00f3nicos de<a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2011\/EFTA02589506.pdf\"> agosto de 2014 <\/a>muestra a Bill Gates y Epstein discutiendo el enfoque de Gates hacia la filantrop\u00eda, con Epstein ofreciendo consejos y Gates estando de acuerdo.<\/p>\n<p>\u201cEstoy seguro de que, con el enfoque correcto, podr\u00e1s recaudar al menos US$ 100.000 millones. Todos los de gran fortuna est\u00e1n lidiando con los mismos problemas: c\u00f3mo donar parte de su dinero\u201d, escribi\u00f3 Epstein. \u201cVeo que venderte a ti mismo no es tu punto fuerte. Normalmente, no es necesario. Aqu\u00ed creo que posiblemente har\u00e1s nuevos amigos, compartir\u00e1s ideas con un nuevo grupo de personas que quieren hacer el bien, pero no saben c\u00f3mo. Sin diapositivas, sin presentaci\u00f3n (excepto para el seguimiento con sus abogados). Me gustar\u00eda ayudarte. Ni m\u00e1s, ni menos. Me encanta la idea. Conozco el tema, conozco a la gente\u201d.<\/p>\n<p>\u201cEstoy de acuerdo en que no debo usar diapositivas ni siquiera hacer una presentaci\u00f3n\u201d, respondi\u00f3 Gates. \u201cHe pensado un poco en lo sorprendido que estoy de lo dif\u00edcil que es hacer buena filantrop\u00eda y lo que realmente ha funcionado podr\u00eda ser interesante para ellos. Encontrar\u00e9 un momento esta semana para que hablemos\u201d.<\/p>\n<p>Ese mismo mes, Epstein <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%2011\/EFTA02387671.pdf\">envi\u00f3 un correo electr\u00f3nico <\/a>al autor Michael Wolff: \u201c\u00bfQuiero que Bill Gates sugiera que la mayor estructura de fondo ben\u00e9fico fue idea m\u00eda y que, seg\u00fan \u00e9l, no conoce mejor asesor financiero, o me estoy buscando problemas?\u201d<\/p>\n<p>Un correo electr\u00f3nico del 15 de marzo de 2017 tambi\u00e9n muestra que Epstein contact\u00f3 a Gates y a Larry Cohen, CEO de Gates Ventures, y los anim\u00f3 a reunirse con Tom Barrack, asesor del presidente Donald Trump que ahora es embajador en Turqu\u00eda.<\/p>\n<p>\u201cPara aumentar la probabilidad de que consigas un impulso significativo, sugiero que te re\u00fanas con Tom Barrack en Washington\u201d, <a href=\"https:\/\/www.justice.gov\/epstein\/files\/DataSet%209\/EFTA01052097.pdf\">escribi\u00f3 <\/a>Epstein.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La reciente publicaci\u00f3n de archivos relacionados con Jeffrey Epstein ha arrojado una nueva sombra sobre los v\u00ednculos del multimillonario Bill Gates con el delincuente sexual convicto, revelando una serie de acusaciones gr\u00e1ficas y no verificadas, as\u00ed como un nivel de coordinaci\u00f3n filantr\u00f3pica entre ambos m\u00e1s detallado de lo que se conoc\u00eda anteriormente. Los elementos m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470913","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\u00f3n de documentos del Departamento de Justicia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\u00f3n de documentos del Departamento de Justicia - Noticias\" \/>\n<meta property=\"og:description\" content=\"La reciente publicaci\u00f3n de archivos relacionados con Jeffrey Epstein ha arrojado una nueva sombra sobre los v\u00ednculos del multimillonario Bill Gates con el delincuente sexual convicto, revelando una serie de acusaciones gr\u00e1ficas y no verificadas, as\u00ed como un nivel de coordinaci\u00f3n filantr\u00f3pica entre ambos m\u00e1s detallado de lo que se conoc\u00eda anteriormente. Los elementos m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-05T23:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\u00f3n de documentos del Departamento de Justicia\",\"datePublished\":\"2026-02-05T23:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/\"},\"wordCount\":2100,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/\",\"name\":\"Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\u00f3n de documentos del Departamento de Justicia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-05T23:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\u00f3n de documentos del Departamento de Justicia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\u00f3n de documentos del Departamento de Justicia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\u00f3n de documentos del Departamento de Justicia - Noticias","og_description":"La reciente publicaci\u00f3n de archivos relacionados con Jeffrey Epstein ha arrojado una nueva sombra sobre los v\u00ednculos del multimillonario Bill Gates con el delincuente sexual convicto, revelando una serie de acusaciones gr\u00e1ficas y no verificadas, as\u00ed como un nivel de coordinaci\u00f3n filantr\u00f3pica entre ambos m\u00e1s detallado de lo que se conoc\u00eda anteriormente. Los elementos m\u00e1s [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-05T23:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/"},"author":{"name":"","@id":""},"headline":"Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\u00f3n de documentos del Departamento de Justicia","datePublished":"2026-02-05T23:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/"},"wordCount":2100,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/","name":"Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\u00f3n de documentos del Departamento de Justicia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-05T23:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\u00f3n de documentos del Departamento de Justicia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\u00f3n de documentos del Departamento de Justicia","url":"http:\/\/noticiasya.com\/reno\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2026\/02\/05\/bill-gates-escrutinio-lazos-epstein-documentos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-05T23:03:41Z","datePublished":"2026-02-05T23:03:41Z","dateModified":"2026-02-05T23:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Bill Gates enfrenta nuevo escrutinio por sus lazos con Epstein tras la publicaci\\u00f3n de documentos del Departamento de Justicia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/02\\\/05\\\/bill-gates-escrutinio-lazos-epstein-documentos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/02\\\/05\\\/bill-gates-escrutinio-lazos-epstein-documentos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-05T23:03:41Z\",\"datePublished\":\"2026-02-05T23:03:41Z\",\"dateModified\":\"2026-02-05T23:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471416,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/18\/bill-gates-cancela-discurso-cumbre-vinculos-epstein-trax\/","url_meta":{"origin":1470913,"position":0},"title":"Bill Gates cancela su discurso inaugural en la cumbre de IA en medio de un nuevo escrutinio sobre los v\u00ednculos con Epstein","author":"","date":"febrero 18, 2026","format":false,"excerpt":"Bill Gates cancel\u00f3 su discurso inaugural en una cumbre de inteligencia artificial en India este jueves, confirm\u00f3 su fundaci\u00f3n, mientras el multimillonario enfrenta el escrutinio por sus v\u00ednculos con el fallecido delincuente sexual convicto Jeffrey Epstein.\u201cDespu\u00e9s de una cuidadosa consideraci\u00f3n, y para garantizar que el enfoque siga estando en las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470807,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/03\/famosos-archivos-epstein-musk-gates-allen-trax\/","url_meta":{"origin":1470913,"position":1},"title":"\u00bfQui\u00e9nes son los famosos que aparecen en los archivos de Epstein? Musk, Gates, Allen y la lista sigue","author":"","date":"febrero 3, 2026","format":false,"excerpt":"Los principales titulares de la \u00faltima filtraci\u00f3n de archivos relacionados con el delincuente sexual convicto Jeffrey Epstein se centran en el presidente Donald Trump, el expresidente Bill Clinton, Bill Gates, Elon Musk y el expr\u00edncipe Andr\u00e9s, entre otros. Y con raz\u00f3n. Esos nombres aparecen dispersos por todos los documentos.Mientras tanto,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470839,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/04\/melinda-french-gates-bill-gates-epstein-trax\/","url_meta":{"origin":1470913,"position":2},"title":"Melinda French Gates dice que su exesposo Bill Gates tiene preguntas que responder sobre sus v\u00ednculos con Epstein","author":"","date":"febrero 4, 2026","format":false,"excerpt":"Melinda French Gates dijo que se sinti\u00f3 llena de una \u201ctristeza incre\u00edble\u201d cuando la semana pasada se publicaron m\u00e1s documentos que detallan los v\u00ednculos de su exesposo y cofundador de Microsoft, Bill Gates, con el difunto delincuente sexual convicto Jeffrey Epstein.La fil\u00e1ntropa, que se divorci\u00f3 de Gates en 2021, habl\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469395,"url":"https:\/\/noticiasya.com\/reno\/2025\/12\/18\/nuevas-fotos-patrimonio-epstein-trax\/","url_meta":{"origin":1470913,"position":3},"title":"Dem\u00f3cratas de la C\u00e1mara revelan m\u00e1s fotos de Epstein ante la fecha l\u00edmite de publicaci\u00f3n de los archivos","author":"","date":"diciembre 18, 2025","format":false,"excerpt":"Los dem\u00f3cratas de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes publicaron este jueves fotos del patrimonio de Jeffrey Epstein, la \u00faltima de una serie de revelaciones intermitentes que han impulsado una importante intriga pol\u00edtica en las \u00faltimas semanas sobre qui\u00e9n podr\u00eda haber estado asociado con el delincuente sexual\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469216,"url":"https:\/\/noticiasya.com\/reno\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/","url_meta":{"origin":1470913,"position":4},"title":"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"Los dem\u00f3cratas de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes publicaron este viernes fotos del patrimonio de Jeffrey Epstein que muestran a numerosas figuras poderosas en la \u00f3rbita del difunto traficante sexual, incluyendo al presidente Donald Trump, al expresidente Bill Clinton, a Steve Bannon, Bill Gates, Richard Branson\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447391,"url":"https:\/\/noticiasya.com\/reno\/2024\/03\/26\/jeffrey-epstein-identidad-anonimato-red-traficante-sexual-trax\/","url_meta":{"origin":1470913,"position":5},"title":"Las identidades de decenas de personas vinculadas a Jeffrey Epstein ser\u00e1n reveladas muy pronto. Esto es lo que sabemos","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Se espera que las identidades de decenas de personas vinculadas a Jeffrey Epstein sean reveladas pronto, lo que podr\u00eda eliminar el manto de anonimato que hab\u00eda protegido del escrutinio p\u00fablico a gran parte de la prominente red de amigos y socios comerciales del acusado traficante sexual.Hacen p\u00fablicos documentos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1470913"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470913\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1470913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1470913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1470913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}